{"id":177320,"date":"2026-07-14T17:37:37","date_gmt":"2026-07-14T23:37:37","guid":{"rendered":"https:\/\/www.unan.edu.ni\/?page_id=177320"},"modified":"2026-07-14T17:46:30","modified_gmt":"2026-07-14T23:46:30","slug":"investigacion-e-innovacion-finca-experimental","status":"publish","type":"page","link":"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental","title":{"rendered":"Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"177320\" class=\"elementor elementor-177320\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<nav class=\"elementor-section elementor-top-section elementor-element elementor-element-64dc0db5 elementor-section-full_width elementor-section-content-middle elementor-section-height-min-height elementor-section-items-top elementor-hidden-desktop elementor-section-height-default\" data-id=\"64dc0db5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f289653\" data-id=\"6f289653\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b3df064 e-grid-align-right e-grid-align-mobile-center elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"3b3df064\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-external-link-alt elementor-repeater-item-140acc6\" href=\"https:\/\/www.unan.edu.ni\/index.php\/informacion-oficial-institucional\" title=\"Informaci\u00f3n oficial institucional\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">External-link-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-external-link-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-mail-bulk elementor-repeater-item-9b91dfe\" href=\"https:\/\/outlook.office.com\/\" target=\"_blank\" title=\"Correo institucional\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Mail-bulk<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mail-bulk\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-repeater-item-a00b9d7\" href=\"https:\/\/www.unan.edu.ni\/index.php\/directorio-telefonico\" title=\"Directorio telef\u00f3nico\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-search elementor-repeater-item-a89c94f\" href=\"#link-popup-buscar\" title=\"Buscar\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Search<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-search\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<nav class=\"elementor-section elementor-top-section elementor-element elementor-element-340999fe elementor-section-full_width elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-hidden-mobile elementor-section-height-default\" data-id=\"340999fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45543c09\" data-id=\"45543c09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b0bb015 e-grid-align-right e-grid-align-mobile-center elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"2b0bb015\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-external-link-alt elementor-repeater-item-140acc6\" href=\"https:\/\/www.unan.edu.ni\/index.php\/informacion-oficial-institucional\" title=\"Informaci\u00f3n oficial institucional\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">External-link-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-external-link-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-mail-bulk elementor-repeater-item-9b91dfe\" href=\"https:\/\/outlook.office.com\/\" target=\"_blank\" title=\"Correo institucional\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Mail-bulk<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mail-bulk\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-repeater-item-a00b9d7\" href=\"https:\/\/www.unan.edu.ni\/index.php\/directorio-telefonico\" title=\"Directorio telef\u00f3nico\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-search elementor-repeater-item-a89c94f\" href=\"#link-popup-buscar\" title=\"Buscar\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Search<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-search\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22823031 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"22823031\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fb310bd\" data-id=\"4fb310bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<nav class=\"elementor-section elementor-top-section elementor-element elementor-element-18ebd10a elementor-section-full_width elementor-section-content-bottom elementor-section-height-default elementor-section-height-default\" data-id=\"18ebd10a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;mobile&quot;],&quot;animation&quot;:&quot;none&quot;,&quot;animation_mobile&quot;:&quot;none&quot;,&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d08f13b\" data-id=\"6d08f13b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbb08ce elementor-widget elementor-widget-image\" data-id=\"cbb08ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"576\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg\" class=\"elementor-animation-shrink attachment-full size-full wp-image-18727\" alt=\"UNAN-Managua, Marca Institucional\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg 1080w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002-300x160.jpg 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002-1024x546.jpg 1024w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002-768x410.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<nav class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1b1b9400\" data-id=\"1b1b9400\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34da80cc elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"34da80cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-130e1a6d elementor-widget elementor-widget-wp-widget-maxmegamenu\" data-id=\"130e1a6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-maxmegamenu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"mega-menu-wrap-max_mega_menu_31\" class=\"mega-menu-wrap\"><div class=\"mega-menu-toggle\"><div class=\"mega-toggle-blocks-left\"><\/div><div class=\"mega-toggle-blocks-center\"><\/div><div class=\"mega-toggle-blocks-right\"><div class='mega-toggle-block mega-menu-toggle-block mega-toggle-block-1' id='mega-toggle-block-1'><button aria-controls=\"mega-menu-max_mega_menu_31\" aria-expanded=\"false\" aria-haspopup=\"true\" class='mega-toggle-standard mega-toggle-label'><span class='mega-toggle-label-closed'><\/span><span class='mega-toggle-label-open'><\/span><\/button><\/div><\/div><\/div><ul id=\"mega-menu-max_mega_menu_31\" class=\"mega-menu max-mega-menu mega-menu-horizontal mega-no-js\" data-event=\"hover_intent\" data-effect=\"fade_up\" data-effect-speed=\"200\" data-effect-mobile=\"slide_right\" data-effect-speed-mobile=\"200\" data-mobile-force-width=\"false\" data-second-click=\"go\" data-document-click=\"collapse\" data-vertical-behaviour=\"standard\" data-breakpoint=\"800\" data-unbind=\"true\" data-mobile-state=\"collapse_all\" data-mobile-direction=\"vertical\" data-mobile-back-text=\"{parent_title}\"><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-115691\" id=\"mega-menu-item-115691\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-115691\">Instituci\u00f3n<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-115691'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-115692\" id=\"mega-menu-item-115692\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-115692\">Autoridades<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-115692'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115693\" id=\"mega-menu-item-115693\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/consejo-de-direccion-superior\">Consejo de Direcci\u00f3n<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115694\" id=\"mega-menu-item-115694\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/direcciones-del-nivel-central\">Direcciones de Nivel Central<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115695\" id=\"mega-menu-item-115695\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/areas-del-conocimiento\">\u00c1reas de Conocimiento<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115696\" id=\"mega-menu-item-115696\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/centros-regionales-cur\">Centros Universitarios Regionales (CUR)<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115697\" id=\"mega-menu-item-115697\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/centros-e-institutos-de-investigacion\">Centros e Institutos de Investigaci\u00f3n<\/a><\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115698\" id=\"mega-menu-item-115698\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/la-institucion-simbolos\">Identidad<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115699\" id=\"mega-menu-item-115699\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/la-institucion-mision-y-vision\">Misi\u00f3n y Visi\u00f3n<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115700\" id=\"mega-menu-item-115700\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/la-institucion-dhc-humanidades\">Honoris Causa<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115701\" id=\"mega-menu-item-115701\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/visitante-distinguido\">Visitante Distinguido<\/a><\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115702\" id=\"mega-menu-item-115702\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/perfiles-estudiantiles\">Vida Universitaria<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-115703\" id=\"mega-menu-item-115703\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-115703\">Oferta Educativa<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-115703'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115704\" id=\"mega-menu-item-115704\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/escuela-preparatoria-acerca-de\">Escuela Preparatoria<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115705\" id=\"mega-menu-item-115705\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/oferta-educativa-areas-de-conocimiento\">Pregrado y Grado<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115706\" id=\"mega-menu-item-115706\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/unicam-universidad-en-el-campo\">Universidad en el Campo<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-130830\" id=\"mega-menu-item-130830\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-130830\">Posgrado<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-130830'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115707\" id=\"mega-menu-item-115707\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/carreras-de-posgrado\">Maestr\u00edas<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-135589\" id=\"mega-menu-item-135589\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/diplomados-unan-managua\">Diplomados<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-132101\" id=\"mega-menu-item-132101\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/cursos\">Cursos<\/a><\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115708\" id=\"mega-menu-item-115708\"><a class=\"mega-menu-link\" href=\"https:\/\/dedv.unan.edu.ni\/\">Educaci\u00f3n a Distancia Virtual<\/a><\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115709\" id=\"mega-menu-item-115709\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/internacionalizacion\">Internacionalizaci\u00f3n<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-176865\" id=\"mega-menu-item-176865\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion\">Investigaci\u00f3n e Innovaci\u00f3n<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115712\" id=\"mega-menu-item-115712\"><a class=\"mega-menu-link\" href=\"https:\/\/biblioteca.unan.edu.ni\/\">Biblioteca<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115713\" id=\"mega-menu-item-115713\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/requisitos-para-tramite-de-titulo\">Tr\u00e1mite de T\u00edtulo<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115714\" id=\"mega-menu-item-115714\"><a class=\"mega-menu-link\" href=\"https:\/\/singu.setec.edu.ni\/PortalEstudiante\">SINGU<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-hide-on-desktop mega-menu-item-120493\" id=\"mega-menu-item-120493\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/institucional\/estrategia-nacional-de-educacion-en-todas-sus-modalidades-bendiciones-y-victorias-2024-2026.odp\">Estrategia Nacional de Educaci\u00f3n<\/a><\/li><\/ul><button aria-controls=\"mega-menu-max_mega_menu_31\" aria-label=\"Close\" class='mega-close'><\/button><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<nav class=\"elementor-section elementor-top-section elementor-element elementor-element-16a206b7 elementor-section-full_width elementor-section-content-bottom elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"16a206b7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;mobile&quot;],&quot;animation&quot;:&quot;none&quot;,&quot;animation_mobile&quot;:&quot;none&quot;,&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-75f69959\" data-id=\"75f69959\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f4093f3 elementor-widget elementor-widget-image\" data-id=\"5f4093f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"576\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg\" class=\"elementor-animation-shrink attachment-full size-full wp-image-18727\" alt=\"UNAN-Managua, Marca Institucional\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg 1080w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002-300x160.jpg 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002-1024x546.jpg 1024w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002-768x410.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<nav class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1f2c8a48\" data-id=\"1f2c8a48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eacfcd8 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"4eacfcd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30b870af elementor-mobile-align-right elementor-widget elementor-widget-button\" data-id=\"30b870af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sigi.unan.edu.ni\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SINGU<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<nav class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4b55c100\" data-id=\"4b55c100\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31c4a708 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"31c4a708\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44bafda7 elementor-widget elementor-widget-wp-widget-maxmegamenu\" data-id=\"44bafda7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-maxmegamenu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"mega-menu-wrap-max_mega_menu_31\" class=\"mega-menu-wrap\"><div class=\"mega-menu-toggle\"><div class=\"mega-toggle-blocks-left\"><\/div><div class=\"mega-toggle-blocks-center\"><\/div><div class=\"mega-toggle-blocks-right\"><div class='mega-toggle-block mega-menu-toggle-block mega-toggle-block-1' id='mega-toggle-block-1'><button aria-controls=\"mega-menu-max_mega_menu_31\" aria-expanded=\"false\" aria-haspopup=\"true\" class='mega-toggle-standard mega-toggle-label'><span class='mega-toggle-label-closed'><\/span><span class='mega-toggle-label-open'><\/span><\/button><\/div><\/div><\/div><ul id=\"mega-menu-max_mega_menu_31\" class=\"mega-menu max-mega-menu mega-menu-horizontal mega-no-js\" data-event=\"hover_intent\" data-effect=\"fade_up\" data-effect-speed=\"200\" data-effect-mobile=\"slide_right\" data-effect-speed-mobile=\"200\" data-mobile-force-width=\"false\" data-second-click=\"go\" data-document-click=\"collapse\" data-vertical-behaviour=\"standard\" data-breakpoint=\"800\" data-unbind=\"true\" data-mobile-state=\"collapse_all\" data-mobile-direction=\"vertical\" data-mobile-back-text=\"{parent_title}\"><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-115691\" id=\"mega-menu-item-115691\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-115691\">Instituci\u00f3n<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-115691'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-115692\" id=\"mega-menu-item-115692\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-115692\">Autoridades<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-115692'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115693\" id=\"mega-menu-item-115693\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/consejo-de-direccion-superior\">Consejo de Direcci\u00f3n<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115694\" id=\"mega-menu-item-115694\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/direcciones-del-nivel-central\">Direcciones de Nivel Central<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115695\" id=\"mega-menu-item-115695\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/areas-del-conocimiento\">\u00c1reas de Conocimiento<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115696\" id=\"mega-menu-item-115696\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/centros-regionales-cur\">Centros Universitarios Regionales (CUR)<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115697\" id=\"mega-menu-item-115697\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/centros-e-institutos-de-investigacion\">Centros e Institutos de Investigaci\u00f3n<\/a><\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115698\" id=\"mega-menu-item-115698\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/la-institucion-simbolos\">Identidad<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115699\" id=\"mega-menu-item-115699\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/la-institucion-mision-y-vision\">Misi\u00f3n y Visi\u00f3n<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115700\" id=\"mega-menu-item-115700\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/la-institucion-dhc-humanidades\">Honoris Causa<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115701\" id=\"mega-menu-item-115701\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/visitante-distinguido\">Visitante Distinguido<\/a><\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115702\" id=\"mega-menu-item-115702\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/perfiles-estudiantiles\">Vida Universitaria<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-115703\" id=\"mega-menu-item-115703\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-115703\">Oferta Educativa<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-115703'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115704\" id=\"mega-menu-item-115704\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/escuela-preparatoria-acerca-de\">Escuela Preparatoria<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115705\" id=\"mega-menu-item-115705\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/oferta-educativa-areas-de-conocimiento\">Pregrado y Grado<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115706\" id=\"mega-menu-item-115706\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/unicam-universidad-en-el-campo\">Universidad en el Campo<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-130830\" id=\"mega-menu-item-130830\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-130830\">Posgrado<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-130830'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115707\" id=\"mega-menu-item-115707\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/carreras-de-posgrado\">Maestr\u00edas<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-135589\" id=\"mega-menu-item-135589\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/diplomados-unan-managua\">Diplomados<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-132101\" id=\"mega-menu-item-132101\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/cursos\">Cursos<\/a><\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115708\" id=\"mega-menu-item-115708\"><a class=\"mega-menu-link\" href=\"https:\/\/dedv.unan.edu.ni\/\">Educaci\u00f3n a Distancia Virtual<\/a><\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115709\" id=\"mega-menu-item-115709\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/internacionalizacion\">Internacionalizaci\u00f3n<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-176865\" id=\"mega-menu-item-176865\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion\">Investigaci\u00f3n e Innovaci\u00f3n<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115712\" id=\"mega-menu-item-115712\"><a class=\"mega-menu-link\" href=\"https:\/\/biblioteca.unan.edu.ni\/\">Biblioteca<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115713\" id=\"mega-menu-item-115713\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/requisitos-para-tramite-de-titulo\">Tr\u00e1mite de T\u00edtulo<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-115714\" id=\"mega-menu-item-115714\"><a class=\"mega-menu-link\" href=\"https:\/\/singu.setec.edu.ni\/PortalEstudiante\">SINGU<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-hide-on-desktop mega-menu-item-120493\" id=\"mega-menu-item-120493\"><a class=\"mega-menu-link\" href=\"https:\/\/www.unan.edu.ni\/index.php\/institucional\/estrategia-nacional-de-educacion-en-todas-sus-modalidades-bendiciones-y-victorias-2024-2026.odp\">Estrategia Nacional de Educaci\u00f3n<\/a><\/li><\/ul><button aria-controls=\"mega-menu-max_mega_menu_31\" aria-label=\"Close\" class='mega-close'><\/button><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<header class=\"elementor-section elementor-top-section elementor-element elementor-element-4475b75 elementor-section-full_width elementor-section-height-min-height elementor-section-items-top elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default\" data-id=\"4475b75\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-414fcedb\" data-id=\"414fcedb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58f12d2e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58f12d2e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3786356a\" data-id=\"3786356a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-325ebdab elementor-widget elementor-widget-spacer\" data-id=\"325ebdab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-50dfa4e7\" data-id=\"50dfa4e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4aa7c375 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4aa7c375\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2124648b\" data-id=\"2124648b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7557f62c elementor-widget elementor-widget-text-editor\" data-id=\"7557f62c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"color: #ffffff;\">Finca Experimental<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e0d4051 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3e0d4051\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c79769b\" data-id=\"7c79769b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c3d6a64 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"7c3d6a64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEspacio t\u00e9cnico cient\u00edfico destinado al desarrollo, validaci\u00f3n y aplicaci\u00f3n de investigaciones, innovaciones y tecnolog\u00edas en el \u00e1mbito socioproductivo. Su prop\u00f3sito es generar, adaptar, validar y transferir conocimientos mediante pr\u00e1cticas experimentales controladas que permiten evaluar sistemas de producci\u00f3n, mejorar procesos, fortalecer la sostenibilidad y promover alternativas tecnol\u00f3gicas pertinentes para el territorio. La finca experimental opera como un laboratorio vivo para la formaci\u00f3n pr\u00e1ctica, la investigaci\u00f3n, la innovaci\u00f3n y la extensi\u00f3n, articulando la generaci\u00f3n y transferencia del conocimiento con las necesidades productivas y comunitarias del territorio. De esta manera, contribuye a la seguridad y soberan\u00eda alimentaria, al manejo responsable de los recursos naturales y al desarrollo humano pleno de las personas, familias y las comunidades.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1448e908 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1448e908\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-372654b5\" data-id=\"372654b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8105e4 elementor-widget elementor-widget-text-editor\" data-id=\"a8105e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Departamento de Investigaci\u00f3n e Innovaci\u00f3n:<\/strong> <i class=\"fa-solid fa-envelope\" style=\"color: #01136F;\"><\/i> <span style=\"color: #01136F;\"><a style=\"color: #01136F;\" href=\"mail&#116;&#111;&#58;&#100;&#105;&#x6e;&#x76;&#x65;&#x73;&#x74;&#x69;&#x6e;nova&#46;&#97;&#99;&#97;&#100;&#x65;&#x6d;&#x69;&#x63;&#x61;&#x40;&#x75;&#x6e;an&#46;e&#100;&#117;&#46;&#110;&#105;\">d&#105;&#110;&#x76;&#x65;&#x73;ti&#110;&#110;&#x6f;&#x76;&#x61;&#46;&#97;&#99;&#97;&#x64;&#x65;&#x6d;i&#99;&#97;&#x40;&#x75;&#x6e;an&#46;&#101;&#x64;&#x75;&#x2e;n&#105;\n<\/a><\/span><i class=\"fa-solid fa-phone\"><\/i> 2278 6764 Ext. 5716 6218\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bc636cb elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"3bc636cb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1078c710\" data-id=\"1078c710\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1aa53f90\" data-id=\"1aa53f90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4083b3df elementor-widget elementor-widget-html\" data-id=\"4083b3df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\r\n\/* Contenedor general para agrupar ambos botones *\/\r\n.contenedor-botones {\r\n  display: flex;\r\n  justify-content: center; \/* Centra los botones horizontalmente *\/\r\n  gap: 20px;              \/* Espacio entre botones *\/\r\n  margin: 20px 0;\r\n}\r\n\r\n\/* Contenedor individual para cada bot\u00f3n (opcional para maquetar) *\/\r\n.contenedor-boton {\r\n  text-align: center;\r\n}\r\n\r\n\/* Estilos comunes para los botones *\/\r\n.boton {\r\n  display: inline-block;\r\n  width: 300px;    \/* Ajusta al ancho real de tus im\u00e1genes *\/\r\n  height: 100px;   \/* Ajusta a la altura real de tus im\u00e1genes *\/\r\n  background-repeat: no-repeat;\r\n  background-size: contain;  \/* Se adapta manteniendo la relaci\u00f3n *\/\r\n  background-position: center;\r\n  position: relative;  \/* Necesario para la superposici\u00f3n del pseudo-elemento *\/\r\n  text-decoration: none;\r\n}\r\n\r\n\/* Pseudo-elemento para aplicar la imagen hover con transici\u00f3n *\/\r\n.boton::after {\r\n  content: \"\";\r\n  position: absolute;\r\n  top: 0;\r\n  left: 0;\r\n  width: 100%;\r\n  height: 100%;\r\n  background-repeat: no-repeat;\r\n  background-size: contain;\r\n  background-position: center;\r\n  opacity: 0;\r\n  transition: opacity 0.3s ease-in-out;\r\n}\r\n\r\n\/* Estilos para el bot\u00f3n del Portal de Revistas *\/\r\n.portal-revistas-boton {\r\n  background-image: url(\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/boton_ra_a.png\");\r\n}\r\n.portal-revistas-boton::after {\r\n  background-image: url(\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/bton_ra_b.png\");\r\n}\r\n.portal-revistas-boton:hover::after {\r\n  opacity: 1;\r\n}\r\n\r\n\/* Estilos para el bot\u00f3n del Repositorio Digital *\/\r\n\/* Aseg\u00farate de sustituir las URLs por las im\u00e1genes correspondientes de tu repositorio *\/\r\n.repositorio-boton {\r\n  background-image: url(\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/boton_rai_a.png\");\r\n}\r\n.repositorio-boton::after {\r\n  background-image: url(\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/boton_ri_b.png\");\r\n}\r\n.repositorio-boton:hover::after {\r\n  opacity: 1;\r\n}\r\n\r\n\/* Estilos para el bot\u00f3n del Repositorio Digital *\/\r\n\/* Aseg\u00farate de sustituir las URLs por las im\u00e1genes correspondientes de tu repositorio *\/\r\n.investigacion-boton {\r\n  background-image: url(\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/Recursos-05-1.png\");\r\n}\r\n.investigacion-boton::after {\r\n  background-image: url(\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/Recursos-06.png\");\r\n}\r\n.investigacion-boton:hover::after {\r\n  opacity: 1;\r\n}\r\n\r\n\r\n\/* Clase para ocultar visualmente el texto pero mantenerlo para la accesibilidad *\/\r\n.sr-only {\r\n  position: absolute !important;\r\n  width: 1px;\r\n  height: 1px;\r\n  padding: 0;\r\n  margin: -1px;\r\n  overflow: hidden;\r\n  clip: rect(0, 0, 0, 0);\r\n  border: 0;\r\n}\r\n<\/style>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73a7eb29 elementor-widget elementor-widget-shortcode\" data-id=\"73a7eb29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"11959\" class=\"elementor elementor-11959\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;fadeIn&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1793abba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1793abba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30f2376a\" data-id=\"30f2376a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b51b6c8 elementor-widget elementor-widget-image\" data-id=\"4b51b6c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"138\" height=\"138\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/Information_1.png\" class=\"attachment-large size-large wp-image-11960\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3783d524 elementor-widget elementor-widget-heading\" data-id=\"3783d524\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Este enlace estar\u00e1 disponible desde el 25 de noviembre hasta el 12 de diciembre<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5571b55e elementor-widget elementor-widget-text-editor\" data-id=\"5571b55e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Direcci\u00f3n:<br \/>Registro Acad\u00e9mico Estudiantil y Estad\u00edstica<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"14887\" class=\"elementor elementor-14887\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-331246fd elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"331246fd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-176a39a6\" data-id=\"176a39a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b69a71\" data-id=\"4b69a71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e53388b elementor-widget elementor-widget-heading\" data-id=\"e53388b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Matem\u00e1tica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6be393 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"b6be393\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33669b2\" data-id=\"33669b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53ee31a elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"53ee31a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8801\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8801\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8802\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8802\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8801\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8801\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8801\" tabindex=\"0\" hidden=\"false\"><p>La Matem\u00e1tica es una ciencia que se ha desarrollado en la historia de la humanidad, conect\u00e1ndose siempre con las necesidades materiales o espirituales de los seres humanos. Actualmente es m\u00e1s patente la interdependencia del desarrollo econ\u00f3mico, tecnol\u00f3gico y cultural de un pa\u00eds con la evoluci\u00f3n conceptual y pr\u00e1ctica de esta ciencia, jugando en este sentido la educaci\u00f3n matem\u00e1tica un papel fundamental.<\/p><p>La Facultad de Educaci\u00f3n e Idiomas de la Unan-Managua responde a las exigencias de nuestro pa\u00eds con la creaci\u00f3n de la Licenciatura en Matem\u00e1tica. El egresado de esta carrera domina los contenidos matem\u00e1ticos de Educaci\u00f3n Secundaria desde una perspectiva universitaria que le permitir\u00e1 cumplir satisfactoriamente estudios de postgrado, est\u00e1 dotado de conocimientos actualizados sobre t\u00e9cnicas educativas, m\u00e9todos did\u00e1cticos, metodol\u00f3gicos, pedag\u00f3gicos y psicol\u00f3gicos, para poder insertarse con calidad y pertinencia en el cumplimiento de su ejercicio profesional. Adem\u00e1s es capaz de vincular la matem\u00e1tica con la investigaci\u00f3n pedag\u00f3gica, proponiendo soluciones a problemas locales y nacionales referidos a la ense\u00f1anza de esta ciencia y ser capaz de un autoaprendizaje efectivo para toda la vida.<\/p><p>Nuestros graduados de Matem\u00e1tica tienen una concepci\u00f3n humanista delmundo, son creativos, cr\u00edticos, reflexivos, propositivos, innovadores, salvaguardas de la identidad nacional, la conservaci\u00f3n y protecci\u00f3n de nuestro planeta, defensores de la justicia y la equidad social.<\/p><p><strong>Funcionesque realiza el Licenciado en Cienciasde la Educaci\u00f3n con Menci\u00f3n en Matem\u00e1tica<\/strong><\/p><ul><li>Planifica, dirige y eval\u00faa el proceso de ense\u00f1anza aprendizaje de Matem\u00e1tica en Educaci\u00f3n Media.<\/li><li>Apoya al proceso educativo con actividades psicopedag\u00f3gicas y propias de la especialidad, que garanticen el \u00e9xito en la obtenci\u00f3n de resultados durante el proceso de ense\u00f1anza aprendizaje.<\/li><li>Coordina, supervisa, controla y eval\u00faa todas las actividades propias del colectivo de Matem\u00e1tica, en funci\u00f3n del cumplimiento de los programas y objetivos de las asignaturas.<\/li><li>Controla y verifica el grado de cientificidad de los contenidos program\u00e1ticos y el cumplimiento del trabajo docente, mediante la implementaci\u00f3n de las pol\u00edticas educativas nacionales.<\/li><li>Establece l\u00edneas de investigaci\u00f3n en Matem\u00e1tica Educativa y coordina equipos de investigaci\u00f3n multidisciplinaria.<\/li><\/ul><p><strong><span style=\"display: inline !important;\">Cargos que desempe\u00f1a el Licenciado en Ciencias de la Educaci\u00f3n con Menci\u00f3n en Matem\u00e1tica<\/span><\/strong><\/p><ul><li><span style=\"display: inline !important;\">Profesor de Matem\u00e1tica.<\/span><\/li><li><span style=\"display: inline !important;\">Jefe de \u00e1rea en Matem\u00e1tica.<\/span><\/li><li><span style=\"display: inline !important;\">Asesor Pedag\u00f3gico en Matem\u00e1tica.<\/span><\/li><li><span style=\"display: inline !important;\">Investigador en Matem\u00e1tica Educativa.<\/span><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8802\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8802\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8802\" tabindex=\"0\" hidden=\"hidden\"><p><strong>Datos generales<\/strong><\/p><ul><li>Nombre de la Carrera: Matem\u00e1tica<\/li><li>Facultad: Educaci\u00f3n e Idiomas<\/li><li>Grado a obtener: Profesor de Educaci\u00f3n Media (PEM), Licenciado en Ciencias de la Educaci\u00f3n con Menci\u00f3n en Matem\u00e1tica<\/li><li>Total de horas del Plan de Estudios: 9630<\/li><li>Total de cr\u00e9ditos acad\u00e9micos: 214<\/li><li>R\u00e9gimen acad\u00e9mico: Semestral<\/li><li>N\u00famero de semanas seg\u00fan r\u00e9gimen acad\u00e9mico: 15<\/li><li>Modalidad: Presencial, Profesionalizaci\u00f3n<\/li><li>Turno: Matutino, Dominical<\/li><li>Sede: Recinto Universitario Rub\u00e9n Dar\u00edo, FAREM-Chontales<\/li><\/ul><p><strong>Asignaturas del plan de estudio<\/strong><\/p><p><div id=\"footable_parent_14932\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap4 colored_table\">\n                <table data-ninja_table_instance=\"ninja_table_instance_0\" data-footable_id=\"14932\" data-filter-delay=\"1000\" aria-label=\"Licenciatura en matem\u00e1tica\"            id=\"footable_14932\"\n           data-unique_identifier=\"ninja_table_unique_id_1222633459_14932\"\n           class=\" foo-table ninja_footable foo_table_14932 ninja_table_unique_id_1222633459_14932 table  nt_type_legacy_table hide_horizonal_borders hide_vertical_borders table-sm ninja_custom_color inverted footable-paging-right ninja_table_search_disabled ninja_table_pro\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                    <\/colgroup>\n        <thead>\n<tr class=\"footable-header\">\n                                                                                        <th scope=\"col\"  class=\"ninja_column_0 ninja_clmn_nm_primer_ano \">Primer a\u00f1o<\/th><th scope=\"col\"  class=\"ninja_column_1 ninja_clmn_nm_segundo_ano \">Segundo a\u00f1o<\/th><th scope=\"col\"  class=\"ninja_column_2 ninja_clmn_nm_tercer_ano \">Tercer a\u00f1o<\/th><th scope=\"col\"  class=\"ninja_column_3 ninja_clmn_nm_cuarto_ano \">Cuarto a\u00f1o<\/th><th scope=\"col\"  class=\"ninja_column_4 ninja_clmn_nm_quinto_ano \">Quinto a\u00f1o<\/th><\/tr>\n<\/thead>\n<tbody>\n\n        <tr data-row_id=\"2693\" class=\"ninja_table_row_0 nt_row_id_2693\">\n            <td>Inform\u00e1tica B\u00e1sica<br \/> T\u00e9cnicas de Lectura, Redacci\u00f3n y Ortograf\u00eda<br \/> Geograf\u00eda e Historia de Nicaragua<br \/> Matem\u00e1tica General<br \/> Introducci\u00f3n a la Filosof\u00eda<br \/> Psicolog\u00eda General y del Aprendizaje<br \/> Taller Did\u00e1ctico de Matem\u00e1tica I<br \/> T\u00e9cnicas de Investigaci\u00f3n Documental<br \/> Funciones Reales<br \/> Introducci\u00f3n a la F\u00edsica<br \/> Pedagog\u00eda General<br \/><\/td><td>Seminario de Formaci\u00f3n Integral<br \/> L\u00f3gica y Teor\u00eda de Conjuntos<br \/> Geometr\u00eda Euclidiana<br \/> Did\u00e1ctica General<br \/> Estad\u00edstica I<br \/> C\u00e1lculo Diferencial<br \/> Pr\u00e1ctica de Especializaci\u00f3n<br \/> Dominio Num\u00e9ricos<br \/> Did\u00e1ctica de la Matem\u00e1tica I<br \/> Taller Did\u00e1ctico de Matem\u00e1ticaIII<br \/><\/td><td>C\u00e1lculo Integral<br \/> Geometr\u00eda Cartesiana<br \/> Curso de Graduaci\u00f3n (PEM)<br \/> Facultativa de Carrera<br \/> Evaluaci\u00f3n Educativa<br \/> Series<br \/> Algebra Lineal<br \/> Geometr\u00eda Lineal del Espacio<br \/> Probabilidad II<br \/> Geometr\u00eda Computacional<br \/><\/td><td>Did\u00e1ctica de la Matem\u00e1tica II<br \/> C\u00e1lculo Vectorial<br \/> Estructuras Algebraicas<br \/> Estad\u00edstica II<br \/> Taller Did\u00e1ctico de Matem\u00e1tica V<br \/> Ecuaciones Diferenciales<br \/> Algebra Computacional<br \/> Pr\u00e1ctica de Profesionalizaci\u00f3n<br \/> nvestigaci\u00f3n Aplicada<br \/><\/td><td>Modalidad de Graduaci\u00f3nz<br \/> An\u00e1lisis Matem\u00e1tico<br \/> Geometr\u00eda Diferencial de Curvas y Superficies<br \/><\/td>        <\/tr>\n    <\/tbody><!--ninja_tobody_rendering_done-->\n    <\/table>\n    \n    \n    \n<\/div>\n<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16119\" class=\"elementor elementor-16119\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;pulse&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33c3450 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"33c3450\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d5289fa\" data-id=\"d5289fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c581cd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c581cd7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c49164b\" data-id=\"c49164b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5c0f2b elementor-widget elementor-widget-image\" data-id=\"c5c0f2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg\" class=\"attachment-large size-large wp-image-805\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg 800w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-300x167.jpg 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-768x427.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d31acb\" data-id=\"5d31acb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-295d4be elementor-shape-circle e-grid-align-right e-grid-align-mobile-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"295d4be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-e465af8\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-53a1a2b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b33d841\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-1ed9e15\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-repeater-item-bd76d6c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Envelope<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-repeater-item-8ab4a17\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-calendar-alt elementor-repeater-item-4f86da0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Calendar-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ed3660 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ed3660\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89273a1\" data-id=\"89273a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d00e011 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d00e011\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c4e8ebd\" data-id=\"c4e8ebd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11489c0\" data-id=\"11489c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16217\" class=\"elementor elementor-16217\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;pulse&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73c77dcc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73c77dcc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-570c1efa\" data-id=\"570c1efa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d3be152 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d3be152\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1ed9367a\" data-id=\"1ed9367a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21660ef elementor-widget elementor-widget-image\" data-id=\"21660ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg\" class=\"attachment-large size-large wp-image-805\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg 800w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-300x167.jpg 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-768x427.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b61b95d\" data-id=\"1b61b95d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54f734f elementor-shape-circle e-grid-align-right e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"54f734f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-e465af8\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-53a1a2b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b33d841\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-1ed9e15\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-repeater-item-bd76d6c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Envelope<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-repeater-item-8ab4a17\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-calendar-alt elementor-repeater-item-4f86da0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Calendar-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8026f59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8026f59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-765c12b1\" data-id=\"765c12b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5730e981 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5730e981\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-826df04\" data-id=\"826df04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7ed671dc\" data-id=\"7ed671dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16221\" class=\"elementor elementor-16221\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;pulse&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c330c9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c330c9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-706d1fd\" data-id=\"706d1fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-330b593a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"330b593a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-223dc6e\" data-id=\"223dc6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21372e26 elementor-widget elementor-widget-image\" data-id=\"21372e26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg\" class=\"attachment-large size-large wp-image-805\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg 800w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-300x167.jpg 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-768x427.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-59b89fa1\" data-id=\"59b89fa1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-476d088 elementor-shape-circle e-grid-align-right e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"476d088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-e465af8\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-53a1a2b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b33d841\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-1ed9e15\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-repeater-item-bd76d6c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Envelope<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-repeater-item-8ab4a17\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-calendar-alt elementor-repeater-item-4f86da0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Calendar-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60eb1f73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60eb1f73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29e6e542\" data-id=\"29e6e542\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-527564ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"527564ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6a331e76\" data-id=\"6a331e76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4aa510df\" data-id=\"4aa510df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16225\" class=\"elementor elementor-16225\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;pulse&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74893680 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74893680\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d69d770\" data-id=\"1d69d770\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4678019d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4678019d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-60c8c7f\" data-id=\"60c8c7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5df60c55 elementor-widget elementor-widget-image\" data-id=\"5df60c55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg\" class=\"attachment-large size-large wp-image-805\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg 800w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-300x167.jpg 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-768x427.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-488005c8\" data-id=\"488005c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55699cc3 elementor-shape-circle e-grid-align-right e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"55699cc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-e465af8\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-53a1a2b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b33d841\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-1ed9e15\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-repeater-item-bd76d6c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Envelope<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-repeater-item-8ab4a17\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-calendar-alt elementor-repeater-item-4f86da0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Calendar-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4de60f58 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4de60f58\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea7ebae\" data-id=\"ea7ebae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3054e0fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3054e0fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b2f8c5d\" data-id=\"1b2f8c5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1c077be3\" data-id=\"1c077be3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16228\" class=\"elementor elementor-16228\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;pulse&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fb6ca63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fb6ca63\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52edd2a5\" data-id=\"52edd2a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5350ea99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5350ea99\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11f66454\" data-id=\"11f66454\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ca54cb5 elementor-widget elementor-widget-image\" data-id=\"4ca54cb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg\" class=\"attachment-large size-large wp-image-805\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg 800w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-300x167.jpg 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-768x427.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f16d15\" data-id=\"f16d15\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e41ffea elementor-shape-circle e-grid-align-right e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"e41ffea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-e465af8\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-53a1a2b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b33d841\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-1ed9e15\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-repeater-item-bd76d6c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Envelope<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-repeater-item-8ab4a17\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-calendar-alt elementor-repeater-item-4f86da0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Calendar-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28a0ab86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28a0ab86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3210dfbd\" data-id=\"3210dfbd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4884261e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4884261e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d69ba0a\" data-id=\"d69ba0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-56b8452a\" data-id=\"56b8452a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16787\" class=\"elementor elementor-16787\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c497ab9 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"c497ab9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b7cbe7e\" data-id=\"5b7cbe7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-649512da\" data-id=\"649512da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6665d7a9 elementor-widget elementor-widget-heading\" data-id=\"6665d7a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Arquitectura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dcbbb8e elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"dcbbb8e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22e8b005\" data-id=\"22e8b005\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b4b5c31 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"7b4b5c31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2061\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2061\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2062\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2062\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2063\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2063\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2061\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2061\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2061\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de Arquitectura es el Desarrollo de Proyectos Arquitect\u00f3nicos para el mejoramiento de la calidad de vida de la sociedad y la sostenibilidad ambiental.<\/p><p>Por lo tanto, el profesional de Arquitectura formula, dise\u00f1a, supervisa y eval\u00faa anteproyectos y proyectos de edificaciones, patrimonio cultural y proyectos urban\u00edsticos; aplicando t\u00e9cnicas de arquitectura ambiental, sostenible y resiliente en proyectos de desarrollo desde una perspectiva hol\u00edstica.<\/p><p>Por sus competencias puede desarrollarse profesionalmente en instituciones gubernamentales, empresa privada y ONG\u00b4s nacionales e internacionales.<\/p><p>Su cultura humanista le permite comprender la realidad socio-econ\u00f3mica, pol\u00edtica, ambiental e hist\u00f3rica del pa\u00eds y actuar en su desarrollo social, con un sentido \u00e9tico y cr\u00edtico en beneficio de la sociedad.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ol><li>Instituciones privadas y p\u00fablicas con dependencias de dise\u00f1o arquitect\u00f3nico, mantenimiento y construcci\u00f3n.<\/li><li>Empresas consultoras de dise\u00f1o arquitect\u00f3nico y construcci\u00f3n.<\/li><li>ONG\u00b4s que requieren de profesionales de dise\u00f1o y construcci\u00f3n<\/li><li>Instituciones privadas y p\u00fablicas con dependencias dedicadas al diagn\u00f3stico y la intervenci\u00f3n patrimonial.<\/li><li>Empresas consultoras dedicadas al diagn\u00f3stico y la intervenci\u00f3n patrimonial<\/li><li>ONG\u00b4s que requieren de profesionales dedicados a la tem\u00e1tica patrimonial.+<\/li><li>Instituciones Privadas y p\u00fablicas con dependencias dedicadas a la planificaci\u00f3n municipal y ordenamiento urbano.<\/li><li>Empresas consultoras dedicadas al diagn\u00f3stico y la intervenci\u00f3n urban\u00edstica.<\/li><li>ONG\u00b4s que requieren de profesionales dedicados al desarrollo urbano.<\/li><\/ol><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ol><li>Diagnostica el \u00e1rea de influencia.<\/li><li>Realiza estudio de Mercado.<\/li><li>Realiza estudio t\u00e9cnico.<\/li><li>Eval\u00faa econ\u00f3mica y social.<\/li><li>Realiza diagn\u00f3stico el sitio.<\/li><li>Conceptualiza la propuesta del dise\u00f1o arquitect\u00f3nico.<\/li><li>Dise\u00f1a anteproyecto y proyecto arquitect\u00f3nico.<\/li><li>Realiza seguimiento y control de calidad.<\/li><li>Realiza seguimiento y control del alcance de la construcci\u00f3n.<\/li><li>Realiza seguimiento y control de costos.<\/li><li>Controla el cronograma de la Obra<\/li><li>Diagnostica el patrimonio cultural.<\/li><li>Interviene el patrimonio cultural.<\/li><li>Diagnostica proyectos urban\u00edsticos.<\/li><li>Planifica y ordena el territorio a nivel municipal y urbano.<\/li><\/ol><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2062\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2062\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2062\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Matem\u00e1tica Aplicada I<\/li><li>Composici\u00f3n<\/li><li>Arquitect\u00f3nica<br \/>Inform\u00e1tica Aplicada<\/li><li>Grafismo I<\/li><li>Integrador I<br \/>Electiva I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Matem\u00e1tica Aplicada II<\/li><li>Topograf\u00eda<\/li><li>Grafismo II<\/li><li>L\u00f3gica Estructural<\/li><li>Integrador II<\/li><li>Electiva II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Arquitectura Ambiental<\/li><li>Estructura I<\/li><li>Historia de la Arquitectura I<\/li><li>Software Arquitect\u00f3nico I<\/li><li>Sistema Arquitect\u00f3nico I<\/li><li>Integrador<\/li><\/ul><p>IIISEMESTRE IV<\/p><ul><li>Sociolog\u00eda Urbana<\/li><li>Estructura II<\/li><li>Historia de la Arquitectura II<\/li><li>Software Arquitect\u00f3nico II<\/li><li>Sistemas Arquitect\u00f3nicos II<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Sistemas<\/li><li>Arquitect\u00f3nicos III<\/li><li>Estructura III<\/li><li>Historia de la<\/li><li>Arquitectura III<\/li><li>Urbanismo I<\/li><li>Integrador V<\/li><li>Optativa I<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Sistemas<\/li><li>Arquitect\u00f3nicos IV<\/li><li>Estructura IV<\/li><li>Historia de la Arquitectura IV<\/li><li>Urbanismo II<\/li><li>Integrador VI<\/li><li>Optativa II<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Formulaci\u00f3n de Proyectos I<\/li><li>Seguridad en Proyectos<\/li><li>Impacto Ambiental<\/li><li>Instalaciones I<\/li><li>Integrador VII<\/li><li>Optativa III<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Formulaci\u00f3n de Proyectos II<\/li><li>Supervisi\u00f3n y Evaluaci\u00f3n de Proyectos I<\/li><li>Patrimonio<\/li><li>Instalaciones II<\/li><li>Integrador VIII<\/li><li>Optativa IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Gerencia de Proyectos en Arquitectura<\/li><li>Supervisi\u00f3n y Evaluaci\u00f3n de Proyectos II<\/li><li>Paisajismo<br \/>Integrador IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Integrador X<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2063\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2063\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2063\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16794\" class=\"elementor elementor-16794\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7db74e8d elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"7db74e8d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6dcabaef\" data-id=\"6dcabaef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30bcc715\" data-id=\"30bcc715\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11127f0d elementor-widget elementor-widget-heading\" data-id=\"11127f0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Biolog\u00eda <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-296f8f39 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"296f8f39\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30eed500\" data-id=\"30eed500\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-653749df elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"653749df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1691\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1691\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1692\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1692\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1693\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1693\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1691\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1691\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1691\" tabindex=\"0\" hidden=\"false\"><p>Analiza, eval\u00faa y propone soluciones a problem\u00e1ticas socio ambientales, formula proyectos de restauraci\u00f3n, conservaci\u00f3n y manejo de la biodiversidad. maneja bases de datos cient\u00edficas de biodiversidad, gestiona acciones de sensibilizaci\u00f3n y educaci\u00f3n ambiental, aplica normas estandarizadas en sistemas de calidad y gesti\u00f3n ambiental, analiza muestras de laboratorio de calidad ambiental y microbiol\u00f3gicas en el ecosistema suelo, agua y aire.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Instituciones p\u00fablicas-privadas de \u00edndole ambiental.<\/li><li>Organizaciones no gubernamentales ambientales<br \/>Empresas.<\/li><li>Laboratorios de calidad ambiental y microbiol\u00f3gicos.<\/li><\/ul><p>Tareas que puede realizar el profesional:<\/p><ul><li>Investigaciones ambientales.<\/li><li>Sensibilizaci\u00f3n ambiental.<\/li><li>Restauraci\u00f3n y conservaci\u00f3n de la biodiversidad y su entorno.<\/li><li>Gesti\u00f3n de proyectos ambientales.<\/li><li>Sistemas de gesti\u00f3n ambientales.<\/li><li>Calidad ambiental y microbiol\u00f3gica.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1692\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1692\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1692\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Introducci\u00f3n a la Comunicaci\u00f3n Cient\u00edfica<\/li><li>Matem\u00e1tica General I<\/li><li>Qu\u00edmica General<\/li><li>Biolog\u00eda General<\/li><li>Inform\u00e1tica Aplicada a la Ciencias Ambientales<br \/>Integrador 1<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Matem\u00e1tica General II<\/li><li>Qu\u00edmica Org\u00e1nica I<\/li><li>Ecolog\u00eda General<\/li><li>Biof\u00edsica<\/li><li>Electiva 1<\/li><li>Integrador 2<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Estad\u00edsticas Aplicadas Al Ambiente<\/li><li>Qu\u00edmica Org\u00e1nica II<\/li><li>Zoolog\u00eda I<\/li><li>Bot\u00e1nica General<\/li><li>Electiva 2<\/li><li>Integrador 3<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Bioqu\u00edmica<\/li><li>Biolog\u00eda Celular Y Molecular<\/li><li>Zoolog\u00eda II<\/li><li>Bot\u00e1nica Sistem\u00e1tica<\/li><li>Electiva 3<\/li><li>Integrador 4<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Fauna Nacional<\/li><li>Flora Nacional<\/li><li>Estrategias de Educaci\u00f3n Ambiental<\/li><li>Optativo 1 (Entomolog\u00eda General o Limnolog\u00eda)<\/li><li>Integrador 5<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Investigaci\u00f3n Aplicada<\/li><li>Fisiolog\u00eda Animal<\/li><li>Gen\u00e9tica<\/li><li>Microbiolog\u00eda General<\/li><li>Optativo 2 (Eco Toxicolog\u00eda o Fisiolog\u00eda Vegetal)<\/li><li>Integrador 6<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>\u00c1reas Protegidas de Nicaragua<\/li><li>Biolog\u00eda de la Conservaci\u00f3n<\/li><li>Biotecnolog\u00eda I<\/li><li>Ecolog\u00eda Humana<\/li><li>Optativo 3: (Valoraci\u00f3n Econ\u00f3mica Del<br \/>Ambiente \u00d3 Sistemas De Gesti\u00f3n Ambiental)<\/li><li>Integrador 7<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Biotecnolog\u00eda II<\/li><li>Microbiolog\u00eda Ambiental<\/li><li>Formulaci\u00f3n de Proyectos Ambientales<\/li><li>Manejo de Cuencas Hidrogr\u00e1ficas<\/li><li>Optativo 4 (Manejo de Recursos Hidrobiol\u00f3gicos \u00d3 Administraci\u00f3n De Recursos)<\/li><li>Integrador 8<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Manejo de Residuos S\u00f3lidos y L\u00edquidos<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><li>Optativo 5 (Evaluaci\u00f3n de Impacto Ambiental o Auditor\u00eda Ambiental)<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1693\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1693\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1693\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16800\" class=\"elementor elementor-16800\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-iambiental\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ef7ce3e elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"2ef7ce3e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30cdf643\" data-id=\"30cdf643\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-50dc9fef\" data-id=\"50dc9fef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-812abb8 elementor-widget elementor-widget-heading\" data-id=\"812abb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda Ambiental <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3b97e5 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"b3b97e5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90d0113\" data-id=\"90d0113\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-528ae2e elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"528ae2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8651\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8651\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8652\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8652\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8651\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8651\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8651\" tabindex=\"0\" hidden=\"false\"><p>Preserva los recursos naturales desde el componente econ\u00f3mico y social, trabaja en la prevenci\u00f3n de la contaminaci\u00f3n, la preservaci\u00f3n de los recursos naturales, reduce y mitiga la contaminaci\u00f3n, dise\u00f1a sistemas de tratamiento de los residuos s\u00f3lidos y l\u00edquidos, realiza valoraciones de los servicios eco sist\u00e9micos y una gesti\u00f3n integrada de recursos naturales y productivos.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Entidades p\u00fablicas y privadas dedicadas al cuido, protecci\u00f3n y restauraci\u00f3n de los recursos naturales.<\/li><li>Unidades ambientales de las alcald\u00edas municipalidades.<\/li><li>\u00c1reas protegidas.<\/li><li>Centros e institutos de investigaci\u00f3n orientados a la preservaci\u00f3n del ambiente.<\/li><li>Empresas que se dedican al desarrollo sostenible.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Intervenciones ambientales.<\/li><li>Afectaciones ambientales antropog\u00e9nicas.<\/li><li>Tratamiento de desechos s\u00f3lidos, l\u00edquidos y gaseosos.<\/li><li>Proyectos ambientales.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8652\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8652\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8652\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Ecolog\u00eda y Problem\u00e1tica Ambiental<\/li><li>Qu\u00edmica y Medio Ambiente<\/li><li>Fundamentos de la Comunicaci\u00f3n Oral y Escrita<\/li><li>Introducci\u00f3n a la Contaminaci\u00f3n Ambiental<\/li><li>Inform\u00e1tica Aplicada a la Ciencias Ambientales<\/li><li>Integrador I (Ensayo)<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Contaminaci\u00f3n Ambiental en los Ecosistemas<\/li><li>Naturaleza de la F\u00edsica<\/li><li>Aritm\u00e9tica<\/li><li>Generalidades de Recursos H\u00eddricos<\/li><li>Integrador II (Soluci\u00f3n de problemas)<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Qu\u00edmica de los Residuos<\/li><li>Geometr\u00eda Elemental<\/li><li>Metodolog\u00eda para la Evaluaci\u00f3n y Manejo de los Impactos Ambientales<\/li><li>Optativo 1.1 (Generalidades del recurso suelo)<\/li><li>Optativo 1.2 (Inform\u00e1tica)<\/li><li>Integrador III (Estudio de caso)<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Mec\u00e1nica de Fluidos<\/li><li>Fundamentos para la Redacci\u00f3n T\u00e9cnico- Cient\u00edfica<\/li><li>Caracterizaci\u00f3n y Diagn\u00f3stico de Cuencas Hidrogr\u00e1ficas<\/li><li>Optativo 2.1 (Principios para la gesti\u00f3n de residuos s\u00f3lidos y l\u00edquidos)<\/li><li>Optativo 2.2 (Estad\u00edstica aplicada)<br \/>Integrador 4<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Hidrodin\u00e1mica<\/li><li>Derivaciones e Integrales<\/li><li>Estudios de los Recursos H\u00eddricos<\/li><li>Diagn\u00f3stico del Estado Actual del Suelo<\/li><li>Integrador V (Trabajo en equipo)<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Termodin\u00e1mica<br \/>Introducci\u00f3n al Manejo Integral del Bosque<\/li><li>Fundamentos de la Investigaci\u00f3n<\/li><li>Optativo 3.1 (T\u00e9cnicas de remedici\u00f3n de suelos)<\/li><li>Optativo 3.2 (Evaluaci\u00f3n de alternativas de manejo del recurso suelo)<\/li><li>Integrador VI (Modelado)<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Ecuaciones Diferenciales<\/li><li>Tratamiento de Residuos S\u00f3lidos<\/li><li>Derecho Ambiental<\/li><li>Optativo 4.1 (Gesti\u00f3n integral de los recursos h\u00eddricos)<\/li><li>Optativo 4.2 (Planificaci\u00f3n de cuencas)<\/li><li>Integrador VII (Soluci\u00f3n de problemas)<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Redacci\u00f3n T\u00e9cnico-Cient\u00edfica<\/li><li>Tratamiento de Aguas Residuales<\/li><li>Sistemas Forestales Tropicales<\/li><li>Perfiles de Proyectos<\/li><li>Optativo 5.1 (Tratamiento de aguas naturales)<\/li><li>Optativo 5.2 (Sistema de Informaci\u00f3n Geogr\u00e1fica)<\/li><li>Integrador VIII (Elaboraci\u00f3n de propuesta<br \/>t\u00e9cnica)<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Dibujo Aplicado a la Ingenier\u00eda Ambiental<\/li><li>Gesti\u00f3n Integral del Recurso Suelo<\/li><li>Evaluaci\u00f3n de Impacto Ambiental<\/li><li>Optativo 6.1 (Dise\u00f1o de plantas de tratamiento de residuos s\u00f3lidos)<\/li><li>Optativo 6.2 (Software para dise\u00f1os ingenieriles)<\/li><li>Pr\u00e1ctica Pre-Profesional<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Dise\u00f1o de Plantas de Tratamiento de Aguas Residuales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><li>Formulaci\u00f3n de Proyectos<\/li><li>Pr\u00e1ctica Profesional<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16811\" class=\"elementor elementor-16811\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-matematica\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b1aa04c elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"b1aa04c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30de70c2\" data-id=\"30de70c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a9d5507\" data-id=\"5a9d5507\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e905825 elementor-widget elementor-widget-heading\" data-id=\"5e905825\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Matem\u00e1tica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ed36719 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"4ed36719\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-673230a\" data-id=\"673230a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49c1a7 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"49c1a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4831\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4831\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4832\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4832\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4833\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4833\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4831\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4831\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4831\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la licenciatura en Matem\u00e1tica Aplicada es dise\u00f1ar modelos matem\u00e1ticos para la soluci\u00f3n \u00f3ptima de problemas vinculando diferentes estrategias t\u00e9cnicas, te\u00f3ricas y pr\u00e1cticas recibidas durante su formaci\u00f3n.<\/p><p>El graduado de la carrera de licenciatura en matem\u00e1tica ser\u00e1 capaz de planificar, evaluar y ejecutar soluciones de problemas reales de forma \u00f3ptima aplicando los fundamentos te\u00f3ricos y pr\u00e1cticos incorporando las tecnolog\u00edas (TIC) y la innovaci\u00f3n en el proceso de investigaci\u00f3n.<\/p><p>Por su formaci\u00f3n en matem\u00e1tica y tecnolog\u00edas digitales puede desarrollarse profesionalmente en instituciones p\u00fablicas y privadas, ONG\u00b4s, PYMES y MIPYMES y Centros de Investigaci\u00f3n.<\/p><p><strong>Ambitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Instituciones p\u00fablicas y privadas que requieran la aplicaci\u00f3n de modelos num\u00e9ricos en el \u00e1mbito de servicio y producci\u00f3n.<\/li><li>ONG\u00b4s que requiera dise\u00f1o determin\u00edstico de comportamiento de datos.<\/li><li>PYMES y MIPYMES que requiera mejoramiento y optimizaci\u00f3n de recursos y productos.<\/li><li>Centros de Investigaci\u00f3n que requiera modelaci\u00f3n matem\u00e1tica para trabajar en equipos multidisciplinarios.<\/li><\/ul><p><strong>Tareas que puede realizar el profesiona<\/strong>l<\/p><ul><li>Elabora estrategias en la resoluci\u00f3n de problemas en el \u00e1mbito de finanzas y econom\u00eda planteando soluciones \u00f3ptimas.<\/li><li>Elabora estrategias en la resoluci\u00f3n de problemas en el \u00e1mbito de la producci\u00f3n, medio ambiente y transporte planteando soluciones \u00f3ptimas.<\/li><li>Aplica t\u00e9cnicas te\u00f3ricas y pr\u00e1cticas de matem\u00e1tica para integrarse al trabajo de equipos multidisciplinario utilizando la tecnolog\u00eda.<\/li><li>Aplica t\u00e9cnicas te\u00f3ricas y pr\u00e1cticas de matem\u00e1tica para la creaci\u00f3n de nuevos proceso de innovaci\u00f3n.<\/li><li>Realiza procesos de investigaci\u00f3n en diferentes \u00e1reas para la soluci\u00f3n de problemas reales.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4832\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4832\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4832\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Inform\u00e1tica aplicada a la Matem\u00e1tica<\/li><li>Introducci\u00f3n al C\u00e1lculo<\/li><li>L\u00f3gica y Teor\u00eda de conjunto<\/li><li>Geometr\u00eda Euclidiana<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Programaci\u00f3n Fundamental<\/li><li>C\u00e1lculo I<\/li><li>Geometr\u00eda Anal\u00edtica<\/li><li>T\u00e9cnicas de investigaci\u00f3n<\/li><li>Matem\u00e1tica<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Software Matem\u00e1tico I<\/li><li>C\u00e1lculo II<\/li><li>Matem\u00e1tica Discreta<\/li><li>Estad\u00edstica I<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Software Matem\u00e1tico II<\/li><li>C\u00e1lculo III<\/li><li>\u00c1lgebra Lineal I<\/li><li>Estad\u00edstica II<\/li><li>F\u00edsica I<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Software Matem\u00e1tico III<\/li><li>\u00c1lgebra Lineal II<\/li><li>An\u00e1lisis Num\u00e9rico I<\/li><li>Ecuaciones diferenciales I<\/li><li>F\u00edsica II<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Componente curricular optativo 1<\/li><li>An\u00e1lisis Vectorial<\/li><li>Estructuras Algebraicas I<\/li><li>An\u00e1lisis Num\u00e9rico II<\/li><li>Modelaci\u00f3n Matem\u00e1tica I<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Componente curricular optativo 2<\/li><li>An\u00e1lisis Matem\u00e1tico I<\/li><li>Investigaci\u00f3n de operaciones I<\/li><li>Modelaci\u00f3n Matem\u00e1tica II<\/li><li>Matem\u00e1tica Financiera<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>An\u00e1lisis Matem\u00e1tico II<\/li><li>Modelaci\u00f3n Matem\u00e1tica III<\/li><li>Estad\u00edstica III<\/li><li>Optativo 3<\/li><li>Optativo 4<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo 5<\/li><li>Optativo 6<\/li><li>Pr\u00e1cticas<\/li><li>Pr\u00e1cticas PreProfesisonales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4833\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4833\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4833\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16817\" class=\"elementor elementor-16817\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-lqa\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e7c7a93 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"5e7c7a93\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-651d0133\" data-id=\"651d0133\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7de7ca0b\" data-id=\"7de7ca0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f86df4f elementor-widget elementor-widget-heading\" data-id=\"4f86df4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Qu\u00edmica Ambiental<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73897bc1 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"73897bc1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-695524d2\" data-id=\"695524d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2edf818a elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"2edf818a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7861\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-7861\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-7861\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7861\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7861\" tabindex=\"0\" hidden=\"false\"><p>La Qu\u00edmica Ambiental, tiene como objeto de estudio los procesos qu\u00edmicos; reacciones, evoluci\u00f3n e interacciones que tienen lugar en el medio ambiente: suelo, agua y aire, as\u00ed como el impacto de las actividades humanas sobre nuestro entorno y la problem\u00e1tica que ello ocasiona.<\/p><p>Asimismo, participa de las posibles soluciones a los impactos ambientales provocados por la acci\u00f3n antropog\u00e9nicas a fin de dar tratamientos adecuados que permita reducir la carga de contaminantes Qu\u00edmicos al medio ambiente, a trav\u00e9s de desarrollo y aplicaci\u00f3n de metodolog\u00edas de diagn\u00f3stico ambiental, incluyendo an\u00e1lisis de par\u00e1metros de calidad y monitoreo de recursos naturales, descargas de residuos de procesos industriales, gesti\u00f3n ambiental, an\u00e1lisis para determinar composici\u00f3nQu\u00edmica, propiedades fisicoqu\u00edmicas, efectos biol\u00f3gicos, registro y control de sustancias t\u00f3xicas.<\/p><p><strong>Funciones que Desempe\u00f1a el Licenciado Qu\u00edmico Ambiental<\/strong><\/p><ul><li>Controla la emisi\u00f3n de gases Contaminantes Industriales.<\/li><li>Planifica los muestreos para cuantificar los contaminantes org\u00e1nicos e inorg\u00e1nicos en agua y suelo.<\/li><li>Administra la deposici\u00f3n y tratamiento de residuos peligrosos seg\u00fan legislaci\u00f3n.<\/li><li>Organiza y gestiona los medios y medidas de protecci\u00f3n ambiental.<\/li><li>Promueve acciones de prevenci\u00f3n y mitigaci\u00f3n delos impactos ambientales.<\/li><li>Administra programas y proyectos de capacitaci\u00f3n relacionados al impacto y control de contaminaci\u00f3n ambiental.<\/li><li>Asesora planes de desarrollo y ordenamiento territorial.<\/li><li>Elabora y eval\u00faa diagn\u00f3sticos, programas y planes de manejo ambiental.<\/li><li>Asesora planes ambientales socioecon\u00f3micos.<\/li><li>Coordina la recolecci\u00f3n, sistematizaci\u00f3n y an\u00e1lisis de informaci\u00f3n en materia ambiental.<\/li><li>Elabora proyectos de mejoramiento y conservaci\u00f3n ambiental.<\/li><li>Supervisa el desempe\u00f1o ambiental de las empresas.<\/li><\/ul><p><strong>Cargos que Desempe\u00f1a el Licenciado Qu\u00edmico Ambiental<\/strong><\/p><ul><li>Analista qu\u00edmico ambiental.<\/li><li>Director del control y la calidad ambiental.<\/li><li>Administrador de proyectos ambientales.<\/li><li>Evaluador de impactos ambientales.<\/li><li>Gestor ambiental.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16826\" class=\"elementor elementor-16826\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d84282e elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"d84282e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4c506c0b\" data-id=\"4c506c0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-32b36ac5\" data-id=\"32b36ac5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2231c1a8 elementor-widget elementor-widget-heading\" data-id=\"2231c1a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Qu\u00edmica Farmac\u00e9utica <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7811e71c elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"7811e71c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ffc72b8\" data-id=\"7ffc72b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49d6eb7d elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"49d6eb7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1231\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1231\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1232\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1232\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1233\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1233\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1231\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1231\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1231\" tabindex=\"0\" hidden=\"false\"><p>Producci\u00f3n, aseguramiento de la calidad y gesti\u00f3n de insumos m\u00e9dicos en los servicios asistenciales.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional: Industria<\/strong><\/p><ul><li>Farmac\u00e9utica<\/li><li>Ministerio de salud<\/li><li>Establecimientos farmac\u00e9uticos<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Fabricaci\u00f3n de productos farmac\u00e9uticos<\/li><li>Regulaci\u00f3n farmac\u00e9utica<\/li><li>Regencia Farmac\u00e9utica<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1232\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1232\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1232\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Anatom\u00eda y Fisiolog\u00eda<\/li><li>Matem\u00e1tica<\/li><li>Qu\u00edmica General I<\/li><li>T\u00e9cnicas de Laboratorio<\/li><li>Electiva 1<\/li><li>Integrador 1<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Biolog\u00eda General<\/li><li>Estad\u00edstica<\/li><li>Fisiopatolog\u00eda<\/li><li>Qu\u00edmica General II<\/li><li>Electiva 2<\/li><li>Integrador 2<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Bot\u00e1nica y medicina natural<\/li><li>Metodolog\u00eda Cient\u00edfica<\/li><li>Qu\u00edmica F\u00edsica I<\/li><li>Qu\u00edmica Inorg\u00e1nica<\/li><li>Qu\u00edmica Org\u00e1nica I<\/li><li>Integrador 3<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Farmacognosia<br \/>Legislaci\u00f3n y Deontolog\u00eda<\/li><li>Qu\u00edmica F\u00edsica II<\/li><li>Qu\u00edmica Org\u00e1nica II<br \/>Integrador 4<\/li><li>Optativa 1 (Operaciones Unitarias Farmac\u00e9uticas)<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Bioqu\u00edmica<\/li><li>Farmacolog\u00eda I<\/li><li>Qu\u00edmica Anal\u00edtica<\/li><li>Tecnolog\u00eda<\/li><li>Farmac\u00e9utica I<\/li><li>Integrador 5<br \/>Optativa 2 (Qu\u00edmica Farmac\u00e9utica)<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Farmacolog\u00eda II<\/li><li>Microbiolog\u00eda<\/li><li>T\u00e9cnicas de An\u00e1lisis Instrumentales<\/li><li>Tecnolog\u00eda<\/li><li>Farmac\u00e9utica II<\/li><li>Integrador 6<br \/>Optativo 3 (Inmunolog\u00eda)<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Control de Calidad de Productos<\/li><li>Farmac\u00e9uticos I<\/li><li>Investigaci\u00f3n en ciencias farmac\u00e9uticas<\/li><li>Farmacia Asistencial<\/li><li>Toxicolog\u00eda<\/li><li>Integrador 7<\/li><li>Optativa 4 (Administraci\u00f3n Farmac\u00e9utica)<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Atenci\u00f3n Farmac\u00e9utica<\/li><li>Control de calidad de productos farmac\u00e9uticos II<\/li><li>Registro Sanitario<\/li><li>Salud P\u00fablica<\/li><li>Integrador 8<\/li><li>Optativa 5 (Control<\/li><li>Microbiol\u00f3gico de Productos Farmac\u00e9uticos)<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Biotecnolog\u00eda<\/li><li>Farmacoterap\u00e9utica<\/li><li>Pr\u00e1cticas pre profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas profesionales<br \/>Modalidad de graduaci\u00f3n<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1233\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1233\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1233\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16832\" class=\"elementor elementor-16832\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot; a[href=\\&quot;#fcei-qi\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e9b0912 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"2e9b0912\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18dee7dc\" data-id=\"18dee7dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e4669b0\" data-id=\"7e4669b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f1a031a elementor-widget elementor-widget-heading\" data-id=\"6f1a031a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Qu\u00edmica Industrial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f265f0c elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"1f265f0c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-343e71ed\" data-id=\"343e71ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e12c766 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"4e12c766\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1301\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1301\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1302\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1302\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1303\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1303\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1301\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1301\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1301\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la Qu\u00edmica Industrial es la transformaci\u00f3n, composici\u00f3n y propiedades de la materia para el desarrollo industrial. Por ello, el profesional en qu\u00edmica industrial domina el an\u00e1lisis de par\u00e1metros f\u00edsicos, qu\u00edmicos, microbiol\u00f3gico y muestreo de la materia prima y producto terminado involucrados en los procesos qu\u00edmicos industriales; siendo apto para dise\u00f1ar, ajustar, verificar y calibrar equipos de laboratorios y operaci\u00f3n.<\/p><p>Tambi\u00e9n, es capaz de realizar Investigaci\u00f3n &#8211; desarrollo \u2013 innovaci\u00f3n (I+D+i), a partir de la experimentaci\u00f3n y aplicaci\u00f3n de m\u00e9todos cuali-cuantitativas con el fin de generar nuevos productos de inter\u00e9s nacional e internacional. Adem\u00e1s de evaluar el cumplimiento de normas y regulaciones mediante sistemas integrados para la gesti\u00f3n de la calidad, asegurando a su vez la calidad y el rendimiento de la producci\u00f3n en plantas de procesos qu\u00edmicos industriales.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1302\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1302\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1302\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Qu\u00edmica General I<\/li><li>T\u00e9cnicas de Laboratorio I<\/li><li>T\u00e9cnicas de Investigaci\u00f3n Documental<\/li><li>F\u00edsica General<\/li><li>Matem\u00e1tica General<\/li><li>Integrador 1<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Qu\u00edmica General II<\/li><li>T\u00e9cnicas de Laboratorio II<\/li><li>Matem\u00e1tica I<\/li><li>Introducci\u00f3n a la Programaci\u00f3n para Qu\u00edmicos<\/li><li>Ofim\u00e1tica<\/li><li>Integrador 2<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Qu\u00edmica Org\u00e1nica I<\/li><li>Qu\u00edmica Inorg\u00e1nica<\/li><li>Qu\u00edmica F\u00edsica I<\/li><li>Matem\u00e1tica II<\/li><li>Expresi\u00f3n Gr\u00e1fica Aplicada<\/li><li>Integrador 3<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Qu\u00edmica Anal\u00edtica<\/li><li>Qu\u00edmica Org\u00e1nica II<\/li><li>Qu\u00edmica F\u00edsica II<\/li><li>Matem\u00e1tica III<\/li><li>Estad\u00edstica Descriptiva e Inferencial<\/li><li>Integrador 4<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>T\u00e9cnicas Instrumentales de An\u00e1lisis<\/li><li>Balances de Materia y Energ\u00eda<\/li><li>Metrolog\u00eda<\/li><li>Ingenier\u00eda Econ\u00f3mica<\/li><li>Integrador 5<\/li><li>Optativa 1<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>T\u00e9cnicas de Separaci\u00f3n Cromatograf\u00edas<\/li><li>Bioqu\u00edmica<\/li><li>Tecnolog\u00eda Qu\u00edmica<\/li><li>Mec\u00e1nica de Fluidos<\/li><li>Integrador 6<\/li><li>Optativo 2<\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0 \u00a0 \u00a0 \u00a0<\/b><\/p><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Microbiolog\u00eda<\/li><li>Transferencia de Calor<\/li><li>Formulaci\u00f3n y Evaluaci\u00f3n de Proyectos<\/li><li>Dise\u00f1o Estad\u00edstico de Experimentos<\/li><li>Integrador 7<\/li><li>Optativa 3<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Transferencia de Masa<\/li><li>Qu\u00edmica de los Alimentos<\/li><li>Seguridad e Higiene Ocupacional<\/li><li>Control de Calidad<\/li><li>Integrador 8<\/li><li>Optativa 4<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li><b>I<\/b>nvestigaci\u00f3n en Qu\u00edmica Industrial<\/li><li>Dise\u00f1o de Reactores Qu\u00edmicos<\/li><li>Control Autom\u00e1tico de Procesos<\/li><li>Optativa 5<\/li><li>Integrador 9: Pr\u00e1cticas Preprofesionales<\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0\u00a0<\/b><\/p><p>SEMESTRE X<\/p><ul><li>Integrador 10: Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0 \u00a0 \u00a0 \u00a0<\/b><\/p><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1303\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1303\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1303\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16839\" class=\"elementor elementor-16839\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-icc\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-428a7dc elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"428a7dc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5575e020\" data-id=\"5575e020\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-76080f02\" data-id=\"76080f02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1acad2a4 elementor-widget elementor-widget-heading\" data-id=\"1acad2a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda en Ciencias de la Computaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1619cac2 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"1619cac2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d5c4530\" data-id=\"5d5c4530\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5af29ebb elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"5af29ebb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1521\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1521\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1522\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1522\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1521\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1521\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1521\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de ingenier\u00eda en Ciencias de la Computaci\u00f3n es intervenir desde las diferentes \u00e1reas de la ingenier\u00eda, en la formulaci\u00f3n y soluci\u00f3n de problemas relacionados con la ingenier\u00eda de software, hardware y las comunicaciones en los diferentes contextos.<\/p><p>La Ingenier\u00eda en Ciencias de la Computaci\u00f3n es apasionante, si de verdad te gusta saber c\u00f3mo son los sistemas inform\u00e1ticos y los dispositivos programables por dentro, y c\u00f3mo construirlos para que funcionen y sean \u00fatiles a otras personas. \u00bfTe has preguntado alguna vez c\u00f3mo funciona un ordenador internamente y c\u00f3mo se programa? \u00bfO c\u00f3mo funciona Internet? \u00bfSabes si un ordenador puede resolver cualquier problema? \u00bfC\u00f3mo se organiza un equipo de cientos de personas como los que desarrollan los videojuegos de \u00faltima generaci\u00f3n? Si te interesan estas cuestiones, te interesa la Ingenier\u00eda en Ciencias de la Computaci\u00f3n.<\/p><p>Adem\u00e1s los ingenieros en ciencias de la computaci\u00f3n son profesionales muy demandados por las empresas, tanto nacionales como internacionales, por lo que existen altas probabilidades de inserci\u00f3n laboral.<\/p><p><strong>Funciones que realiza el Ingeniero en Ciencias de la Computaci\u00f3n<\/strong><\/p><ul><li>Algunas \u00e1reas t\u00edpicas de desempe\u00f1o profesional del Ingeniero en Computaci\u00f3n son: Desarrollo y Gesti\u00f3n de Sistemas de Informaci\u00f3n, Planificaci\u00f3n y Administraci\u00f3n de Redes de Computadores, Administraci\u00f3n de Recursos Inform\u00e1ticos.<\/li><li>La Ingenier\u00eda en Ciencias de la Computaci\u00f3n (ICC) busca unificar eficientemente aparatos digitales con el software apropiado para satisfacer las necesidades cient\u00edficas, tecnol\u00f3gicas y administrativas de los negocios y la industria en una econom\u00eda global.<\/li><\/ul><p><strong>Cargos que desempe\u00f1a el Ingeniero en Ciencias de la Computaci\u00f3n<\/strong><\/p><ul><li>Director de Proyecto de TI.<\/li><li>Director de Centros de Investigaci\u00f3n y Desarrollo.<\/li><li>Auditor de Sistemas de Informaci\u00f3n.<\/li><li>Gerente de Inform\u00e1tica.<\/li><li>Administrador de Redes.<\/li><li>Responsable de Soporte T\u00e9cnico en Hardware y Software.<\/li><li>Analista de Sistemas.<\/li><li>Programador.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1522\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1522\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1522\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16963\" class=\"elementor elementor-16963\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15c8f424 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"15c8f424\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6924feac\" data-id=\"6924feac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-657592f5\" data-id=\"657592f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71db2aeb elementor-widget elementor-widget-heading\" data-id=\"71db2aeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda Civil<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dca97dc elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"dca97dc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75307cf8\" data-id=\"75307cf8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5218845 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"5218845\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8601\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8601\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8602\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8602\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8603\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8603\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8601\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8601\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8601\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la ingenier\u00eda civil son las obras civiles, y tiene tres grandes campos de acci\u00f3n como son; la planificaci\u00f3n, el dise\u00f1o y la supervisi\u00f3n de obras, siendo el \u00e1mbito acci\u00f3n; Organizaciones no gubernamentales e Instituciones p\u00fablicas y privadas relacionadas al sector de la construcci\u00f3n. Por tanto, el egresado de la carrera ingenier\u00eda civil es un profesional integral con compromiso social, con valores \u00e9ticos, morales y humanistas capaz de gestionar, planificar y dise\u00f1ar obras civiles que sean sostenibles en el tiempo. Adem\u00e1s, tiene las competencias necesarias para desempe\u00f1arse en los diferentes campos de acci\u00f3n de la profesi\u00f3n, lo que lo hace un profesional que contribuye en la construcci\u00f3n de una Nicaragua m\u00e1s justa y solidaria y, por tanto, m\u00e1s humana y en beneficio de las grandes mayor\u00edas.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Organizaciones No Gubernamentales e Instituciones P\u00fablicas y Privadas relacionadas al sector de la construcci\u00f3n.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Planificar, dise\u00f1ar y supervisar obras civiles verticales y horizontales.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8602\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8602\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8602\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Introducci\u00f3n a la Ingenier\u00eda Civil<\/li><li>Calculo I<\/li><li>Dibujo e Interpretaci\u00f3n de planos.<\/li><li>Topograf\u00eda I<\/li><li>Integradora 1<\/li><li>Electiva 1<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Calculo II<\/li><li>F\u00edsica general I<\/li><li>Topograf\u00eda II.<\/li><li>Integradora 2<\/li><li>M\u00e9todos y explotaci\u00f3n de equipos<\/li><li>Electiva 2<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Calculo III<\/li><li>F\u00edsica general II<\/li><li>Materiales de construcci\u00f3n<\/li><li>Integradora 3<\/li><li>Mec\u00e1nica vectorial Est\u00e1tica<\/li><li>Electiva 3<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Ecuaciones diferenciales<\/li><li>Integradora 4<\/li><li>Costo y presupuesto<\/li><li>Mec\u00e1nica de Materiales I.<\/li><li>Mec\u00e1nica vectorial Din\u00e1mica.<\/li><li>Hidrolog\u00eda aplicada.<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE<\/p><ul><li>Mec\u00e1nica de suelos I.<\/li><li>Mec\u00e1nica de materiales II<\/li><li>Programaci\u00f3n de Obras<\/li><li>Hidr\u00e1ulica I<\/li><li>Integradora 5<\/li><li>Optativa 1<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Mec\u00e1nica de suelos II<\/li><li>An\u00e1lisis estructural I<\/li><li>Hidr\u00e1ulica II<\/li><li>Administraci\u00f3n de obras<\/li><li>Optativa 2<\/li><li>Integradora 6<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Integradora<\/li><li>Ingenier\u00eda sanitaria<\/li><li>An\u00e1lisis estructural II<\/li><li>Ingenier\u00eda de tr\u00e1nsito<\/li><li>Formulaci\u00f3n de proyecto de obras Civiles<\/li><li>Optativa 3<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Estructuras de acero<\/li><li>Ingenier\u00eda sanitaria II<\/li><li>Concreto Reforzado I<\/li><li>Dise\u00f1o geom\u00e9trico de carreteras<\/li><li>Integradora 8<\/li><li>Optativa 4<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Concreto reforzado II<\/li><li>Practicas pre profesionales<\/li><li>Ingenier\u00eda Sismo resistente<\/li><li>Dise\u00f1o de pavimentos<\/li><li>Instalaciones hidrosanitarias en edificaciones<\/li><li>Optativa 5<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas de profesionalizaci\u00f3n<\/li><li>Modalidad de graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8603\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8603\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8603\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16972\" class=\"elementor elementor-16972\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16c8be41 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"16c8be41\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64089c5b\" data-id=\"64089c5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63632aa\" data-id=\"63632aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55bcfed2 elementor-widget elementor-widget-heading\" data-id=\"55bcfed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda Electr\u00f3nica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63239a89 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"63239a89\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3cfbb241\" data-id=\"3cfbb241\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ebffde0 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"4ebffde0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1321\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1321\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1322\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1322\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1323\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1323\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1321\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1321\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1321\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera ingenier\u00eda electr\u00f3nica es proponer soluciones a los sistemas electr\u00f3nicos enfocados en el \u00e1rea de control autom\u00e1tico, telecomunicaciones y redes IP. El ingeniero electr\u00f3nico ser\u00e1 capaz de analizar y dise\u00f1ar sistemas de control autom\u00e1tico y sistemas de telecomunicaciones, as\u00ed mismo implementa, administra y gestiona los sistemas de redes IP.<br \/>Por su formaci\u00f3n, el ingeniero electr\u00f3nico puede desarrollarse profesionalmente en instituciones p\u00fablicas\/privadas, organismos no gubernamentales e industrias que demanden servicios tecnol\u00f3gicos en las \u00e1reas de telecomunicaciones, redes IP y control de procesos industriales.<br \/>El graduado en ingenier\u00eda electr\u00f3nica, deber\u00e1 mostrar creatividad, habilidad para comunicarse de manera oral y escrita, que permita avanzar en los distintas instituciones y empresas tecnol\u00f3gicas, as\u00ed tambi\u00e9n su desarrollo en los campos de acci\u00f3n profesionales tales como sistemas electr\u00f3nicos, sistemas de redes IP, sistemas de telecomunicaciones y sistemas de control automatizado, donde se desempe\u00f1e; adem\u00e1s deber\u00e1 mostrar respeto al medio ambiente, a la diversidad cultural y de g\u00e9nero, inclusi\u00f3n social de personas con capacidades diferentes, como contribuci\u00f3n al buen vivir de los pueblos.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Empresas de servicios de telefon\u00eda fija y m\u00f3vil<\/li><li>Empresas proveedoras de servicio de internet (IPS)<\/li><li>Empresas de servicio de transporte de datos banda ancha<\/li><li>Empresas de servicio de TV digital y radio<\/li><li>Empresas de desarrollo tecnol\u00f3gico en diferentes \u00e1reas de aplicaci\u00f3n<\/li><li>Organizaciones p\u00fablicas o privadas que demanden redes de telecomunicaciones<\/li><li>Organismos reguladores de servicios de telecomunicaciones<\/li><li>Empresas de servicios de redes de geoposicionamiento<\/li><li>Empresas de servicios de control, mantenimiento y ciberseguridad de redes convergentes<\/li><li>Instituciones p\u00fablicas y privadas que demanden administraci\u00f3n y gesti\u00f3n de redes convergentes<\/li><li>Industrias, instituciones p\u00fablicas y privadas que tengan sistemas automatizados de procesos industriales<\/li><li>Industrias de manufactura, producci\u00f3n del sector pecuario, av\u00edcola y agr\u00edcola<\/li><li>Instituciones p\u00fablicas y privadas que realizan investigaciones en el \u00e1rea de telecomunicaciones, automatizaci\u00f3n y control industrial<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Identificar problemas o necesidades de nuevos servicios o infraestructura de redes basadas en tecnolog\u00eda IP<\/li><li>Determinar problema o necesidades en sistemas de automatizaci\u00f3n totalmente integrados en el \u00e1rea industrial<\/li><li>Crear redes de telecomunicaciones convergentes basadas en tecnolog\u00eda IP<\/li><li>Realizar y Trazar sistemas de seguridad (video vigilancia y control de acceso)<\/li><li>Plantear sistemas b\u00e1sicos de automatizaci\u00f3n totalmente integrados en el \u00e1rea industrial<\/li><li>Instalar redes convergentes basadas en tecnolog\u00eda IP<\/li><li>Operar redes de telecomunicaciones convergentes basadas en tecnolog\u00eda IP<\/li><li>Efectuar soluciones b\u00e1sicas de automatizaci\u00f3n totalmente integrados en el \u00e1rea industrial<\/li><li>Supervisar y controlar sistemas de automatizaci\u00f3n totalmente integrados en el \u00e1rea industrial<\/li><li>Realizar mantenimiento de equipos, dispositivos y sistemas de control de procesos industriales<\/li><li>Controlar y monitorear la transmisi\u00f3n de datos sobre redes basadas en tecnolog\u00eda IP<\/li><li>Resolver aver\u00edas en las capas de distribuci\u00f3n y acceso de redes basadas en tecnolog\u00eda IP<\/li><li>Realizar mantenimiento correctivo y preventivo de equipos y dispositivos electr\u00f3nicos para sus diferentes aplicaciones<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1322\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1322\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1322\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>C\u00e1lculo I<\/li><li>F\u00edsica I<\/li><li>Electr\u00f3nica y Electricidad B\u00e1sica<\/li><li>Componentes Electr\u00f3nicos<\/li><li>Electiva I<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>C\u00e1lculo II<\/li><li>Electr\u00f3nica Anal\u00f3gica I<\/li><li>Introducci\u00f3n a los Microcontroladores<\/li><li>Circuitos El\u00e9ctricos I<\/li><li>Electiva II<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Electr\u00f3nica Anal\u00f3gica II<\/li><li>Electr\u00f3nica Digital I<\/li><li>Microcontroladores<\/li><li>Circuitos El\u00e9ctricos II<\/li><li>Electiva III<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>F\u00edsica II<\/li><li>Instrumentaci\u00f3n Electr\u00f3nica<\/li><li>Electr\u00f3nica Digital II<\/li><li>Microprocesadores<\/li><li>Maquinas El\u00e9ctricas<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Comunicaciones I<\/li><li>Optativa I<\/li><li>Optativa II<\/li><li>Redes IP I<\/li><li>Accionamiento El\u00e9ctrico<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Comunicaciones II<\/li><li>Optativa III<\/li><li>Optativa IV<\/li><li>Sensores y Acondicionadores de Se\u00f1al<\/li><li>Redes IP II<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Antenas<\/li><li>Radiocomunicaciones<\/li><li>Servicios de Redes IP<\/li><li>Control Autom\u00e1tico I<\/li><li>Optativa V<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Telefon\u00eda<\/li><li>Sistemas de Comunicaciones \u00d3pticas<\/li><li>Control autom\u00e1tico II<\/li><li>Optativa VI<\/li><li>Optativa VII<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Comunicaciones M\u00f3viles<\/li><li>Gesti\u00f3n de Redes<\/li><li>Sistemas Automatizados<\/li><li>Pr\u00e1cticas Pre-profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas <span style=\"font-family: inherit; font-size: inherit;\">Profesionales<\/span><\/li><li>Modalidad de graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1323\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1323\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1323\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"16982\" class=\"elementor elementor-16982\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-isi\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f4300a4 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"5f4300a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c4e11b\" data-id=\"2c4e11b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2959eb09\" data-id=\"2959eb09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-173eb2c7 elementor-widget elementor-widget-heading\" data-id=\"173eb2c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda en Sistemas de la Informaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32019145 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"32019145\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46d64430\" data-id=\"46d64430\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-363af7e1 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"363af7e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9091\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9091\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9092\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9092\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9093\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9093\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9091\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9091\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9091\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de Sistemas de Informaci\u00f3n son los sistemas inform\u00e1ticos. Por ello, el profesional de Sistemas de Informaci\u00f3n domina todo el ciclo de desarrollo de un sistema inform\u00e1tico, gestiona los procesos del \u00e1rea de TI y es capaz de realizar el an\u00e1lisis de datos, todo esto para facilitar las operaciones diarias en las empresas y la toma de decisiones por la gerencia. Por tanto, el profesional puede desarrollarse en entidades p\u00fablicas y privadas, nacionales e internacionales, as\u00ed como trabajar de forma independiente, con base en una formaci\u00f3n integral, human\u00edstica y cr\u00edtica centrada en el ser humano.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9092\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9092\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9092\" tabindex=\"0\" hidden=\"hidden\"><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0 \u00a0 \u00a0 \u00a0<\/b><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Fundamentos matem\u00e1ticos<\/li><li>T\u00e9cnicas de redacci\u00f3n y comunicaci\u00f3n<\/li><li>TIC<\/li><li>Dise\u00f1o de interfaces de usuario<\/li><li>Pensamiento computacional<\/li><li>Integrador I<b>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/b><\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Estructuras discretas<\/li><li>Fundamentos de ingenier\u00eda<\/li><li>TI en la empresa<\/li><li>Programaci\u00f3n de software I<\/li><li>Fundamentos de base de datos<\/li><li>Integrador II<b>\u00a0\u00a0\u00a0<\/b><\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Fundamentos de estad\u00edstica<\/li><li>Modelaci\u00f3n de procesos de negocios<\/li><li>Base de datos<\/li><li>Programaci\u00f3n de software II<\/li><li>Ingenier\u00eda de Software I<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Programaci\u00f3n web I<\/li><li>Ingenier\u00eda de software II<\/li><li>Programaci\u00f3n con estructuras de datos<\/li><li>Administraci\u00f3n de base de datos relacionales<\/li><li>Resguardo de la informaci\u00f3n<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Calidad del software<\/li><li>Programaci\u00f3n web II<\/li><li>Base de datos multidimensionales<\/li><li>An\u00e1lisis exploratorio de datos<\/li><li>Proyecto de TI I<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Programaci\u00f3n m\u00f3vil<\/li><li>Programaci\u00f3n en la nube<\/li><li>Base de datos no relacional<\/li><li>Base de datos anal\u00edticas<\/li><li>Proyectos de TI II<\/li><li>Integrador VI<\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\">\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/b><\/p><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Visualizaci\u00f3n de la informaci\u00f3n<\/li><li>\u00abOptativa I<\/li><li>\u00abOptativa II<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Miner\u00eda de datos<\/li><li>Optativa III<\/li><li>Optativa IV<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Proyecto de anal\u00edtica de datos<\/li><li>\u00abOptativa V<\/li><li>Pr\u00e1cticas de Pre-Profesionales<\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0\u00a0<\/b><\/p><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/b><\/p><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9093\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9093\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9093\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17298\" class=\"elementor elementor-17298\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d421d40 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"d421d40\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b7be380\" data-id=\"3b7be380\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52a08444\" data-id=\"52a08444\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29fcdcd9 elementor-widget elementor-widget-heading\" data-id=\"29fcdcd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda Industrial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5de5bc33 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"5de5bc33\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59bca4ed\" data-id=\"59bca4ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e378b3 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"1e378b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3161\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3161\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3162\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3162\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3163\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3163\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3161\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3161\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3161\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de Ingenier\u00eda Industrial se encuentra en la optimizaci\u00f3n de los recursos en los sistemas productivos. El ingeniero industrial cuenta con la capacidad de la b\u00fasqueda de reducci\u00f3n de desperdicios de los recursos, implementar proyectos de mejora en los procesos, productividad y sistemas de gesti\u00f3n de calidad; adem\u00e1s tiene dominio de la gesti\u00f3n de integraci\u00f3n de cadenas de suministro.<\/p><p>El Ingeniero Industrial desarrolla planes de producci\u00f3n a trav\u00e9s del uso de estad\u00edsticas, uso de simulaci\u00f3n y bajo los principios de eficiencia, eficacia y efectividad, minimizando el impacto ambiental bajo criterios de desarrollo sostenible. Por lo tanto, el profesional tiene una gran versatilidad en el campo laboral, puede dedicarse a cualquier \u00e1rea de giro industrial, aportando al desarrollo de innovaciones y emprendimientos; as\u00ed como tambi\u00e9n, puede desarrollarse en sectores econ\u00f3micos de servicios.<\/p><p>Es comprometido con el desarrollo personal y tecnol\u00f3gico para mejora de la calidad de vida en el trabajo y selecci\u00f3n de tecnolog\u00eda de acuerdo a la cultura y condiciones socioecon\u00f3micas en que se desenvuelve.<\/p><p>El profesional en Ingenier\u00eda Industrial tiene una formaci\u00f3n integral, su actuaci\u00f3n es con sentido \u00e9tico, equidad de g\u00e9nero, aportando al desarrollo social y econ\u00f3mico del pa\u00eds<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>El ingeniero industrial es un profesional polivalente, desempe\u00f1a su profesi\u00f3n fundamentalmente en empresas industriales, pero tambi\u00e9n en empresas de servicios como en unidades de negocio de log\u00edstica, distribuci\u00f3n y almacenes, instituciones financieras. Su cualificaci\u00f3n, permite la presencia en entidades p\u00fablicas, organismos no gubernamentales y Pymes.<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><p>Con base a los resultados del diagn\u00f3stico, se encontr\u00f3 que los campos de acci\u00f3n son los siguientes:<br \/>\u2022 Producci\u00f3n de bienes y servicios<br \/>\u2022 Calidad en los procesos<br \/>\u2022 Desarrollo Industrial<br \/>\u2022 Cadena de Suministros<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3162\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3162\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3162\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p>I A\u00d1O<\/p><p><strong>SEMESTRE I<\/strong><\/p><ul><li>C\u00e1lculo I<\/li><li>Introducci\u00f3n a Ingenier\u00eda Industrial<\/li><li>Inform\u00e1tica aplicada a Ingenier\u00eda<\/li><li>T\u00e9cnica de Investigaci\u00f3n Documental<\/li><li>Integrador I<\/li><li>Electiva I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>C\u00e1lculo II<\/li><li>F\u00edsica I<\/li><li>Dibujo Industrial<\/li><li>Emprendimiento<\/li><li>Integrador II<\/li><\/ul><\/td><td><p>II A\u00d1O<\/p><p><strong>SEMESTRE III<\/strong><\/p><ul><li>C\u00e1lculo III<\/li><li>F\u00edsica II<\/li><li>Mec\u00e1nica<\/li><li>Contabilidad<\/li><li>Integrador III<\/li><li>Electiva III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>M\u00e9todos Num\u00e9ricos<\/li><li>Mec\u00e1nica de Fluidos<\/li><li>Proceso de Manufactura<\/li><li>Estad\u00edsticas y Probabilidad<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Termodin\u00e1mica<\/li><li>Estudio del Trabajo<\/li><li>Control Estad\u00edstico de la Calidad de los procesos<\/li><li>Integrador V<\/li><li>Optativa I<\/li><li>Optativa II<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Investigaci\u00f3n de Operaciones<\/li><li>Ingenier\u00eda de la Calidad<\/li><li>Seguridad e Higiene en el Trabajo<\/li><li>Simulaci\u00f3n<\/li><li>Integrador VI<\/li><li>Optativa III<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Planificaci\u00f3n y Control de la Producci\u00f3n<\/li><li>Productividad<\/li><li>Gesti\u00f3n Industrial del Talento Humano<\/li><li>Cadena de Suministro I<\/li><li>Integrador VII<\/li><li>Optativa IV<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Dise\u00f1o y Desarrollo de Productos<\/li><li>Ingenier\u00eda Econ\u00f3mica<\/li><li>Cadena de Suministro II<\/li><li>Integrador VIII<\/li><li>Optativa V<\/li><li>Optativa VI<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Formulaci\u00f3n y Evaluaci\u00f3n de Proyectos<\/li><li>Optativa VII<\/li><li>Pr\u00e1ctica Pre Profesional<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1ctica Profesionalizante<\/li><li>Modalidad de culminaci\u00f3n de estudio<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3163\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3163\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3163\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Estel\u00ed<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17304\" class=\"elementor elementor-17304\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20318c14 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"20318c14\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5ad0766\" data-id=\"5ad0766\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59cfa79\" data-id=\"59cfa79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66a8c7b5 elementor-widget elementor-widget-heading\" data-id=\"66a8c7b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda Ambiental<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2574594c elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"2574594c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50bf0743\" data-id=\"50bf0743\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54ba5c44 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"54ba5c44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1421\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1421\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1422\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1422\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1423\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1423\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1421\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1421\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1421\" tabindex=\"0\" hidden=\"false\"><p>Preserva los recursos naturales desde el componente econ\u00f3mico y social, trabaja en la prevenci\u00f3n de la contaminaci\u00f3n, la preservaci\u00f3n de los recursos naturales, reduce y mitiga la contaminaci\u00f3n, dise\u00f1a sistemas de tratamiento de los residuos s\u00f3lidos y l\u00edquidos, realiza valoraciones de los servicios eco sist\u00e9micos y una gesti\u00f3n integrada de recursos naturales y productivos.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Entidades p\u00fablicas y privadas dedicadas al cuido, protecci\u00f3n y restauraci\u00f3n de los recursos naturales.<\/li><li>Unidades ambientales de las alcald\u00edas municipalidades.<\/li><li>\u00c1reas protegidas.<\/li><li>Centros e institutos de investigaci\u00f3n orientados a la preservaci\u00f3n del ambiente.<\/li><li>Empresas que se dedican al desarrollo sostenible.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Intervenciones ambientales.<\/li><li>Afectaciones ambientales antropog\u00e9nicas.<\/li><li>Tratamiento de desechos s\u00f3lidos, l\u00edquidos y gaseosos.<\/li><li>Proyectos ambientales.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1422\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1422\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1422\" tabindex=\"0\" hidden=\"hidden\"><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style>\n<table class=\"tftable\" border=\"1\">\n<tbody>\n<tr>\n<td><strong>I A\u00d1O<\/strong>\n\nSEMESTRE I\n<ul>\n \t<li>Ecolog\u00eda y Problem\u00e1tica Ambiental<\/li>\n \t<li>Qu\u00edmica y Medio Ambiente<\/li>\n \t<li>Fundamentos de la Comunicaci\u00f3n Oral y Escrita<\/li>\n \t<li>Introducci\u00f3n a la Contaminaci\u00f3n Ambiental<\/li>\n \t<li>Inform\u00e1tica Aplicada a<\/li>\n \t<li>la Ciencias Ambientales<\/li>\n \t<li>Integrador I (Ensayo)<\/li>\n<\/ul>\nSEMESTRE II\n<ul>\n \t<li>Contaminaci\u00f3n Ambiental en los Ecosistemas<\/li>\n \t<li>Naturaleza de la F\u00edsica\nAritm\u00e9tica<\/li>\n \t<li>Generalidades de Recursos H\u00eddricos<\/li>\n \t<li>Integrador II (Soluci\u00f3n de problemas)<\/li>\n<\/ul>\n<\/td>\n<td><strong>II A\u00d1O<\/strong>\n\nSEMESTRE III\n<ul>\n \t<li>Qu\u00edmica de los Residuos<\/li>\n \t<li>Geometr\u00eda Elemental<\/li>\n \t<li>Metodolog\u00eda para la Evaluaci\u00f3n y Manejo de los Impactos Ambientales<\/li>\n \t<li>Optativo 1.1 (Generalidades del recurso suelo)<\/li>\n \t<li>Optativo 1.2 (Inform\u00e1tica)<\/li>\n \t<li>Integrador III (Estudio de caso)<\/li>\n<\/ul>\nSEMESTRE IV\n<ul>\n \t<li>Mec\u00e1nica de Fluidos<\/li>\n \t<li>Fundamentos para la Redacci\u00f3n T\u00e9cnico- Cient\u00edfica<\/li>\n \t<li>Caracterizaci\u00f3n y Diagn\u00f3stico de Cuencas Hidrogr\u00e1ficas<\/li>\n \t<li>Optativo 2.1 (Principios para la gesti\u00f3n de residuos s\u00f3lidos y l\u00edquidos)<\/li>\n \t<li>Optativo 2.2 (Estad\u00edstica aplicada)<\/li>\n \t<li>Integrador 4<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td><strong>III A\u00d1O<\/strong>\n\nSEMESTRE V\n<ul>\n \t<li>Hidrodin\u00e1mica<\/li>\n \t<li>Derivaciones e Integrales<\/li>\n \t<li>Estudios de los Recursos H\u00eddricos<\/li>\n \t<li>Diagn\u00f3stico del Estado Actual del Suelo<\/li>\n \t<li>Integrador V (Trabajo en equipo)<\/li>\n<\/ul>\nSEMESTRE VI\n<ul>\n \t<li>Termodin\u00e1mica<\/li>\n \t<li>Introducci\u00f3n al Manejo Integral del Bosque<\/li>\n \t<li>Fundamentos de la Investigaci\u00f3n<\/li>\n \t<li>Optativo 3.1 (T\u00e9cnicas de remedici\u00f3n de suelos)<\/li>\n \t<li>Optativo 3.2 (Evaluaci\u00f3n de alternativas de manejo del recurso suelo)<\/li>\n \t<li>Integrador VI (Modelado)<\/li>\n<\/ul>\n<\/td>\n<td><strong>IV A\u00d1O<\/strong>\n\nSEMESTRE VII\n<ul>\n \t<li>Ecuaciones Diferenciales<\/li>\n \t<li>Tratamiento de Residuos S\u00f3lidos\nDerecho Ambiental<\/li>\n \t<li>Optativo 4.1 (Gesti\u00f3n integral de los recursos h\u00eddricos)<\/li>\n \t<li>Optativo 4.2 (Planificaci\u00f3n de cuencas)<\/li>\n \t<li>Integrador VII (Soluci\u00f3n de problemas)<\/li>\n<\/ul>\nSEMESTRE VIII\n<ul>\n \t<li>Redacci\u00f3n T\u00e9cnico-Cient\u00edfica<\/li>\n \t<li>Tratamiento de Aguas Residuales<\/li>\n \t<li>Sistemas Forestales Tropicales<\/li>\n \t<li>Perfiles de Proyectos<\/li>\n \t<li>Optativo 5.1 (Tratamiento de aguas naturales)<\/li>\n \t<li>Optativo 5.2 (Sistema de Informaci\u00f3n Geogr\u00e1fica)<\/li>\n \t<li>Integrador VIII (Elaboraci\u00f3n de propuesta\nt\u00e9cnica)<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td><strong>V A\u00d1O<\/strong>\n\nSEMESTRE IX\n<ul>\n \t<li>Dibujo Aplicado a la Ingenier\u00eda Ambiental<\/li>\n \t<li>Gesti\u00f3n Integral del Recurso Suelo<\/li>\n \t<li>Evaluaci\u00f3n de Impacto Ambiental<\/li>\n \t<li>Optativo 6.1 (Dise\u00f1o de plantas de tratamiento de residuos s\u00f3lidos)<\/li>\n \t<li>Optativo 6.2 (Software para dise\u00f1os ingenieriles)<\/li>\n \t<li>Pr\u00e1ctica Pre-Profesional<\/li>\n<\/ul>\nSEMESTRE X\n<ul>\n \t<li>Dise\u00f1o de Plantas de Tratamiento de Aguas Residuales<\/li>\n \t<li>Modalidad de Graduaci\u00f3n<\/li>\n \t<li>Formulaci\u00f3n de Proyectos<\/li>\n \t<li>Pr\u00e1ctica Profesional<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1423\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1423\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1423\" tabindex=\"0\" hidden=\"hidden\"><ul><li>CUR-Estel\u00ed<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17308\" class=\"elementor elementor-17308\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-ingest\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5977ed89 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"5977ed89\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1908d0ac\" data-id=\"1908d0ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40ca10be\" data-id=\"40ca10be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-590d1be5 elementor-widget elementor-widget-heading\" data-id=\"590d1be5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda Estad\u00edstica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c7444ac elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"3c7444ac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65a6d33b\" data-id=\"65a6d33b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6c941f elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"b6c941f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1911\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1911\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1912\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1912\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1913\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1913\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1911\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1911\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1911\" tabindex=\"0\" hidden=\"false\"><p>Considerando que el objeto de estudio de la Ingenier\u00eda Estad\u00edstica es la variabilidad de tipo aleatoria y\/o determin\u00edstica de los fen\u00f3menos naturales, sociales e industriales y que el campo de acci\u00f3n de la ingenier\u00eda estad\u00edstica es la participaci\u00f3n en una o m\u00e1s etapas del proceso de investigaci\u00f3n en diversas \u00e1reas del conocimiento, por tanto el ingeniero estad\u00edstico planifica y ejecuta estudios en relaci\u00f3n a la recolecci\u00f3n, almacenamiento, procesamiento, an\u00e1lisis de datos, as\u00ed como la interpretaci\u00f3n y presentaci\u00f3n de informaci\u00f3n para una \u00f3ptima toma de decisiones, con altos valores de servicio, integridad y profesionalismo para desempe\u00f1arse en instituciones p\u00fablicas y privadas de los sectores productivos y de servicios, ONG\u00b4s, Instituciones de Educaci\u00f3n Superior (IES) y centros de investigaci\u00f3n.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Instituciones p\u00fablicas y privadas de los sectores productivos y de servicios, ONGs, IES y centros de investigaci\u00f3n.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Participaci\u00f3n en la identificaci\u00f3n y formulaci\u00f3n de problemas de estudios en las \u00e1reas de las ciencias naturales, sociales e industriales.<\/li><li>Detecci\u00f3n de las actividades que requieran de mayor prioridad en los estudios.<\/li><li>Ejercicio de la autoridad y liderazgo para coordinar y controlar a los grupos de trabajo para cumplir con las actividades seg\u00fan el cronograma de trabajo en el proceso de investigaci\u00f3n.<\/li><li>Identificaci\u00f3n los factores asociados a los problemas de estudios en las \u00e1reas de las ciencias naturales, sociales e industriales.<\/li><li>Dise\u00f1o de instrumentos de recolecci\u00f3n de datos acorde a los factores asociados a los problemas de estudios a partir de distintas fuentes disponibles.<\/li><li>Participaci\u00f3n como encuestador, empadronador y\/o supervisor de campo para el levantamiento de datos, utilizando diversos tipos de instrumentos.<\/li><li>Aplicaci\u00f3n de t\u00e9cnicas de muestreo para la cr\u00edtica en el levantamiento de datos.<\/li><li>Utilizaci\u00f3n de lenguajes de programaci\u00f3n y programas estad\u00edsticos computacionales especializados en el procesamiento de grandes cantidades de datos.<\/li><li>El manejo de t\u00e9cnicas de muestreo para la cr\u00edtica de datos en el procesamiento de los mismos.<\/li><li>Identificaci\u00f3n de los modelos estad\u00edsticos adecuados para el an\u00e1lisis de los datos.<\/li><li>Interpretaci\u00f3n de resultados en la investigaci\u00f3n.<\/li><li>Elaboraci\u00f3n de informes t\u00e9cnicos\/cient\u00edficos para su presentaci\u00f3n oral y escrita.<\/li><li>Participaci\u00f3n en la creaci\u00f3n de sistemas de alerta temprana.<\/li><li>Gesti\u00f3n y administraci\u00f3n de grandes bases de datos.<\/li><li>Evaluaci\u00f3n de la probabilidad de ocurrencia de eventos futuros mediante modelos estad\u00edsticos.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1912\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1912\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1912\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Estad\u00edstica Descriptiva<\/li><li>Matem\u00e1tica B\u00e1sica<\/li><li>Inform\u00e1tica B\u00e1sica<\/li><li>Matem\u00e1ticas Discretas<\/li><li>Integrador 1<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Formulaci\u00f3n y dise\u00f1o de encuestas en l\u00ednea<\/li><li>Calculo Diferencial e Integral<\/li><li>Algoritmos y Estructura de Datos<\/li><li>C\u00e1lculo de Probabilidades I<\/li><li>Integrador 2<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Algebra Lineal para Ingenieros<\/li><li>C\u00e1lculo de Probabilidades II<\/li><li>Programaci\u00f3n SQL Server<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Integrador 3<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Procesos Estoc\u00e1sticos<\/li><li>An\u00e1lisis de indicadores<\/li><li>Inferencia Estad\u00edstica<\/li><li>Investigaci\u00f3n de Operaciones<\/li><li>Manejo de bases de datos con ACCES<\/li><li>Integrador 4<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Modelos Lineales I<\/li><li>Estad\u00edstica no Param\u00e9trica<\/li><li>Programaci\u00f3n en R<\/li><li>Optativa 1<\/li><li>Optativa 2<\/li><li>Integrador 5<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Estad\u00edstica y Sistemas Georreferenciados<\/li><li>Planes de Negocios<\/li><li>Modelos Lineales II<\/li><li>Optativa 3<\/li><li>Optativa 4<\/li><li>Integrador 6<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>An\u00e1lisis Multivariado I<\/li><li>Demograf\u00eda<\/li><li>Series Temporales<\/li><li>T\u00e9cnicas de Muestreo I<\/li><li>Optativa 5<\/li><li>Integrador 7<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>An\u00e1lisis Multivariado II<\/li><li>Gobierno de Datos I<\/li><li>T\u00e9cnicas de Muestreo II<\/li><li>Programaci\u00f3n en Python<\/li><li>Optativa 6<\/li><li>Integrador 8<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Miner\u00eda de Datos<\/li><li>Gobierno de Datos II<\/li><li>Pr\u00e1ctica PreProfesionales<\/li><li>SEMESTRE X<\/li><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1913\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1913\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1913\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17311\" class=\"elementor elementor-17311\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-geo-fisica\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2989961e elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"2989961e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3c8165eb\" data-id=\"3c8165eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-10a298e6\" data-id=\"10a298e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-543f7cb7 elementor-widget elementor-widget-heading\" data-id=\"543f7cb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda en Geof\u00edsica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2459378c elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"2459378c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79ee1f49\" data-id=\"79ee1f49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fd2dfe0 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"1fd2dfe0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5331\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-5331\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5332\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5332\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-5331\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5331\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5331\" tabindex=\"0\" hidden=\"false\"><p>El egresado de la carrera de Ingenier\u00eda Geof\u00edsica ser\u00e1 un profesional competente con conocimientos en ciencias de la tierra, astrof\u00edsica, geof\u00edsica planetaria, energ\u00edas renovables, f\u00edsica de la atm\u00f3sfera; que le permitan entender, emplear y desarrollar diferentes metodolog\u00edas de geof\u00edsica aplicada.<\/p><p>El ingeniero geof\u00edsico estar\u00e1 facultado para: explorar, descubrir y delimitar los recursos naturales estrat\u00e9gicos para el desarrollo sostenible, socio econ\u00f3mico del pa\u00eds. Adem\u00e1s de desarrollar investigaciones cient\u00edficas en ciencias de la tierra y de atm\u00f3sfera, astrof\u00edsica, geof\u00edsica planetaria. Por ende, estudia, eval\u00faa y da soluci\u00f3n a problemas de ingenier\u00eda e impacto ambiental, producidos como consecuencia de la interacci\u00f3n de las actividades humanas con el medio ambiente.<\/p><p>As\u00ed como, monitorear y aprovechar los mecanismos de los fen\u00f3menos terrestres y extraterrestres para la prevenci\u00f3n, mitigaci\u00f3n y alerta temprana de desastres naturales que afecten a la sociedad. Adem\u00e1s, ser\u00e1 capaz de procesar e interpretar datos derivados de estudios geof\u00edsicos aplicados a problemas ingenieriles haciendo uso de la tecnolog\u00eda..<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5332\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5332\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5332\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Geo-Inform\u00e1tica<\/li><li>Integrador I<\/li><li>F\u00edsica Experimental<\/li><li>Introducci\u00f3n a la Ingenier\u00eda Geof\u00edsica<\/li><li>Qu\u00edmica Aplicada a Ciencias de la Tierra<\/li><li>Matem\u00e1tica B\u00e1sica y Geometr\u00eda Anal\u00edtica<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>C\u00e1lculo Diferencial en una y varias variables<\/li><li>Geoqu\u00edmica<\/li><li>F\u00edsica General I<\/li><li>Integrador II<\/li><li>Fundamento de Programaci\u00f3n<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Fundamentos de Geolog\u00eda Estructural<\/li><li>\u00c1lgebra lineal<\/li><li>C\u00e1lculo integral<\/li><li>F\u00edsica General II<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>C\u00e1lculo vectorial<\/li><li>F\u00edsica General III<\/li><li>Integrador IV<\/li><li>Sistema de Informaci\u00f3n Geogr\u00e1fica (SIG)<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Programaci\u00f3n y An\u00e1lisis Num\u00e9rico<\/li><li>Geolog\u00eda Econ\u00f3mica<\/li><li>Ecuaciones diferenciales ordinarias<\/li><li>F\u00edsica General IV<\/li><li>Mec\u00e1nica Te\u00f3rica<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Optativo I<\/li><li>Introducci\u00f3n al Tratamiento de Se\u00f1ales<\/li><li>Prospecci\u00f3n Magn\u00e9tica y Gravim\u00e9trica<\/li><li>Teor\u00eda Electromagn\u00e9tica<\/li><li>M\u00e9todos Matem\u00e1ticos Aplicados a la Geof\u00edsica<\/li><li>Integrador VI<\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0 \u00a0 \u00a0\u00a0<\/b><\/p><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Vulcanolog\u00eda<\/li><li>Optativo II<\/li><li>Sismolog\u00eda<\/li><li>Prospecci\u00f3n S\u00edsmica<\/li><li>Optativo III<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Prospecci\u00f3n Geoel\u00e9ctrica<\/li><li>Petrof\u00edsica y Registro de Pozo<\/li><li>Hidrogeolog\u00eda<\/li><li>Optativo IV<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Prospecci\u00f3n Electromagn\u00e9tica<\/li><li>Pr\u00e1cticas Pre-Profesionales<\/li><li>Mineralog\u00eda F\u00edsica<\/li><li>Optativo V<\/li><li>Optativo VI<\/li><li>Integrador IX<\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0\u00a0<\/b><\/p><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0 \u00a0 \u00a0\u00a0<\/b><\/p><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17314\" class=\"elementor elementor-17314\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-ingeologica\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40387d1b elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"40387d1b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-70922521\" data-id=\"70922521\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b9195dd\" data-id=\"5b9195dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a74a2ff elementor-widget elementor-widget-heading\" data-id=\"2a74a2ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda Geol\u00f3gica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35f1be85 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"35f1be85\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56f1963\" data-id=\"56f1963\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c658453 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"4c658453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1281\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1281\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1282\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1282\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1283\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1283\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1281\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1281\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1281\" tabindex=\"0\" hidden=\"false\"><p>El ingeniero ge\u00f3logo tiene como objeto el estudio de las ciencias de la Tierra, desarrolla investigaciones multi e interdisciplinarias, interactuando con otros profesionales relacionados en los diferentes campos de la geociencia, participando en estudios de amenazas y riesgos geol\u00f3gicos, ordenamiento territorial y realiza trabajos geot\u00e9cnicos para la construcci\u00f3n de obras civiles. Tambi\u00e9n, podr\u00e1 desarrollarse como profesional independiente o gestor de su propia empresa, cuyo desempe\u00f1o est\u00e9 relacionado con el \u00e1rea de su formaci\u00f3n.<\/p><p>Adem\u00e1s, las competencias del ingeniero ge\u00f3logo lo faculta para: estudiar, evaluar y dar soluci\u00f3n a problemas de ingenier\u00eda e impacto ambiental, producidos como consecuencia de la interacci\u00f3n de las actividades humanas con el medio geol\u00f3gico. As\u00ed mismo, debe ser capaz de establecer e interpretar los conocimientos requeridos en la elaboraci\u00f3n de la cartograf\u00eda geol\u00f3gica y datos tem\u00e1ticos mediante el uso integral de las herramientas de la geom\u00e1tica, que contribuye en la planificaci\u00f3n y ejecuci\u00f3n de proyectos en la exploraci\u00f3n y manejo integral de recursos geol\u00f3gicos.<\/p><p>El ingeniero ge\u00f3logo debe ser un profesional con una concepci\u00f3n cient\u00edfica y human\u00edstica del mundo, capaz de interpretar los fen\u00f3menos sociales y naturales con un sentido cr\u00edtico, reflexivo. Al mismo tiempo, debe de ser un profesional con conocimientos s\u00f3lidos que sirvan como referente en el \u00e1mbito p\u00fablico y privado, logrando influir en la toma de decisiones empresariales e institucionales vinculados al desarrollo econ\u00f3mico del pa\u00eds.<\/p><p><b>\u00c1mbitos<\/b><strong>\u00a0de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Instituciones del estado relacionadas con el campo de ciencias de la Tierra.<\/li><li>Centros de investigaciones a fines a las geociencias p\u00fablicos y privados.<\/li><li>Empresas consultoras que prestan servicios geol\u00f3gicos.<\/li><li>Campos geot\u00e9rmicos<\/li><\/ul><p><strong>Tareas que puede realizar el profesional: &#8211; Cartograf\u00eda geol\u00f3gica<\/strong><\/p><ul><li>Geolog\u00eda aplicada a obras civiles.<\/li><li>Amenazas geol\u00f3gicas.<\/li><li>Recursos naturales geol\u00f3gicos.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1282\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1282\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1282\" tabindex=\"0\" hidden=\"hidden\"><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style>\n<table class=\"tftable\" border=\"1\">\n<tbody>\n<tr>\n<td><strong>I A\u00d1O<\/strong>\n\nSEMESTRE I\n<ul>\n \t<li>Fundamentos de Geolog\u00eda<\/li>\n \t<li>Qu\u00edmica Aplicada a Ciencias de la Tierra I<\/li>\n \t<li>Algebra<\/li>\n \t<li>F\u00edsica I<\/li>\n \t<li>Electiva I<\/li>\n \t<li>Integradora I<\/li>\n<\/ul>\nSEMESTRE II\n<ul>\n \t<li>Geolog\u00eda F\u00edsica<\/li>\n \t<li>Geolog\u00eda Hist\u00f3rica de Nicaragua<\/li>\n \t<li>Qu\u00edmica Aplicada a Ciencias de la Tierra II<\/li>\n \t<li>Calculo I<\/li>\n \t<li>F\u00edsica II<\/li>\n \t<li>Integradora II<\/li>\n<\/ul>\n<\/td>\n<td><strong>II A\u00d1O<\/strong>\n\nSEMESTRE III\n<ul>\n \t<li>Calculo II<\/li>\n \t<li>Termodin\u00e1mica y Electromagnetismo<\/li>\n \t<li>Mineralog\u00eda I<\/li>\n \t<li>Geodin\u00e1mica<\/li>\n \t<li>Electiva II<\/li>\n \t<li>Integradora III<\/li>\n<\/ul>\nSEMESTRE IV\n<ul>\n \t<li>Fundamentos de Recursos Naturales<\/li>\n \t<li>Mineralog\u00eda II<\/li>\n \t<li>Tect\u00f3nica<\/li>\n \t<li>Exploraci\u00f3n Geof\u00edsica<\/li>\n \t<li>Electiva III<\/li>\n \t<li>Integradora IV<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td><strong>III A\u00d1O<\/strong>\n\nSEMESTRE V\n<ul>\n \t<li>Petrolog\u00eda<\/li>\n \t<li>Yacimientos<\/li>\n \t<li>Minerales<\/li>\n \t<li>Geolog\u00eda Estructural<\/li>\n \t<li>Geolog\u00eda ambiental<\/li>\n \t<li>Hidrogeolog\u00eda<\/li>\n \t<li>Integradora V<\/li>\n<\/ul>\nSEMESTRE VI\n<ul>\n \t<li>Petrograf\u00eda<\/li>\n \t<li>Paleontolog\u00eda<\/li>\n \t<li>Sismolog\u00eda<\/li>\n \t<li>Geomorfolog\u00eda<\/li>\n \t<li>Optativa I<\/li>\n \t<li>Integradora IV<\/li>\n<\/ul>\n<\/td>\n<td><strong>IV A\u00d1O<\/strong>\n\nSEMESTRE VII\n<ul>\n \t<li>SIG<\/li>\n \t<li>Estratigraf\u00eda y Sedimentolog\u00eda<\/li>\n \t<li>Mec\u00e1nica de Roca y Suelo<\/li>\n \t<li>Optativa II<\/li>\n \t<li>Optativa III<\/li>\n \t<li>Integradora VII<\/li>\n<\/ul>\nSEMESTRE VIII\n<ul>\n \t<li>Cartograf\u00eda<\/li>\n \t<li>Geol\u00f3gica<\/li>\n \t<li>Volcanolog\u00eda<\/li>\n \t<li>Ingenier\u00eda Geol\u00f3gica Aplicada a la Ingenier\u00eda Civil<\/li>\n \t<li>Optativa IV<\/li>\n \t<li>Optativa V<\/li>\n \t<li>Integradora VIII<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td><strong>V A\u00d1O<\/strong>\n\nSEMESTRE IX\n<ul>\n \t<li>Exploraci\u00f3n<\/li>\n \t<li>Minera<\/li>\n \t<li>Optativa VI<\/li>\n \t<li>Optativa VII<\/li>\n \t<li>Pr\u00e1cticas Pre Profesionales<\/li>\n<\/ul>\nSEMESTRE X\n<ul>\n \t<li>Modalidad de Graduaci\u00f3n<\/li>\n \t<li>Pr\u00e1cticas Profesionales<\/li>\n<\/ul>\n<\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1283\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1283\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1283\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17320\" class=\"elementor elementor-17320\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#cei-ier\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e62750d elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"2e62750d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51676036\" data-id=\"51676036\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-12626f9e\" data-id=\"12626f9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34105f22 elementor-widget elementor-widget-heading\" data-id=\"34105f22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda en Energ\u00edas Renovables<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15edf4ff elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"15edf4ff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6252f321\" data-id=\"6252f321\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c829db9 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3c829db9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1011\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1011\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1012\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1012\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1013\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1013\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1011\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1011\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la Ingenier\u00eda en Energ\u00edas Renovables se basa en la naturaleza misma, al enfocar \u00e9ste al estudio de los recursos naturales y las potencialidades que \u00e9stos presentan mediante fuentes renovables de energ\u00eda, amigables con el medio ambiente, que de ser aprovechadas de forma sostenible dan respuesta a la problem\u00e1tica mundial en relaci\u00f3n con el tema de la energ\u00eda y la degradaci\u00f3n irreversible de nuestro planeta causado por fuentes convencionales, como el petr\u00f3leo, carb\u00f3n y gas natural.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1012\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1012\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1012\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Derivaci\u00f3n de funciones<br \/>Electricidad y magnetismo<\/li><li>Principios de electrotecnia<\/li><li>Introducci\u00f3n a mediciones de eficiencia energ\u00e9tica<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Integraci\u00f3n de funciones<\/li><li>Fundamentos de termometr\u00eda y termodin\u00e1mica<\/li><li>Marco legal y t\u00e9cnico para la generaci\u00f3n el\u00e9ctrica y la eficiencia energ\u00e9tica<\/li><li>Principios b\u00e1sicos<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Ecuaciones diferenciales ordinales<\/li><li>Potencia y energ\u00eda en circuitos el\u00e9ctrico de corriente alterna<\/li><li>Energ\u00eda solar<\/li><li>Fotovoltaica<\/li><li>Aplicaciones de los principios de conservaci\u00f3n de masa y energ\u00eda<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>M\u00e1quinas el\u00e9ctricas y sistemas de generaci\u00f3n, transmisi\u00f3n y distribuci\u00f3n de la energ\u00eda el\u00e9ctrica<\/li><li>Aplicaci\u00f3n de t\u00e9cnicas de lectura<\/li><li>Balanceo de materia y energ\u00eda<\/li><li>Dise\u00f1o de Sistemas solares t\u00e9rmicos<br \/>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Electr\u00f3nica b\u00e1sica<\/li><li>Comprensi\u00f3n escrita<\/li><li>Energ\u00eda E\u00f3lica<\/li><li>Generaci\u00f3n distribuida y<\/li><li>Cogeneraci\u00f3n de la energ\u00eda<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Componente curricular optativo 1<\/li><li>Conversores de potencia y microcontroladores<\/li><li>Diagnosis de ahorro y eficiencia energ\u00e9tica<br \/>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Componente curricular optativo 2<\/li><li>Estequiometria y cin\u00e9tica de las reacciones<\/li><li>An\u00e1lisis Estad\u00edsticos de<\/li><li>Par\u00e1metros de Recursos<\/li><li>Renovables<\/li><li>Integrador VIII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Componente curricular optativo 3<\/li><li>Evaluaci\u00f3n del Potencial<\/li><li>Energ\u00e9tico de Recursos<\/li><li>Renovables<\/li><li>Reactores qu\u00edmicos<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Componente curricular optativo 4<\/li><li>Formulaci\u00f3n de<\/li><li>Proyectos Energ\u00e9ticos<br \/>Hidrogenar\u00eda<\/li><li>Pr\u00e1ctica Pre Profesional<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Componente curricular optativo 5<\/li><li>Fundamentos de la combusti\u00f3n<\/li><li>Modalidad de Graduaci\u00f3n<\/li><li>Sistemas de generaci\u00f3n de biocombustibles<\/li><li>Practica de profesionalizaci\u00f3n<\/li><\/ul><p>\u00a0<\/p><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1013\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1013\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1013\" tabindex=\"0\" hidden=\"hidden\"><ul><li>CUR-Estel\u00ed<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17324\" class=\"elementor elementor-17324\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-fmed\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fdb3870 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"3fdb3870\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c3801ef\" data-id=\"2c3801ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45a4c43d\" data-id=\"45a4c43d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68e5338 elementor-widget elementor-widget-heading\" data-id=\"68e5338\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F\u00edsica M\u00e9dica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-180579b5 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"180579b5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-204040b\" data-id=\"204040b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3486bc6b elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3486bc6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8811\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8811\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8812\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8812\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8813\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8813\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8811\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8811\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8811\" tabindex=\"0\" hidden=\"false\"><p style=\"text-align: justify;\">La Licenciatura en F\u00edsica M\u00e9dica es una carrera en la que se prepara al F\u00edsico para trabajar en el \u00e1mbito hospitalario y en la docencia universitaria como formador e investigador, la F\u00edsica M\u00e9dica se desarrolla principalmente en las \u00e1reas disciplinares de Radiodiagn\u00f3stico, Radioterapia, Medicina Nuclear, F\u00edsica y Matem\u00e1tica. Otras \u00e1reas de inter\u00e9s son la metrolog\u00eda de las radiaciones ionizantes, resonancia magn\u00e9tica nuclear, ultrasonido y distintas t\u00e9cnicas que involucren conceptos F\u00edsicos aplicados a la Medicina.<\/p><p style=\"text-align: justify;\">La evoluci\u00f3n de los equipos diagn\u00f3sticos y tratamientos utilizados en la medicina cada d\u00eda se vuelven m\u00e1s sofisticados y se involucra a un grupo multidisciplinario de profesionales, en el cual el F\u00edsico M\u00e9dico participa activamente para la implementaci\u00f3n de programas de seguridad y radioprotecci\u00f3n en las distintas \u00e1reas en las instalaciones, esto implica una optimizaci\u00f3n de los procedimiento en donde entre otros se incluye la evaluaci\u00f3n de la calidad de imagen y su relaci\u00f3n con la dosis que se generan con los diferentes equipos de radiodiagn\u00f3stico por otro lado adem\u00e1s se realizan planificaciones de los tratamientos contra el c\u00e1ncer en las unidades de radioterapia.<\/p><p style=\"text-align: justify;\">El Licenciado en F\u00edsica con menci\u00f3n en F\u00edsica M\u00e9dica debe saber reconocer la calidad de imagen obtenidas con los equipos de radiodiagn\u00f3stico, interpretar los resultados de los controles de calidad realizados a los equipos de radiodiagn\u00f3stico, radioterapia braquiterapia y medicina nuclear, participar en la puesta en marcha de los diferentes equipos tales como equipos de rayos X diagn\u00f3stico tales como hemodinamia, Tom\u00f3grafos, Mastografos, unidades de cobalto terapia y aceleradores lineales, realiza investigaciones en el campo de la F\u00edsica M\u00e9dica<\/p><p style=\"text-align: justify;\"><strong>Funciones que realiza el Licenciado en F\u00edsica con Menci\u00f3n en F\u00edsica M\u00e9dica<\/strong><\/p><ul><li style=\"text-align: justify;\">Asesora a las instituciones en las especificaciones t\u00e9cnicas de equipos y dise\u00f1o de instalaciones.<\/li><li style=\"text-align: justify;\">Supervisa la efectividad del mantenimiento, controles de calidad peri\u00f3dicos de los equipos de radiodiagn\u00f3stico y\/o radioterapia\/ medicina nuclear.<\/li><li style=\"text-align: justify;\">Responsable de ejecutar un sistema de Garant\u00eda de Calidad.<\/li><li style=\"text-align: justify;\">Asesora la organizaci\u00f3n y planificaci\u00f3n de las funciones del personal involucrado.<\/li><li style=\"text-align: justify;\">Asesora en las pruebas de aceptaci\u00f3n y puesta en servicio de equipos.<\/li><li style=\"text-align: justify;\">Responsable de la dosimetr\u00eda f\u00edsica y cl\u00ednica.<\/li><li style=\"text-align: justify;\">Impulsa investigaci\u00f3n en el \u00e1rea de la F\u00edsica M\u00e9dica.<\/li><li style=\"text-align: justify;\">Responsable de elaborar el manual de protecci\u00f3n radiol\u00f3gica de la instituci\u00f3n basados en normas internacionales.<\/li><li style=\"text-align: justify;\">Vela por que se cumplan las normas establecidas en materia de protecci\u00f3n radiol\u00f3gica para garantizar la seguridad de los pacientes, del personal ocupacionalmente expuesto y del p\u00fablico en general.<\/li><li style=\"text-align: justify;\">Garantizar la gesti\u00f3n de la dosimetr\u00eda personal de la instituci\u00f3n.<\/li><li style=\"text-align: justify;\">Garantizar la seguridad f\u00edsica de las fuentes y elabora un inventario actualizado de las fuentes que est\u00e9n en uso y en desuso.<\/li><li style=\"text-align: justify;\">Representante ante la autoridad reguladora de la protecci\u00f3n radiol\u00f3gica de la instalaci\u00f3n.<\/li><li style=\"text-align: justify;\">Responsable del seguimiento al programa de garant\u00eda de calidad en la instalaci\u00f3n.<\/li><li style=\"text-align: justify;\">Desarrolla y propone temas de investigaci\u00f3n<\/li><li style=\"text-align: justify;\">Asesora a la autoridad reguladora en la aplicaci\u00f3n de las normas nacionales.<\/li><\/ul><p style=\"text-align: justify;\"><strong>Cargos que desempe\u00f1a el Licenciado en F\u00edsica con Menci\u00f3n en F\u00edsica M\u00e9dica<\/strong><\/p><ul><li style=\"text-align: justify;\">F\u00edsico M\u00e9dico Cl\u00ednico<\/li><li style=\"text-align: justify;\">Encargado de Protecci\u00f3n Radiol\u00f3gica<\/li><li style=\"text-align: justify;\">F\u00edsico M\u00e9dico No Cl\u00ednico, Investigador<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8812\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8812\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8812\" tabindex=\"0\" hidden=\"hidden\"><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0 \u00a0 \u00a0 \u00a0<\/b><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Geograf\u00eda e Historia de Nicaragua<\/li><li>Introducci\u00f3n a la Biolog\u00eda<\/li><li>T\u00e9cnicas de Lectura, Redacci\u00f3n y Ortograf\u00eda<\/li><li>Inform\u00e1tica B\u00e1sica<\/li><li>Matem\u00e1tica General<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Principios de programaci\u00f3n<\/li><li>\u00c1lgebra Lineal<\/li><li>Anatom\u00eda Humana<\/li><li>Introducci\u00f3n a la F\u00edsica<\/li><li>T\u00e9cnicas de Investigaci\u00f3n Documental<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>C\u00e1lculo I<\/li><li>Estad\u00edstica<\/li><li>Fisiolog\u00eda Humana<\/li><li>Seminario de Formaci\u00f3n Integral<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>C\u00e1lculo II<\/li><li>F\u00edsica General I<\/li><li>Ingles T\u00e9cnico<\/li><li>Laboratorio I<\/li><li>Programaci\u00f3n aplicada\u00a0<b>\u00a0<\/b><\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Ecuaciones Diferenciales Ordinarias<\/li><li>F\u00edsica General II<\/li><li>Qu\u00edmica Anal\u00edtica Farmac\u00e9utica<\/li><li>C\u00e1lculo III<\/li><li>Laboratorio II<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>M\u00e9todos Matem\u00e1ticos para la F\u00edsica<\/li><li>Laboratorio III<\/li><li>F\u00edsica General III<\/li><li>An\u00e1lisis Vectorial<\/li><li>Termodin\u00e1mica<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>F\u00edsica Estad\u00edstica<\/li><li>Teor\u00eda Electromagn\u00e9tica<\/li><li>Instrumentaci\u00f3n Nuclear<\/li><li>F\u00edsica At\u00f3mica y Nuclear<\/li><li>Pr\u00e1cticas de Familiarizaci\u00f3n<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Protecci\u00f3n Radiol\u00f3gica<\/li><li>F\u00edsica del Estado S\u00f3lido<\/li><li>F\u00edsica de Radiaciones<\/li><li>Mec\u00e1nica Cu\u00e1ntica<\/li><li>Pr\u00e1cticas de Especializaci\u00f3n<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>F\u00edsica de la Medicina Nuclear<\/li><li>Fundamentos de F\u00edsica de Radioterapia<\/li><li>Fundamentos de Radiobiolog\u00eda<\/li><li>Imagenolog\u00eda Diagn\u00f3stica<\/li><li>Investigaci\u00f3n Aplicada<\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\"> \u00a0\u00a0<\/b><\/p><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas de Profesionalizaci\u00f3n<\/li><li>Modalidad de Graduaci\u00f3n<b>\u00a0<\/b><\/li><\/ul><p><b style=\"font-family: inherit; font-size: inherit;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/b><\/p><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8813\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8813\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8813\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17331\" class=\"elementor elementor-17331\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6409326d elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"6409326d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67cb0a76\" data-id=\"67cb0a76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-19caf0db\" data-id=\"19caf0db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4419daaa elementor-widget elementor-widget-heading\" data-id=\"4419daaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F\u00edsica menci\u00f3n Geof\u00edsica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37565930 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"37565930\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a5fe2c5\" data-id=\"6a5fe2c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d170001 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"7d170001\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2091\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2091\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2091\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2091\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2091\" tabindex=\"0\" hidden=\"false\"><p style=\"text-align: justify;\">La Licenciatura en F\u00edsica menci\u00f3n Geof\u00edsica es una disciplina de las Ciencias de la Tierra que emplea mediciones f\u00edsicas y modelos f\u00edsico-matem\u00e1ticos para explorar, analizar y comprender la estructura, din\u00e1mica y propiedades de la Tierra, incluyendo su interior, el oc\u00e9ano y la atm\u00f3sfera, mediante la aplicaci\u00f3n de diferentes t\u00e9cnicas y m\u00e9todos de investigaci\u00f3n. La complejidad del sistema terrestre (Terremotos, tsunamis, cambio clim\u00e1tico), junto a la dificultad inherente de observar y medir procesos naturales de gran escala, plantea desaf\u00edos formidables que los geof\u00edsicos intentan resolver integrando la teor\u00eda con la modelaci\u00f3n num\u00e9rica y la toma de datos adquiridos con sofisticados instrumentos de medici\u00f3n.<\/p><p style=\"text-align: justify;\">El Licenciado en F\u00edsica menci\u00f3n Geof\u00edsica sabe describir y explicar la din\u00e1mica de la Tierra, el oc\u00e9ano, la atm\u00f3sfera y la corteza terrestre a trav\u00e9s del estudio de los campos f\u00edsicos y sus interacciones, haciendo uso de la tecnolog\u00eda moderna. Debe adem\u00e1s, procesar, reducir, interpretar y modelar datos geof\u00edsicos que le permitan la soluci\u00f3n de la tarea geol\u00f3gica en la b\u00fasqueda de recursos mineros, h\u00eddricos y energ\u00e9ticos considerando un enfoque sostenible en los problemas a enfrentar. Debe realizar el monitoreo y alerta temprana de los fen\u00f3menos geol\u00f3gicos, meteorol\u00f3gicos y clim\u00e1ticos a fin de minimizar el impacto en la econom\u00eda y la sociedad nicarag\u00fcense. Se destaca por su compromiso \u00e9tico, respeto al medio ambiente, la interculturalidad, diversidad y responsabilidad social y ciudadana.<\/p><p style=\"text-align: justify;\"><strong>Funciones que realiza el Licenciado en F\u00edsica menci\u00f3n Geof\u00edsica<\/strong><\/p><ul><li style=\"text-align: justify;\">Efect\u00faa estudios geof\u00edsicos regionales, semi-regionales y en detalle.<\/li><li style=\"text-align: justify;\">Supervisa y garantiza la calidad de los trabajos geof\u00edsicos de campo.<\/li><li style=\"text-align: justify;\">Aplica las normas utilizadas en la planificaci\u00f3n y ejecuci\u00f3n de los trabajos de campo.<\/li><li style=\"text-align: justify;\">Procesa, reduce, interpreta y modela datos geof\u00edsicos para resolver la tarea geol\u00f3gica.<\/li><li style=\"text-align: justify;\">Apoya grupos de investigaci\u00f3n geof\u00edsica en instituciones estatales y universidades.<\/li><li style=\"text-align: justify;\">Participa en equipos interuniversitarios de investigaci\u00f3n en Geociencias.<\/li><li style=\"text-align: justify;\">Supervisa el desarrollo de proyectos geof\u00edsicos de incidencia nacional.<\/li><li style=\"text-align: justify;\">Integra colectivos de investigaci\u00f3n en proyectos de importancia econ\u00f3mica nacional (recursos geot\u00e9rmicos e h\u00eddricos, minerales, medio ambiente, vigilancia volc\u00e1nica y s\u00edsmica).<\/li><\/ul><p style=\"text-align: justify;\"><strong>Cargos que desempe\u00f1a el Licenciado en F\u00edsica menci\u00f3n Geof\u00edsica<\/strong><\/p><ul><li style=\"text-align: justify;\">Geof\u00edsico de Campo<\/li><li style=\"text-align: justify;\">Geof\u00edsico Interpretador<\/li><li style=\"text-align: justify;\">Investigador Geof\u00edsico<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17347\" class=\"elementor elementor-17347\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-502473cb elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"502473cb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37a7ee83\" data-id=\"37a7ee83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6f04c80a\" data-id=\"6f04c80a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c4485 elementor-widget elementor-widget-heading\" data-id=\"3c4485\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9cnico Superior en Construcci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3146a9 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"c3146a9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59244a86\" data-id=\"59244a86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a2d78b3 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3a2d78b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9761\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9761\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9761\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9761\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9761\" tabindex=\"0\" hidden=\"false\"><p style=\"text-align: justify;\">La Ingenier\u00eda Civil es la rama de la ingenier\u00eda que se dedica exclusivamente a dise\u00f1ar, construir y asimismo de mantener infraestructuras como obras viales, hidr\u00e1ulicas, entre otras. Cabe destacar que tambi\u00e9n la Ingenier\u00eda Civil se ocupa de ejercer control y preservar las obras construidas siempre trabajando con responsabilidad y seguridad.<\/p><p style=\"text-align: justify;\">El T\u00e9cnico Superior en Construcci\u00f3n es un profesional \u00edntimamente ligado al Ingeniero Civil. Tiene la capacidad de desarrollar labores similares al Ingeniero y en la mayor\u00eda de los casos es su asistente en ejecuci\u00f3n y toma de decisiones en un proyecto. Debe ser capaz de reconocer, analizar y diagnosticar problemas en la construcci\u00f3n y dar soluciones t\u00e9cnicas en el sitio para que la obra no tenga atraso alguno. La cierta circunstancia tendr\u00e1 la capacidad de efectuar dise\u00f1os integrales basados en los reglamentos locales e internacionales de dise\u00f1o.<\/p><p style=\"text-align: justify;\"><strong>Funciones que realiza el T\u00e9cnico Superior en Construcci\u00f3n<\/strong><\/p><ul><li style=\"text-align: justify;\">Organiza y dirige el personal de campo.<\/li><li style=\"text-align: justify;\">Apoya la buena administraci\u00f3n de los recursos materiales y financieros.<\/li><li style=\"text-align: justify;\">Responsable de garantizar la calidad de las obras.<\/li><li style=\"text-align: justify;\">Administra los recursos materiales y financieros del proyecto. Apoya las gestiones t\u00e9cnicas y administrativas del Residente.<\/li><li style=\"text-align: justify;\">Apoya al Residente en la toma de decisiones para el desarrollo de los procesos constructivos. Apoya las gestiones t\u00e9cnicas y aditivas del Residente.<\/li><li style=\"text-align: justify;\">Apoya al Residente en la toma de decisiones para el desarrollo de los procesos constructivos.<\/li><li style=\"text-align: justify;\">Eval\u00faa la ejecuci\u00f3n de los vol\u00famenes de obra. Elabora presupuestos de obra civiles.<\/li><\/ul><p style=\"text-align: justify;\"><strong>Cargos que desempe\u00f1a el T\u00e9cnico Superior en Construcci\u00f3n<\/strong><\/p><ul><li style=\"text-align: justify;\">Maestro de obra.<\/li><li style=\"text-align: justify;\">Auxiliar del Ingeniero Supervisor.<\/li><li style=\"text-align: justify;\">Auxiliar del Ingeniero Residente.<\/li><li style=\"text-align: justify;\">Planificador de obras.<\/li><li style=\"text-align: justify;\">Administrador de obras.<\/li><li style=\"text-align: justify;\">Calculista y presupuestista.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17351\" class=\"elementor elementor-17351\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-iet\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44ad0934 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"44ad0934\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-89b0f8f\" data-id=\"89b0f8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4c9a7408\" data-id=\"4c9a7408\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7de58cfd elementor-widget elementor-widget-heading\" data-id=\"7de58cfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9cnico Superior en Topograf\u00eda<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21496c99 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"21496c99\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff48e0c\" data-id=\"ff48e0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c8e168 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"9c8e168\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1641\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1641\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1642\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1642\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1643\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1643\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1641\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1641\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1641\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio del T\u00e9cnico Superior en Topograf\u00eda es representar gr\u00e1ficamente la superficie terrestre con sus diferentes formas y detalles. Por ello, el profesional en Topograf\u00eda domina las t\u00e9cnicas, procedimientos y equipos topogr\u00e1ficos parea realizar levantamiento, trazado y replanteo de obras menores civiles y catastrales.<\/p><p>Por su formaci\u00f3n en el \u00e1rea del sector construcci\u00f3n y catastro, puede desarrollarse profesionalmente en empresas constructoras, consultoras, catastro f\u00edsico, municipal y fiscal.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Empresas constructoras.<\/li><li>Consultor\u00eda en topograf\u00eda.<\/li><li>Alcald\u00edas municipales.<\/li><li>Instituto Nicarag\u00fcense de Estudios Territoriales.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Capacidad para ejecutar levantamiento de puntos geod\u00e9sicos usando t\u00e9cnicas y equipos especializados, avalados t\u00e9cnicamente por INETER, con la finalidad de vincular los levantamientos topogr\u00e1ficos a la Red Geod\u00e9sica Nacional.<\/li><li>Capacidad para realizar levantamientos topogr\u00e1ficos, trazo y replanteo en obras civiles menores.<\/li><li>Capacidad para realizar c\u00e1lculos de topograf\u00eda con la finalidad de dibujar planos topogr\u00e1ficos mediante el uso de programas computarizados para el dise\u00f1o de obras civiles en 2D y 3D.<\/li><li>Capacidad de mantener y actualizar las bases de datos del Catastro F\u00edsico Nacional.<\/li><li>Capacidad para elaborar y revisar aval\u00faos catastrales para actualizar bienes p\u00fablicos y privados del Catastro Municipal.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1642\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1642\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1642\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Estad\u00edsticas y Probabilidades<\/li><li>Ofim\u00e1tica<\/li><li>T\u00e9cnicas de Lectura, Redacci\u00f3n y Ortograf\u00eda<\/li><li>Planimetr\u00eda<\/li><li>Integradora 1<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>T\u00e9cnicas de Investigaci\u00f3n Documental<\/li><li>Excel aplicado a la Topograf\u00eda<\/li><li>Software Topogr\u00e1fico Aplicado a la planimetr\u00eda<\/li><li>Levanamiento Planim\u00e9trico de Campo<\/li><li>Electiva 1<\/li><li>Integradora 2<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Introducci\u00f3n a la Geodesia<\/li><li>Metodolog\u00eda de la investigaci\u00f3n<\/li><li>Altimetr\u00eda<\/li><li>Cartogr\u00e1fica<\/li><li>Electiva 2<\/li><li>Integradora 3<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Fotogrametr\u00eda<\/li><li>Levantamiento altim\u00e9trico de campo<\/li><li>Optativa 1<\/li><li>Software topogr\u00e1fico aplicado a la altimetr\u00eda<\/li><li>Optativa 2<\/li><li>Integradora 4<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Movimiento de tierra<\/li><li>Topograf\u00eda aplicada a obras verticales<\/li><li>Levantamiento hidrot\u00e9cnico<\/li><li>Topograf\u00eda aplicada a obras horizontales<\/li><li>Optativa 3<\/li><li>Asignatura Integradora 5<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Aval\u00fao catastral<\/li><li>Derecho catastral<\/li><li>Geom\u00e1tica aplicada a la topograf\u00eda<\/li><li>Levantamiento catastral<\/li><li>Optativa 4<\/li><li>Pr\u00e1ctica PreProfesional<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1643\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1643\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1643\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17381\" class=\"elementor elementor-17381\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2064f37a elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"2064f37a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-227862e1\" data-id=\"227862e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-797f1aa1\" data-id=\"797f1aa1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd5ca10 elementor-widget elementor-widget-heading\" data-id=\"cd5ca10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Biolog\u00eda<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b5f404d elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"3b5f404d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-468da881\" data-id=\"468da881\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ae7d8fe elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"7ae7d8fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2061\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2061\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2062\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2062\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2063\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2063\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2061\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2061\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2061\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la Biolog\u00eda es el proceso de ense\u00f1anza-aprendizaje de esta disciplina. Por ello el profesional de esta ciencia manifiesta dominio te\u00f3rico y habilidades en el desarrollo de los contenidos disciplinares propios de la carrera, a fin de promover estos en su entorno familiar y social. Asimismo, utiliza t\u00e9cnicas investigativas para la soluci\u00f3n de problemas educativos suscitados en su entorno laboral, con la finalidad de contribuir a elevar la calidad de los procesos educativos de la Biolog\u00eda.<\/p><p>Como facilitador de la Biolog\u00eda, emplea conocimientos y habilidades b\u00e1sicas de las tecnolog\u00edas de la informaci\u00f3n y comunicaci\u00f3n, mediante la utilizaci\u00f3n de recursos al alcance de sus posibilidades, con el fin de mejorar el aprendizaje de los estudiantes atendiendo la inclusividad educativa.<\/p><p>Por su formaci\u00f3n cient\u00edfica y psicopedagog\u00eda el profesional de Biolog\u00eda puede desempe\u00f1arse como docente en las escuelas de educaci\u00f3n media, p\u00fablicas, privadas y subvencionadas adscritas al MINED.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>El principal \u00e1mbito de actuaci\u00f3n del graduado en la carrera de Biolog\u00eda son los Centros P\u00fablicos y Privados adscritos al MINED, que imparten Educaci\u00f3n Media, as\u00ed como las delegaciones municipales y departamentales del MINED.<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><p>Las tareas que puede desempe\u00f1ar el graduado en la carrera de Biolog\u00eda son:<\/p><ul><li>La docencia de Biolog\u00eda en educaci\u00f3n media<\/li><li>Investigaci\u00f3n educativa<\/li><li>Asesor\u00eda pedag\u00f3gica<\/li><li>Consejer\u00eda escolar<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2062\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2062\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2062\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Educaci\u00f3n Ambiental I<\/li><li>Comprensi\u00f3n lectora y expresi\u00f3n oral<\/li><li>Ofim\u00e1tica<\/li><li>Formaci\u00f3n ciudadana<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Expresi\u00f3n Escrita<\/li><li>Matem\u00e1tica aplicada a la Biolog\u00eda<\/li><li>F\u00edsica General<\/li><li>Biolog\u00eda fundamental<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Did\u00e1ctica General con \u00e9nfasis en el aprendizaje<\/li><li>Biof\u00edsica<\/li><li>Ecolog\u00eda General<br \/>Investigaci\u00f3n<\/li><li>Cualitativa<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Pedagog\u00eda General<\/li><li>Introducci\u00f3n a la Qu\u00edmica<\/li><li>Zoolog\u00eda I<\/li><li>Bot\u00e1nica General<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Qu\u00edmica org\u00e1nica<\/li><li>Zoolog\u00eda II<\/li><li>Geolog\u00eda General<\/li><li>Educaci\u00f3n ambiental II<\/li><li>Optativo I<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Bioestad\u00edstica<\/li><li>Bot\u00e1nica sistem\u00e1tica<\/li><li>Investigaci\u00f3n educativa<\/li><li>Did\u00e1ctica de la Biolog\u00eda<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Evaluaci\u00f3n educativa por competencias<\/li><li>Psicolog\u00eda del aprendizaje<\/li><li>Flora Nacional<\/li><li>Estrategia para la educaci\u00f3n ambiental<\/li><li>Optativo II<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Optativo III<\/li><li>Inform\u00e1tica aplicada a la Biolog\u00eda<\/li><li>Bioqu\u00edmica<\/li><li>Biolog\u00eda de los Microorganismos<\/li><li>Biolog\u00eda molecular y celular<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo IV<\/li><li>Curr\u00edculo<\/li><li>Gesti\u00f3n Educativa<\/li><li>Anatom\u00eda y fisiolog\u00eda humana<\/li><li>Gen\u00e9tica General<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2063\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2063\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2063\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17384\" class=\"elementor elementor-17384\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-667d076d elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"667d076d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-70c9800f\" data-id=\"70c9800f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a6454b1\" data-id=\"a6454b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-291ce33f elementor-widget elementor-widget-heading\" data-id=\"291ce33f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Ciencias Naturales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60285fea elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"60285fea\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b4ae338\" data-id=\"4b4ae338\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1320af39 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"1320af39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3201\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3201\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3202\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3202\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3203\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3203\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3201\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3201\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3201\" tabindex=\"0\" hidden=\"false\"><p>La licenciatura en Ciencias de la Educaci\u00f3n con menci\u00f3n en Ciencias Naturales, tiene como objeto de estudio la Ense\u00f1anza Aprendizaje de las Ciencias Naturales, contribuyendo al sistema de Educaci\u00f3n Media, a trav\u00e9s de la formaci\u00f3n de profesionales con calidad.<\/p><p>Por tanto, el graduado tiene las competencias para desarrollarse en diferentes campos de acci\u00f3n como: Docencia, investigaci\u00f3n educativa, consejer\u00eda escolar en los centros de Educaci\u00f3n Media del pa\u00eds y asesor\u00eda pedag\u00f3gica en delegaciones municipales y departamentales.<\/p><p>Por consiguiente, aplica los fundamentos te\u00f3ricos y pr\u00e1cticos en el proceso de Ense\u00f1anza-Aprendizaje, a trav\u00e9s de metodolog\u00edas did\u00e1cticas y pedag\u00f3gicas, haciendo uso de las tecnolog\u00edas, la creatividad e innovaci\u00f3n para contribuir a la promoci\u00f3n, protecci\u00f3n y conservaci\u00f3n de los recursos naturales. Asimismo, dise\u00f1a, implementa y asesora trabajos pr\u00e1cticos experimentales con materiales del entorno a trav\u00e9s de actividades pr\u00e1cticas, adem\u00e1s realiza investigaciones educativas para contribuir con la mejora del proceso de Ense\u00f1anza-Aprendizaje y favorecer un aprendizaje significativo.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>El principal \u00e1mbito de actuaci\u00f3n del graduado en la carrera de Ciencias Naturales son los Centros P\u00fablicos y Privados adscritos al MINED, que imparten Educaci\u00f3n Media, as\u00ed como las delegaciones municipales y departamentales del MINED.<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><p>Las tareas que puede desempe\u00f1ar el graduado en la carrera de Ciencias Naturales son:<\/p><ul><li>Docencia de Ciencias Naturales en educaci\u00f3n media<\/li><li>Investigaci\u00f3n educativa<\/li><li>Asesor\u00eda pedag\u00f3gica<\/li><li>Consejer\u00eda escolar<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3202\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3202\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3202\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comprensi\u00f3n lectora y expresi\u00f3n oral<\/li><li>Ofim\u00e1tica<\/li><li>Energ\u00eda Ciencia y Medio Ambiente<\/li><li>Qu\u00edmica, materia y Medio Ambiente<\/li><li>Biolog\u00eda General<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Trabajo Experimental I en CCNN<\/li><li>Expresi\u00f3n Escrita<\/li><li>Elementos de Qu\u00edmica Inorg\u00e1nica<\/li><li>Zoolog\u00eda de Invertebrados<\/li><li>Elementos Cuantitativos I<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Formaci\u00f3n ciudadana<\/li><li>Pedagog\u00eda General<\/li><li>Elementos Cuantitativos II<\/li><li>Zoolog\u00eda de vertebrados<\/li><li>Fundamentos de Investigaci\u00f3n cualitativa<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Did\u00e1ctica General con \u00e9nfasis en el aprendizaje<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>Sistema de part\u00edculas<\/li><li>Energ\u00eda y reacciones qu\u00edmicas<\/li><li>Trabajo experimental II en CCNN<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Optativo I<\/li><li>Oscilaciones y Ondas<\/li><li>Educaci\u00f3n Ambiental<\/li><li>Bot\u00e1nica General<\/li><li>Estad\u00edstica descriptiva<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Gesti\u00f3n Educativa<\/li><li>Evaluaci\u00f3n de los Aprendizajes<\/li><li>Elementos de Electricidad y magnetismo<\/li><li>Qu\u00edmica del Carbono I<\/li><li>Did\u00e1ctica experimental en CCNN<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo II<\/li><li>Elementos de \u00d3ptica<\/li><li>Qu\u00edmica del Carb\u00f3n II<\/li><li>Did\u00e1ctica de las Ciencias<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Optativo III<\/li><li>Inform\u00e1tica aplicada a las CCNN<\/li><li>Curr\u00edculo<\/li><li>Investigaci\u00f3n educativa<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo IV<\/li><li>Optativo V<\/li><li>Optativo VI<\/li><li>Anatom\u00eda y Fisiolog\u00eda Humana<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3203\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3203\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3203\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17395\" class=\"elementor elementor-17395\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20e96763 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"20e96763\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6b06e37d\" data-id=\"6b06e37d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4221d014\" data-id=\"4221d014\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-177451c7 elementor-widget elementor-widget-heading\" data-id=\"177451c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F\u00edsica\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5094d2ad elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"5094d2ad\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5368c645\" data-id=\"5368c645\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68021f60 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"68021f60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1741\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1741\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1742\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1742\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1743\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1743\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1741\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1741\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1741\" tabindex=\"0\" hidden=\"false\"><p>La licenciatura en Ciencias de la Educaci\u00f3n con menci\u00f3n en F\u00edsica, tiene como objeto de estudio el proceso de ense\u00f1anza-aprendizaje de la F\u00edsica para el nivel medio, es por ello que el profesional de la carrera tendr\u00e1 las competencias (conocimientos, habilidades, destrezas y actitudes) necesarias para desarrollarse en diferentes campos de acci\u00f3n como: Docencia de F\u00edsica, Instructor de laboratorio de F\u00edsica, investigaci\u00f3n educativa, uso de las TIC en los aprendizaje de la F\u00edsica y asesor\u00eda pedag\u00f3gica.<\/p><p>En estos campos de acci\u00f3n, el egresado aplica los fundamentos te\u00f3ricos y pr\u00e1cticos en el proceso del aprendizaje de la f\u00edsica, mediante la implementaci\u00f3n de los elementos metodol\u00f3gicos, did\u00e1cticos y pedag\u00f3gicos, haciendo uso de las herramientas TIC. Adem\u00e1s, planifica, dise\u00f1a, implementa y eval\u00faa experimentos con materiales del entorno. Por otra parte, realiza investigaciones cient\u00edficas en el \u00e1mbito educativo. Asesora pedag\u00f3gicamente el desempe\u00f1o docente y proyectos educativos innovadores para fortalecer el aprendizaje de la F\u00edsica. Finalmente puede ejecutar acciones de gesti\u00f3n administrativa con el fin de mejorar la calidad en la educaci\u00f3n media y t\u00e9cnica.<\/p><p>Los profesionales de esta carrera deben manifestar en su actuaci\u00f3n (comportamiento) la interiozaci\u00f3n individual y grupal de los valores declarados por la universidad, tales como: compromiso social, equidad, honestidad y transparencia, respeto a los derechos humanos, a la diversidad y al medio ambiente, \u00e9tica profesional, responsabilidad social e institucional, tolerancia, solidaridad, identidad, cultura nacional y valores patri\u00f3ticos, identidad institucional y sentimiento de pertenencia, responsabilidad social e institucional, autonom\u00eda universitaria.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>El \u00e1mbito de actuaci\u00f3n del graduado de la carrera de F\u00edsica son los Centros P\u00fablicos y Privados adscritos al MINED, que imparten Educaci\u00f3n Media, as\u00ed como las delegaciones municipales y departamentales del MINED.<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><p>Las tareas que puede desempe\u00f1ar el graduado en la carrera de F\u00edsica son:<\/p><ul><li>Docencia en F\u00edsica para la educaci\u00f3n secundaria<\/li><li>Instrucci\u00f3n en laboratorios de F\u00edsica<\/li><li>Asesor\u00eda Pedag\u00f3gica<\/li><li>Investigaci\u00f3n Educativa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1742\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1742\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1742\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comprensi\u00f3n Lectora y Expresi\u00f3n Oral<\/li><li>Energ\u00eda, Ciencia y Medio Ambiente I<\/li><li>Elementos Cuantitativos de F\u00edsica I<\/li><li>Modelos Cuantitativos b\u00e1sicos para la F\u00edsica<\/li><li>Ofim\u00e1tica<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Trabajo Experimental en F\u00edsica<\/li><li>Movimiento de la part\u00edcula<\/li><li>Energ\u00eda, Ciencia y Medio Ambiente II<\/li><li>Expresi\u00f3n Escrita<\/li><li>Elementos Cuantitativos de F\u00edsica II<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Elementos Cuantitativos de F\u00edsica III<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>Pedagog\u00eda General<\/li><li>Movimiento de sistema de part\u00edculas<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n cualitativa<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Did\u00e1ctica General con \u00e9nfasis en el Aprendizaje<\/li><li>Movimiento peri\u00f3dico y ondulatorio<\/li><li>Ecuaciones de F\u00edsica I<\/li><li>Mec\u00e1nica Experimental<\/li><li>Inform\u00e1tica Aplicada a la F\u00edsica<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Electricidad<\/li><li>Laboratorio Did\u00e1ctico de F\u00edsica I<\/li><li>Did\u00e1ctica I de F\u00edsica<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n cuantitativa<\/li><li>Optativo I<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Evaluaci\u00f3n educativa por competencias<\/li><li>Electromagnetismo<\/li><li>Ecuaciones de F\u00edsica II<\/li><li>Did\u00e1ctica II de F\u00edsica<\/li><li>Optativo II<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Fluidos, Temperatura y Calor<\/li><li>Formaci\u00f3n Ciudadana<\/li><li>Laboratorio Did\u00e1ctico de F\u00edsica II<\/li><li>Elementos de F\u00edsica Relativista<\/li><li>Optativo III<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Curr\u00edculo<\/li><li>F\u00edsica Cu\u00e1ntica I<\/li><li>Estad\u00edsticas y Probabilidades<\/li><li>Optativo IV<\/li><li>Optativo V<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Gesti\u00f3n Educativa<\/li><li>Energ\u00eda y Medio Ambiente<\/li><li>F\u00edsica Cu\u00e1ntica II<\/li><li>Optativo VI<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1743\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1743\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1743\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17398\" class=\"elementor elementor-17398\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-429a5234 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"429a5234\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5aa051ff\" data-id=\"5aa051ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-27fd6578\" data-id=\"27fd6578\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b0c013b elementor-widget elementor-widget-heading\" data-id=\"6b0c013b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F\u00edsica \u2013 Matem\u00e1tica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a7b419d elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"2a7b419d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27d82ecd\" data-id=\"27d82ecd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7974dcea elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"7974dcea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2031\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2031\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2032\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2032\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2033\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2033\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2031\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2031\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2031\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de F\u00edsica &#8211; Matem\u00e1tica es la ense\u00f1anza y el aprendizaje de la F\u00edsica y la Matem\u00e1tica en educaci\u00f3n secundaria. Por ello, el profesional de dicha carrera posee dominio cient\u00edfico y metodol\u00f3gico de los contenidos propios de estas ciencias, siendo capaz de dise\u00f1ar, implementar y evaluar los procesos educativos de las mismas en la docencia, asesor\u00eda pedag\u00f3gica e investigaci\u00f3n educativa para el desarrollo eficaz de dichos procesos.<\/p><p>Por su preparaci\u00f3n cient\u00edfica, metodol\u00f3gica, dominio de recursos tecnol\u00f3gicos y uso materiales de laboratorio, puede ejercer eficazmente la docencia, desarrollar investigaciones y resolver problemas en el \u00e1mbito educativo, desempe\u00f1\u00e1ndose de forma profesional en los centros de educaci\u00f3n secundaria, delegaciones municipales y departamentales demostrando el uso del pensamiento cr\u00edtico, la creatividad, la innovaci\u00f3n, habilidades para una comunicaci\u00f3n asertiva y cualidades para trabajar cooperativamente.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>Los principales \u00e1mbitos de actuaci\u00f3n de los egresados de la carrera de F\u00edsica-Matem\u00e1tica son los Centros p\u00fablicos y privados de Educaci\u00f3n Secundaria, y las delegaciones municipales y departamentales del MINED.<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Planifica, ejecuta y eval\u00faa el proceso de ense\u00f1anza-aprendizaje de la F\u00edsica-Matem\u00e1tica de manera te\u00f3rico-experimental.<\/li><li>Dise\u00f1a materiales educativos para la ense\u00f1anza y aprendizaje de la F\u00edsica y\/o Matem\u00e1tica.<\/li><li>Planifica y ejecuta asesor\u00edas cient\u00edfico-pedag\u00f3gicas para el proceso de ense\u00f1anza-aprendizaje de F\u00edsica y Matem\u00e1tica.<\/li><li>Realiza investigaciones educativas referidas a la mejora del proceso de ense\u00f1anza-aprendizaje de la F\u00edsica-Matem\u00e1tica.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2032\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2032\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2032\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p>I A\u00d1O<\/p><p>SEMESTRE I<\/p><ul><li>Trabajo Experimental en F\u00edsica-Matem\u00e1tica<\/li><li>Comprensi\u00f3n Lectora y Expresi\u00f3n Oral<\/li><li>Matem\u00e1tica Fundamental<\/li><li>Funciones Reales y Trigonometr\u00eda<\/li><li>Energ\u00eda, Ciencia y Medio Ambiente<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>C\u00e1lculo I<\/li><li>Expresi\u00f3n Escrita<\/li><li>Geometr\u00eda Euclidiana<\/li><li>Ofim\u00e1tica<\/li><li>Mec\u00e1nica de la Part\u00edcula<\/li><li>Integrador II<\/li><\/ul><\/td><td><p>II A\u00d1O<\/p><p>SEMESTRE III<\/p><ul><li>Mec\u00e1nica de Sistemas de Part\u00edculas<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n cualitativa<\/li><li>Pedagog\u00eda General<\/li><li>C\u00e1lculo II<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Did\u00e1ctica General con \u00e9nfasis en el Aprendizaje<\/li><li>Geometr\u00eda Anal\u00edtica<\/li><li>Movimiento Oscilatorio y Ondulatorio<\/li><li>C\u00e1lculo III<\/li><li>Laboratorio de F\u00edsica General<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p>III A\u00d1O<\/p><p>SEMESTRE V<\/p><ul><li>Electromagnetismo I<\/li><li>Estad\u00edsticas y Probabilidades<\/li><li>Fluidos, Temperatura y Calor<\/li><li>Estructuras Num\u00e9ricas<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n cuantitativa<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Did\u00e1ctica de la Matem\u00e1tica<\/li><li>Did\u00e1ctica de la Matem\u00e1tica Evaluaci\u00f3n de los aprendizajes por competencias<\/li><li>Electromagnetismo II<\/li><li>Optativo I<\/li><li>Integrador VI<\/li><li>Did\u00e1ctica de la F\u00edsica<\/li><\/ul><\/td><td><p>IV A\u00d1O<\/p><p>SEMESTRE VII<\/p><ul><li>Optativo II<\/li><li>Optativo III<\/li><li>\u00d3ptica<\/li><li>Taller Did\u00e1ctico de Matem\u00e1tica I<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Teor\u00eda Especial de la Relatividad<\/li><li>Taller Did\u00e1ctico de Matem\u00e1tica II<\/li><li>Formaci\u00f3n Ciudadana<\/li><li>Optativo IV<\/li><li>Curr\u00edculo<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p>V A\u00d1O<\/p><p>SEMESTRE IX<\/p><ul><li>Optativo V<\/li><li>Gesti\u00f3n Educativa<\/li><li>F\u00edsica Cu\u00e1ntica<\/li><li>Optativo VI<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2033\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2033\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2033\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17401\" class=\"elementor elementor-17401\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a94a89e elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"1a94a89e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41a0de90\" data-id=\"41a0de90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1f90f99\" data-id=\"1f90f99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a4a593f elementor-widget elementor-widget-heading\" data-id=\"7a4a593f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Franc\u00e9s\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64451630 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"64451630\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59c03209\" data-id=\"59c03209\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d10e791 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"2d10e791\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7561\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-7561\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7562\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7562\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7563\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7563\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-7561\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7561\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de Franc\u00e9s es el proceso de ense\u00f1anza-aprendizaje del franc\u00e9s lengua extranjera. Por ello el profesional de franc\u00e9s se comunica de manera aut\u00f3noma tanto al oral y escrito en este idioma. Tambi\u00e9n concibe, organiza y ejecuta el acto docente, por ende, es capaz de seleccionar adecuar y crear material did\u00e1ctico necesario para la ense\u00f1anza de esta lengua.<\/p><p>Su formaci\u00f3n integral e intercultural le permite ser un ciudadano con valores human\u00edsticos con un alto grado de sensibilidad ante los diferentes contextos sociales.<\/p><p>Su formaci\u00f3n en lengua extranjera le permite desempe\u00f1arse profesionalmente en los sistemas de educaci\u00f3n b\u00e1sica, media y superior en instituciones p\u00fablicas y privadas tambi\u00e9n en centros de ense\u00f1anza de idiomas extranjeros.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Educaci\u00f3n B\u00e1sica y Media en centros p\u00fablico y privado<\/li><li>Educaci\u00f3n superior<\/li><li>Centros de idiomas extranjeros.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Docencia<\/li><li>Asesor\u00eda Pedag\u00f3gica<\/li><li>Investigaci\u00f3n Educativa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7562\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7562\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7562\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Franc\u00e9s Integral I<\/li><li>Fon\u00e9tica del Franc\u00e9s I<\/li><li>Comprensi\u00f3n Lectora y Expresi\u00f3n Oral<\/li><li>Pedagog\u00eda General<\/li><li>Ofim\u00e1tica<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Franc\u00e9s Integral II<\/li><li>Fon\u00e9tica del Franc\u00e9s II<\/li><li>Expresi\u00f3n Escrita<\/li><li>Psicolog\u00eda de los Aprendizajes<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Franc\u00e9s Integral III<\/li><li>Optativa I<\/li><li>Did\u00e1ctica General con \u00c9nfasis en el Aprendizaje<\/li><li>Herramientas Inform\u00e1ticas para la Investigaci\u00f3n<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Franc\u00e9s Integral IV<\/li><li>Optativa II<\/li><li>Evaluaci\u00f3n de los aprendizajes por Competencias.<\/li><li>Investigaci\u00f3n Aplicada<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Franc\u00e9s Integral V<\/li><li>Optativa III<\/li><li>Expresi\u00f3n Francesa<\/li><li>Curr\u00edculo<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Franc\u00e9s Integral VI<\/li><li>Optativa IV<\/li><li>Did\u00e1ctica del Franc\u00e9s<\/li><li>Gesti\u00f3n Educativa<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Franc\u00e9s Integral VII<\/li><li>Optativa V<\/li><li>Did\u00e1ctica del Franc\u00e9s para Ni\u00f1os I<\/li><li>Ingl\u00e9s I<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Franc\u00e9s Integral VIII<\/li><li>Literatura Franc\u00f3fona<\/li><li>Optativo VI<\/li><li>Ingl\u00e9s II<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo VII<\/li><li>T\u00e9cnicas de Correcci\u00f3n Oral y Escrita en Franc\u00e9s<\/li><li>Las TICE del Franc\u00e9s Lengua Extranjera<\/li><li>Formaci\u00f3n Ciudadana<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7563\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7563\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7563\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17404\" class=\"elementor elementor-17404\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7325ef61 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"7325ef61\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1bda3848\" data-id=\"1bda3848\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c55225a\" data-id=\"2c55225a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2855b9bb elementor-widget elementor-widget-heading\" data-id=\"2855b9bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Inform\u00e1tica Educativa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22342b6 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"22342b6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34ed052d\" data-id=\"34ed052d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ea15e3b elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"6ea15e3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1851\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1851\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1852\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1852\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1853\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1853\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1851\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1851\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1851\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de Inform\u00e1tica Educativa es La docencia de las TIC y su integraci\u00f3n curricular en el proceso de Ense\u00f1anza y Aprendizaje. Por tanto, el egresado de la carrera ser\u00e1 capaz de integrar las TIC en el proceso de ense\u00f1anza y aprendizaje, desarrollar materiales did\u00e1cticos y audiovisuales contextualizados, implementar las t\u00e9cnicas de investigaci\u00f3n educativa y aplicar las habilidades tecno pedag\u00f3gicas para la tutor\u00eda, gesti\u00f3n y administraci\u00f3n de plataformas virtuales en el \u00e1mbito educativo.<\/p><p>As\u00ed mismo el egresado de Inform\u00e1tica Educativa posee una formaci\u00f3n integral en la que se fomentan valores como el compromiso social, honestidad y transparencia, respeto a los derechos humanos, la diversidad y al medio ambiente, con \u00e9tica profesional, responsabilidad social e institucional, entre otros.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Escuelas de Educaci\u00f3n Media P\u00fablicas y Privadas<\/li><li>ONG enfocadas a la educaci\u00f3n TIC<\/li><li>Direcciones de Tecnolog\u00eda Gubernamentales<\/li><li>Centros de Educaci\u00f3n T\u00e9cnica<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Asesor\u00eda pedag\u00f3gica en el \u00e1mbito de las TIC<\/li><li>Desarrollo de materiales educativos digitales<\/li><li>Docencia en Inform\u00e1tica Educativa<\/li><li>Investigaci\u00f3n Educativa de la integraci\u00f3n de las TIC<\/li><li>Educaci\u00f3n en l\u00ednea<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1852\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1852\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1852\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Integrador I<\/li><li>Matem\u00e1tica para Inform\u00e1tica I<\/li><li>Formaci\u00f3n Ciudadana<\/li><li>Comprensi\u00f3n Lectora y Expresi\u00f3n Oral<\/li><li>Introducci\u00f3n al Desarrollo de Aplicaciones<\/li><li>Programas Ofim\u00e1ticos I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Programas Ofim\u00e1ticos II<\/li><li>Integrador II<\/li><li>Matem\u00e1tica para Inform\u00e1tica II<\/li><li>T\u00e9cnicas de Redacci\u00f3n<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>Desarrollo de Aplicaciones I<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Herramientas Inform\u00e1ticas para la Investigaci\u00f3n<\/li><li>Pedagog\u00eda General<\/li><li>Dise\u00f1o Gr\u00e1fico<\/li><li>Desarrollo de Aplicaciones II<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Curr\u00edculo<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n Educativa<\/li><li>Did\u00e1ctica General con \u00e9nfasis en el Aprendizaje<\/li><li>Desarrollo de Aplicaciones III<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Evaluaci\u00f3n educativa por competencias<\/li><li>Optativo I<\/li><li>Entornos de Desarrollo<\/li><li>Optativo II<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Hardware de Recursos TIC<\/li><li>Dise\u00f1o Web<\/li><li>Optativo III<\/li><li>Dise\u00f1o de soluciones Educativas<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo IV<\/li><li>Bases de Datos<\/li><li>Desarrollo de Soluciones Educativas<\/li><li>Sistemas Manejadores de Contenido<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Optativo V<\/li><li>Desarrollo y Gesti\u00f3n de Proyectos Educativos<\/li><li>Gesti\u00f3n Educativa<\/li><li>Optativo VI<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Taller de tesis<\/li><li>Optativo VII<\/li><li>Tutor\u00eda Virtual<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1853\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1853\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1853\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Matagalpa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17407\" class=\"elementor elementor-17407\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45fb6c67 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"45fb6c67\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1fec58b0\" data-id=\"1fec58b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-24320ce9\" data-id=\"24320ce9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11b3d0b0 elementor-widget elementor-widget-heading\" data-id=\"11b3d0b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Ingl\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4949f344 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"4949f344\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c2b5db6\" data-id=\"2c2b5db6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17d9c0a3 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"17d9c0a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4001\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4001\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4002\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4002\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4003\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4003\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4001\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4001\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4001\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de ingl\u00e9s es el proceso de ense\u00f1anza-aprendizaje del idioma ingl\u00e9s como idioma extranjero. Para este fin, el futuro egresado deber\u00e1 dominar las macro y micro habilidades del idioma ingl\u00e9s: escucha, habla, lectura, escritura, gram\u00e1tica, pronunciaci\u00f3n y cultura.<\/p><p>Asimismo, deber\u00e1 poseer s\u00f3lidas bases cient\u00edficas, pedag\u00f3gicas, human\u00edsticas y tecnol\u00f3gicas para desarrollar procesos de ense\u00f1anza-aprendizaje cient\u00edfico y de calidad en primaria, secundaria y en academias de ingl\u00e9s. Estar\u00e1 capacitado para proponer estrategias de ense\u00f1anza innovadoras y de emprendimiento.<\/p><p>Podr\u00e1 estudiar de manera sistem\u00e1tica problemas que puedan emerger del proceso de ense\u00f1anza-aprendizaje para proponer soluciones efectivas que contribuyan al desarrollo del proceso educativo. Promover\u00e1 un pensamiento de respeto y pr\u00e1cticas en beneficio de la pluriculturalidad y diferencias de g\u00e9nero. Habr\u00e1 desarrollado valores \u00e9ticos, morales, c\u00edvicos, y utilizar\u00e1 sus conocimientos y habilidades con un esp\u00edritu de pertenencia y contribuci\u00f3n a su entorno social.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Educativas especializadas en la ense\u00f1anza del Ingl\u00e9s<\/li><li>Sistemas Educativos en diferentes niveles de educaci\u00f3n tanto p\u00fablicas como privadas<\/li><li>Plataformas Virtuales Educativas en la Ense\u00f1anza del Ingl\u00e9s<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><p><strong>Docencia<\/strong><\/p><p><strong>Acompa\u00f1amiento y Asesor\u00eda Pedag\u00f3gica<\/strong><br \/><strong>Investigaci\u00f3n Educativa<\/strong><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4002\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4002\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4002\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comprensi\u00f3n Lectora y Expresi\u00f3n Oral<\/li><li>Ingl\u00e9s Integral I<\/li><li>Ofim\u00e1tica<\/li><li>Formaci\u00f3n Ciudadana<\/li><li>Introducci\u00f3n a la Lecto-escritura<\/li><li>\u00a0Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Psicolog\u00eda del Aprendizaje<\/li><li>Taller de Expresi\u00f3n Escrita<\/li><li>Ingl\u00e9s Integral II<\/li><li>Gesti\u00f3n Educativa<\/li><li>Herramientas Ofim\u00e1ticas<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Lectura<\/li><li>Ingl\u00e9s Integral III<\/li><li>Pedagog\u00eda General<\/li><li>Comunicaci\u00f3n Oral I<\/li><li>Did\u00e1ctica General con \u00c9nfasis en el Aprendizaje<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Evaluaci\u00f3n de los aprendizajes por Competencia<\/li><li>Ingl\u00e9s Integral IV<\/li><li>Comunicaci\u00f3n Oral II<\/li><li>Pronunciaci\u00f3n<\/li><li>Dise\u00f1o Curricular<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Gram\u00e1tica<\/li><li>Ingl\u00e9s Integral V<\/li><li>Optativo I<\/li><li>Introducci\u00f3n al TESOL<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Introducci\u00f3n a la Investigaci\u00f3n en TESOL<\/li><li>Ingl\u00e9s Integral VI<\/li><li>Optativa II<\/li><li>Did\u00e1ctica de TESOL para Ni\u00f1os<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativa III<\/li><li>Optativa IV<\/li><li>Escritura<\/li><li>Did\u00e1ctica de TESOL para adultos<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Taller de Investigaci\u00f3n<\/li><li>Estad\u00edstica Descriptiva<\/li><li>Introducci\u00f3n a la Ling\u00fc\u00edstica<\/li><li>Evaluaci\u00f3n de las Habilidades para Ni\u00f1os<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Investigaci\u00f3n Aplicada<\/li><li>Ling\u00fc\u00edstica Aplicada al TESOL<\/li><li>Evaluaci\u00f3n de las Habilidades para Adultos<\/li><li>Optativa V<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4003\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4003\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4003\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17415\" class=\"elementor elementor-17415\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ebb180 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"3ebb180\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-533eaae\" data-id=\"533eaae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4efdceb8\" data-id=\"4efdceb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c82aee5 elementor-widget elementor-widget-heading\" data-id=\"4c82aee5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Innovaci\u00f3n y Emprendimiento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-258b1f9b elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"258b1f9b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98e096e\" data-id=\"98e096e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3645ff0d elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3645ff0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9101\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9101\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9102\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9102\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9103\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9103\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9101\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9101\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9101\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de Innovaci\u00f3n y Emprendimiento es la ense\u00f1anza y aprendizaje de los procesos de innovaci\u00f3n y emprendimiento. Por tanto, el egresado, es un profesional competitivo, din\u00e1mico y l\u00edder que tiene la capacidad de facilitar, asesorar y mediar pedag\u00f3gicamente tareas relacionadas con la organizaci\u00f3n, gesti\u00f3n de ambientes de aprendizajes utilizando las tecnolog\u00edas, investigaci\u00f3n, proyectos y dise\u00f1o de estrategias did\u00e1cticas innovadoras.<\/p><p>El egresado de Innovaci\u00f3n y Emprendimiento es un profesional humanista con valores \u00e9ticos y con un gran compromiso social, desempe\u00f1\u00e1ndose en \u00e1mbitos de actuaci\u00f3n tales como, centros de educaci\u00f3n media y t\u00e9cnica, delegaciones departamentales y municipales, e instituciones con proyecci\u00f3n socioeducativa.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Centros de Educaci\u00f3n Media.<\/li><li>Centros de Educaci\u00f3n T\u00e9cnica<\/li><li>Instituciones con Proyecci\u00f3n Socioeducativa<\/li><li>Alcald\u00edas municipales y departamentales<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Docencia en Aprender Emprender Prosperar<\/li><li>Investigaci\u00f3n Educativa sobre innovaci\u00f3n y emprendimiento<\/li><li>Asesor\u00eda pedag\u00f3gica en el \u00e1mbito de la innovaci\u00f3n y emprendimiento<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9102\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9102\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9102\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Ofim\u00e1tica<\/li><li>Comprensi\u00f3n lectora y expresi\u00f3n oral<\/li><li>Proceso creativo<\/li><li>Formaci\u00f3n ciudadana<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Ofim\u00e1tica avanzada<\/li><li>Expresi\u00f3n escrita<\/li><li>T\u00e9cnicas de dibujo<\/li><li>Cultura emprendedora<br \/>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Pedagog\u00eda general<\/li><li>Metodolog\u00eda de la investigaci\u00f3n<\/li><li>Herramientas Inform\u00e1ticas para la investigaci\u00f3n<\/li><li>Metodolog\u00eda de la innovaci\u00f3n<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Psicolog\u00eda de los aprendizajes<\/li><li>T\u00e9cnicas de procesamiento y an\u00e1lisis de datos<\/li><li>Proceso de innovaci\u00f3n<br \/>Dise\u00f1o de producto<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Optativo I<\/li><li>Evaluaci\u00f3n de los aprendizajes por competencias<\/li><li>Curr\u00edculo<\/li><li>Did\u00e1ctica General con \u00e9nfasis en el Aprendizaje<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Desarrollo de materiales educativos multimedia<\/li><li>Optativo II<\/li><li>Optativo III<\/li><li>Introducci\u00f3n a proyectos<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Gesti\u00f3n educativa<\/li><li>Optativo IV<\/li><li>Formulaci\u00f3n de proyectos sociales<\/li><li>Optativo V<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Asesor\u00eda Educativa I<\/li><li>Modelos econ\u00f3micos<\/li><li>Optativo VI<\/li><li>Estructura de costos<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Asesor\u00eda Educativa II<\/li><li>Taller de tesis<\/li><li>Optativo VII<\/li><li>T\u00e9cnicas para la evaluaci\u00f3n de proyectos<\/li><li>Pr\u00e1ctica Pre profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de graduaci\u00f3n<\/li><li>Pr\u00e1cticas profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9103\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9103\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9103\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17418\" class=\"elementor elementor-17418\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-552a2f6f elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"552a2f6f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-745a3d64\" data-id=\"745a3d64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e97376f\" data-id=\"5e97376f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15411ee7 elementor-widget elementor-widget-heading\" data-id=\"15411ee7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lengua y Literatura Hisp\u00e1nicas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6049900c elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"6049900c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d3b9230\" data-id=\"2d3b9230\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cd47bc elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"9cd47bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1641\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1641\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1642\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1642\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1643\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1643\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1641\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1641\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1641\" tabindex=\"0\" hidden=\"false\"><p>Proceso de ense\u00f1anza aprendizaje de la lengua y la literatura en educaci\u00f3n media.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Docencia en lengua y literatura para educaci\u00f3n media<\/li><li>Investigaci\u00f3n educativa en lengua y literatura Asesor\u00eda pedag\u00f3gica en lengua y literatura<\/li><\/ul><p>Gesti\u00f3n de proyectos educativos<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Docencia en lengua y literatura para educaci\u00f3n media<\/li><li>Investigaci\u00f3n educativa en lengua y literatura Asesor\u00eda pedag\u00f3gica en lengua y literatura<\/li><li>Gesti\u00f3n de proyectos educativos<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1642\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1642\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1642\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comunicaci\u00f3n Oral<br \/>Ofim\u00e1tica I<br \/>Herramientas Ling\u00fc\u00edstica I<br \/>Taller de Lectura<br \/>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Formaci\u00f3n Ciudadana<\/li><li>Comunicaci\u00f3n Escrita I<\/li><li>Ofim\u00e1tica II<\/li><li>Herramientas Ling\u00fc\u00edstica II<\/li><li>Introducci\u00f3n a la Compresi\u00f3n del Texto Literario<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Comunicaci\u00f3n Escrita II<\/li><li>Pedagog\u00eda General<\/li><li>Curr\u00edculo<\/li><li>Gram\u00e1tica de la lengua espa\u00f1ola I<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Did\u00e1ctica General con \u00e9nfasis en el Aprendizaje<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>T\u00e9cnica del comentario literario<\/li><li>Gram\u00e1tica de la lengua espa\u00f1ola II<\/li><li>Investigaci\u00f3n educativa en lengua y literatura<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Optativo I<\/li><li>Ofim\u00e1tica aplicada<\/li><li>Literatura nicarag\u00fcense<\/li><li>Estudios Rubendarianos<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Evaluaci\u00f3n de los aprendizajes por competencias<\/li><li>Literatura latinoamericana<\/li><li>An\u00e1lisis del discurso docente<\/li><li>Estad\u00edstica aplicada a la investigaci\u00f3n did\u00e1ctica en lengua y literatura<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo II<\/li><li>Optativo III<\/li><li>Optativo IV<\/li><li>Espa\u00f1ol hispanoamericano<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Did\u00e1ctica de la comprensi\u00f3n y expresi\u00f3n oral<\/li><li>Did\u00e1ctica de la comprensi\u00f3n lectora<\/li><li>Did\u00e1ctica de la literatura<\/li><li>Did\u00e1ctica de la gram\u00e1tica y la ortograf\u00eda<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Gesti\u00f3n Educativa<\/li><li>Did\u00e1ctica de la expresi\u00f3n escrita<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1643\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1643\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1643\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17421\" class=\"elementor elementor-17421\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-debe716 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"debe716\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1fa13936\" data-id=\"1fa13936\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-19e37a1\" data-id=\"19e37a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6286c12c elementor-widget elementor-widget-heading\" data-id=\"6286c12c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Matem\u00e1tica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23a024eb elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"23a024eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-143167e4\" data-id=\"143167e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62fba441 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"62fba441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1661\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1661\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1662\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1662\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1663\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1663\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1661\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1661\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1661\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de Matem\u00e1tica de la Facultad de Educaci\u00f3n e Idiomas es el proceso de ense\u00f1anza aprendizaje de la Matem\u00e1tica en la educaci\u00f3n secundaria. Por ello, el profesional de dicha carrera posee dominio cient\u00edfico y metodol\u00f3gico de esta ciencia, siendo capaz de dise\u00f1ar, implementar y evaluar los procesos para el aprendizaje de la Matem\u00e1tica en los diferentes \u00e1mbitos de actuaci\u00f3n, a su vez, brindar asesoramiento y capacitaci\u00f3n para el desarrollo eficaz de dichos procesos.<\/p><p>Posee la capacidad de desarrollar investigaciones educativas, para resolver problemas ligados al aprendizaje de la Matem\u00e1tica, utilizando las TIC en ambientes de educaci\u00f3n inclusiva. Por su cultura humanista, es capaz de analizar y contextualizar la realidad con sentido \u00e9tico y cr\u00edtico, y el respeto de la interculturalidad, en los procesos educativos que desarrolla, desempe\u00f1\u00e1ndose de forma profesional en los centros de educaci\u00f3n secundaria, delegaciones municipales y departamentales, y otras instituciones que promueven proyectos educativos.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>El principal \u00e1mbito de actuaci\u00f3n del graduado de la carrera de Matem\u00e1tica lo conforman los centros de educaci\u00f3n secundaria p\u00fablicos y privados, as\u00ed como las delegaciones municipales y departamentales del MINED.<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Planifica, ejecuta y eval\u00faa el proceso de ense\u00f1anza aprendizaje de la Matem\u00e1tica en educaci\u00f3n secundaria, con base en la preparaci\u00f3n cient\u00edfica, metodol\u00f3gica y psicopedag\u00f3gica requerida.<\/li><li>Promoci\u00f3n de la educaci\u00f3n incluyente, el emprendimiento, la \u00e9tica profesional, la interculturalidad y la pr\u00e1ctica de valores.<\/li><li>Asesoramiento cient\u00edfico y metodol\u00f3gico brindado desde las pr\u00e1cticas de acompa\u00f1amiento pedag\u00f3gico y los EPI.<\/li><li>Desarrollo de investigaciones para resolver problemas de ense\u00f1anza y aprendizaje de la Matem\u00e1tica en el campo educativo.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1662\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1662\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1662\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p>I A\u00d1O<\/p><p>SEMESTRE I<\/p><ul><li>Comprensi\u00f3n lectora y expresi\u00f3n oral<\/li><li>L\u00f3gica y teor\u00eda de conjuntos<\/li><li>Pedagog\u00eda General<\/li><li>Funciones reales<\/li><li>Geometr\u00eda Euclidiana I<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Psicolog\u00eda del Aprendizaje<\/li><li>Estad\u00edstica Descriptiva<\/li><li>Laboratorio de Matem\u00e1tica I<\/li><li>Expresi\u00f3n Escrita<\/li><li>Did\u00e1ctica General con \u00e9nfasis en el aprendizaje<\/li><li>Integrador II<\/li><\/ul><\/td><td><p>II A\u00d1O<\/p><p>SEMESTRE III<\/p><ul><li>Curr\u00edculo<\/li><li>Did\u00e1ctica de la Matem\u00e1tica I<\/li><li>Trigonometr\u00eda<\/li><li>Geometr\u00eda Euclidiana II<br \/>\u00c1lgebra Polinomial<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>C\u00e1lculo Diferencial<\/li><li>Geometr\u00eda din\u00e1mica del plano<\/li><li>Taller did\u00e1ctico de Geometr\u00eda<\/li><li>Laboratorio de Matem\u00e1tica II<\/li><li>Evaluaci\u00f3n de los aprendizajes por competencias<\/li><li>Integrador IV<\/li><\/ul><p>\u00a0<\/p><\/td><\/tr><tr><td><p>III A\u00d1O<\/p><p>SEMESTRE V<\/p><ul><li>Taller did\u00e1ctico de aritm\u00e9tica<\/li><li>Dominios num\u00e9ricos<\/li><li>C\u00e1lculo integral<\/li><li>Elementos de Probabilidades<\/li><li>Metodolog\u00eda de la investigaci\u00f3n cualitativa<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Geometr\u00eda cartesiana<\/li><li>Laboratorio III<\/li><li>\u00c1lgebra lineal<\/li><li>Taller did\u00e1ctico de \u00c1lgebra<\/li><li>Did\u00e1ctica de la Matem\u00e1tica II<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p>IV A\u00d1O<\/p><p>SEMESTRE VII<\/p><ul><li>Optativo I<\/li><li>C\u00e1lculo vectorial<\/li><li>Optativo II<\/li><li>\u00c1lgebra computacional<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Metodolog\u00eda cuantitativa<\/li><li>Optativo III<\/li><li>Optativo IV<\/li><li>Taller did\u00e1ctico de funciones<\/li><li>Estad\u00edstica Inferencial<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p>V A\u00d1O<\/p><p>SEMESTRE IX<\/p><ul><li>Pr\u00e1cticas Pre Profesionales<\/li><li>Optativo V<\/li><li>Optativo VI<\/li><li>Gesti\u00f3n Educativa<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1663\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1663\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1663\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17424\" class=\"elementor elementor-17424\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4736db96 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"4736db96\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30e717d3\" data-id=\"30e717d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3011aa04\" data-id=\"3011aa04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bf4b922 elementor-widget elementor-widget-heading\" data-id=\"7bf4b922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Cultura y Artes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-792c74d elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"792c74d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-456152d3\" data-id=\"456152d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b7dd7df elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"1b7dd7df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4611\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4611\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4612\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4612\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4613\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4613\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4611\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4611\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4611\" tabindex=\"0\" hidden=\"false\"><p>Formaci\u00f3n de docentes en el \u00e1mbito art\u00edstico cultural para la educaci\u00f3n secundaria.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Escuelas de educaci\u00f3n general<\/li><li>Centros culturales p\u00fablicos y privados<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Docencia en artes en el nivel escolar<\/li><li>Gesti\u00f3n Cultural<\/li><li>Investigaci\u00f3n educativa en el campo cultural y art\u00edstico<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4612\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4612\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4612\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comprensi\u00f3n Lectora y Expresi\u00f3n oral<\/li><li>Expresi\u00f3n danzaria del folclor de Nicaragua I<\/li><li>T\u00e9cnicas de Dibujo, Pintura y Manualidades<\/li><li>Apreciaci\u00f3n Musical<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Expresi\u00f3n Escrita<\/li><li>Formaci\u00f3n Ciudadana<\/li><li>Ofim\u00e1tica<\/li><li>Expresi\u00f3n Danzaria del folclor de Nicaragua II<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Pedagog\u00eda General<\/li><li>Historia Cultural y Antropol\u00f3gica de Nicaragua<\/li><li>Optativa I<\/li><li>Matem\u00e1ticas para las artes<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Did\u00e1ctica General con \u00e9nfasis en el Aprendizaje<\/li><li>Investigaci\u00f3n educativa en las Artes I<\/li><li>Taller de artes pl\u00e1sticas<\/li><li>Optativo II<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Evaluaci\u00f3n Educativa por competencias<\/li><li>Historia del Arte<\/li><li>Optativa III<\/li><li>Educaci\u00f3n Musical<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Gesti\u00f3n Educativa<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>Apreciaci\u00f3n de la Danza<\/li><li>Optativo IV<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Curr\u00edculo<\/li><li>Dramaturgia<\/li><li>Optativo V<\/li><li>Did\u00e1ctica especial de las Artes<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Direcci\u00f3n Teatral<\/li><li>Gesti\u00f3n Cultural<br \/>Producci\u00f3n Art\u00edstica<\/li><li>Propuesta did\u00e1ctica en Artes<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Investigaci\u00f3n educativa en las Artes II<\/li><li>Optativo VI<\/li><li>Proyectos Cultural a la comunidad<\/li><li>Practicas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4613\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4613\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4613\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Chontales<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17427\" class=\"elementor elementor-17427\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56950e1d elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"56950e1d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61720baf\" data-id=\"61720baf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-171e2ccb\" data-id=\"171e2ccb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d52ff83 elementor-widget elementor-widget-heading\" data-id=\"5d52ff83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Danza<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b19d379 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"1b19d379\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f613298\" data-id=\"6f613298\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67c5918a elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"67c5918a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1741\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1741\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1742\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1742\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1743\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1743\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1741\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1741\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1741\" tabindex=\"0\" hidden=\"false\"><p>Perfil de la Carrera : Tiene como objeto de estudio la docencia y promotor\u00eda de la danza; con la capacidad de aplicar los modelos pedag\u00f3gicos en los procesos de ense\u00f1anza aprendizaje de la danza en distintos contextos y niveles educativos y la producci\u00f3n art\u00edstica en el \u00e1rea de la danza, est\u00e1 facultado para el dominio de la metodolog\u00eda de la investigaci\u00f3n educativa y coreogr\u00e1fica, que permita mejorar la promoci\u00f3n danzar\u00eda con respeto a la diversidad cultural como contribuci\u00f3n al buen vivir de los pueblos, tambi\u00e9n tiene la capacidad de producir espect\u00e1culos danzarios que promueven las creaciones nacionales con est\u00e1ndares internacionales en el arte de la danza, capaz de realizar creaciones art\u00edstica en el \u00e1mbito de la danza haciendo uso de t\u00e9cnicas esenciales en el campo de la docencia en danza en el nivel escolar, educaci\u00f3n art\u00edstica y agrupaciones danzarias, coreograf\u00eda y ensayo, producci\u00f3n art\u00edstica en danza, promotor\u00eda cultural Danzaria.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Institutos de Educaci\u00f3n B\u00e1sica y Media<\/li><li>Escuelas de educaci\u00f3n general<\/li><li>Centros culturales p\u00fablicos y privados<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Docencia en Danza, en contexto Escolar y especializado<\/li><li>Producci\u00f3n Art\u00edstica en la Danza<\/li><li>Investigaci\u00f3n educativa en el campo de la Danza<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1742\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1742\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1742\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Compresi\u00f3n Lectora y Expresi\u00f3n Oral<\/li><li>Historia Cultural nicarag\u00fcense<\/li><li>Morfolog\u00eda funcional de la Danza<\/li><li>Danza Folkl\u00f3rica del Pacifico Nicarag\u00fcense<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Expresi\u00f3n Escrita<\/li><li>Danza Folkl\u00f3rica del centro y norte Nicarag\u00fcense<\/li><li>Ofim\u00e1tica<\/li><li>Kinesiolog\u00eda de la Danza<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Pedagog\u00eda General<\/li><li>Formaci\u00f3n Ciudadana<\/li><li>Antropolog\u00eda de la Danza<\/li><li>Danza Folkl\u00f3rica de la costa Caribe de Nicaragua<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Did\u00e1ctica General con \u00e9nfasis en el aprendizaje<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n en Danza<\/li><li>Introducci\u00f3n a las T\u00e9cnicas de la Danza<\/li><li>Optativo I<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Evaluaci\u00f3n de los Aprendizajes por competencias<\/li><li>\u00a0Tecnolog\u00eda para las Artes<\/li><li>Historia y Apreciaci\u00f3n de la Danza I<\/li><li>Optativo II<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Gesti\u00f3n Educativa<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>Historia y Apreciaci\u00f3n de la Danza II<\/li><li>Optativo III<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Matem\u00e1tica para la Danza<\/li><li>Diagn\u00f3stico situacional de la Danza<\/li><li>Curr\u00edculo<\/li><li>Optativo IV<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Investigaci\u00f3n en Danza<\/li><li>Critica del Arte de la Danza<\/li><li>Optativo V<\/li><li>Proyector Danzar\u00edo a la Comunidad<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Evaluaci\u00f3n de la Artisticidad<\/li><li>Optativa VI<\/li><li>Producci\u00f3n Art\u00edstica en Danza<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1743\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1743\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1743\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17429\" class=\"elementor elementor-17429\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fei-ldm\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-743c5651 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"743c5651\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-542a7189\" data-id=\"542a7189\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6310d205\" data-id=\"6310d205\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c7ca911 elementor-widget elementor-widget-heading\" data-id=\"6c7ca911\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Dise\u00f1o Gr\u00e1fico y Multimedia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7610dca6 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"7610dca6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b993b24\" data-id=\"5b993b24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47a3195b elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"47a3195b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1201\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1201\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1202\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1202\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1203\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1203\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1201\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1201\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1201\" tabindex=\"0\" hidden=\"false\"><p>Perfil de la carrera: El objeto de estudio de la Carrera de Dise\u00f1o Gr\u00e1fico y Multimedia es el dise\u00f1o gr\u00e1fico y multimedia de recursos publicitarios empresariales y sociales, por tanto, es un profesional integral competente en la creaci\u00f3n de recursos gr\u00e1ficos y audiovisuales utilizando herramientas profesionales del dise\u00f1o y la multimedia para la divulgaci\u00f3n de los sectores del pa\u00eds.<\/p><p>Asimismo, aplica t\u00e9cnicas de investigaci\u00f3n que contribuyen a la soluci\u00f3n de problemas y ejecuci\u00f3n de proyectos gr\u00e1ficos y audiovisuales desde su \u00e1mbito de actuaci\u00f3n. A su vez implementa principios pedag\u00f3gicos en el proceso de ense\u00f1anza y aprendizaje del dise\u00f1o gr\u00e1fico y multimedia en instituciones educativas t\u00e9cnicas.<\/p><p>Desarrollando en el profesional la creatividad, \u00e9tica y la visi\u00f3n art\u00edstica, con formaci\u00f3n humanista en correspondencia con la misi\u00f3n de la Universidad.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>\u00c1rea de dise\u00f1o Gr\u00e1fico.<\/p><p>\u00c1rea de publicidad.<\/p><p>\u00c1rea Editorial.<\/p><p>Departamento de Producci\u00f3n audiovisual.<\/p><p>\u00c1rea de Dise\u00f1o Web.<\/p><p>\u00c1rea de fotograf\u00eda.<\/p><p>Centros de educaci\u00f3n t\u00e9cnica.<\/p><p>\u00c1rea de Planificaci\u00f3n de Proyectos.<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Dise\u00f1o Gr\u00e1fico<\/li><li>Dise\u00f1o Multimedia<\/li><li>Gesti\u00f3n de Proyectos<\/li><li>Arte Fotogr\u00e1fico<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1202\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1202\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1202\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Ofim\u00e1tica para Dise\u00f1o<\/li><li>Comprensi\u00f3n Lectora y Expresi\u00f3n Oral<\/li><li>Introducci\u00f3n al Dise\u00f1o Gr\u00e1fico<\/li><li>Teor\u00eda del Color<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Expresi\u00f3n escrita<\/li><li>Semi\u00f3tica<\/li><li>Psicolog\u00eda de la Comunicaci\u00f3n Visual<\/li><li>Fotograf\u00eda<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Metodolog\u00eda del dise\u00f1o gr\u00e1fico<\/li><li>Tratamiento de Im\u00e1genes Digitales<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Ilustraci\u00f3n Digital I<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Ilustraci\u00f3n Digital II<\/li><li>Dise\u00f1o asistido por computadoras<\/li><li>Dise\u00f1o UX \/UI<\/li><li>Historia del Arte y el dise\u00f1o<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Dise\u00f1o editorial<\/li><li>Dise\u00f1o Web<\/li><li>Redacci\u00f3n de Guiones<\/li><li>Optativo I<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Optativo II<\/li><li>Taller de Medios audiovisuales<\/li><li>Dibujo anat\u00f3mico<\/li><li>Optativo III<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo IV<\/li><li>Dise\u00f1o Publicitario<\/li><li>Producci\u00f3n Audio Visual I<\/li><li>Optativo V<\/li><li>\u00a0Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Producci\u00f3n Audivisual II<\/li><li>Animaci\u00f3n I<\/li><li>Modelado 3D<\/li><li>Optativo VI<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Taller de Tesis<\/li><li>Optativo VII<\/li><li>Animaci\u00f3n II<\/li><li>Optativo VIII<\/li><li>Pr\u00e1ctica Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1203\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1203\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1203\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17432\" class=\"elementor elementor-17432\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66cc8eb9 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"66cc8eb9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6b293005\" data-id=\"6b293005\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-413cbe49\" data-id=\"413cbe49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46f56ccf elementor-widget elementor-widget-heading\" data-id=\"46f56ccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Educaci\u00f3n F\u00edsica y Deportes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55618752 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"55618752\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7be422ab\" data-id=\"7be422ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1554af68 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"1554af68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3571\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3571\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3572\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3572\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3573\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3573\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3571\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3571\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3571\" tabindex=\"0\" hidden=\"false\"><p>Formaci\u00f3n para el ejercicio de la docencia en el \u00e1rea de educaci\u00f3n f\u00edsica, recreaci\u00f3n y deportes, capacitado para que dirija, controle y eval\u00fae el desarrollo de las habilidades cient\u00edficas \u2013 t\u00e9cnica del deporte; asimismo, el desarrollo de las capacidades, habilidades y destrezas f\u00edsicas, t\u00e9cnicas y t\u00e1cticas del entrenamiento deportivo.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Instituciones Municipales, clubes o academias deportivas, gimnasios de actividad f\u00edsica p\u00fablicos y privados y ONG a nivel Nacional<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Docencia en Educaci\u00f3n F\u00edsica y Deportes<\/li><li>Entrenamiento deportivo<\/li><li>Promotor\u00eda en tem\u00e1ticas relacionadas con la educaci\u00f3n f\u00edsica y el deporte<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3572\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3572\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3572\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comprensi\u00f3n Lectora y Expresi\u00f3n Oral<\/li><li>Ofim\u00e1tica<\/li><li>Cultura F\u00edsica y Recreaci\u00f3n<\/li><li>Anatom\u00eda y fisiolog\u00eda humana<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Optativo I<\/li><li>Herramientas Inform\u00e1ticas para la Investigaci\u00f3n<\/li><li>Educaci\u00f3n F\u00edsica Inicial<\/li><li>Integrador II<\/li><li>Expresi\u00f3n Escrita<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Formaci\u00f3n Ciudadana<\/li><li>Pedagog\u00eda General<\/li><li>Atletismo I<\/li><li>Preparaci\u00f3n F\u00edsica<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Did\u00e1ctica General con \u00e9nfasis en el Aprendizaje<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>Atletismo II<\/li><li>Pedagog\u00eda de la Actividad F\u00edsica y el Deporte<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Gesti\u00f3n Educativa<\/li><li>Pesas Aplicadas al Deporte<\/li><li>Psicolog\u00eda Aplicada al Deporte<\/li><li>Teor\u00eda y Metodolog\u00eda del Entrenamiento Deportivo I<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Optativo II<\/li><li>Evaluaci\u00f3n de los aprendizajes por competencias<\/li><li>Futbol<\/li><li>Teor\u00eda y Metodolog\u00eda del Entrenamiento Deportivo II<\/li><li>Biomec\u00e1nica Aplicada al Deporte<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo III<\/li><li>Cultura F\u00edsica Terap\u00e9utica<\/li><li>B\u00e9isbol<\/li><li>Bioqu\u00edmica Aplicada al Deporte<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Optativo IV<\/li><li>Curr\u00edculo<\/li><li>Baloncesto<\/li><li>Voleibol<\/li><li>Planificaci\u00f3n y Evaluaci\u00f3n del Entrenamiento deportivo<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo V<\/li><li>Gesti\u00f3n Deportiva<\/li><li>An\u00e1lisis de Datos Aplicado al Deporte<\/li><li>Investigaci\u00f3n aplicada<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3573\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3573\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3573\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17435\" class=\"elementor elementor-17435\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fei-ltile\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e61413a elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"1e61413a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-397e2599\" data-id=\"397e2599\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6ca4ec11\" data-id=\"6ca4ec11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31bc0b45 elementor-widget elementor-widget-heading\" data-id=\"31bc0b45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Traducci\u00f3n e Interpretaci\u00f3n de Lenguas Extranjeras<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-323988fc elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"323988fc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42e72308\" data-id=\"42e72308\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc2597d elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"dc2597d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2301\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2301\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2302\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2302\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2303\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2303\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2301\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2301\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2301\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera Traducci\u00f3n e Interpretaci\u00f3n de Lenguas Extranjeras es formar traductores e int\u00e9rpretes como mediadores ling\u00fc\u00edsticos y culturales. Para ello el profesional debe tener dominio de su lengua materna y otros idiomas.<\/p><p>Asimismo, cuenta con las competencias que responden a la demanda de la sociedad y del mercado laboral actual, tales como: la competencia tecnol\u00f3gica que le permite el uso de las Tics, procesadores de textos, utilizaci\u00f3n de software de manera efectiva para la traducci\u00f3n y la revisi\u00f3n.<\/p><p>Por otra parte, el profesional debe ser competente en la realizaci\u00f3n de investigaciones documentales, lo que le permite un amplio bagaje terminol\u00f3gico y cultural para tomar decisiones adecuadas en cada contexto referido al proceso traductol\u00f3gico e interpretativo. Asimismo, cuenta con las habilidades para la interacci\u00f3n con personas de culturas diferentes a la suya, a trav\u00e9s de la negociaci\u00f3n de productos y servicios espec\u00edficos.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Traducci\u00f3n en l\u00ednea<\/li><li>Bufetes de Traductores<\/li><li>Entidades Gubernamentales<br \/>y no Gubernamentales<\/li><li>Instituciones franc\u00f3fonas: Embajadas, Consulados, Centros Culturales<\/li><li>Independiente<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Traduce documentos en lenguas de trabajo, franc\u00e9s e ingl\u00e9s, hacia la lengua materna.<\/li><li>Revisa terminolog\u00eda con fines espec\u00edficos para traducir.<\/li><li>Detecta y usa recursos tecnol\u00f3gicos de ayuda a la traducci\u00f3n.<\/li><li>Interpreta discursos orales y escritos de las lenguas de trabajo, franc\u00e9s e ingl\u00e9s, hacia la lengua materna.<\/li><li>Realiza interpretaci\u00f3n de acompa\u00f1amiento para garantizar un adecuado enlace comunicativo en eventos nacionales e internacionales, as\u00ed como asistencia biling\u00fce en diferentes contextos.<\/li><li>Planifica y desarrolla eventos de car\u00e1cter nacional e internacional haciendo uso de los aspectos comunicativos, interpretativos, protocolarios, ling\u00fc\u00edsticos correspondiente a otras culturas.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2302\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2302\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2302\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comprensi\u00f3n Lectora y Expresi\u00f3n Oral<\/li><li>Franc\u00e9s I<\/li><li>Fon\u00e9tica Francesa<\/li><li>Ingl\u00e9s I<\/li><li>Fon\u00e9tica Inglesa<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Introducci\u00f3n a la Cultura Franc\u00f3fona y Angl\u00f3fona<\/li><li>Franc\u00e9s II<\/li><li>Ingl\u00e9s II<\/li><li>Expresi\u00f3n Escrita<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Franc\u00e9s III<\/li><li>Ling\u00fc\u00edstica Francesa I<\/li><li>Ingl\u00e9s III<\/li><li>Ling\u00fc\u00edstica Inglesa<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Franc\u00e9s IV<\/li><li>Ling\u00fc\u00edstica Francesa II<\/li><li>Ingl\u00e9s IV<\/li><li>Cultura y civilizaci\u00f3n Franc\u00f3fona y Angl\u00f3fona<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Franc\u00e9s V<\/li><li>Ingl\u00e9s V<\/li><li>Optativo I<\/li><li>Herramientas de la Inform\u00e1tica para la Traducci\u00f3n<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Franc\u00e9s VI<\/li><li>Optativo II<\/li><li>Teor\u00eda y Pr\u00e1ctica de la Interpretaci\u00f3n Francesa<\/li><li>Interpretaci\u00f3n Inglesa I<br \/>Traducci\u00f3n Inglesa I<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo III<\/li><li>Interpretaci\u00f3n Inglesa II<\/li><li>Traducci\u00f3n Inglesa II<\/li><li>Traducci\u00f3n Francesa General<\/li><li>Taller de Expresi\u00f3n Escrita y Oral en Franc\u00e9s para la Traducci\u00f3n<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Terminolog\u00eda<\/li><li>Dise\u00f1o Gr\u00e1fico para la Traducci\u00f3n<\/li><li>Optativo IV<\/li><li>Taller de Expresi\u00f3n Escrita y Oral en Ingl\u00e9s para la Traducci\u00f3n<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Pr\u00e1cticas Pre Profesionales<\/li><li>Optativo V<\/li><li>Taller de Revisi\u00f3n de Textos para la<br \/>Traducci\u00f3n<\/li><li>Herramientas Web y Marketing Digital para<br \/>la Traducci\u00f3n<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2303\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2303\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2303\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17438\" class=\"elementor elementor-17438\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fei-lts\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24f2ea00 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"24f2ea00\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a6e540f\" data-id=\"5a6e540f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b0f18e2\" data-id=\"b0f18e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5df7d8af elementor-widget elementor-widget-heading\" data-id=\"5df7d8af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Turismo Sostenible<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-630ba7fd elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"630ba7fd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6bedf7d4\" data-id=\"6bedf7d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a4d479c elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"7a4d479c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2051\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2051\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2052\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2052\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2053\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2053\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2051\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2051\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2051\" tabindex=\"0\" hidden=\"false\"><p>La carrera de Turismo Sostenible tiene por objeto la gesti\u00f3n tur\u00edstica con enfoque de sostenibilidad ambiental, sociocultural y econ\u00f3mico. El graduado de esta carrera tendr\u00e1 la capacidad de planificar el turismo con enfoque sostenible e innovador; administrar y emprender MIPYMES tur\u00edsticas; investigar problemas o necesidades en el sector; brindar asistencia t\u00e9cnica en sostenibilidad; comercializar servicios y productos tur\u00edsticos; atender al cliente en las distintas \u00e1reas del servicio tur\u00edstico de forma eficaz y eficiente; competencias que podr\u00e1 desempe\u00f1ar en los campos de acci\u00f3n de la planificaci\u00f3n tur\u00edstica sostenible del territorio, la administraci\u00f3n de MIPYMES y el marketing en turismo, teniendo como \u00e1mbitos de actuaci\u00f3n las MIPYMES tur\u00edsticas e instituciones p\u00fablicas y privadas vinculadas al turismo.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Instituciones p\u00fablicas vinculadas al turismo.<\/li><li>Micro, peque\u00f1as y medianas empresas tur\u00edsticas (hoteles, restaurantes, agencias de viajes y tour operadoras).<\/li><li>Organizaciones no gubernamentales vinculadas al turismo.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Planificar el turismo con enfoque sostenible, a trav\u00e9s de metodolog\u00edas de planificaci\u00f3n tur\u00edstica con el fin de contribuir al desarrollo sostenible de los territorios y a la micro, peque\u00f1a y mediana empresa (Mipymes).<\/li><li>Administrar Mipymes tur\u00edsticas, a trav\u00e9s del aprendizaje de los procesos de planificaci\u00f3n, organizaci\u00f3n, direcci\u00f3n y control, con el fin de apoyar la gesti\u00f3n eficiente y eficaz para su rentabilidad y sostenibilidad.<\/li><li>Formular emprendimientos tur\u00edsticos micros y peque\u00f1os aplicando los conceptos y herramientas espec\u00edficas de cada una de las distintas dimensiones microempresariales con el fin de facilitar el impulso de un negocio.<\/li><li>Comercializar servicios y productos tur\u00edsticos innovadores, a trav\u00e9s de la implementaci\u00f3n de estrategias de marketing y el uso de tecnolog\u00edas de la informaci\u00f3n y comunicaci\u00f3n (TIC\u2019s).<\/li><li>Atender al cliente en las distintas \u00e1reas del servicio tur\u00edstico de forma eficaz y eficiente apoy\u00e1ndose en t\u00e9cnicas de comunicaci\u00f3n para la satisfacci\u00f3n de los visitantes.<\/li><li>Guiar a los visitantes en los idiomas ingl\u00e9s y franc\u00e9s brindando informaci\u00f3n de los destinos y servicios de las empresas tur\u00edsticas.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2052\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2052\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2052\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Ofim\u00e1tica<\/li><li>Ingles Comunicativo I<\/li><li>Turismo y desarrollo sostenible<\/li><li>Comprensi\u00f3n lectora y expresi\u00f3n oral<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Dise\u00f1o de mapas tur\u00edsticos<\/li><li>Ingles comunicativo II<\/li><li>Planificaci\u00f3n Tur\u00edstica<\/li><li>Investigaci\u00f3n I<\/li><li>Expresi\u00f3n escrita<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Ingl\u00e9s Comunicativo III<\/li><li>Sostenibilidad del Turismo<\/li><li>Marketing tur\u00edstico<\/li><li>Investigaci\u00f3n II<\/li><li>Integrador III<\/li><li>Optativo I<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Ingl\u00e9s Comunicativo IV<\/li><li>An\u00e1lisis del Entorno Tur\u00edstico<\/li><li>Investigaci\u00f3n de mercados<\/li><li>Estad\u00edstica General<\/li><li>Integrador IV<\/li><li>Optativo II<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Franc\u00e9s b\u00e1sico<\/li><li>Planificaci\u00f3n estrat\u00e9gica del turismo<\/li><li>Desarrollo de Productos tur\u00edsticos<\/li><li>Estad\u00edstica descriptiva en la investigaci\u00f3n tur\u00edstica<\/li><li>Integrador V<\/li><li>Optativo III<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Dise\u00f1o publicitario I<\/li><li>Franc\u00e9s comunicativo I<\/li><li>Administraci\u00f3n de MIPYMES Tur\u00edsticas I<\/li><li>Gesti\u00f3n de la calidad y sostenibilidad empresarial<\/li><li>Contabilidad Aplicada<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Dise\u00f1o publicitario II<\/li><li>Franc\u00e9s comunicativo II<\/li><li>Administraci\u00f3n de MIPYMES Tur\u00edsticas II<\/li><li>Marketing digital y gesti\u00f3n de redes sociales<\/li><li>Marketing estrat\u00e9gico<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Franc\u00e9s comunicativo III<\/li><li>Liderazgo y gesti\u00f3n de la organizaci\u00f3n<\/li><li>Emprendimiento tur\u00edstico<\/li><li>An\u00e1lisis financiero para MIPYMES Tur\u00edsticas I<\/li><li>Integrador VIII<\/li><li>Optativo IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Franc\u00e9s para guiado<\/li><li>An\u00e1lisis financiero para MIPYMES Tur\u00edsticas II<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><li>Optativo V<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas profesionales<\/li><li>Modalidad de graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2053\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2053\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2053\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17441\" class=\"elementor elementor-17441\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20d42186 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"20d42186\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bfe0c18\" data-id=\"bfe0c18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40d8cec7\" data-id=\"40d8cec7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-291235e6 elementor-widget elementor-widget-heading\" data-id=\"291235e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Administraci\u00f3n de la Educaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7651f139 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"7651f139\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-281ef08c\" data-id=\"281ef08c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14d9e9dd elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"14d9e9dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3491\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3491\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3492\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3492\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3491\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3491\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3491\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la Carrera de Pedagog\u00eda con menci\u00f3n en Administraci\u00f3n de la Educaci\u00f3n es la Administraci\u00f3n y Gesti\u00f3n de la calidad de la educaci\u00f3n en instituciones educativas.<\/p><p>El profesional egresado de la carrera de Administraci\u00f3n de la Educaci\u00f3n investiga problemas educativos, gestiona la calidad de la educaci\u00f3n a trav\u00e9s de la planificaci\u00f3n y ejecuci\u00f3n de proyectos en centros educativos, acompa\u00f1a procesos pedag\u00f3gicos, capacita metodol\u00f3gicamente al personal administrativo y docente.<\/p><p>Elabora diferentes tipos de planes a cortos y largo plazo para los centros educativos, facilitando el mejoramiento de los procesos de ense\u00f1anza y aprendizaje en el aula de clase a trav\u00e9s del uso de las TIC (Tecnolog\u00eda de la informaci\u00f3n y comunicaci\u00f3n.<br \/>Por su formaci\u00f3n puede desempe\u00f1arse en Centros de Ense\u00f1anza B\u00e1sica o Media, en el Ministerio de Educaci\u00f3n Nacional, Departamental o Municipal, en Instituciones Educativas y ONG.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional <\/strong><\/p><ul><li>Centros de ense\u00f1anza b\u00e1sica o media.<\/li><li>Ministerio de Educaci\u00f3n Nacional, departamental o municipal.<br \/>Instituciones educativas y ONG.<\/li><li>Tareas que puede realizar el profesional<\/li><li>Investiga problemas educativos.<\/li><li>Elabora proyectos Educativos de centro.<\/li><li>Elabora planes operativos anuales para los centros educativos.<\/li><li>Gestiona la calidad de la educaci\u00f3n en instituciones educativas.<br \/>Acompa\u00f1a procesos pedag\u00f3gicos.<\/li><li>Capacita metodol\u00f3gicamente al personal docente.<\/li><li>Desarrolla procesos de ense\u00f1anza \u2013 aprendizaje en el aula de clase.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3492\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3492\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3492\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Matem\u00e1tica B\u00e1sica<\/li><li>Formaci\u00f3n<\/li><li>Ciudadana<\/li><li>Comprensi\u00f3n lectora y<\/li><li>Expresi\u00f3n Oral<\/li><li>Pedagog\u00eda General<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Educaci\u00f3n y Sociedad<\/li><li>Desarrollo Humano<\/li><li>Ofim\u00e1tica I<\/li><li>Administraci\u00f3n y Gesti\u00f3n Educativa<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Higiene Escolar<\/li><li>Expresi\u00f3n Escrita<\/li><li>Ofim\u00e1tica II<\/li><li>Did\u00e1ctica General con \u00e9nfasis en el aprendizaje<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Estad\u00edstica Descriptiva<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>Metodolog\u00eda Investigativa para la educaci\u00f3n<\/li><li>Administraci\u00f3n y gesti\u00f3n de la Educaci\u00f3n II<\/li><li>Integrador IV<\/li><\/ul><\/td><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Optativo I<\/li><li>Gesti\u00f3n de Recursos did\u00e1cticos y tecnol\u00f3gicos<\/li><li>Curr\u00edculo<\/li><li>Evaluaci\u00f3n de los aprendizajes por competencias<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Optativo II<\/li><li>Software de an\u00e1lisis de datos cualitativos<\/li><li>Acreditaci\u00f3n de instituciones educativas<\/li><li>Clima Organizacional<\/li><li>Integrador VI<\/li><\/ul><\/td><\/tr><tr><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo III<\/li><li>Gesti\u00f3n Educativa<\/li><li>Curr\u00edculo II<\/li><li>Did\u00e1ctica para la Educaci\u00f3n B\u00e1sica<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Optativo IV<\/li><li>Software para el an\u00e1lisis de datos cuantitativos<\/li><li>Metodolog\u00eda de la Capacitaci\u00f3n<\/li><li>Did\u00e1ctica para la educaci\u00f3n media<\/li><li>Integrador VIII<\/li><\/ul><\/td><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo V<\/li><li>Sistema de control de la calidad en educaci\u00f3n<\/li><li>Legislaci\u00f3n educativa<\/li><li>Pr\u00e1ctica Preprofesional<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1ctica Profesional<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17444\" class=\"elementor elementor-17444\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-128bc647 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"128bc647\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b3f4933\" data-id=\"7b3f4933\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-107e7443\" data-id=\"107e7443\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18670065 elementor-widget elementor-widget-heading\" data-id=\"18670065\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pedagog\u00eda con menci\u00f3n en Educaci\u00f3n para la Diversidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49e00abf elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"49e00abf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3595bcaf\" data-id=\"3595bcaf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11fc13ba elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"11fc13ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3011\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3011\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3011\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3011\" tabindex=\"0\" hidden=\"false\"><p style=\"text-align: justify;\">\u00abEducaci\u00f3n Inclusiva: Por educaci\u00f3n inclusiva se entiende el proceso mediante el cual, la escuela o servicio educativo alternativo incorpora a las personas con discapacidad, grupos sociales excluidos, marginados y vulnerables, especialmente en el \u00e1mbito rural, sin distinci\u00f3n de etnia, sexo u otra causa de discriminaci\u00f3n contribuyendo as\u00ed a la eliminaci\u00f3n de la pobreza, la exclusi\u00f3n y las desigualdades. Se propone responder a todos los estudiantes como individuos, reconsiderando su organizaci\u00f3n y su propuesta curricular\u00bb.<\/p><p style=\"text-align: justify;\">La carrera de Pedagog\u00eda con menci\u00f3n en Educaci\u00f3n para la Diversidad es una carrera pedag\u00f3gica; su disciplina cient\u00edfica es la Pedagog\u00eda como ciencia de la educaci\u00f3n, por lo tanto, su objeto de estudio es primero el hecho educativo, los m\u00e9todos para la ense\u00f1anza y el aprendizaje; es la relaci\u00f3n maestro(a)-alumno(a), es la situaci\u00f3n educativa que se concreta en el aula de clase, pero que se refleja en todos los escenarios sociales. Pero de forma espec\u00edfica, y considerando la Menci\u00f3n o Enfoque de la carrera, su objeto de estudio es la formaci\u00f3n de profesionales que sean capaces de dar respuestas a las demandas educativas que presentan ni\u00f1os, ni\u00f1as y j\u00f3venes con o sin deficiencia, ni\u00f1os que han sido excluidos por sus diferencias sociales, culturales, \u00e9tnicas, ling\u00fc\u00edsticas, sexuales, etc.<\/p><p style=\"text-align: justify;\">Esta carrera es la Pedagog\u00eda que har\u00e1 de los nuevos profesionales de la educaci\u00f3n, profesionales que sabr\u00e1n emplear las t\u00e9cnicas cient\u00edficas apropiadas para el tratamiento educativo de las m\u00faltiples diferencias entre los ni\u00f1os, ni\u00f1as y adolescentes que llegan a formarse como nuevos ciudadanos a la escuela. Este pedagogo(a) ser\u00e1 un(a) cient\u00edfico(a) que investigar\u00e1 los m\u00e9todos tanto educativos o de formaci\u00f3n como de la Did\u00e1ctica para atender las diferencias individuales y contribuir a la formaci\u00f3n de altos valores humanos en la sociedad nicarag\u00fcense.<\/p><p style=\"text-align: justify;\">La formaci\u00f3n en Pedagog\u00eda con menci\u00f3n en Educaci\u00f3n para la Diversidad estar\u00e1 dirigida por un lado a las personas que ya est\u00e1n ejerciendo docencia en el campo de la Educaci\u00f3n Especial, a los orientadores, asesores, directores de centros de educaci\u00f3n especial y todos aquellos que est\u00e9n vinculados y comprometidos con el desarrollo de la educaci\u00f3n especial en Nicaragua; y por otro lado, tambi\u00e9n a todos y todas las docentes emp\u00edricos y profesionales (que quieran continuar perfeccionando su formaci\u00f3n), que trabajan en el sector educaci\u00f3n (formal o no formal): en el sistema educativo, en ONG, en centros de rehabilitaci\u00f3n, en organizaciones que hacen actividad comunitaria, etc.. La formaci\u00f3n tambi\u00e9n podr\u00e1 orientarse a otras personas, con estudios universitarios o no, que deseen iniciarse por vocaci\u00f3n o formaci\u00f3n en el \u00e1rea de la educaci\u00f3n especial, educaci\u00f3n inicial, educaci\u00f3n primaria regular, educaci\u00f3n secundaria, etc.<\/p><p style=\"text-align: justify;\"><strong>Funciones que realiza el Licenciado en Pedagog\u00eda con menci\u00f3n en Educaci\u00f3n para la Diversidad<\/strong><\/p><ul><li style=\"text-align: justify;\">Educa y forma valores, conocimientos, habilidades y h\u00e1bitos.<\/li><li style=\"text-align: justify;\">Facilita y eval\u00faa el proceso de ense\u00f1anza-aprendizaje.<\/li><li style=\"text-align: justify;\">Facilita la inclusi\u00f3n educativa de todos los ni\u00f1os, ni\u00f1as y adolescentes.<\/li><li style=\"text-align: justify;\">Administrar\u00e1 los procesos educativos, Acompa\u00f1ar\u00e1 pedag\u00f3gica y metodol\u00f3gicamente a los maestros. Eventualmente podr\u00e1 capacitar a los docentes para garantizar la atenci\u00f3n a la diversidad.<\/li><li style=\"text-align: justify;\">Capacita a la comunidad educativa.<\/li><li style=\"text-align: justify;\">Hace diagn\u00f3sticos psico-pedag\u00f3gicos.<\/li><li style=\"text-align: justify;\">Hace promoci\u00f3n social.<\/li><li style=\"text-align: justify;\">Dise\u00f1a estrategias metodol\u00f3gicas.<\/li><li style=\"text-align: justify;\">Realiza evaluaciones.<\/li><\/ul><p style=\"text-align: justify;\"><strong>Cargos que desempe\u00f1a el Licenciado en Pedagog\u00eda con menci\u00f3n en Educaci\u00f3n para la Diversidad<\/strong><\/p><ul><li style=\"text-align: justify;\">Educa y forma valores, conocimientos, habilidades y h\u00e1bitos.<\/li><li style=\"text-align: justify;\">Facilita y eval\u00faa el proceso de ense\u00f1anza-aprendizaje.<\/li><li style=\"text-align: justify;\">Facilita la inclusi\u00f3n educativa de todos los ni\u00f1os, ni\u00f1as y adolescentes.<\/li><li style=\"text-align: justify;\">Administrar\u00e1 los procesos educativos, Acompa\u00f1ar\u00e1 pedag\u00f3gica y metodol\u00f3gicamente a los maestros. Eventualmente podr\u00e1 capacitar a los docentes para garantizar la atenci\u00f3n a la diversidad.<\/li><li style=\"text-align: justify;\">Capacita a la comunidad educativa.<\/li><li style=\"text-align: justify;\">Hace diagn\u00f3sticos psico-pedag\u00f3gicos.<\/li><li style=\"text-align: justify;\">Hace promoci\u00f3n social.<\/li><li style=\"text-align: justify;\">Dise\u00f1a estrategias metodol\u00f3gicas.<\/li><li style=\"text-align: justify;\">Realiza evaluaciones.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17447\" class=\"elementor elementor-17447\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f02a5f7 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"5f02a5f7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-248f275f\" data-id=\"248f275f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6684123f\" data-id=\"6684123f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45e2a988 elementor-widget elementor-widget-heading\" data-id=\"45e2a988\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Educaci\u00f3n Infantil<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6db1c0e0 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"6db1c0e0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dccbffe\" data-id=\"7dccbffe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68ed6c72 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"68ed6c72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1761\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1761\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1762\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1762\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1761\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1761\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1761\" tabindex=\"0\" hidden=\"false\"><p>La carrera de Educaci\u00f3n Infantil tiene como objeto el proceso de ense\u00f1anza y aprendizaje en la Educaci\u00f3n Infantil. El profesional, se desempe\u00f1a en Centros de educaci\u00f3n infantil, en Organismos gubernamentales y no gubernamentales, Instituciones del estado que atienden Programas de atenci\u00f3n a la ni\u00f1ez.<\/p><p>Para ello el profesional de la educaci\u00f3n infantil, planifica el proceso de aprendizaje implementando estrategias l\u00fadicas que favorezca el desarrollo integral de la ni\u00f1ez, desarrolla procesos de gesti\u00f3n y administraci\u00f3n curricular en los centros que atienden a la ni\u00f1ez de 0 a 6 a\u00f1os en todas sus modalidades. Acompa\u00f1a pedag\u00f3gicamente al personal que atiende la ni\u00f1ez de 0 a 6 a\u00f1os, formula proyectos educativos a favor de la primera infancia, familia y comunidad para dar respuesta a las necesidades educativas e investiga y propone alternativas innovadoras en el campo de la educaci\u00f3n infantil para la mejora de la calidad educativa.<\/p><p>Posee una s\u00f3lida formaci\u00f3n cient\u00edfica, pedag\u00f3gica, ambiental, sociocultural, \u00e9tica y human\u00edstica. Utiliza las TIC, como herramienta de apoyo para fortalecer su acci\u00f3n pedag\u00f3gica. Es competente en el establecimiento de relaciones, compromisos, participaci\u00f3n e integraci\u00f3n de la familia y otros agentes de la comunidad para potenciar con ello el desarrollo integral de todos los ni\u00f1os y ni\u00f1as.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Centro de educaci\u00f3n infantil (gubernamental y no gubernamental)<\/li><li>Programas de atenci\u00f3n a la ni\u00f1ez en instituciones educativas y ONG<\/li><li>Instituciones del estado que atienden la ni\u00f1ez.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Docencia en educaci\u00f3n infantil<\/li><li>Organizaci\u00f3n y direcci\u00f3n de Centros infantiles<\/li><li>Asesor\u00eda Pedag\u00f3gica<\/li><li>Investigaci\u00f3n educativa<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1762\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1762\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1762\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Compresi\u00f3n lectora y expresi\u00f3n Oral<\/li><li>Pedagog\u00eda General<\/li><li>Curr\u00edculo<\/li><li>Marco legal y Normativo de la Primera Infancia<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Did\u00e1ctica General con \u00e9nfasis en el Aprendizaje<\/li><li>Psicolog\u00eda de los Aprendizajes<\/li><li>Desarrollo y Aprendizaje Infantil<\/li><li>Expresi\u00f3n Escrita<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Ofim\u00e1tica<\/li><li>Evaluaci\u00f3n de los Aprendizajes<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Curr\u00edculo de la Educaci\u00f3n Infantil<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Did\u00e1ctica de la Educaci\u00f3n Infantil I<\/li><li>Investigaci\u00f3n Acci\u00f3n<\/li><li>Formaci\u00f3n Ciudadana<\/li><li>Neurociencia y Desarrollo Infantil<\/li><li>Integrador IV<\/li><\/ul><\/td><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Taller de Literatura y Teatro Infantil<\/li><li>Did\u00e1ctica de la Educaci\u00f3n Infantil II Investigaci\u00f3n Aplicada<\/li><li>Juego como Herramienta Pedag\u00f3gica<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Herramientas Inform\u00e1ticas para la Investigaci\u00f3n<\/li><li>Salud y Nutrici\u00f3n Infantil<\/li><li>Taller de Expresi\u00f3n Musical y Corporal<\/li><li>Curso de Graduaci\u00f3n T\u00e9cnico Superior<\/li><li>Integrador VI<\/li><\/ul><\/td><\/tr><tr><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Acompa\u00f1amiento Familiar<\/li><li>Innovaci\u00f3n Educativa<\/li><li>Optativa I<\/li><li>Optativa II<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Did\u00e1ctica de la Educaci\u00f3n F\u00edsica infantil<\/li><li>Formulaci\u00f3n y Evaluaci\u00f3n de Proyectos Educativos<\/li><li>Optativa III<\/li><li>Optativa IV<\/li><li>Integrador VIII<\/li><\/ul><\/td><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Metodolog\u00eda de la Capacitaci\u00f3n<\/li><li>Optativa V<\/li><li>Optativa VI<\/li><li>Pr\u00e1cticas Pre profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17453\" class=\"elementor elementor-17453\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b82dddb elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"b82dddb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14ee2f3e\" data-id=\"14ee2f3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-12558f60\" data-id=\"12558f60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c1f0742 elementor-widget elementor-widget-heading\" data-id=\"6c1f0742\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Educaci\u00f3n Primaria<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12a6ba5b elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"12a6ba5b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c6a68d1\" data-id=\"2c6a68d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ca18ed4 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3ca18ed4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1011\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1011\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1012\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1012\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1011\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1011\" tabindex=\"0\" hidden=\"false\"><p>La Licenciatura en Educaci\u00f3n Primaria tiene como objeto de estudio el proceso de ense\u00f1anza y aprendizaje de la educaci\u00f3n primaria en sus distintas modalidades de atenci\u00f3n a trav\u00e9s de la actuaci\u00f3n de un profesional de la educaci\u00f3n formado para desempe\u00f1arse como docente, investigador y gestor de la educaci\u00f3n primaria tanto en instituciones educativas p\u00fablicas y privadas, as\u00ed como en organismos no gubernamentales con incidencia en el campo de la educaci\u00f3n primaria principalmente.<\/p><p>El profesional de la carrera tiene la capacidad de desarrollar procesos did\u00e1cticos atendiendo enfoques y modelos educativos, con el fin de generar innovaciones pedag\u00f3gicas que le aseguren una pr\u00e1ctica docente de calidad, a trav\u00e9s de su habilidad para implementar procesos de investigaci\u00f3n educativa en el campo de la educaci\u00f3n primaria a fin de generar soluciones innovadoras y pertinentes a las demandas educativas.<\/p><p>Adem\u00e1s, es capaz de ejecutar procesos de gesti\u00f3n educativa en la educaci\u00f3n primaria mediante intervenciones que permitan el desarrollo eficaz y eficiente de las instituciones escolares que aseguren la calidad, por lo que, su formaci\u00f3n profesional le brinda la oportunidad de desempe\u00f1arse como un directivo, docente e investigador en las distintas modalidades de atenci\u00f3n de la educaci\u00f3n primaria, adem\u00e1s de ser competente para asesorar, gestionar y evaluar procesos educativos.<\/p><p>Desde el campo de la educaci\u00f3n primaria el accionar del profesional de la carrera se ve impregnado de compromiso social, valores \u00e9ticos, morales, humanistas y liderazgo al analizar el contexto educativo, social y ambiental bajo un enfoque cr\u00edtico y constructivo hacia una pr\u00e1ctica docente de calidad con propuestas de soluciones pertinentes y factibles en el contexto nacional.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Centros de estudio de educaci\u00f3n primaria (tanto p\u00fablicos como privados)<\/li><li>Escuelas Normales<\/li><li>Dependencia de ejecuci\u00f3n de proyectos educativos en ONG`s<\/li><li>Direcciones de Centro de estudios de educaci\u00f3n primaria (p\u00fablicos y privados)<\/li><li>\u00c1rea de Asesor\u00eda Pedag\u00f3gica de las distintas dependencias o delegaciones del Ministerio de Educaci\u00f3n (MINED)<\/li><li>Direcci\u00f3n de Formaci\u00f3n Docente en el Ministerio de Educaci\u00f3n (MINED<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Capacidad de desarrollar procesos did\u00e1cticos atendiendo enfoques y modelos educativos, con el fin de generar innovaciones pedag\u00f3gicas que aseguren una pr\u00e1ctica docente de calidad.<\/li><li>Habilidad para implementar procesos de investigaci\u00f3n en el campo de la educaci\u00f3n primaria a fin de generar soluciones innovadoras y pertinentes a las demandas educativas.<\/li><li>Ser capaz de ejecutar procesos de gesti\u00f3n educativa en la educaci\u00f3n primaria mediante intervenciones que permitan el desarrollo eficaz y eficiente de las instituciones escolares que aseguren la calidad.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1012\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1012\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1012\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>\u00a0<\/p><p>SEMESTRE I<\/p><ul><li>Ofim\u00e1tica<\/li><li>Comunicaci\u00f3n I<\/li><li>Pedagog\u00eda General<\/li><li>Did\u00e1ctica General con \u00e9nfasis en el aprendizaje<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Herramientas Inform\u00e1ticas para la Investigaci\u00f3n<\/li><li>Matem\u00e1tica B\u00e1sica I<\/li><li>Comunicaci\u00f3n II<\/li><li>Metodolog\u00eda investigativa para la educaci\u00f3n<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Optativo I<\/li><li>Matem\u00e1tica B\u00e1sica II<\/li><li>Did\u00e1ctica de la Lengua y la Literatura para Educaci\u00f3n Primaria<\/li><li>Evaluaci\u00f3n de los aprendizajes por competencias<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Matem\u00e1tica B\u00e1sica II<\/li><li>Plan de Investigaci\u00f3n<\/li><li>Did\u00e1ctica de la Matem\u00e1tica para educaci\u00f3n primaria<\/li><li>Psicolog\u00eda de los aprendizajes<\/li><li>Integrador IV<\/li><\/ul><\/td><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Ciencias Sociales<\/li><li>Ciencias Naturales<\/li><li>Did\u00e1ctica de las Ciencias Sociales para educaci\u00f3n primaria<\/li><li>Did\u00e1ctica de las Ciencias Naturales para Educaci\u00f3n Primaria<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Formaci\u00f3n Ciudadana<\/li><li>Matem\u00e1tica B\u00e1sica III<\/li><li>Acciones innovadoras<\/li><li>Modalidades de atenci\u00f3n de la Educaci\u00f3n Primaria<\/li><li>Integrador VI<\/li><\/ul><\/td><\/tr><tr><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Did\u00e1ctica de la Educaci\u00f3n F\u00edsica y Deporte<\/li><li>Proceso de ense\u00f1anza y aprendizaje en la Educaci\u00f3n Primaria<\/li><li>Metodolog\u00edas para el aprendizaje<\/li><li>Curr\u00edculo<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Optativo II<\/li><li>Optativo III<\/li><li>Optativo IV<\/li><li>Investigaci\u00f3n Acci\u00f3n<\/li><li>Integrador VIII<\/li><\/ul><\/td><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Talleres Did\u00e1cticos y Pedag\u00f3gicos<\/li><li>Elaboraci\u00f3n de Textos Educativos<\/li><li>Gesti\u00f3n Educativa<\/li><li>Proyecto Educativo<\/li><li>Pr\u00e1cticas Pre &#8211; Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de graduaci\u00f3n (Licenciatura)<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17450\" class=\"elementor elementor-17450\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4947093 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"4947093\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-424e738c\" data-id=\"424e738c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4114556f\" data-id=\"4114556f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ba1d18f elementor-widget elementor-widget-heading\" data-id=\"4ba1d18f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Educaci\u00f3n Musical<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47b5d5a elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"47b5d5a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2be61d00\" data-id=\"2be61d00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3854bd0e elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3854bd0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9451\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9451\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9452\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9452\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9453\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9453\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9451\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9451\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9451\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de Educaci\u00f3n Musical es el Proceso de ense\u00f1anza y aprendizaje de la m\u00fasica en educaci\u00f3n b\u00e1sica, media y t\u00e9cnica. A trav\u00e9s de la creaci\u00f3n y administraci\u00f3n de agrupaciones y proyectos musicales.<\/p><p>El profesional egresado de la licenciatura en educaci\u00f3n musical posee las competencias que le permitan aplicar el conocimiento Pedag\u00f3gico-Did\u00e1ctico de la educaci\u00f3n musical como recurso inclusivo y de conservaci\u00f3n de las distintas manifestaciones culturales del pa\u00eds.<\/p><p>Siendo capaz de llevar a cabo tareas de investigaci\u00f3n, y adecuaciones pertinentes en los modelos educativos para el fortalecimiento del proceso de ense\u00f1anza y aprendizaje.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>En centros de ense\u00f1anza b\u00e1sica o media.<\/li><li>\u00c1reas de cultura en Instituciones gubernamentales y privadas en las \u00e1reas de:<\/li><li>Docencia.<\/li><li>Investigaci\u00f3n educativa Musical<\/li><li>Administraci\u00f3n de proyectos Musicales<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Planifica y eval\u00faa el proceso de ense\u00f1anza aprendizaje de la educaci\u00f3n musical.<\/li><li>Investiga problemas educativos<\/li><li>Desarrolla estrategias metodol\u00f3gicas de car\u00e1cter inclusivo mediante el recurso musical<\/li><li>Utiliza software para la virtualizaci\u00f3n de cursos y capacitaciones<\/li><li>Domina la metodolog\u00eda de la Investigaci\u00f3n Cient\u00edfica, orientada al campo de la M\u00fasica<\/li><li>Analiza los problemas relacionados con el Proceso de Ense\u00f1anza-aprendizaje de la educaci\u00f3n musical<\/li><li>Investiga manifestaciones musicales aut\u00f3ctonas de las diferentes regiones del pa\u00eds<\/li><li>Coordina departamentos de cultura en instituciones p\u00fablicas o privadas<\/li><li>Dirige centros de formaci\u00f3n musical<\/li><li>Domina los procesos metodol\u00f3gicos para la planificaci\u00f3n, organizaci\u00f3n, ejecuci\u00f3n de proyectos y programas educativos y culturales<\/li><li>Administra proyectos musicales (bandas, orquestas, coros, ensambles entre otros)<\/li><li>Adapta el entorno de aprendizaje de la educaci\u00f3n musical para la atenci\u00f3n de necesidades educativas (trabajo social con j\u00f3venes en riesgo)<\/li><li>Utiliza software para componer, arreglar, grabar y producir obras musicales<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9452\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9452\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9452\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Ofim\u00e1tica<\/li><li>Formaci\u00f3n ciudadana<\/li><li>Percusi\u00f3n y cognici\u00f3n<\/li><li>Lenguaje musical I<br \/>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Comprensi\u00f3n lectora y expresi\u00f3n oral<\/li><li>Estad\u00edstica descriptiva<\/li><li>Flauta dulce I<\/li><li>Lenguaje musical II<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Expresi\u00f3n escrita<\/li><li>Practica coral<\/li><li>Flauta dulce II<\/li><li>Lenguaje musical III<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Pedagog\u00eda General<\/li><li>Piano Funcional I<\/li><li>Lenguaje Musical IV<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n Educativa<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Did\u00e1ctica General<\/li><li>Piano Funcional II<\/li><li>Lenguaje Musical V<\/li><li>Optativo I<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Evaluaci\u00f3n de los aprendizajes por competencias<\/li><li>Guitarra Funcional I<\/li><li>Did\u00e1ctica de la Educaci\u00f3n Musical<\/li><li>Optativo II<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Psicolog\u00eda del Aprendizaje<\/li><li>Guitarra Funcional II<\/li><li>Armon\u00eda Musical I<\/li><li>Optativo III<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>T\u00e9cnicas de Inclusi\u00f3n Musical<\/li><li>Gesti\u00f3n Educativa<\/li><li>Armon\u00eda Musical II<\/li><li>Optativo IV<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Historia de la M\u00fasica Nicarag\u00fcense<\/li><li>Curr\u00edculo<\/li><li>Composici\u00f3n Musical<\/li><li>Optativo V<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de graduaci\u00f3n<\/li><li>Pr\u00e1ctica Profesional<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9453\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9453\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9453\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17468\" class=\"elementor elementor-17468\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2194ea34 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"2194ea34\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-189bbe9f\" data-id=\"189bbe9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-39c062bb\" data-id=\"39c062bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1910b1e2 elementor-widget elementor-widget-heading\" data-id=\"1910b1e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Antropolog\u00eda Social<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ffc5c4f elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"2ffc5c4f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b6c1c6e\" data-id=\"2b6c1c6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b29228 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3b29228\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6201\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6201\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6202\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6202\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6203\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6203\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6201\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6201\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6201\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera Antropolog\u00eda Social es el ser humano y su cultura. Por ello, el profesional investiga las realidades socio-culturales, a trav\u00e9s de los m\u00e9todos antropol\u00f3gicos. Adem\u00e1s de ser capaz de formular proyectos sociales y culturales, a trav\u00e9s del acompa\u00f1amiento de iniciativas comunitarias, pol\u00edticas p\u00fablicas, que contribuyan a la promoci\u00f3n de la interculturalidad.<\/p><p>Su visi\u00f3n humanista le permite comprometerse con los procesos de protagonismo y liderazgo comunitario, promoviendo el desarrollo humano sostenible, la cultura de paz y la no violencia.<\/p><p>Por su formaci\u00f3n en investigaci\u00f3n antropol\u00f3gica, formulaci\u00f3n de proyectos sociales y culturales, gesti\u00f3n socio-cultural y di\u00e1logo intercultural, puede desarrollarse profesionalmente en: Oficinas de proyectos de Instituciones del Estado y Organismos No Gubernamentales; \u00c1rea de Patrimonio Cultural de las Municipalidades; Asociaciones, cooperativas, gremios; Organizaciones comunitarias; Emprendimientos familiares y comunitarios.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Centros de investigaci\u00f3n<\/li><li>Instituciones del Estado<\/li><li>Organismos no gubernamentales<\/li><li>Oficina de Proyectos Sociales de Municipalidades<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Capacidad de investigar las realidades socio-culturales, a trav\u00e9s de los m\u00e9todos antropol\u00f3gicos, con el fin de analizar de manera integral al ser humano y su cultura.<\/li><li>Capacidad de formular proyectos sociales con pertinencia cultural, que aporten al desarrollo humano sostenible.<\/li><li>Capacidad de acompa\u00f1ar iniciativas desde las pr\u00e1cticas culturales de las poblaciones, con el fin de aportar al desarrollo de las comunidades.<\/li><li>Capacidad de promover el di\u00e1logo intercultural, con el fin de aportar a la convivencia local y Fortalecer las identidades<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6202\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6202\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6202\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p>I A\u00f1o<\/p><p>Semestre I<\/p><ul><li>Inform\u00e1tica b\u00e1sica<\/li><li>Epistemolog\u00eda de las ciencias sociales<\/li><li>Introducci\u00f3n al estudio de la cultura<\/li><li>Investigaci\u00f3n documental<\/li><li>Integrador I<\/li><\/ul><p>Semestre II<\/p><ul><li>Filosof\u00eda latinoamericana<\/li><li>Introducci\u00f3n a los proyectos sociales<\/li><li>Estudios de Comunidad<\/li><li>Metodolog\u00eda para la etnograf\u00eda comunitaria<\/li><li>Integrador II<\/li><\/ul><\/td><td><p>II A\u00f1o<\/p><p>Semestre III<\/p><ul><li>Ofim\u00e1tica b\u00e1sica<\/li><li>Econom\u00eda y desarrollo<\/li><li>Proyectos para el desarrollo humano<\/li><li>Etnograf\u00edas situadas<\/li><li>Pr\u00e1cticas en contextos etnogr\u00e1ficos<\/li><li>Integrador III<\/li><\/ul><p>Semestre IV<\/p><ul><li>Ofim\u00e1tica avanzada<\/li><li>Desarrollo humano<\/li><li>Estudios interculturales<\/li><li>Taller de investigaci\u00f3n antropol\u00f3gica I<\/li><li>Optativo I<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p>III A\u00f1o<\/p><p>Semestre V<\/p><ul><li>Gesti\u00f3n de base de datos culturales I<\/li><li>Econom\u00eda Pol\u00edtica<\/li><li>Estrategia para el an\u00e1lisis de proyectos<\/li><li>Antropolog\u00eda pol\u00edtica<\/li><li>Pr\u00e1cticas en contextos etnogr\u00e1ficos II<\/li><li>Integrador V<\/li><\/ul><p>Semestre VI<\/p><ul><li>Gesti\u00f3n de base de datos culturales II<\/li><li>Dimensi\u00f3n social de la Globalizaci\u00f3n<\/li><li>Antropolog\u00eda innovaci\u00f3n y emprendimiento<\/li><li>Taller de investigaci\u00f3n antropol\u00f3gica II<\/li><li>Optativo II<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p>IV A\u00f1o<\/p><p>Semestre VII<\/p><ul><li>Estad\u00edstica aplicada a las ciencias sociales<\/li><li>Planificaci\u00f3n estrat\u00e9gica de proyectos sociales<\/li><li>Antropolog\u00eda de las instituciones sociales<\/li><li>Metodolog\u00edas interdisciplinarias de investigaci\u00f3n<\/li><li>Optativo III<\/li><li>Integrador VII<\/li><\/ul><p>\u00a0<\/p><p>Semestre VIII<\/p><ul><li>T\u00e9cnicas de organizaci\u00f3n y procesamiento de datos cualitativos<\/li><li>Gesti\u00f3n comunitaria de proyectos sociales I<\/li><li>Etnograf\u00edas multisituadas<\/li><li>Sistematizaci\u00f3n de pr\u00e1cticas comunitarias<\/li><li>Optativo IV<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p>V A\u00f1o<\/p><p>Semestre IX<\/p><ul><li>Divulgaci\u00f3n de producci\u00f3n cient\u00edfica<\/li><li>Gesti\u00f3n comunitaria de proyectos sociales II<\/li><li>Estrategias de comunicaci\u00f3n para la participaci\u00f3n y convivencia<\/li><li>Construcci\u00f3n audiovisual cultural<\/li><li>Optativo V<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>Semestre X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6203\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6203\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6203\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17471\" class=\"elementor elementor-17471\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-407772a2 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"407772a2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-75a2b2ff\" data-id=\"75a2b2ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-231e6dba\" data-id=\"231e6dba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e99c27e elementor-widget elementor-widget-heading\" data-id=\"2e99c27e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ciencia Pol\u00edtica y Relaciones Internacionales\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1694ff5a elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"1694ff5a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53a0c872\" data-id=\"53a0c872\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2672481d elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"2672481d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6451\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6451\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6452\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6452\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6453\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6453\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6451\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6451\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6451\" tabindex=\"0\" hidden=\"false\"><p>La carrera de Ciencia Pol\u00edtica y Relaciones Internacionales tiene por objeto el estudio del sistema pol\u00edtico, la gesti\u00f3n p\u00fablica y las relaciones internacionales.<\/p><p>Para ello el profesional en este campo domina con idoneidad las nociones y herramientas b\u00e1sicas de la disciplina y de disciplinas afines, en el an\u00e1lisis de procesos pol\u00edticos nacionales e internacionales, siendo capaz de explicar e incidir en las coyunturas pol\u00edticas, los procesos de negociaci\u00f3n y aportar al desarrollo de la sociedad.<\/p><p>Su formaci\u00f3n humanista le permite adoptar una conducta \u00e9tica y critica ante los conflictos. Su preparaci\u00f3n profesional le permite desempe\u00f1ar funciones en el \u00e1mbito p\u00fablico y privado, atinentes a la pol\u00edtica y las relaciones internacionales, en instituciones tales como las correspondientes a los poderes del Estado, gobiernos municipales, adem\u00e1s de partidos pol\u00edticos, gremios, sindicatos, medios de comunicaci\u00f3n y ONG\u00b4s.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Poderes del Estado, gobiernos municipales, partidos pol\u00edticos, gremios, sindicatos, universidades, medios de comunicaci\u00f3n y ONG\u00b4s.<\/li><li>Instituciones p\u00fablicas, instituciones privadas de servicio p\u00fablico.<\/li><li>Oficinas de relaciones internacionales de ministerios, Canciller\u00eda, Organismos Internacionales, instituciones p\u00fablicas y privada de competencia internacional radicadas en el pa\u00eds.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Asistencia en materia de pol\u00edtica interna a instituciones p\u00fablicas y privadas, partidos pol\u00edticos, medios de comunicaci\u00f3n y ONG\u00b4s.<\/li><li>Efect\u00faa sondeos de opini\u00f3n y produce conocimientos actualizados referente a la coyuntura pol\u00edtica nacional y regional.<\/li><li>Acompa\u00f1amiento en pol\u00edtica exterior y relaciones pol\u00edticas internacionales.<\/li><li>Produce conocimientos actualizados referente a pol\u00edtica internacional.<\/li><li>Formula programas y estrategias de cooperaci\u00f3n internacional para el desarrollo local y comunitario.<\/li><li>Gestionar acciones y recursos a trav\u00e9s del establecimiento de alianzas estrat\u00e9gicas en cooperaci\u00f3n internacional para el desarrollo.<\/li><li>Asistencia t\u00e9cnica en dise\u00f1o y ejecuci\u00f3n de proyecto cooperaci\u00f3n internacional para el desarrollo.<\/li><li>Gesti\u00f3n de las relaciones y la cooperaci\u00f3n internacional en instituciones de servicio p\u00fablico y privada.<\/li><li>Administraci\u00f3n del servicio p\u00fablico en instituciones p\u00fablicas y privadas.<\/li><li>Elaboraci\u00f3n de diagn\u00f3sticos institucionales para intervenci\u00f3n social.<\/li><li>Desarrolla y conduce el capital humano del \u00e1mbito pol\u00edtico y privado para mejorar la administraci\u00f3n y la pol\u00edtica p\u00fablica.<\/li><li>Formulaci\u00f3n de pol\u00edticas p\u00fablicas.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6452\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6452\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6452\" tabindex=\"0\" hidden=\"hidden\"><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style>\n<table class=\"tftable\" border=\"1\">\n<tbody>\n<tr>\n<td><strong>I A\u00d1O<\/strong>\n\nSEMESTRE I\n<ul>\n \t<li>Lectura y Redacci\u00f3n Sociopol\u00edtica<\/li>\n \t<li>Filosof\u00eda<\/li>\n \t<li>Econom\u00eda y Sociedad<\/li>\n \t<li>Sociolog\u00eda<\/li>\n \t<li>Introducci\u00f3n a la Ciencia Pol\u00edtica<\/li>\n \t<li>Integrador I<\/li>\n<\/ul>\nSEMESTRE II\n<ul>\n \t<li>Historia de las Ideas Pol\u00edticas<\/li>\n \t<li>Teor\u00edas del Desarrollo<\/li>\n \t<li>Metodolog\u00eda de la Investigaci\u00f3n Sociopol\u00edtica<\/li>\n \t<li>Historia Sociopol\u00edtica de Nicaragua<\/li>\n \t<li>Introducci\u00f3n a las Relaciones Internacionales<\/li>\n \t<li>Integrador II<\/li>\n<\/ul>\n<\/td>\n<td><strong>II A\u00d1O<\/strong>\n\nSEMESTRE III\n<ul>\n \t<li>Comunicaci\u00f3n Pol\u00edtica<\/li>\n \t<li>Filosof\u00eda Social\nSociolog\u00eda del Desarrollo<\/li>\n \t<li>M\u00e9todos Estad\u00edsticos Aplicados a las Ciencias Sociales<\/li>\n \t<li>Teor\u00eda de las Relaciones Internacionales<\/li>\n \t<li>Integrador III<\/li>\n<\/ul>\nSEMESTRE IV\n<ul>\n \t<li>An\u00e1lisis del Discurso Pol\u00edtico<\/li>\n \t<li>Estado y Derecho en Nicaragua<\/li>\n \t<li>Pensamiento Pol\u00edtico Latinoamericano<\/li>\n \t<li>Historia del Sistema Pol\u00edtico Internacional<\/li>\n \t<li>Organismos Internacionales\nIntegrador IV<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td><strong>III A\u00d1O<\/strong>\n\nSEMESTRE V\n<ul>\n \t<li>Teor\u00eda y Pr\u00e1ctica de Resoluci\u00f3n de Conflicto<\/li>\n \t<li>Pensamiento Pol\u00edtico Nicarag\u00fcense<\/li>\n \t<li>Gobierno y Gesti\u00f3n P\u00fablica<\/li>\n \t<li>Geopol\u00edtica<\/li>\n \t<li>Optativo I<\/li>\n \t<li>Integrador V<\/li>\n<\/ul>\nSEMESTRE VI\n<ul>\n \t<li>Derecho Internacional P\u00fablico y Privado<\/li>\n \t<li>Cultura Pol\u00edtica Nicarag\u00fcense<\/li>\n \t<li>Pol\u00edticas P\u00fablicas<\/li>\n \t<li>Marketing Pol\u00edtico y Opini\u00f3n P\u00fablica<\/li>\n \t<li>Movimientos Sociales y Pol\u00edticos<\/li>\n \t<li>Integrador VI<\/li>\n<\/ul>\n<\/td>\n<td><strong>IV A\u00d1O<\/strong>\n\nSEMESTRE VII\n<ul>\n \t<li>Gesti\u00f3n de Proyecto de Desarrollo Social<\/li>\n \t<li>Pol\u00edtica Comparada<\/li>\n \t<li>Pol\u00edtica Exterior Nicarag\u00fcense<\/li>\n \t<li>Cooperaci\u00f3n Internacional<\/li>\n \t<li>Optativo II<\/li>\n \t<li>Integrador VII<\/li>\n<\/ul>\nSEMESTRE VIII\n<ul>\n \t<li>Derecho Diplom\u00e1tico y Consular<\/li>\n \t<li>Econom\u00eda Pol\u00edtica Internacional<\/li>\n \t<li>Investigaci\u00f3n aplicada<\/li>\n \t<li>Ceremonial y Protocolo de Estado<\/li>\n \t<li>Optativo III<\/li>\n \t<li>Integrador VIII<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td><strong>V A\u00d1O<\/strong>\n\nSEMESTRE IX\n<ul>\n \t<li>Ingl\u00e9s T\u00e9cnico<\/li>\n \t<li>Optativa IV<\/li>\n \t<li>Integrador IX<\/li>\n<\/ul>\nSEMESTRE X\n<ul>\n \t<li>Modalidad de Graduaci\u00f3n<\/li>\n \t<li>Integrador X<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6453\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6453\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6453\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17474\" class=\"elementor elementor-17474\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1985d1c4 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"1985d1c4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-75fb5bd3\" data-id=\"75fb5bd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-53150d41\" data-id=\"53150d41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f062bc0 elementor-widget elementor-widget-heading\" data-id=\"7f062bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comunicaci\u00f3n para el Desarrollo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42d6cb1e elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"42d6cb1e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73f3daae\" data-id=\"73f3daae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1efb745e elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"1efb745e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5191\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-5191\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5192\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5192\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5193\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5193\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-5191\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5191\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5191\" tabindex=\"0\" hidden=\"false\"><p>La carrera de Comunicaci\u00f3n para el Desarrollo tiene como objeto de estudio la comunicaci\u00f3n social y estrat\u00e9gica. Por consiguiente, el egresado de esta carrera posee una formaci\u00f3n te\u00f3rica y conceptual para el an\u00e1lisis comunicacional de los fen\u00f3menos sociales, adem\u00e1s posee las competencias investigativas y las herramientas profesionales para intervenir de manera cr\u00edtica, \u00e9tica y responsable en distintos \u00e1mbitos del campo de la comunicaci\u00f3n a partir del compromiso con el Modelo Socio-Pol\u00edtico que regula la profesi\u00f3n en el pa\u00eds, as\u00ed como la cultura e identidad nacional.<\/p><ul><li>Capacidad de crear y gestionar productos comunicativos para multiplataformas.<\/li><li>Capacidad de crear y gestionar estrategias de comunicaci\u00f3n aplicables a cualquier tipo de organizaci\u00f3n.<\/li><li>Capacidad de organizar y dirigir medios de comunicaci\u00f3n comunitarios, institucionales y medios masivos.<\/li><\/ul><p>La carrera de Comunicaci\u00f3n para el Desarrollo busca profundizar el avance hacia la calidad educativa, que impacte en la formaci\u00f3n integral y el aprendizaje, aportando soluciones a los desaf\u00edos sociales mediante la investigaci\u00f3n period\u00edstica, la gesti\u00f3n oportuna de la comunicaci\u00f3n en el entorno tecnol\u00f3gico desde el acceso y dominio de conocimientos de la ciencia.<\/p><p>\u00c9sta est\u00e1 sustentada en tres campos de acci\u00f3n: Periodismo, cuyo proceso de ense\u00f1anza-aprendizaje consiste en brindar las t\u00e9cnicas y herramientas para hacer periodismo, tomando en cuenta enfoques sociales recientes como: los derechos humanos, equilibrio ambiental, etc.; Comunicaci\u00f3n estrat\u00e9gica, m\u00e9todos y t\u00e9cnicas de investigaci\u00f3n social y de mercado para dise\u00f1ar planes, estrategias comunicacionales y proyectos de los diferentes actores p\u00fablicos y privados; Comunicaci\u00f3n social, la que enfatiza en un elevado sentido cr\u00edtico, anal\u00edtico e interpretativo de la sociedad a trav\u00e9s de la transmisi\u00f3n de valores, asimismo, basado en los nuevos enfoques de la comunicaci\u00f3n para el cambio social.<\/p><p><strong>Objeto de estudio de la profesi\u00f3n<\/strong><\/p><ul><li>Comunicaci\u00f3n social y estrat\u00e9gica<\/li><\/ul><p><strong>Campos de acci\u00f3n:<\/strong><\/p><ul><li><strong>Periodismo<\/strong><\/li><\/ul><p style=\"padding-left: 40px;\">Brinda las t\u00e9cnicas y herramientas period\u00edsticas para informar debidamente a la poblaci\u00f3n nicarag\u00fcense y mejorar la calidad de vida de las personas mediante la difusi\u00f3n de informaci\u00f3n honesta y objetiva de los hechos a trav\u00e9s de la verdad.<\/p><ul><li><strong>Comunicaci\u00f3n estrat\u00e9gica<\/strong><\/li><\/ul><p style=\"padding-left: 40px;\">Permite planificar, desarrollar y controlar la informaci\u00f3n por medio de herramientas comunicacionales para establecer, mantener y fortalecer relaciones positivas entre las instituciones o personas con el fin de conseguir objetivos tangibles e intangibles para las mismas.<\/p><ul><li><strong>Comunicaci\u00f3n social<\/strong><\/li><\/ul><p style=\"padding-left: 40px;\">Permite analizar, enfatizar e interpretar empleando m\u00e9todos, t\u00e9cnicas y estrategias de investigaci\u00f3n e intervenci\u00f3n social para formar reforzar y transmitir valores, basado en los nuevos enfoques de la comunicaci\u00f3n para el cambio social.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5192\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5192\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5192\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comunicaci\u00f3n Ling\u00fc\u00edstica<\/li><li>Introducci\u00f3n a la Literatura<\/li><li>Ofim\u00e1tica Aplicada a la Comunicaci\u00f3n<\/li><li>Teor\u00edas Cl\u00e1sicas de la Comunicaci\u00f3n<\/li><li>\u00c9tica y Deontolog\u00eda de la Comunicaci\u00f3n<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>T\u00e9cnicas de Redacci\u00f3n<\/li><li>Literatura Latinoamericana y Caribe\u00f1a<\/li><li>Teor\u00edas de la Comunicaci\u00f3n para el Desarrollo<\/li><li>Comunicaci\u00f3n, Sociedad y Cultura<\/li><li>Globalizaci\u00f3n y Comunicaci\u00f3n Ambiental<\/li><li>Integrador I<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Geopol\u00edtica y Comunicaci\u00f3n<\/li><li>Introducci\u00f3n a la Investigaci\u00f3n en Comunicaci\u00f3n<\/li><li>Comunicaci\u00f3n Comunitaria y Alternativa<\/li><li>Redacci\u00f3n Period\u00edstica y Prensa Escrita<\/li><li>Rutinas Productivas en los Medios de Comunicaci\u00f3n<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Fundamentos de la Comunicaci\u00f3n Gr\u00e1fica<\/li><li>Comunicaci\u00f3n Interpersonal<\/li><li>Periodismo Informativo y Cr\u00edtico<\/li><li>Integrador IV<\/li><li>Optativo I<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Producci\u00f3n Audiovisual I<\/li><li>Comunicaci\u00f3n y Desarrollo Sostenible<\/li><li>Producci\u00f3n Radiof\u00f3nica<\/li><li>Integrador V<\/li><li>Optativo II<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Producci\u00f3n Audiovisual II<\/li><li>Comunicaci\u00f3n y Pol\u00edticas P\u00fablicas<\/li><li>Producci\u00f3n Televisiva<\/li><li>Comunicaci\u00f3n Publicitaria y<\/li><li>Mercadeo Social<\/li><li>Integrador VI<\/li><li>Optativo III<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Herramientas Inform\u00e1ticas para la<\/li><li>Investigaci\u00f3n en Comunicaci\u00f3n<\/li><li>Formulaci\u00f3n y Evaluaci\u00f3n de<\/li><li>Proyectos Comunicacionales<\/li><li>Relaciones P\u00fablicas<\/li><li>Integrador VII<\/li><li>Optativo IV<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Cibermedios<\/li><li>Comunicaci\u00f3n Digital e Interactiva<\/li><li>M\u00e9todos y T\u00e9cnicas de Investigaci\u00f3n en Comunicaci\u00f3n<\/li><li>Integrador VIII<\/li><li>Optativo V<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Integrador IX<\/li><li>Direcci\u00f3n y Gesti\u00f3n de la<\/li><li>Comunicaci\u00f3n Organizacional<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Integrador X<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5193\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5193\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5193\" tabindex=\"0\" hidden=\"hidden\"><ul><li>CUR-Estel\u00ed<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17477\" class=\"elementor elementor-17477\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-757f4a50 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"757f4a50\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-140c89a7\" data-id=\"140c89a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-681976b9\" data-id=\"681976b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5855609b elementor-widget elementor-widget-heading\" data-id=\"5855609b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Derecho<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6acef0d7 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"6acef0d7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68baab04\" data-id=\"68baab04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ee5c096 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"6ee5c096\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1861\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1861\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1862\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1862\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1863\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1863\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1861\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1861\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1861\" tabindex=\"0\" hidden=\"false\"><p>Ejercicio de la Abogac\u00eda y Notariado<\/p><p><strong>\u00c1mbito de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>Instituciones P\u00fablicas, Despachos Jur\u00eddicos, Empresas Privadas, ONG, Campos de Investigaci\u00f3n<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><p>Tutela como operador Jur\u00eddicos los Derechos de las Personas Naturales y Jur\u00eddicas, Asesora, Acompa\u00f1a, Asiste, Representa a las partes en procedimientos administrativos y procesos judiciales, promueve los M\u00e9todos Alternos de Soluci\u00f3n de Conflictos, Redacta documentos escritos, Realiza Investigaciones Jur\u00eddicas.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1862\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1862\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1862\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Introducci\u00f3n al Estudio del Derecho<\/li><li>Historia del Derecho y del Estado<\/li><li>Derecho Romano<\/li><li>Teor\u00eda General del Estado<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Derecho de Familia<\/li><li>T\u00e9cnicas de Investigaci\u00f3n Jur\u00eddica<\/li><li>Teor\u00eda General del Derecho Procesal<\/li><li>Derecho Constitucional I<\/li><li>Derecho Penal I<\/li><li>Integrador I<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Derecho Constitucional II<\/li><li>Derecho Procesal de Familia<\/li><li>Derecho Penal II<\/li><li>Derecho de Bienes<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Derecho Laboral<\/li><li>Derecho de las Obligaciones<\/li><li>Derecho Internacional P\u00fablico<\/li><li>Derecho Procesal Penal I<\/li><li>G\u00e9nero y Poder<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Derecho de la Seguridad Social<\/li><li>Derecho Procesal Penal II<\/li><li>Derecho de los Contratos<\/li><li>Derecho Procesal Civil I<\/li><li>Derecho Internacional Privado<\/li><li>Derecho Administrativo I<\/li><li>Optativo I<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Derecho Procesal Civil II<\/li><li>Medicina Legal<\/li><li>Derecho Administrativo II<\/li><li>Derecho Procesal Laboral y de la Seguridad Social<\/li><li>Derecho de Sucesiones<\/li><li>Derecho Mercantil I<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VI<\/p><ul><li>Derecho Mercantil II<\/li><li>Derecho Notarial I<\/li><li>Derecho Tributario<\/li><li>Derecho Procesal Civil III<\/li><li>Derecho Ambiental<\/li><li>Optativo II<\/li><li>Integrador VII<\/li><\/ul><p><span style=\"font-family: inherit; font-size: inherit;\">SEMESTRE VIII<\/span><\/p><ul><li>Pr\u00e1ctica Procesal Civil<\/li><li>T\u00e9cnicas de Oralidad y Litigaci\u00f3n<\/li><li>Derecho Notarial II<\/li><li>Derecho Bancario<\/li><li>Filosof\u00eda del Derecho<\/li><li>M\u00e9todos Alternos de Resoluci\u00f3n de Conflictos<\/li><li>Optativo III<\/li><li>Optativo IV<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Pr\u00e1ctica Notarial<\/li><li>Investigaci\u00f3n aplicada<\/li><li>Derecho Registral<\/li><li>Derecho Comunitario<\/li><li>Optativo V<\/li><li>Integrador IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Deontolog\u00eda Jur\u00eddica<br \/>Derecho de la Propiedad Intelectual<\/li><li>Modalidad de Graduaci\u00f3n<\/li><li>Integrador X<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1863\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1863\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1863\" tabindex=\"0\" hidden=\"hidden\"><ul><li>CUR-Estel\u00ed<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17480\" class=\"elementor elementor-17480\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43e809de elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"43e809de\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7df1c65d\" data-id=\"7df1c65d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-511309c0\" data-id=\"511309c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51d35022 elementor-widget elementor-widget-heading\" data-id=\"51d35022\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Geograf\u00eda<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37150391 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"37150391\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ddfcd40\" data-id=\"6ddfcd40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70010d7 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"70010d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1171\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1171\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1172\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1172\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1173\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1173\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1171\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1171\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1171\" tabindex=\"0\" hidden=\"false\"><p>El profesional de la Geograf\u00eda domina y aplica modelos, m\u00e9todos, t\u00e9cnicas y procesos cient\u00edficos basados en la estad\u00edstica, las ciencias naturales, sociales y los Sistemas de Informaci\u00f3n Geogr\u00e1fica para la resoluci\u00f3n de problemas socioecon\u00f3micos y conflictos ambientales que respondan al Plan Nacional de Desarrollo Humano. Su cultura humanista le permite analizar la realidad con sentido \u00e9tico y cr\u00edtico, situando al ser humano como centro de toda reflexi\u00f3n y acci\u00f3n. Por su formaci\u00f3n en Geograf\u00eda, puede desarrollarse profesionalmente en instituciones p\u00fablicas y privadas vinculadas al an\u00e1lisis territorial a nivel nacional.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Instituciones p\u00fablicas y privadas vinculadas al an\u00e1lisis territorial<\/li><li>Consultor\u00edas p\u00fablicas y privadas vinculadas al an\u00e1lisis territorial<\/li><\/ul><p><strong>Competencias (generales y espec\u00edficas) Competencias Generales<\/strong><\/p><ul><li>Se comunica de manera oral y escrita en diferentes contextos de actuaci\u00f3n.<\/li><li>Resuelve problemas de manera individual y en equipos, en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n.<\/li><li>Demuestra creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional donde se desempe\u00f1a. Utiliza las TIC como apoyo para mejorar el aprendizaje de en diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional.<\/li><li>Comprende la realidad socio-econ\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Georreferencia, crea y administra base de datos geogr\u00e1ficos.<\/li><li>\u00a0Elabora cartograf\u00eda digital y mapas tem\u00e1ticos.<\/li><li>Elabora diagn\u00f3sticos socio ambiental a nivel territorial.<\/li><li>Realiza an\u00e1lisis espacial utilizando los Sistemas de Informaci\u00f3n Geogr\u00e1fica.<\/li><li>Crea, organiza y aplica planes de capacitaci\u00f3n ambiental y uso de herramientas geogr\u00e1ficas.<\/li><li>Interpreta im\u00e1genes satelitales para la planificaci\u00f3n territorial.<\/li><li>Formula y gestiona proyectos sociales y ambientales.<\/li><li>Realiza procesamiento y an\u00e1lisis estad\u00edstico de datos geogr\u00e1ficos.<\/li><li>Elabora protocolo e informe t\u00e9cnico e investigativo de car\u00e1cter geogr\u00e1fico.<\/li><li>Monitorea variables socioambientales con Sistema de Informaci\u00f3n Geogr\u00e1fica.<\/li><li>Elabora planes para el ordenamiento territorial.<\/li><li>Realiza zonificaci\u00f3n tur\u00edstica para proyectos de desarrollo territorial.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1172\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1172\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1172\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Matem\u00e1tica General<\/li><li>Introducci\u00f3n a la Geograf\u00eda<\/li><li>Fundamentos de Computaci\u00f3n<\/li><li>Comunicaci\u00f3n Oral y Escrita<\/li><li>Geolog\u00eda<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Introducci\u00f3n a la Qu\u00edmica<\/li><li>Introducci\u00f3n a la Estad\u00edstica<\/li><li>Geomorfolog\u00eda<\/li><li>Laboratorio de Introducci\u00f3n al An\u00e1lisis Espacial<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n Geogr\u00e1fica I<\/li><li>Integrador II<\/li><li>Demograf\u00eda<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>An\u00e1lisis Qu\u00edmico<\/li><li>Ambiental I<\/li><li>Estad\u00edstica Aplicada a la Geograf\u00eda<\/li><li>Edafolog\u00eda<\/li><li>Geograf\u00eda de la Poblaci\u00f3n<\/li><li>Sistemas de Informaci\u00f3n Geogr\u00e1ficas Aplicada I<br \/>Metodolog\u00eda de la Investigaci\u00f3n Geogr\u00e1fica II<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Introducci\u00f3n a la F\u00edsica<\/li><li>An\u00e1lisis Qu\u00edmico Ambiental II<\/li><li>Edafolog\u00eda Aplicada<\/li><li>Geograf\u00eda Econ\u00f3mica<\/li><li>Sistemas de Informaci\u00f3n Geogr\u00e1ficas Aplicada II<\/li><li>M\u00e9todos para la Evaluaci\u00f3n de los Recursos Naturales<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Topograf\u00eda<\/li><li>Ecolog\u00eda del Paisaje<\/li><li>Geograf\u00eda de los Servicios<\/li><li>Sistemas de Informaci\u00f3n Geogr\u00e1ficas<\/li><li>Diagnostico Territorial<\/li><li>Planificaci\u00f3n Territorial con enfoque de Paisaje<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Hidrolog\u00eda Aplicada I<\/li><li>Geograf\u00eda del Transporte<\/li><li>Modelos de An\u00e1lisis Espacial I<\/li><li>Optativo I<\/li><li>Planificaci\u00f3n Territorial con enfoque de cuenca hidrogr\u00e1fica<\/li><li>Integrador VI<\/li><li>Meteorolog\u00eda<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Geof\u00edsica<\/li><li>Hidrolog\u00eda Aplicada II<\/li><li>Geograf\u00eda Urbana<\/li><li>Modelos de An\u00e1lisis Espacial II<\/li><li>Optativo II<\/li><li>Planificaci\u00f3n Urbana<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Optativo III<\/li><li>Geograf\u00eda Rural<\/li><li>Modelos de An\u00e1lisis Espacial III<\/li><li>Formulaci\u00f3n de Proyectos<\/li><li>Planificaci\u00f3n Rural<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo IV<\/li><li>Optativo V<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><li>Ordenamiento Territorial<\/li><li>Integrador IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><li>Integrador X<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1173\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1173\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1173\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17483\" class=\"elementor elementor-17483\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-634c7cf7 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"634c7cf7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-32388783\" data-id=\"32388783\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f564d87\" data-id=\"f564d87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a445ca1 elementor-widget elementor-widget-heading\" data-id=\"6a445ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gesti\u00f3n de la Informaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8207ba elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"8207ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10b37697\" data-id=\"10b37697\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6336ca21 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"6336ca21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1661\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1661\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1662\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1662\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1663\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1663\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1661\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1661\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1661\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de Gesti\u00f3n de la Informaci\u00f3n es la administraci\u00f3n e investigaci\u00f3n de la informaci\u00f3n. Por ello el profesional de esta carrera administra de forma integral el trabajo de unidades de informaci\u00f3n, promociona los servicios, capacita a usuarios sobre el acceso y uso de la informaci\u00f3n; y sistematiza las diferentes fuentes de informaci\u00f3n para la investigaci\u00f3n y la gesti\u00f3n del conocimiento.<\/p><p>Por su formaci\u00f3n es capaz de organizar de forma integral el trabajo de las unidades de informaci\u00f3n, de conformidad con los est\u00e1ndares de calidad, asimismo, elabora pol\u00edticas, normas y procedimientos para garantizar los servicios y desarrollo de las unidades de informaci\u00f3n a trav\u00e9s de estrategias de marketing. Tambi\u00e9n contribuye en el desarrollo de habilidades y destrezas de usuarios en el acceso y uso de la informaci\u00f3n haciendo uso de la tecnolog\u00eda; y sistematiza fuentes de informaci\u00f3n para aportar a la gesti\u00f3n del conocimiento.<\/p><p>El graduado de Gesti\u00f3n de la Informaci\u00f3n en el ejercicio de su profesi\u00f3n est\u00e1 llamado a garantizar el uso responsable de la informaci\u00f3n de manera transparente y con sentido \u00e9tico apegado al marco jur\u00eddico en la administraci\u00f3n de los diferentes procesos que se desarrollan en las unidades de informaci\u00f3n.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Unidades de Informaci\u00f3n p\u00fablicas y privadas en todos los niveles educativos y administrativos.<\/li><li>Bibliotecas, centros de Documentaci\u00f3n, centros de investigaci\u00f3n especializados, museos, centros de difusi\u00f3n, editoriales, Centros culturales, Archivos, ONG`s, medios de comunicaci\u00f3n<\/li><li>Unidades de Informaci\u00f3n p\u00fablicas y privadas en todos los niveles educativos y administrativos.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Organiza de forma integral el trabajo de las unidades de informaci\u00f3n, de conformidad con los est\u00e1ndares de calidad.<\/li><li>Selecciona sistemas inform\u00e1ticos para la gesti\u00f3n de la informaci\u00f3n en todos sus aspectos.<\/li><li>Elabora pol\u00edticas para el desarrollo de las unidades de informaci\u00f3n.<\/li><li>Aplica normas y procedimientos de preservaci\u00f3n y restauraci\u00f3n de documentos bibliogr\u00e1ficos, hemerogr\u00e1ficos y de archivos.<\/li><li>Elaboraci\u00f3n y ejecuci\u00f3n de pol\u00edticas, normativas, manuales y procedimientos.<\/li><li>Elabora l\u00edneas estrat\u00e9gicas de marketing en las unidades de informaci\u00f3n.<\/li><li>Garantiza servicios de informaci\u00f3n que demandan los usuarios.<\/li><li>Capacita en el proceso de aprendizaje del uso de herramientas tecnol\u00f3gicas y de informaci\u00f3n.<\/li><li>Desarrolla habilidades y destrezas para el acceso y uso de la informaci\u00f3n (Alfabetizaci\u00f3n informacional)<\/li><li>Organiza fuentes de informaci\u00f3n para la investigaci\u00f3n.<\/li><li>Sistematiza fuentes de informaci\u00f3n para la investigaci\u00f3n<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1662\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1662\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1662\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Estrategias de difusi\u00f3n de la informaci\u00f3n<\/li><li>Comunicaci\u00f3n oral y escrita I<\/li><li>Introducci\u00f3n a la inform\u00e1tica<\/li><li>Gesti\u00f3n y administraci\u00f3n de la informaci\u00f3n<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Seminario de la Historia<\/li><li>Contempor\u00e1nea de Nicaragua<\/li><li>Comunicaci\u00f3n oral y escrita II<\/li><li>Sistemas de informaci\u00f3n y b\u00fasqueda del conocimiento<\/li><li>Fundamentos te\u00f3ricos de Unidades de Informaci\u00f3n<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>T\u00e9cnicas de lectura y redacci\u00f3n<\/li><li>Herramientas y redes en la gesti\u00f3n de la informaci\u00f3n I<\/li><li>Archiv\u00edstica I<\/li><li>Administraci\u00f3n de Unidades de Informaci\u00f3n<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Metodolog\u00eda de la investigaci\u00f3n<\/li><li>Herramientas y redes en la gesti\u00f3n de la informaci\u00f3n II<\/li><li>Archiv\u00edstica II<\/li><li>Almacenamiento y recuperaci\u00f3n de la informaci\u00f3n I<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Marketing para unidades de informaci\u00f3n I<\/li><li>Almacenamiento y recuperaci\u00f3n de la informaci\u00f3n II<\/li><li>Desarrollo de colecciones<\/li><li>Optativo I<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Marketing para unidades de informaci\u00f3n II<\/li><li>Almacenamiento y recuperaci\u00f3n de la informaci\u00f3n III<\/li><li>\u00c9tica y sistemas de informaci\u00f3n<\/li><li>Optativo II<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Estudios m\u00e9tricos de la informaci\u00f3n I<\/li><li>Paleograf\u00eda<\/li><li>Control de calidad en Unidades de Informaci\u00f3n<\/li><li>Automatizaci\u00f3n y preservaci\u00f3n de la informaci\u00f3n<\/li><li>Optativo III<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Estudios m\u00e9tricos de la informaci\u00f3n II<\/li><li>Normas, pol\u00edticas y est\u00e1ndares en Unidades de informaci\u00f3n<\/li><li>Formulaci\u00f3n y evaluaci\u00f3n de proyectos<\/li><li>Servicios en l\u00ednea para Unidades de Informaci\u00f3n<\/li><li>Optativo IV<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Pol\u00edticas de desarrollo de Unidades de Informaci\u00f3n<\/li><li>Preservaci\u00f3n y conservaci\u00f3n de la informaci\u00f3n<\/li><li>Sistema interno de aseguramiento de la calidad en Unidades de Informaci\u00f3n<\/li><li>Indicadores de gesti\u00f3n para Unidades de Informaci\u00f3n<\/li><li>Optativo V<\/li><li>Integrador IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Integrador X<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1663\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1663\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1663\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17486\" class=\"elementor elementor-17486\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ef736d2 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"2ef736d2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5632cd05\" data-id=\"5632cd05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-253d102e\" data-id=\"253d102e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3fe77b elementor-widget elementor-widget-heading\" data-id=\"d3fe77b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Historia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a544a38 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"5a544a38\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43ef853b\" data-id=\"43ef853b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-135d9a81 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"135d9a81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3241\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3241\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3242\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3242\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-3243\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3243\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-3241\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3241\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3241\" tabindex=\"0\" hidden=\"false\"><p>La Historia es la Ciencia del ser humano en todas sus dimensiones destinada a explicar procesos y comportamientos colectivos. Su objeto de estudio, son las sociedades humanas del pasado en relaci\u00f3n con el presente, considerando las tendencias futuras.<\/p><p>El licenciado en Historia, por su formaci\u00f3n, es capaz de analizar procesos hist\u00f3ricos a trav\u00e9s de la investigaci\u00f3n cient\u00edfica en los \u00e1mbitos pol\u00edtico, social, econ\u00f3mico, cultural y testimonial, de cara a la comprensi\u00f3n integral de la realidad nacional e internacional. Difundir el conocimiento integral de la ciencia hist\u00f3rica, generando sentimientos de pertenencia, identidad, solidaridad y compromiso social y rescatar el patrimonio hist\u00f3rico y cultural local, regional y nacional, a partir de la ejecuci\u00f3n de jornadas de sensibilizaci\u00f3n, en funci\u00f3n de la preservaci\u00f3n, conservaci\u00f3n y an\u00e1lisis.<\/p><p>El graduado de esta carrera, en el ejercicio de su profesi\u00f3n, est\u00e1 llamado a comprender y explicar los procesos y hechos acaecidos en el pasado en Nicaragua, Centroam\u00e9rica y el mundo. Indaga y busca respuestas, a partir de las inquietudes presentes, con vocaci\u00f3n para promover los cambios sociales y contribuir al desarrollo sostenible, equitativo e incluyente.<\/p><p>El conocimiento hist\u00f3rico proporciona las respuestas fundamentales que a diario los seres humanos se plantean, su origen, presente y futuro. Ayuda a tomar conciencia de sus propios valores y a fundamentar sus relaciones sociales, su pr\u00e1ctica a lo largo de la vida, es vital para la construcci\u00f3n de una nueva y mejor sociedad.<\/p><p>El estudio del pasado a partir del an\u00e1lisis de procesos hist\u00f3ricos y el protagonismo de sus actores, entra en conexi\u00f3n con la vida presente y se convierte en una v\u00eda para la identidad nacional, necesaria para rescatar los valores nacionales.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Centros de investigaci\u00f3n.<\/li><li>Instituciones educativas y culturales.<\/li><li>Alcald\u00edas.<\/li><li>Archivos, unidades de informaci\u00f3n y sitios hist\u00f3ricos.<\/li><li>Museos.<\/li><li>Editoriales<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Analiza procesos hist\u00f3ricos a trav\u00e9s de la investigaci\u00f3n cient\u00edfica en los \u00e1mbitos pol\u00edtico, social, econ\u00f3mico, cultural y testimonial.<\/li><li>Difunde el conocimiento hist\u00f3rico en distintos formatos y espacios p\u00fablicos y privados, contribuyendo al desarrollo de la Ciencia y aportando a la soluci\u00f3n de problemas en sus distintos \u00e1mbitos.<\/li><li>Rescata la memoria colectiva y el patrimonio hist\u00f3rico y cultural, en funci\u00f3n de su preservaci\u00f3n, conservaci\u00f3n e identidad nacional, regional y local.<\/li><li>Brinda capacitaciones sobre temas de su competencia en instituciones p\u00fablicas y privadas.<\/li><li>Analiza, organiza y difunde documentos hist\u00f3ricos<br \/>en sus distintas tipolog\u00edas.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3242\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3242\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3242\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Geograf\u00eda Hist\u00f3rica<br \/>Historia y Comunicaci\u00f3n Social<\/li><li>Fundamentos cient\u00edficos de la Ciencia Hist\u00f3rica<\/li><li>Bases del Pensamiento Filos\u00f3fico<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Nuevas Tecnolog\u00edas y Herramientas para el quehacer hist\u00f3rico<\/li><li>Ciencia y Comunicaci\u00f3n Cient\u00edfica<\/li><li>Civilizaciones Antiguas: Europa, Asia y \u00c1frica<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Psicolog\u00eda Social Aplicada a la Historia<\/li><li>Espacio y Sociedades Antiguas de Nicaragua<\/li><li>Memoria, Patrimonio y Comunicaci\u00f3n<\/li><li>Sociedades Medievales<br \/>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>M\u00e9todos Cuantitativos Aplicados a la Historia<\/li><li>Sociedades Originarias de Am\u00e9rica y el Caribe<\/li><li>Investigaci\u00f3n Hist\u00f3rica I<\/li><li>Paleograf\u00eda y Diplom\u00e1tica<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Espacio y Dominio Colonial en Nicaragua<\/li><li>Sociedades Modernas<\/li><li>Investigaci\u00f3n Hist\u00f3rica II<\/li><li>Optativo I<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Am\u00e9rica Colonial<\/li><li>Introducci\u00f3n a la Filosof\u00eda de la Historia<\/li><li>Taller de Investigaci\u00f3n Hist\u00f3rica<\/li><li>Optativo II<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Estado y Territorio de Nicaragua en el siglo<\/li><li>Tendencias de la Historia I<\/li><li>Optativo III<\/li><li>Integrador VII<\/li><li>El Mundo en el Siglo XI<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Psicolog\u00eda Social y Comportamiento Humano<\/li><li>Seminario del Discurso en la Ciencia Hist\u00f3rica<\/li><li>Am\u00e9rica en el siglo XIX<br \/>Tendencias de la Historia II<\/li><li>Optativo IV<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>El Quehacer Hist\u00f3rico en los Entornos Virtuales.<\/li><li>Seminario de Historia de Centroam\u00e9rica y Nicaragua. Siglos XX y XXI<\/li><li>Europa, Asia y \u00c1frica: Siglos XX y XXI<\/li><li>Problem\u00e1tica Latinoamericana y Caribe\u00f1a. Siglos XX y XXI<\/li><li>Optativo V<\/li><li>Integrador IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Integrador X<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-3243\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3243\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-3243\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17489\" class=\"elementor elementor-17489\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bbf8903 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"2bbf8903\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1f9af9ed\" data-id=\"1f9af9ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79f86ca7\" data-id=\"79f86ca7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ede7cd4 elementor-widget elementor-widget-heading\" data-id=\"5ede7cd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Psicolog\u00eda <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae83912 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"ae83912\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a669804\" data-id=\"2a669804\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51097163 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"51097163\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1351\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1351\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1352\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1352\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1353\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1353\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1351\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1351\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1351\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la Carrera de Psicolog\u00eda es formar profesionales capaces de potencializar la salud mental de la persona y\/o restablecer la misma en funci\u00f3n del desarrollo propio, humano y social, es decir, la Psicolog\u00eda es una profesi\u00f3n cuyo ejercicio compromete el inter\u00e9s p\u00fablico. Por tanto, se garantiza una s\u00f3lida formaci\u00f3n acad\u00e9mica general (contenidos b\u00e1sicos del curr\u00edculo, con amplia visi\u00f3n disciplinaria, integrando la diversidad de temas y problemas psicol\u00f3gicos), de manera particular certifica un compromiso humanista y \u00e9tico.<\/p><p>En este sentido, se necesita formar psic\u00f3logos (as) conscientes de su propia identidad, comprometidos con el saber, el sentir y los cambios de s\u00ed mismo y su entorno. Lo anterior exige, que el profesional de la Psicolog\u00eda tenga equilibrio emocional, conciencia social y sea capaz de respetar la diversidad individual, biopsicosocial, cultural y jur\u00eddica. Asimismo, que muestre habilidades en observaci\u00f3n cient\u00edfica, escucha emp\u00e1tica y comprensiva.<\/p><p>La formaci\u00f3n de \u00e9l y la estudiante de Psicolog\u00eda, estar\u00e1 constituida por los siguientes campos de acci\u00f3n: Cl\u00ednica, Jur\u00eddica, Social-comunitaria, Educativa y Gesti\u00f3n del talento humano. De modo que, los graduados mediante este plan de estudio se podr\u00e1n desempe\u00f1ar competentemente en cualquiera de estos campos, manifestando capacidad de organizaci\u00f3n, planificaci\u00f3n, toma de decisiones y habilidad para trabajar en equipos. Propiciando en todo momento la investigaci\u00f3n, elaboraci\u00f3n de evaluaciones psicol\u00f3gicas con \u00e9tica y profesionalismo, an\u00e1lisis de contenido, uso correcto de la ortograf\u00eda, redacci\u00f3n y escritura para la emisi\u00f3n de informes psicol\u00f3gicos. Adem\u00e1s, el profesional en Psicolog\u00eda debe lograr una visi\u00f3n actualizada de los alcances de la ciencia, para la comprensi\u00f3n hol\u00edstica del ser humano, de cara a la resoluci\u00f3n de conflictos, con innovaci\u00f3n y creatividad.<\/p><p>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/p><ul><li>\u00c1reas de salud p\u00fablica y privadas.<\/li><li>Centros de estudio p\u00fablicos y privados.<\/li><li>\u00c1reas educativas en ONG<\/li><li>Empresas p\u00fablicas y privadas.<\/li><li>\u00c1reas policial-criminol\u00f3gico, judicial, administrativo y legislativo<br \/>Comunidades.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>\u00c1reas de salud p\u00fablica y privadas<\/li><li>Realiza evaluaci\u00f3n Psicol\u00f3gicas.<\/li><li>Dise\u00f1a planes de intervenci\u00f3n psicoterap\u00e9utica.<\/li><li>Ejecuta y da seguimiento al plan de intervenci\u00f3n psicoterap\u00e9utico.<\/li><li>Acompa\u00f1a interconsulta Psiqui\u00e1trica.<\/li><li>Centros de estudio p\u00fablicos y privados, \u00c1reas educativas en ONG<\/li><li>Realiza evaluaci\u00f3n psicoeducativa.<\/li><li>Elabora planes de intervenci\u00f3n psicoeducativo.<\/li><li>Ejecuta y da seguimiento a planes de intervenci\u00f3n.<\/li><li>Asesora u orienta al estudiantado, direcci\u00f3n, maestros y padres de familia.<\/li><li>Brinda orientaci\u00f3n psicol\u00f3gica, vocacional y profesional.<\/li><li>Realiza propuesta de planes preventives y correctivos.<\/li><li>Empresas p\u00fablicas y privadas.<\/li><li>Analiza puestos.<\/li><li>Recluta, selecciona y lleva a cabo inducci\u00f3n al personal.<\/li><li>Realiza evaluaci\u00f3n al desempe\u00f1o.<\/li><li>Interviene en la cultura y clima organizacional.<\/li><li>Elabora planes de motivaci\u00f3n y satisfacci\u00f3n laboral.<\/li><li>Interviene en el proceso de higiene y seguridad ocupacional.<\/li><li>Interviene en los procesos de estr\u00e9s laboral.<\/li><li>\u00c1reas policial-criminol\u00f3gico, judicial, administrativo y legislativo<\/li><li>Elabora perfiles criminol\u00f3gicos, peligrosidad y victimol\u00f3gicos.<\/li><li>Dise\u00f1a planes de prevenci\u00f3n e intervenci\u00f3n psico-criminol\u00f3gicos.<\/li><li>Dise\u00f1a planes de intervenci\u00f3n psicopenitenciarios: adaptaci\u00f3n, rehabilitaci\u00f3n, reinserci\u00f3n social y prevenci\u00f3n de reincidencia delictiva.<\/li><li>Dise\u00f1a planes de intervenci\u00f3n psicojur\u00eddica.<\/li><li>Realiza peritaciones psicol\u00f3gicas.<\/li><li>Realiza evaluaciones psicol\u00f3gicas forenses.<\/li><li>Brinda asesor\u00edas psicocriminol\u00f3gicas.<\/li><li>Brinda asesor\u00edas psicopenitenciarias.<\/li><li>Brinda asesor\u00edas psicojur\u00eddicas.<\/li><li>Comunidades.<\/li><li>Dise\u00f1a planes de intervenci\u00f3n comunitario.<\/li><li>Contribuye a desarrollar procesos de liderazgos.<\/li><li>Contribuye a desarrollar procesos organizativos-comunitarios.<\/li><li>Dise\u00f1a proyectos de desarrollo socio \u2013 comunitario.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1352\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1352\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1352\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Bases filos\u00f3ficas de la Psicolog\u00eda<\/li><li>Base anat\u00f3mica de la Psicolog\u00eda<\/li><li>Comunicaci\u00f3n aplicada a la Psicolog\u00eda<\/li><li>Psicolog\u00eda Social<\/li><li>Taller de crecimiento personal<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Bases Fisiol\u00f3gica de la Psicolog\u00eda<\/li><li>Introducci\u00f3n a la Investigaci\u00f3n Psicol\u00f3gica<\/li><li>Psicolog\u00eda General<\/li><li>Psicolog\u00eda Socio comunitaria<\/li><li>M\u00e9todos y t\u00e9cnicas de la Psicolog\u00eda Cl\u00ednica<\/li><li>Integrador I<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Psicoestadistica<\/li><li>Historia de la Psicolog\u00eda<\/li><li>Psicolog\u00eda de la Personalidad I<\/li><li>Psicolog\u00eda de los Grupos<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Metodolog\u00eda de la Investigaci\u00f3n Psicol\u00f3gica<\/li><li>Intervenci\u00f3n Psicosocio comunitaria<\/li><li>Gesti\u00f3n del Talento Humano<\/li><li>Psicolog\u00eda Educativa<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Optativo I<\/li><li>Psicolog\u00eda Evolutiva II<\/li><li>Psicolog\u00eda Aplicada a la gesti\u00f3n del talento Humano.<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>Evaluaci\u00f3n psicol\u00f3gica Infantil<\/li><li>Psicopatolog\u00eda del ni\u00f1o y del adolescente<br \/>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Optativo II<\/li><li>Psicolog\u00eda del Neurodesarrollo<\/li><li>Din\u00e1mica administrativa del talento Humano<\/li><li>Orientaci\u00f3n Psicol\u00f3gica<\/li><li>Evaluaci\u00f3n Psicol\u00f3gica en la adolescencia<\/li><li>Psicopatolog\u00eda del Adulto<\/li><li>Integrador IV<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo III<\/li><li>Investigaci\u00f3n cuantitativa en la Psicolog\u00eda<\/li><li>Psicolog\u00eda Jur\u00eddica I<\/li><li>Proyecto Psicosociales<\/li><li>Intervenci\u00f3n Psicopedag\u00f3gica<\/li><li>Evaluaci\u00f3n psicol\u00f3gica en la Adultez<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Optativo IV<\/li><li>Trastornos neurodegenerativos y evaluaci\u00f3n cognitiva en adultos mayores<\/li><li>Investigaci\u00f3n cualitativa en la Psicolog\u00eda<\/li><li>Psicolog\u00eda Jur\u00eddica II<\/li><li>Psicoterapia I<\/li><li>Intervenci\u00f3n en situaciones de emergencia<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo V<\/li><li>Intervenci\u00f3n y tratamiento en trastornos generalizados del desarrollo.<\/li><li>Investigaci\u00f3n Psicol\u00f3gica aplicada<\/li><li>Diagn\u00f3stico psicol\u00f3gico forense<\/li><li>Psicoterapia II<\/li><li>Integrador IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Integrador X<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1353\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1353\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1353\" tabindex=\"0\" hidden=\"hidden\"><ul><li>CUR-Carazo<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17492\" class=\"elementor elementor-17492\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cf5788a elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"6cf5788a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-143af55a\" data-id=\"143af55a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e34a510\" data-id=\"4e34a510\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27078fbb elementor-widget elementor-widget-heading\" data-id=\"27078fbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trabajo Social\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-163f8303 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"163f8303\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a5ce4a3\" data-id=\"1a5ce4a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-205d5bb2 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"205d5bb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5421\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-5421\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5422\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5422\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5423\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5423\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-5421\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5421\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5421\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de Trabajo Social es la intervenci\u00f3n social con individuos, grupos y comunidad. Por lo cual, el profesional del Trabajo Social domina la investigaci\u00f3n diagn\u00f3stica participativa, el dise\u00f1o de planes y proyectos de intervenci\u00f3n, Habilidad de promover la participaci\u00f3n social y sistematizaci\u00f3n de la pr\u00e1ctica social. Su formaci\u00f3n human\u00edstica y comprometida con los sujetos sociales y su entorno, le permite desarrollar la intervenci\u00f3n con actitud cr\u00edtica y \u00e9tica para la promoci\u00f3n del desarrollo humano y social sustentable.<\/p><p>Con la formaci\u00f3n de las competencias gen\u00e9ricas y espec\u00edficas le permitir\u00e1 desempe\u00f1arse en instituciones del estado, organismos gubernamentales y no gubernamentales, movimientos sociales, asociaciones y cooperativas comunitarias y vecinales en \u00e1reas de trabajo como: salud, educaci\u00f3n, cultura, medio ambiente y grupos sociales.<\/p><p>La formaci\u00f3n profesional del Trabajo Social, se sustenta en los siguientes valores: humanismo, identidad institucional y sentimiento de pertenencia, compromiso social e institucional, equidad, justicia, inclusi\u00f3n social, transparencia, respeto a los Derechos Humanos, a la diversidad y al medio ambiente, \u00e9tica profesional, tolerancia y solidaridad<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>\u00c1rea de consejer\u00edas escolar en colegios de educaci\u00f3n b\u00e1sica p\u00fablico y privada<\/li><li>\u00c1reas de trabajo social hospitalario<\/li><li>\u00c1rea de adopci\u00f3n en ministerios del estado, \u00e1rea de recursos humanos<\/li><li>Centros de Rehabilitaci\u00f3n<\/li><li>\u00c1rea de consejer\u00eda familiar en instituciones del estado y organismos gubernamentales\/no gubernamentale<\/li><li>Casas hogares del adulto mayo<\/li><li>Casas maternas<\/li><li>Casas hogares de la ni\u00f1ez<\/li><li>Gobiernos locales<\/li><li>Organizaciones sociales<\/li><li>Centros culturales<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Implementaci\u00f3n de procesos de intervenci\u00f3n social<\/li><li>Realizaci\u00f3n de estudios diagn\u00f3sticos para la identificaci\u00f3n de necesidades y problemas<\/li><li>Elabora planes y proyectos de intervenci\u00f3n social<\/li><li>Seguimiento y evaluaci\u00f3n a los procesos de intervenci\u00f3n social<\/li><li>Realizaci\u00f3n de procesos de sistematizaci\u00f3n de la pr\u00e1ctica social<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5422\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5422\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5422\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comprensi\u00f3n lectora y comunicativa<\/li><li>Sociolog\u00eda del Trabajo Social<\/li><li>Introducci\u00f3n al Trabajo Social.<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Redacci\u00f3n y composici\u00f3n de texto<\/li><li>Cultura y Sociedad<\/li><li>Investigaci\u00f3n y Trabajo Social<\/li><li>Teor\u00eda y M\u00e9todos de Trabajo Social<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Sociolog\u00eda Pol\u00edtica y del Desarrollo<\/li><li>Legislaci\u00f3n Social I<\/li><li>Metodolog\u00eda de la investigaci\u00f3n Social<\/li><li>T\u00e9cnicas de Trabajo Social comunitario<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Teor\u00eda Psicol\u00f3gica<\/li><li>Legislaci\u00f3n Social II<\/li><li>Metodolog\u00eda de la investigaci\u00f3n social cuantitativa<\/li><li>Planificaci\u00f3n Social<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Psicolog\u00eda Social<\/li><li>Legislaci\u00f3n Social III<\/li><li>Investigaci\u00f3n social cualitativa<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>M\u00e9todos Psico sociales<\/li><li>Investigaci\u00f3n Acci\u00f3n participativa<\/li><li>Capacitaci\u00f3n Social<\/li><li>Intervenci\u00f3n social<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo I<\/li><li>Optativo II<\/li><li>Gesti\u00f3n social participativa<\/li><li>Proyecto Social I<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Optativo III<\/li><li>Optativas IV<\/li><li>Sistematizaci\u00f3n de la Pr\u00e1ctica Social I<\/li><li>Proyecto Social II<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo V<\/li><li>Optativa VI<\/li><li>Sistematizaci\u00f3n de la Pr\u00e1ctica Social II<\/li><li>Planificaci\u00f3n de la Gesti\u00f3n Social<\/li><li>Pr\u00e1cticas Pre profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5423\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5423\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5423\" tabindex=\"0\" hidden=\"hidden\"><ul><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17497\" class=\"elementor elementor-17497\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6785a5f0 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"6785a5f0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e742e7e\" data-id=\"6e742e7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-184a005d\" data-id=\"184a005d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e461af1 elementor-widget elementor-widget-heading\" data-id=\"e461af1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Administraci\u00f3n de Empresas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47b4ead5 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"47b4ead5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61df9629\" data-id=\"61df9629\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36d69d6c elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"36d69d6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9201\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9201\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9202\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9202\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9203\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9203\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9201\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9201\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9201\" tabindex=\"0\" hidden=\"false\"><p style=\"text-align: justify;\">La Administraci\u00f3n de Empresas tiene como objeto de estudio el accionar din\u00e1mico de las organizaciones modernas. Esta carrera universitaria es relativamente nueva dado que anteriormente, en sus inicios quienes realizaron las actividades administrativas fueron economistas, ingenieros, contadores, entre todo un conjunto de profesionales que hac\u00edan de las labores de gesti\u00f3n su quehacer diario.<\/p><p style=\"text-align: justify;\">Al estudiar el dinamismo de las empresas los que se dedican a esta profesi\u00f3n tienen la intenci\u00f3n de poder solucionar todo un conjunto de acciones propias de la administraci\u00f3n tales como la toma de decisiones, \u00e9l sabe hacer uso del trabajo en equipo, el planeamiento de la organizaci\u00f3n a corto, mediano y largo plazo, la organizaci\u00f3n de todas las actividades empresariales, la direcci\u00f3n del proceso administrativo con su correspondiente motivaci\u00f3n, liderazgo y comunicaci\u00f3n fluida entre todos los componentes humanos de la empresa, y por supuesto el necesario y conveniente control de los procesos, equipos y personas que integran la organizaci\u00f3n.<\/p><p style=\"text-align: justify;\"><strong>Funciones que realiza el Administrador de Empresas<\/strong><\/p><ul><li style=\"text-align: justify;\">Administrar la empresa en funci\u00f3n de la globalizaci\u00f3n de mercado.<\/li><li style=\"text-align: justify;\">Desarrollar nuevas estrategias de negocios.<\/li><li style=\"text-align: justify;\">Orientar en cultura organizacional a un medio de apertura y competitividad.<\/li><li style=\"text-align: justify;\">Desarrollar el esp\u00edritu emprendedor e innovador.<\/li><li style=\"text-align: justify;\">Formular y establecer mecanismo de comunicaci\u00f3n corporativo.<\/li><li style=\"text-align: justify;\">Dise\u00f1a y formula estrategias comerciales y de competitividad, administra ventas.<\/li><li style=\"text-align: justify;\">Recluta, selecciona personal de la empresa.<\/li><li style=\"text-align: justify;\">Capacita y desarrolla en recursos humanos.<\/li><li style=\"text-align: justify;\">Dise\u00f1a y administra programas de compensaci\u00f3n.<\/li><li style=\"text-align: justify;\">Eval\u00faa, asigna y optimiza recursos en la empresa.<\/li><li style=\"text-align: justify;\">Eval\u00faa la rentabilidad de la empresa.<\/li><li style=\"text-align: justify;\">Maneja las implicaciones econ\u00f3micas, legales y pol\u00edticas de los negocios internacionales.<\/li><li style=\"text-align: justify;\">Desarrollar y adquirir franquicias.<\/li><li style=\"text-align: justify;\">Formula y establece programas de calidad.<\/li><\/ul><p style=\"text-align: justify;\"><strong>Cargos que desempe\u00f1a el Administrador de Empresas<\/strong><\/p><ul><li style=\"text-align: justify;\">Gerente general.<\/li><li style=\"text-align: justify;\">Gerente administrativo.<\/li><li style=\"text-align: justify;\">Gerente financiero.<\/li><li style=\"text-align: justify;\">Gerente de recursos humanos.<\/li><li style=\"text-align: justify;\">Gerente de marketing.<\/li><li style=\"text-align: justify;\">Gerente de comercializaci\u00f3n.<\/li><li style=\"text-align: justify;\">Gerente imagen corporativa.<\/li><li style=\"text-align: justify;\">Importaci\u00f3n y exportaci\u00f3n.<\/li><li style=\"text-align: justify;\">Planeaci\u00f3n estrat\u00e9gica de negocios.<\/li><li style=\"text-align: justify;\">An\u00e1lisis de costo y productividad.<\/li><li style=\"text-align: justify;\">Ejecutivo bancario y burs\u00e1til.<\/li><li style=\"text-align: justify;\">Comercio internacional.<\/li><li style=\"text-align: justify;\">ATM (log\u00edstica).<\/li><li style=\"text-align: justify;\">Formulaci\u00f3n y evaluaci\u00f3n de proyecto.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9202\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9202\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9202\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Filosof\u00eda Empresarial<\/li><li>Derecho Laboral<\/li><li>T\u00f3picos Matem\u00e1ticos<\/li><li>Microeconom\u00eda<\/li><li>Proceso Administrativo<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Integrador II<\/li><li>Sociolog\u00eda y Empresa<\/li><li>Derecho Mercantil<\/li><li>Macroeconom\u00eda<\/li><li>Organizaci\u00f3n y Procedimientos<\/li><li>Matem\u00e1tica I<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Estad\u00edstica Descriptiva<\/li><li>Mercadotecnia I<\/li><li>Contabilidad I<\/li><li>Enfoques administrativos contempor\u00e1neos<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Administraci\u00f3n de suministro<\/li><li>Estad\u00edstica Inferencial<\/li><li>Mercadotecnia II<\/li><li>Contabilidad II<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Sistemas de informaci\u00f3n de mercadotecnia<\/li><li>Contabilidad de Costo<\/li><li>Administraci\u00f3n operaciones de bienes y servicios<\/li><li>Matem\u00e1tica financiera<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Planeaci\u00f3n e integraci\u00f3n de los recursos humanos<\/li><li>Mercadotecnia de servicios<\/li><li>Presupuesto<\/li><li>Creaci\u00f3n de organizaciones<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Desarrollo y calidad de los recursos humanos<\/li><li>Contabilidad Financiera I<\/li><li>Administraci\u00f3n de proyectos de inversi\u00f3n<\/li><li>Optativo I<\/li><li>Integrador VII<\/li><li>Administraci\u00f3n de ventas<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Administraci\u00f3n de remuneraci\u00f3n<\/li><li>Plan de mercadotecnia<\/li><li>Contabilidad Financiera II<\/li><li>Administraci\u00f3n p\u00fablica<\/li><li>Optativo II<\/li><li>Integrador VIII<\/li><li>Administraci\u00f3n estrat\u00e9gica<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo III<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9203\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9203\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9203\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17500\" class=\"elementor elementor-17500\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20468bc2 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"20468bc2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f66fe66\" data-id=\"f66fe66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ef2554d\" data-id=\"7ef2554d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-445fa1fb elementor-widget elementor-widget-heading\" data-id=\"445fa1fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contadur\u00eda P\u00fablica y Finanzas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72e01772 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"72e01772\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1bcd58b6\" data-id=\"1bcd58b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19ca0e5f elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"19ca0e5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4321\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4321\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4322\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4322\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4323\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4323\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4321\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4321\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4321\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la Contadur\u00eda P\u00fablica es la ense\u00f1anza y aprendizaje de los procedimientos de control contable para proveer de informaci\u00f3n financiera en forma de estados financieros a la gerencia de la entidad, el an\u00e1lisis financiero y el examen de los estados financieros. En consecuencia, el profesional de la contadur\u00eda p\u00fablica domina la preparaci\u00f3n de la informaci\u00f3n financiera para su an\u00e1lisis de la informaci\u00f3n financiera y el examen(auditor\u00eda) de los estados financieros, adem\u00e1s de tener la capacidad de ejercer tareas de mayor responsabilidad y liderazgo en el campo de su profesional lo interno de las empresas.<\/p><p>Su cultura humanista le permite analizar la realidad con sentido \u00e9tico y cr\u00edtico y situar al profesional como centro de toda reflexi\u00f3n y toda acci\u00f3n enfocado en el ejercicio de su profesi\u00f3n de contador p\u00fablico.<\/p><p>Por su formaci\u00f3n en contabilidad financiera, contabilidad de costos, finanzas y auditor\u00eda de estados financieros puede desarrollarse profesionalmente en empresas comerciales, de servicios, industriales, agroindustriales, del sector p\u00fablico y organizaciones sin fines de lucro. Tambi\u00e9n puede desempe\u00f1arse como profesional dependiente (empleado por tiempo indefinido y constante) e independiente al celebrar contratos por servicios profesionales para ejercer actividades enfocadas al \u00e1mbito de la profesi\u00f3n de contador p\u00fablico.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Empresas del sector comercial industrial, agroindustrial y Organizaciones del sector servicio.<\/li><li>Instituciones p\u00fablicas.<\/li><li>Organizaciones sin fines de lucro.<\/li><li>Empresas Multinacionales y transnacionales.<\/li><li>Micro financieras.<\/li><li>Instituciones financieras.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Prepara y presenta el estado de resultados y el estado de situaci\u00f3n financiera en peque\u00f1as y medianas empresas.<\/li><li>Registro contable de transacciones de cuentas por cobrar, propiedad planta y equipo cuentas por pagar e inventarios, para empresas privadas, estatales y del sistema financiero de Nicaragua.<\/li><li>Maneja sistemas inform\u00e1ticos para el procesamiento de la informaci\u00f3n contable.<\/li><li>Elabora conciliaciones bancarias.<\/li><li>An\u00e1lisis financiero y econ\u00f3mico.<\/li><li>Fiscaliza y audita el cumplimiento de las Leyes tributarias vigentes en Nicaragua.<\/li><li>Realiza registro y declaraciones de los impuestos nacionales y municipales.<\/li><li>L\u00edquida y registra los costos de producci\u00f3n.<\/li><li>Auxilia en las auditor\u00edas internas y financieras.<\/li><li>Docente universitario de las ciencias econ\u00f3micas y financieras.<\/li><li>Auditar estados financieros de manera independiente.<\/li><li>Auditor\u00eda interna del sector p\u00fablico.<\/li><li>Elabora presupuestos financieros.<\/li><li>Asesor\u00eda contable y financiero.<\/li><li>Elaboraci\u00f3n de C\u00e9dulas de Trabajo de auditor\u00eda.<\/li><li>Elaboraciones de plan de tareas financieras del \u00e1rea.<\/li><li>Liquidaci\u00f3n de pago a proveedores.<\/li><li>Elaboraci\u00f3n de cheques.<\/li><li>Realiza an\u00e1lisis econ\u00f3mico y financiero.<\/li><li>Elabora planes financieros.<\/li><li>Elabora presupuestos econ\u00f3micos.<\/li><li>Elabora presupuestos de tesorer\u00eda.<\/li><li>Elabora presupuesto de inversiones.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4322\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4322\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4322\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Integrador I<\/li><li>Administraci\u00f3n I<\/li><li>Inform\u00e1tica I<\/li><li>Expresi\u00f3n Oral y Escrita<\/li><li>Matem\u00e1tica I<\/li><li>Contabilidad Financiera I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Administraci\u00f3n II<\/li><li>Inform\u00e1tica II<\/li><li>T\u00e9cnica de Investigaci\u00f3n Documental<\/li><li>Estad\u00edstica Descriptiva<\/li><li>Contabilidad Financiera II<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Fundamentos de Econom\u00eda I<\/li><li>Matem\u00e1tica II<\/li><li>Contabilidad Financiera III<\/li><li>Contabilidad de Costos I<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Fundamentos de Econom\u00eda II<\/li><li>Estad\u00edstica Financiera<\/li><li>Contabilidad Financiera IV<\/li><li>Contabilidad de Costos II<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Fundamentos de Medici\u00f3n en Contabilidad Financiera<\/li><li>Derecho de Empresas<\/li><li>Contabilidad de Sociedades<\/li><li>Contabilidad de Costos III<\/li><li>Finanzas a Corto Plazo<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>M\u00e9todos para Operaciones Financieras<\/li><li>Contabilidad Tributaria<\/li><li>Contabilidad de Costos IV<\/li><li>Finanzas a Largo Plazo<\/li><li>Optativo I<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Normas Internacionales de Auditor\u00eda<\/li><li>Contabilidad Financiera y de Seguros<\/li><li>Auditor\u00eda I<\/li><li>Optativo II<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>\u00c9tica Profesional<\/li><li>Auditor\u00eda II<\/li><li>Auditor\u00eda Interna<\/li><li>Optativo III<\/li><li>Optativo IV<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Pr\u00e1cticas Pre Profesionales<\/li><li>Auditor\u00eda III<\/li><li>Optativo V<\/li><li>Integrador IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Integrador X<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4323\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4323\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4323\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17503\" class=\"elementor elementor-17503\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-789384aa elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"789384aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aa25a\" data-id=\"aa25a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ecdaa94\" data-id=\"2ecdaa94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15b111b4 elementor-widget elementor-widget-heading\" data-id=\"15b111b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Banca y Finanzas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c7b6666 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"3c7b6666\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e536e98\" data-id=\"6e536e98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c0c38f9 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"1c0c38f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4701\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4701\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4702\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4702\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4703\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4703\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4701\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4701\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4701\" tabindex=\"0\" hidden=\"false\"><p style=\"text-align: justify;\">La carrera de Banca y Finanzas, est\u00e1 dise\u00f1ada para formar profesionales en el campo de las Finanzas y la Banca. Responde a una necesidad real de dotar al sistema empresarial de cuadros altamente capacitados en la planeaci\u00f3n financiera y toma de decisiones gerenciales, tomando en cuenta el entorno nacional e internacional.<\/p><p style=\"text-align: justify;\">Los licenciados en Banca y Finanzas son los encargados de efectuar los an\u00e1lisis financieros de los diferentes tipos de empresas para llegar a determinar la salud financiera de \u00e9stas, y ejecutar una planeaci\u00f3n financiera acorde a las necesidades de su producci\u00f3n y venta. Tambi\u00e9n se encarga de proponer las diferentes estrategias a seguir para cumplir con la misi\u00f3n y la visi\u00f3n de todos los tipos de entidades, en la banca es el encargado de realizar las diferentes operaciones bancarias y en la bolsa de valores de negociar activamente los diferentes t\u00edtulos financieros. La sociedad nicarag\u00fcense realiza constantemente estas operaciones por lo que el licenciado en Banca y Finanzas es de suma importancia para garantizar el cumplimiento de dichas operaciones. El Licenciado en Banca y Finanzas en su ejercicio profesional contribuye a mejorar la administraci\u00f3n eficiente del efectivo, la toma de decisiones de inversi\u00f3n, la toma de decisiones de financiamiento, la toma de decisiones de distribuci\u00f3n de utilidades, en todos los tipos de entidades, por su tama\u00f1o ya sea micro, peque\u00f1a, mediana o gran empresa, de servicios, industriales, al igual que estas labores las desempe\u00f1a de manera eficiente en el Sistema Financiero Nacional, Bolsa de Valores, Bancos Privados, Financieras, Compa\u00f1\u00edas Arrendadoras, Almacenes Generales de Dep\u00f3sito, Direcci\u00f3n General de Aduanas, entre otros.<\/p><p style=\"text-align: justify;\"><strong>Funciones que realiza el Licenciado en Banca y Finanzas<\/strong><\/p><ul><li style=\"text-align: justify;\">Administrar eficientemente las diferentes entidades del sistema financiero nacional.<\/li><li style=\"text-align: justify;\">Tomar decisiones de inversi\u00f3n y financiamiento.<\/li><li style=\"text-align: justify;\">Aplicar las leyes del sistema financiero nacional en la realizaci\u00f3n de sus funciones.<\/li><li style=\"text-align: justify;\">Analizar cr\u00e9ditos comerciales, productivos, agropecuarios, agr\u00edcolas, tomar decisiones de otorgar los diferentes tipos de cr\u00e9ditos.<\/li><li style=\"text-align: justify;\">Gerenciar las diferentes instituciones bancarias proponer, evaluar y desarrollar nuevos servicios bancarios.<\/li><li style=\"text-align: justify;\">Evaluar bonos, acciones, derivados y otros activos financieros.<\/li><li style=\"text-align: justify;\">Efectuar estudios de mercado para la promoci\u00f3n y colocaci\u00f3n de valores financieros.<\/li><li style=\"text-align: justify;\">Administrar empresas aseguradoras y reaseguradoras.<\/li><li style=\"text-align: justify;\">Evaluar los diferentes tipos de seguros.<\/li><li style=\"text-align: justify;\">Promover seguros y reaseguros.<\/li><li style=\"text-align: justify;\">Gestionar cobros de hipotecas.<\/li><li style=\"text-align: justify;\">Gestionar todos tipos de cobros de las diferentes entidades comerciales, industriales, bancaria.<\/li><li style=\"text-align: justify;\">Valorar y analizar inversiones de activos reales y activos financieros.<\/li><li style=\"text-align: justify;\">Servir de intermediario entre los inversionistas, ahorrantes y solicitantes de financiamiento.<\/li><li style=\"text-align: justify;\">Asesor financiero de inversiones.<\/li><li style=\"text-align: justify;\">Administrar financieramente puestos de bolsas.<\/li><li style=\"text-align: justify;\">Asesor para la colocaci\u00f3n y valoraci\u00f3n de activos financieros en los puestos de bolsa.<\/li><li style=\"text-align: justify;\">Formular proyectos de inversi\u00f3n.<\/li><li style=\"text-align: justify;\">Evaluar financieramente los diferentes tipos de proyectos de inversi\u00f3n.<\/li><li style=\"text-align: justify;\">Tomar decisiones sobre la aceptaci\u00f3n o no de los proyectos de inversi\u00f3n.<\/li><li style=\"text-align: justify;\">Analizar los diferentes tipos de riesgos.<\/li><li style=\"text-align: justify;\">Evaluar los diferentes tipos de riesgos para activos reales y activos financieros.<\/li><li style=\"text-align: justify;\">Efectuar la administraci\u00f3n de los diferentes tipos de riesgos.<\/li><li style=\"text-align: justify;\">Evaluar riesgo y rendimiento para la toma de decisiones de inversi\u00f3n y de financiamiento.<\/li><li style=\"text-align: justify;\">De trabajo de asesor\u00eda de inversiones.<\/li><li style=\"text-align: justify;\">Evaluar proyectos de inversi\u00f3n y de financiamiento y asesor\u00eda financiera para toma de las mejores decisiones.<\/li><li style=\"text-align: justify;\">Administraci\u00f3n financiera de fondos de pensiones.<\/li><li style=\"text-align: justify;\">Evaluar y analizar la cartera de inversi\u00f3n de empresas, estado, instituciones e individuos.<\/li><li style=\"text-align: justify;\">Toma de decisiones de inversi\u00f3n.<\/li><li style=\"text-align: justify;\">Toma de decisiones de financiamiento.<\/li><li style=\"text-align: justify;\">Toma de decisiones de Distribuci\u00f3n de utilidades.<\/li><li style=\"text-align: justify;\">Elaboraci\u00f3n, control, seguimiento y evaluaci\u00f3n de presupuesto.<\/li><li style=\"text-align: justify;\">Revisar la evaluaci\u00f3n de los expedientes de los diferentes tipos de cr\u00e9ditos.<\/li><li style=\"text-align: justify;\">Tomar decisiones para el otorgamiento de cr\u00e9ditos a corto y largo plazo.<\/li><li style=\"text-align: justify;\">Manejo del recurso dinero en los diferentes tipos de negocios, estado e instituciones publicas.<\/li><li style=\"text-align: justify;\">Preparar informes financieros para la direcci\u00f3n superior.<\/li><li style=\"text-align: justify;\">Asesor\u00eda Financiera. Agente libre.<\/li><li style=\"text-align: justify;\">Consultor de Empresas.<\/li><li style=\"text-align: justify;\">Diagnosticar estados financieros.<\/li><li style=\"text-align: justify;\">Administrar, evaluar y controlar todos los tipos de riesgos corporativos.<\/li><li style=\"text-align: justify;\">Controlar, evaluar y coordinar el departamento de contralor\u00eda de las Corporativas.<\/li><li style=\"text-align: justify;\">Asesor\u00eda Financiera.<\/li><li style=\"text-align: justify;\">Analista de Cr\u00e9dito y de Proyecto.<\/li><li style=\"text-align: justify;\">Gerente de su propio negocio.<\/li><\/ul><p style=\"text-align: justify;\"><strong>Cargos que desempe\u00f1a el Licenciado en Banca y Finanzas<\/strong><\/p><ul><li style=\"text-align: justify;\">Gerente de Instituciones del Sistema Financiero Nacional.<\/li><li style=\"text-align: justify;\">Analista y\/o asesor de cr\u00e9dito.<\/li><li style=\"text-align: justify;\">Gerente y\/o de Servicios Bancarios.<\/li><li style=\"text-align: justify;\">Promotor de Valores.<\/li><li style=\"text-align: justify;\">Agente de Ventas de Seguros.<\/li><li style=\"text-align: justify;\">Gestor de Cobranzas.<\/li><li style=\"text-align: justify;\">Gerente de Inversiones.<\/li><li style=\"text-align: justify;\">Corredor de Bolsas.<\/li><li style=\"text-align: justify;\">Administrador de puesto de Bolsa.<\/li><li style=\"text-align: justify;\">Analista Financiero de Proyectos de Inversi\u00f3n.<\/li><li style=\"text-align: justify;\">Analista de Riesgo.<\/li><li style=\"text-align: justify;\">Consulto y\/o asesor de Inversiones.<\/li><li style=\"text-align: justify;\">Administrador de Fondos de Pensiones.<\/li><li style=\"text-align: justify;\">Director y\/o Gerente Financiero.<\/li><li style=\"text-align: justify;\">Gerente de Cr\u00e9dito.<\/li><li style=\"text-align: justify;\">Tesorero.<\/li><li style=\"text-align: justify;\">Asistente de Direcci\u00f3n Superior.<\/li><li style=\"text-align: justify;\">Gerente de Riesgo Corporativo.Controlador Corporativo.<\/li><li style=\"text-align: justify;\">Junior de Despacho de Auditoria.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4702\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4702\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4702\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>T\u00e9cnicas de Comunicaci\u00f3n y Lectura<\/li><li>Derecho Empresarial<\/li><li>Principios de econom\u00eda<\/li><li>Matem\u00e1tica General<\/li><li>Contabilidad I<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Integrador II<\/li><li>Contabilidad II<\/li><li>Estad\u00edstica Descriptiva<\/li><li>Microeconom\u00eda<\/li><li>Taller contable, tributario y laboral<\/li><li>T\u00e9cnicas de Investigaci\u00f3n<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Macroeconom\u00eda<\/li><li>Operaciones Financieras I<\/li><li>Gesti\u00f3n Financiera I<\/li><li>Contabilidad Intermedia<\/li><li>Administraci\u00f3n y organizaci\u00f3n<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Integrador IV<\/li><li>Operaciones Financieras II<\/li><li>Pol\u00edtica econ\u00f3mica y monetaria<\/li><li>Contabilidad Superior<\/li><li>Administraci\u00f3n Financiera I<\/li><li>Optativo I<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Gesti\u00f3n Financiera II<\/li><li>Estad\u00edstica Financiera<\/li><li>Planificaci\u00f3n y Control de Costos<\/li><li>Administraci\u00f3n Financiera II<\/li><li>Operaciones Bancarias<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Integrador VI<\/li><li>M\u00e9todos de investigaci\u00f3n de operaciones<\/li><li>Presupuesto<\/li><li>An\u00e1lisis Financiero de instituciones<\/li><li>Finanzas gubernamentales<\/li><li>Cr\u00e9dito bancario y no bancario<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Finanzas corporativas I<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Cooperativas y ONGs<\/li><li>Optativo II<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Integrador VIII<\/li><li>Optativo III<\/li><li>Finanzas corporativas II<\/li><li>T\u00e9cnicas de Cobranza y administraci\u00f3n de cartera<\/li><li>\u00c9tica Profesional<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Medici\u00f3n Financiera<\/li><li>Supervisi\u00f3n de instituciones<\/li><li>Gesti\u00f3n de riesgos bancarios<\/li><li>Optativo IV<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><li>Integrador IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Integrador X<\/li><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><li>Optativo V<\/li><li>Valoraci\u00f3n financiera de proyectos<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4703\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4703\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4703\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17506\" class=\"elementor elementor-17506\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fa2b8b elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"8fa2b8b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-984543f\" data-id=\"984543f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c29e4d5\" data-id=\"5c29e4d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1befd2bb elementor-widget elementor-widget-heading\" data-id=\"1befd2bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Econom\u00eda<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c5597dd elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"5c5597dd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b333416\" data-id=\"4b333416\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-495b9ce6 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"495b9ce6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1231\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1231\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1232\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1232\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1233\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1233\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1231\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1231\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1231\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la Econom\u00eda es \u201clos procesos de producci\u00f3n, distribuci\u00f3n, intercambio y consumo de bienes y servicios que contribuyen al desarrollo humano sostenible\u201d. Por ello, el profesional egresado posee las capacidades, habilidades y destrezas para desarrollarse en los campos microecon\u00f3micos y macroecon\u00f3mico, en los \u00e1mbitos privado y gubernamental. Tiene la capacidad para contribuir con el desarrollo econ\u00f3mico sustentable; analizar la situaci\u00f3n econ\u00f3mica nacional e internacional y recomendar la aplicaci\u00f3n de pol\u00edticas econ\u00f3micas; dirigir y\/o asesorar empresas tanto del sector p\u00fablico como privado; formular y evaluar proyectos privados y sociales; realizar investigaciones, aplicando principios y teor\u00edas de la econom\u00eda; asumir con liderazgo la toma de decisiones econ\u00f3mica-financieras sobre la base de destrezas cualitativas, cuantitativas y tecnol\u00f3gicas; as\u00ed como emprender su propia empresa. Su cultura humanista le permite al profesional de la econom\u00eda analizar la realidad con sentido \u00e9tico y cr\u00edtico, con visi\u00f3n hol\u00edstica y con capacidad para diagnosticar problemas complejos y abordar su soluci\u00f3n de manera sist\u00e9mica, inter y multidisciplinaria; situando al hombre como centro de toda reflexi\u00f3n y acci\u00f3n. Permiti\u00e9ndola expresarse no solo con un pensamiento renovado de los valores humanos esenciales sino, sobre todo, con una renovada propuesta de conducta personal dentro de la sociedad; pasando de una \u00e9tica individualista a una \u00e9tica de \u201clo p\u00fablico\u201d que les permita responder por personas y recursos encomendados.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>Por su formaci\u00f3n puede desarrollarse profesionalmente en el sector p\u00fablico, privado, en empresas e instituciones financieras, o en empresas e instituciones industriales, comerciales, mineras y agropecuarias, en cooperativas, en asociaciones y en organizaciones no gubernamentales de desarrollo, empresas e instituciones de servicios acad\u00e9micos, de investigaci\u00f3n y de consultor\u00eda y en empresas o instituciones propias.<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Plantear escenarios en estructuras de mercados, ante cambios en las variables.<\/li><li>Analizar entornos generales y espec\u00edficos para la definici\u00f3n de estrategia empresarial.<\/li><li>Identificar estrategias de desarrollo empresarial para el proceso de toma de decisiones<\/li><li>Construir indicadores de an\u00e1lisis para el comercio exterior.<\/li><li>Analizar riesgos financieros y su incidencia en los indicadores de rentabilidad.<\/li><li>Establecer los procedimientos para la creaci\u00f3n de una empresa.<\/li><li>Valorar el comportamiento de la econom\u00eda nacional e internacional, basado en indicadores.<\/li><li>Evaluar la incidencia de las pol\u00edticas p\u00fablicas sobre el quehacer econ\u00f3mico y social.<\/li><li>Plantear estrategias de desarrollo econ\u00f3mico y social, acorde al contexto de pa\u00eds.<\/li><li>Dise\u00f1ar perfiles de investigaciones econ\u00f3micas, sociales y ambientales.<\/li><li>Estimar el comportamiento de variables econ\u00f3micas y sociales, para el seguimiento de la econom\u00eda.<\/li><li>Pronosticar e interpretar el comportamiento de variables econ\u00f3micas y sociales, para el seguimiento de la econom\u00eda.<\/li><li>Integrar cr\u00edticamente en el an\u00e1lisis econ\u00f3mico las distintas expresiones del pensamiento econ\u00f3mico.<\/li><li>Contribuir a la transformaci\u00f3n de la realidad, mediante la interpretaci\u00f3n de las distintas expresiones del pensamiento econ\u00f3mico.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1232\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1232\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1232\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Matem\u00e1tica para Econom\u00eda I<\/li><li>An\u00e1lisis Estad\u00edstico I<\/li><li>Reflexiones<\/li><li>Filos\u00f3ficas en la Econom\u00eda<\/li><li>Introducci\u00f3n a la Econom\u00eda<\/li><li>Taller de Investigaci\u00f3n Econ\u00f3mica I<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Matem\u00e1tica para Econom\u00eda II<\/li><li>An\u00e1lisis Estad\u00edstico II<\/li><li>Econom\u00eda y Sociolog\u00eda<\/li><li>Historia Econ\u00f3mica<\/li><li>Formas Organizativas de la Producci\u00f3n<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Modelos de Decisiones<\/li><li>An\u00e1lisis Microecon\u00f3mico I<\/li><li>An\u00e1lisis Macroecon\u00f3mico I<\/li><li>Legislaci\u00f3n Econ\u00f3mica<\/li><li>Taller de Investigaci\u00f3n Econ\u00f3mica II<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>An\u00e1lisis Contable I<\/li><li>Doctrinas Econ\u00f3micas I<\/li><li>An\u00e1lisis Microecon\u00f3mico II<\/li><li>An\u00e1lisis Macroecon\u00f3mico II<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>An\u00e1lisis Contable II<\/li><li>Doctrinas Econ\u00f3micas II<\/li><li>Fundamentos Econ\u00f3micos de la Empresa<\/li><li>Integrador V<\/li><li>An\u00e1lisis Financiero I<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>An\u00e1lisis Financiero II<\/li><li>Econom\u00eda Pol\u00edtica<\/li><li>Contabilidad Nacional<\/li><li>An\u00e1lisis Econom\u00e9trico I<\/li><li>Optativo I<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>An\u00e1lisis Ambiental<br \/>Econom\u00eda<\/li><li>Internacional I<\/li><li>An\u00e1lisis Econom\u00e9trico II<\/li><li>Pol\u00edtica Econ\u00f3mica<\/li><li>Integrador VII<\/li><li>Finanzas P\u00fablicas y Pol\u00edtica Fiscal<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Econom\u00eda Internacional II<\/li><li>Teor\u00eda y Pol\u00edtica Monetaria<\/li><li>Econom\u00eda del Crecimiento y del Desarrollo<\/li><li>Formulaci\u00f3n y Evaluaci\u00f3n de Proyectos<\/li><li>Optativo II<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Optativo III<\/li><li>Evaluaci\u00f3n Econ\u00f3mica de Proyectos<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1233\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1233\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1233\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17509\" class=\"elementor elementor-17509\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbb69e1 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"bbb69e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a1a388e\" data-id=\"5a1a388e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-60ed30dc\" data-id=\"60ed30dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cc2dbc5 elementor-widget elementor-widget-heading\" data-id=\"2cc2dbc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Econom\u00eda Agr\u00edcola<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f2865d5 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"6f2865d5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-703d390\" data-id=\"703d390\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6afe0167 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"6afe0167\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1791\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1791\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1791\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1791\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1791\" tabindex=\"0\" hidden=\"false\"><p style=\"text-align: justify;\">La carrera Econom\u00eda Agr\u00edcola es un \u00e1rea de las Ciencias Econ\u00f3micas, que estudia el sector primario y rural del pa\u00eds, sus actividades agropecuarias, agroindustriales, medio ambientales y plantea retos de gran envergadura y diferentes para los profesionales de la econom\u00eda agr\u00edcola, quienes deben resolver grandes desaf\u00edos vinculados con el desarrollo de la familia productora y de la comunidad, en condiciones de dependencia econ\u00f3mica, de presiones del mercado internacional y del mercado interno, del fen\u00f3meno de la pobreza generalizada y de muchas otras variables socio-econ\u00f3micas.<\/p><p style=\"text-align: justify;\">Es una disciplina integradora de conocimientos, habilidades y destrezas que permiten acompa\u00f1ar procesos de desarrollo tanto en lo agroindustrial, agropecuario, como en otros campos afines y que utilizando un enfoque multidisciplinario aborda los procesos de transformaci\u00f3n y desarrollo.<\/p><p style=\"text-align: justify;\"><strong>Funciones que realiza el Licenciado en Econom\u00eda Agr\u00edcola<\/strong><\/p><ul><li style=\"text-align: justify;\">Administrar la empresa y organizaciones agropecuarias, agroindustriales, forestales entre otras.<\/li><li style=\"text-align: justify;\">Mejora la inserci\u00f3n de empresas vinculadas al agro en mercados nacionales e internacionales, cuidando de la competitividad y la sostenibilidad de sus acciones.<\/li><li style=\"text-align: justify;\">Aplicar herramientas cuantitativas que les permite realizar un uso racional de los recursos asignados a las peque\u00f1as, medianas y grandes empresas rurales.<\/li><li style=\"text-align: justify;\">Realizar an\u00e1lisis de pol\u00edticas p\u00fablicas agropecuarias (seguridad alimentaria, comercio internacional de productos agropecuarios, bolsa de valores).<\/li><li style=\"text-align: justify;\">Diagnostica, valora y plantea soluciones sobre el comportamiento de la producci\u00f3n distribuci\u00f3n y consumo nacional e internacional en su dimensi\u00f3n temporal y espacial, as\u00ed como en su contexto hist\u00f3rico y de perspectiva.<\/li><li style=\"text-align: justify;\">Administra la empresa en funci\u00f3n de la globalizaci\u00f3n de mercado.<\/li><li style=\"text-align: justify;\">Desarrollar el esp\u00edritu emprendedor e innovador.<\/li><\/ul><p style=\"text-align: justify;\"><strong>Cargos que desempe\u00f1a el Licenciado en Econom\u00eda Agr\u00edcola<\/strong><\/p><ul><li style=\"text-align: justify;\">Analista de cr\u00e9dito agr\u00edcola en Bancos, Microfinanzas, agrupaciones de productores.<\/li><li style=\"text-align: justify;\">Formulador y evaluador de inversiones agropecuarias, para el Gobierno Central, o Instituciones aut\u00f3nomas u Organismos Internacionales.<\/li><li style=\"text-align: justify;\">Responsables de centro de investigaci\u00f3n y extensi\u00f3n rural.<\/li><li style=\"text-align: justify;\">Extensionista agr\u00edcola.<\/li><li style=\"text-align: justify;\">Gerente de empresas vinculadas con la producci\u00f3n y transformaci\u00f3n de la producci\u00f3n primaria.<\/li><li style=\"text-align: justify;\">Empresario.<\/li><li style=\"text-align: justify;\">Investigador.<\/li><li style=\"text-align: justify;\">Docente.<\/li><li style=\"text-align: justify;\">Consultor.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17512\" class=\"elementor elementor-17512\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53ab59fb elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"53ab59fb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30d3097a\" data-id=\"30d3097a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-faa865a\" data-id=\"faa865a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-650e543 elementor-widget elementor-widget-heading\" data-id=\"650e543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mercadotecnia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a3f7d18 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"2a3f7d18\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ecbbc1c\" data-id=\"3ecbbc1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c859cd1 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3c859cd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1011\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1011\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1012\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1012\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1013\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1013\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1011\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1011\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de licenciatura de mercadotecnia es satisfacer necesidades de los consumidores a trav\u00e9s de la comercializaci\u00f3n y venta de productos y servicios, de manera eficiente y eficaz. Esta disciplina est\u00e1 presente en las \u00e1reas de ventas, servicios al cliente, mercadeo, distribuci\u00f3n, comercializaci\u00f3n, promoci\u00f3n y publicidad.<\/p><p>En los \u00e1mbitos de actuaci\u00f3n de la mercadotecnia est\u00e1n las empresas del sector manufacturero, de comercializaci\u00f3n y de distribuci\u00f3n; dedicadas a actividades de exportaci\u00f3n e importaci\u00f3n de bienes y servicios que conforman la cadena de suministro.<\/p><p>El profesional de la carrera de mercadotecnia aplica competencias dirigidas al manejo de planes de negocios, de medios de publicidad y negociaci\u00f3n con proveedores de servicios de marketing; uso de herramientas de marketing tales como: investigaci\u00f3n de mercado, enfoque de innovaci\u00f3n y emprendimientos de dise\u00f1o de productos y servicios; formulaci\u00f3n de proyectos, estudios de mercados y planes de negocios.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>Empresas comercializadoras de productos por sectores p\u00fablicos y privados: Agr\u00edcolas, pecuarios, industrial, de construcci\u00f3n, servicios b\u00e1sicos, salud, educaci\u00f3n, transporte, financieros, tur\u00edsticos, comunicaci\u00f3n digital, bancos, comercio, cosm\u00e9ticos, electrodom\u00e9sticos, prendas de vestir, equipos tecnol\u00f3gicos de informaci\u00f3n y comunicaci\u00f3n, agroqu\u00edmicos, repuestos automotrices, seguros, bienes inmuebles.<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Formular proyectos publicitarios para la mejora del proceso de comercializaci\u00f3n de productos y servicios.<\/li><li>Elaborar planes estrat\u00e9gicos en marketing digital.<\/li><li>Dise\u00f1ar estrategias de marketing de relaciones.<\/li><li>Administrar las redes sociales utilizadas para la comercializaci\u00f3n y ventas de productos y servicios.<\/li><li>Proponer la elaboraci\u00f3n de nuevos productos y servicio de acuerdo a las necesidades identificadas en el mercado.<\/li><li>Crear actividades relacionadas con el neuromarketing, para tomar decisiones.<\/li><li>Elaborar un plan de publicidad relacionados a eventos sociales, empresariales.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1012\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1012\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1012\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>A\u00d1O I<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Administraci\u00f3n I<\/li><li>Psicolog\u00eda en la mercadotecnia I<\/li><li>Matem\u00e1tica I<\/li><li>Mercadeo I<\/li><li>Ventas I<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Mercadeo II<\/li><li>Ventas II<\/li><li>Integrador II<\/li><li>Comunicaci\u00f3n en la mercadotecnia<\/li><li>Estad\u00edstica I<\/li><li>Administraci\u00f3n II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE II<\/p><ul><li>Psicolog\u00eda en la mercadotecnia II<\/li><li>Administraci\u00f3n de recursos humanos I<\/li><li>Estad\u00edstica II<\/li><li>Investigaci\u00f3n de mercados<\/li><li>Ventas III<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Psicolog\u00eda del consumidor<\/li><li>Matem\u00e1tica II<\/li><li>Mercadeo de servicio<\/li><li>Ventas IV<\/li><li>Integrador IV<\/li><li>Administraci\u00f3n de recursos humanos II<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Mercadeo de contenido y relacional<\/li><li>Introducci\u00f3n a la demograf\u00eda<\/li><li>Publicitaria I<\/li><li>Ventas V<\/li><li>Optativo I<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Demograf\u00eda en el Neuromarketing<\/li><li>Publicitaria II<\/li><li>Marketing online<\/li><li>Ventas VI<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Demograf\u00eda Econ\u00f3mica I<\/li><li>Publicitaria III<\/li><li>Mercadeo internacional<\/li><li>Optativo II<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Demograf\u00eda Econ\u00f3mica II<\/li><li>Publicitaria IV<\/li><li>Mercadeo estrat\u00e9gico<\/li><li>Optativo III<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Control y evaluaci\u00f3n del mercadeo<\/li><li>Optativo IV<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionales<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1013\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1013\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1013\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17578\" class=\"elementor elementor-17578\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37fd5f43 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"37fd5f43\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a245264\" data-id=\"3a245264\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a70ae21\" data-id=\"a70ae21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7aa46ceb elementor-widget elementor-widget-heading\" data-id=\"7aa46ceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Medicina<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76ffcd67 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"76ffcd67\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33fba2c6\" data-id=\"33fba2c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ba0c87f elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"2ba0c87f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7311\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-7311\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7312\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7312\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7313\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7313\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-7311\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7311\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de Medicina es la salud humana, para ello el graduado de la carrera de grado de Medicina tiene como competencia brindar atenci\u00f3n m\u00e9dica integral, con la capacidad de diagnosticar y tratar las diferentes situaciones de salud, tomando en cuenta sus determinantes. As\u00ed mismo, promociona la salud, a trav\u00e9s de la educaci\u00f3n, prevenci\u00f3n y control de enfermedades en sus expresiones individual, familiar y colectiva, en unidades de atenci\u00f3n de salud p\u00fablicas, privadas, as\u00ed como de seguridad social y otras instituciones relacionadas con el \u00e1rea de la salud y la comunidad, haciendo uso racional de los medios disponibles a su alcance. Demuestra ser un profesional con una s\u00f3lida formaci\u00f3n human\u00edstica, \u00e9tica, bio\u00e9tica y social, fundamentada en los avances cient\u00edficos. Adem\u00e1s, participa en el proceso gerencial e investigativo, que permita la resoluci\u00f3n de los problemas en salud en el contexto nacional y regional.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Unidades de atenci\u00f3n de salud primarias y secundarias, p\u00fablicas y privadas<\/li><li>Seguridad social<\/li><li>Otras instituciones relacionadas con el \u00e1rea de la salud<\/li><li>Comunidad<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><p><strong>Asistencial<\/strong><\/p><ul><li>Brinda atenci\u00f3n m\u00e9dica integral, seg\u00fan ciclo de la vida del individuo, en su familia y la comunidad<\/li><li>Proporciona asistencia en las urgencias m\u00e9dico quir\u00fargicas seg\u00fan ciclo de vida, estabilizando al paciente y refiri\u00e9ndolo a un nivel de mayor resoluci\u00f3n, si lo amerita<\/li><li>Identifica factores de riesgo en pacientes que ameriten un mayor nivel de resoluci\u00f3n, de forma oportuna<\/li><\/ul><p><strong>Promoci\u00f3n de la salud<\/strong><\/p><ul><li>Implementa acciones con el fin de mejorar el comportamiento individual y colectivo en relaci\u00f3n con la conservaci\u00f3n y recuperaci\u00f3n de la salud.<\/li><li>Ejecuta actividades encaminadas a evitar, retardar la enfermedad o atenuar sus consecuencias, seg\u00fan la evidencia cient\u00edfica, condiciones y caracter\u00edsticas de la poblaci\u00f3n.<\/li><\/ul><p><strong>Gerencial<\/strong><\/p><ul><li>Gestiona y administra los servicios y programas de salud con fines de mejora de la calidad en la atenci\u00f3n en salud.<\/li><\/ul><p>Lidera los servicios de salud en los diversos \u00e1mbitos de acci\u00f3n.<\/p><p><strong>Investigaci\u00f3n<\/strong><\/p><ul><li>Gestiona el conocimiento cient\u00edfico para la comprensi\u00f3n y soluci\u00f3n de las necesidades y problemas de salud individual y colectiva.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7312\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7312\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7312\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Anatom\u00eda Humana I<\/li><li>Histolog\u00eda Humana I<\/li><li>Embriolog\u00eda<\/li><li>Humana I<\/li><li>Biof\u00edsica M\u00e9dica<\/li><li>Biolog\u00eda Molecular<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Anatom\u00eda Humana II<\/li><li>Histolog\u00eda Humana II<\/li><li>Embriolog\u00eda<\/li><li>Humana II<\/li><li>Bioqu\u00edmica<\/li><li>Fisiolog\u00eda M\u00e9dica I<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Anatom\u00eda Humana III<\/li><li>Histolog\u00eda Humana III<\/li><li>Embriolog\u00eda<\/li><li>Humana III<\/li><li>Fisiolog\u00eda M\u00e9dica II<\/li><li>Optativo I<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Patolog\u00eda M\u00e9dica I<\/li><li>Farmacolog\u00eda<\/li><li>M\u00e9dica I<\/li><li>Fisiopatolog\u00eda y Semiolog\u00eda M\u00e9dica I<\/li><li>Inmunolog\u00eda<\/li><li>Optativo II<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Patolog\u00eda M\u00e9dica II<\/li><li>Farmacolog\u00eda<\/li><li>M\u00e9dica II<\/li><li>Fisiopatolog\u00eda y Semiolog\u00eda M\u00e9dica II<\/li><li>Microbiolog\u00eda M\u00e9dica<\/li><li>Higiene y Epidemiolog\u00eda<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Patolog\u00eda M\u00e9dica III<\/li><li>Farmacolog\u00eda M\u00e9dica III<\/li><li>Fisiopatolog\u00eda y Semiolog\u00eda M\u00e9dica III<\/li><li>Parasitolog\u00eda M\u00e9dica<\/li><li>Psicolog\u00eda M\u00e9dica<br \/>Investigaci\u00f3n en salud I<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Cirug\u00eda general<\/li><li>Oftalmolog\u00eda<\/li><li>Otorrinolaringolog\u00eda<\/li><li>Investigaci\u00f3n en salud I<\/li><li>Optativo III<br \/>Practica<\/li><li>preprofesional I<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Medicina Interna<\/li><li>Dermatolog\u00eda<\/li><li>Imagenolog\u00eda<\/li><li>Psiquiatr\u00eda<\/li><li>Salud ocupacional<\/li><li>Practica preprofesional II<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Ginecobstetricia<\/li><li>Farmacolog\u00eda Cl\u00ednica<\/li><li>Epidemiolog\u00eda anal\u00edtica<\/li><li>Optativo IV<\/li><li>Practica preprofesional III<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pediatr\u00eda<\/li><li>Medicina Legal<\/li><li>Administraci\u00f3n en salud<\/li><li>Optativo V<\/li><li>Practica preprofesional IV<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7313\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7313\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7313\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17581\" class=\"elementor elementor-17581\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4001d8f9 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"4001d8f9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-56816820\" data-id=\"56816820\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-620c36a2\" data-id=\"620c36a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-789e73bd elementor-widget elementor-widget-heading\" data-id=\"789e73bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Odontolog\u00eda<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62e3eb3a elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"62e3eb3a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e86a5d8\" data-id=\"6e86a5d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c650537 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"c650537\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2071\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2071\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2072\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2072\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2073\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2073\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2071\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2071\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2071\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio del cirujano dentista es la salud estomatogn\u00e1tica. Este profesional tiene la capacidad de realizar actividades de educaci\u00f3n, prevenci\u00f3n y promoci\u00f3n de la salud oral, brindar atenci\u00f3n integral a las patolog\u00edas y alteraciones odontol\u00f3gicas seg\u00fan ciclo de vida.<\/p><p>As\u00ed como, administrar recursos humanos y materiales optimiz\u00e1ndolos en el \u00e1mbito p\u00fablico y privado.<\/p><p>De igual manera, investiga situaciones relacionados con el sistema estomatogn\u00e1tico que den respuesta a problemas concretos en el contexto nacional e internacional, respetando los principios bio\u00e9ticos.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Servicio odontol\u00f3gico p\u00fablico y privado<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Asistencial, promoci\u00f3n y prevenci\u00f3n de la salud bucal, investigaci\u00f3n y administraci\u00f3n odontol\u00f3gica<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2072\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2072\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2072\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>IA\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Principios de Odontolog\u00eda<\/li><li>Anatom\u00eda Humana Aplicada<br \/>Biof\u00edsica<\/li><li>Estrategia Integradora I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Bioqu\u00edmica General<\/li><li>Fisiolog\u00eda General<\/li><li>Materiales Dentales<\/li><li>Estrategia Integradora II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Histoembriolog\u00eda bucodental<\/li><li>Estomatolog\u00eda Morfofuncional<\/li><li>Odontolog\u00eda social y preventiva<\/li><li>Laboratorio dental<\/li><li>Estrategia Integradora III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Farmacolog\u00eda bucodental<\/li><li>Semiolog\u00eda Bucodental<\/li><li>Patolog\u00eda Oral<\/li><li>Odontolog\u00eda Legal y Forense<\/li><li>Estrategia Integradora IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Anestesia Bucodental<\/li><li>Radiolog\u00eda Bucodental<\/li><li>Operatoria Dental I<\/li><li>Medicina Interna para Odontolog\u00eda<\/li><li>Optativo I<\/li><li>Estrategia Integradora V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Cirug\u00eda oral I<br \/>Periodoncia<\/li><li>Operatoria dental II<\/li><li>Endodoncia I<br \/>Optativo II<\/li><li>Estrategia Integradora VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Cirug\u00eda oral II<\/li><li>Operatoria dental III<\/li><li>Endodoncia II<\/li><li>Precl\u00ednica pr\u00f3tesis fija y removible<\/li><li>Optativo III<\/li><li>Estrategia Integradora VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Administraci\u00f3n de consultorio<\/li><li>Cl\u00ednica pr\u00f3tesis fija y removible<\/li><li>Odontopediatr\u00eda I<\/li><li>Investigaci\u00f3n Aplicada<\/li><li>Optativo IV<\/li><li>Estrategia Integradora VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Pr\u00e1cticas profesionalizantes administrativas<\/li><li>Optativo V<\/li><li>Integradora IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas profesionalizantes asistenciales<\/li><li>Optativo VI<\/li><li>Integradora IX<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2073\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2073\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2073\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Chontales<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17584\" class=\"elementor elementor-17584\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-422d00e elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"422d00e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4d479b66\" data-id=\"4d479b66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3cbf4406\" data-id=\"3cbf4406\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c53354d elementor-widget elementor-widget-heading\" data-id=\"1c53354d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Optometr\u00eda M\u00e9dica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-494b2d12 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"494b2d12\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fa45e29\" data-id=\"2fa45e29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d46fba2 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"1d46fba2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4911\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4911\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4912\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4912\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4913\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4913\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4911\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4911\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4911\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la Optometr\u00eda M\u00e9dica es la salud visual humana. Por ello, el profesional tiene como competencia evaluar el sistema visual, brindar la correcci\u00f3n \u00f3ptica y\/o terapia visual seg\u00fan sea el caso, as\u00ed como diagnosticar los problemas oculares m\u00e1s comunes y referir condiciones m\u00e1s serias. De igual manera educa al individuo, la familia y la comunidad, mediante acciones de promoci\u00f3n y prevenci\u00f3n de disfunciones visuales, realiza investigaciones sobre la salud visual que contribuyan a la soluci\u00f3n de problemas del contexto nacional y regional, adem\u00e1s de realizar actividades administrativas en servicios de salud visual. Ello le permite desempe\u00f1arse en unidades de atenci\u00f3n optom\u00e9tricas p\u00fablicas y privadas y otras Instituciones afines.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Unidades de atenci\u00f3n optom\u00e9tricas p\u00fablicas y privadas<\/li><li>Instituciones vinculadas a la salud visual y ocular<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Brinda atenci\u00f3n visual primaria integral al individuo, la familia y la comunidad<\/li><li>Diagnostica las anomal\u00edas de refracci\u00f3n y del sistema de acomodaci\u00f3n y de vergencia del sistema visual a trav\u00e9s de procedimientos optom\u00e9tricos de diagn\u00f3stico cl\u00ednico.<\/li><li>Detecta las condiciones patol\u00f3gicas propias del ojo.<\/li><li>Deriva al profesional sanitario apropiado.<\/li><li>Prescribe correcci\u00f3n mediante lentes oft\u00e1lmicas, lentes de contacto o terapia y ayudas \u00f3pticas para baja visi\u00f3n.<\/li><li>Realiza control de calidad del montaje, par\u00e1metros de adaptaci\u00f3n de las prescripciones \u00f3pticas y ajuste de aros oft\u00e1lmicos.<\/li><li>Realiza acciones educativas sobre prevenci\u00f3n, control y promoci\u00f3n de la salud visual.<\/li><li>Realiza y promueve investigaci\u00f3n para la soluci\u00f3n de problemas en el \u00e1rea de salud visual.<\/li><li>Administra servicios de salud visual.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4912\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4912\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4912\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>\u00d3ptica Geom\u00e9trica<\/li><li>Anatom\u00eda Ocular<\/li><li>Biof\u00edsica<\/li><li>Fundamentos de Optometr\u00eda<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Bioqu\u00edmica<\/li><li>\u00d3ptica Fisiol\u00f3gica<\/li><li>Optometr\u00eda I<\/li><li>Biolog\u00eda General<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Fisiolog\u00eda Ocular<\/li><li>Optometr\u00eda II<\/li><li>Salud P\u00fablica<\/li><li>\u00d3ptica Oft\u00e1lmica I<br \/>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Semiolog\u00eda Ocular<\/li><li>Microbiolog\u00eda y Parasitolog\u00eda Ocular<\/li><li>Optometr\u00eda III<\/li><li>\u00d3ptica Oft\u00e1lmica II<\/li><li>Psicolog\u00eda de la Salud Visual<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Optometr\u00eda Cl\u00ednica I<\/li><li>Percepci\u00f3n Visual<\/li><li>Patolog\u00eda Ocular<\/li><li>Farmacolog\u00eda Ocular<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Optometr\u00eda Cl\u00ednica II<\/li><li>Investigaci\u00f3n Cuantitativa<\/li><li>Optometr\u00eda M\u00e9dica Pedi\u00e1trica<\/li><li>Visi\u00f3n Binocular<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Cl\u00ednica Integral I<\/li><li>Terapia Visual<\/li><li>Investigaci\u00f3n Cualitativa<\/li><li>Lentes de Contacto<\/li><li>Integrador VIII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Cl\u00ednica Integral II<\/li><li>Baja Visi\u00f3n y Rehabilitaci\u00f3n Visual<\/li><li>Investigaci\u00f3n Mixta<\/li><li>Gerencia en servicios de Salud Visual<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Pr\u00e1cticas profesionalizantes<\/li><li>administrativas<br \/>Integrador IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas profesionalizantes asistenciales<\/li><li>Integrador X<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4913\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4913\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4913\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17587\" class=\"elementor elementor-17587\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#polisalar\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5db10de elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"5db10de\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-43b575b2\" data-id=\"43b575b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c645e90\" data-id=\"5c645e90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-743441f8 elementor-widget elementor-widget-heading\" data-id=\"743441f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Anestesia y Reanimaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53982223 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"53982223\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37b09d00\" data-id=\"37b09d00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fbbaed7 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3fbbaed7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1061\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1061\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1062\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1062\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1063\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1063\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1061\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1061\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1061\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la licenciatura en Anestesia y Reanimaci\u00f3n humana es la asistencia al anestesi\u00f3logo antes, durante y despu\u00e9s del acto quir\u00fargico, el profesional de esta licenciatura obtendr\u00e1 las capacidades, habilidades y destrezas para asistir al acto anest\u00e9sico, administrar materiales, equipos y suministros propios de anestesia y resolver problemas en el \u00e1rea de trabajo aplicando el m\u00e9todo investigaci\u00f3n cient\u00edfica.<\/p><p>Estas capacidades, habilidades y destrezas las podr\u00e1n desarrollar en salas operatorias p\u00fablicas o privadas, sala de procedimientos y diagn\u00f3sticos m\u00e9dicos -quir\u00fargico ambulatorio p\u00fablico y privado.<\/p><p>La Carrera en Anestesia y Reanimaci\u00f3n sustenta la formaci\u00f3n de los educandos en la creaci\u00f3n de profesionales con una concepci\u00f3n cient\u00edfica y humanista, con sentido \u00e9tico y cr\u00edtico capaces de responder a situaciones particulares que se le presenten con sentido de responsabilidad, compromiso y de calidad cimentado en criterios como la eficiencia, la gesti\u00f3n, la pertinencia y que tienen como funci\u00f3n ser puestos al servicio del mercado laboral.<\/p><p><strong>Competencias Gen\u00e9ricas<\/strong><\/p><ul><li>Capacidad de comunicarse de manera oral y escrita en diferentes contextos de actuaci\u00f3n.<\/li><li>Habilidad para resolver problemas de manera individual y en equipos, en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n.<\/li><li>Capacidad de demostrar creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional donde se desempe\u00f1a.<\/li><li>Destreza para utiliza las TIC como apoyo para mejorar el aprendizaje de en diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional.<\/li><li>Capacidad para comprender la realidad socio-econ\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds.<\/li><li>Capacidad para mostrar respeto hacia la diversidad cultural como contribuci\u00f3n al buen vivir de los pueblos<\/li><\/ul><p><strong>Competencias Espec\u00edficas<\/strong><\/p><ul><li>Capacidad de asistir al anestesi\u00f3logo antes, durante y despu\u00e9s del acto anest\u00e9sico.<\/li><li>Habilidad para administrar materiales, equipos y suministros propios de anestesia.<\/li><li>Destreza para resolver problemas en el \u00e1rea de trabajo aplicando el m\u00e9todo investigaci\u00f3n cient\u00edfica.<\/li><\/ul><p><strong>Tareas esenciales de la profesi\u00f3n<\/strong><\/p><ul><li>Asiste al anestesi\u00f3logo en todo momento del acto anest\u00e9sico<\/li><li>Maneja correctamente la v\u00eda a\u00e9rea y la ventilaci\u00f3n del paciente<\/li><li>Controla la actividad hemodin\u00e1mica<\/li><li>Hace reanimaci\u00f3n b\u00e1sica y avanzada<\/li><li>Vigila al paciente durante todo el acto anest\u00e9sico<\/li><li>Gestiona la adquisici\u00f3n de materiales, equipos y suministros propios de su campo profesional.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1062\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1062\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1062\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>\u00a0Anatom\u00eda I.<\/li><li>Fisiolog\u00eda I<\/li><li>Embriolog\u00eda<\/li><li>Semiolog\u00eda I<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Anatom\u00eda II<\/li><li>Fisiolog\u00eda II<\/li><li>Semiolog\u00eda II<\/li><li>Fisiopatolog\u00eda I<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>\u00a0Fisiopatolog\u00eda II<\/li><li>Anestesia I<\/li><li>Bioseguridad<\/li><li>Farmacolog\u00eda General<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Farmacolog\u00eda en anestesia I<\/li><li>Anestesia regional<\/li><li>Urgencia I<\/li><li>Reanimaci\u00f3n B\u00e1sica<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>\u00a0Farmacolog\u00eda anestesia II<\/li><li>Administraci\u00f3n en salud I<\/li><li>Urgencia II<\/li><li>Reanimaci\u00f3n Avanzada<\/li><li>Integrador IV<\/li><li>Optativo I<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Anestesia y Comorbilidades<\/li><li>Administraci\u00f3n en salud II<\/li><li>Investigaci\u00f3n cuantitativa<\/li><li>Ventiloterapia<\/li><li>Integrador VI<\/li><li>Optativo II<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Anestesia y especialidades I<\/li><li>Investigaci\u00f3n cualitativa<\/li><li>Anestesia Pedi\u00e1trica I<\/li><li>Anestesia Gineco obst\u00e9trica I<\/li><li>Integrador VII<\/li><li>Optativo III<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Anestesia y especialidades II<\/li><li>Investigaci\u00f3n mixta<\/li><li>Anestesia Pedi\u00e1trica II<\/li><li>Anestesia Gineco obst\u00e9trica II<\/li><li>Integrador VIII<\/li><li>Optativo IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Practicas Profesionalizante asistencial<\/li><li>Integrador IX<\/li><li>Optativo V<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Practicas Profesionalizante administrativo<\/li><li>Integrador X<\/li><li>Optativo VI<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1063\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1063\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1063\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17596\" class=\"elementor elementor-17596\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#polisallbc\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b3d261 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"3b3d261\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6da62026\" data-id=\"6da62026\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3aa01e21\" data-id=\"3aa01e21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-223c94a4 elementor-widget elementor-widget-heading\" data-id=\"223c94a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Bioan\u00e1lisis Cl\u00ednico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2805d444 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"2805d444\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13b5f5ae\" data-id=\"13b5f5ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79de7b2c elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"79de7b2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2041\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2041\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2042\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2042\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2043\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2043\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2041\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2041\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2041\" tabindex=\"0\" hidden=\"false\"><p>El licenciado en Bioan\u00e1lisis Cl\u00ednico tiene como objeto de estudio el an\u00e1lisis de muestras biol\u00f3gicas humanas, por medio de la aplicaci\u00f3n de m\u00e9todos diagn\u00f3sticos, la interpretaci\u00f3n de resultados, la gerencia del laboratorio y la investigaci\u00f3n relacionada con la salud humana.<\/p><p>Por su formaci\u00f3n y como parte del equipo de salud que atiende a la poblaci\u00f3n, el bioanalista cl\u00ednico tendr\u00e1 un desempe\u00f1o profesional basado en la \u00e9tica, humanismo, actitud propositiva, solidario y con liderazgo en laboratorios cl\u00ednicos p\u00fablicos y privados, banco de sangre y servicio transfusional.<\/p><p><strong>Objeto de la profesi\u00f3n<\/strong><\/p><ul><li>An\u00e1lisis de muestras biol\u00f3gicas humanas.<\/li><li>\u00c1mbitos de actuaci\u00f3n.<\/li><li>Laboratorios cl\u00ednicos p\u00fablicos y privados.<\/li><li>Servicio transfusional.<\/li><li>Banco de sangre.<\/li><\/ul><p><strong>Competencias gen\u00e9ricas<\/strong><\/p><ul><li>Se comunica de manera oral y escrita en diferentes contextos de actuaci\u00f3n.<\/li><li>Resuelve problemas de manera individual y en equipos, en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n.<\/li><li>Demuestra creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional donde se desempe\u00f1a.<\/li><li>Utiliza las TIC como apoyo para mejorar el aprendizaje de en diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional.<\/li><li>Comprende la realidad socio-econ\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds.<\/li><\/ul><p><strong>Competencias espec\u00edficas<\/strong><\/p><ul><li>Capacidad para analizar muestras biol\u00f3gicas por medio de m\u00e9todos inmunohematol\u00f3gicos, qu\u00edmicos, inmunol\u00f3gicos y moleculares que permitan la detecci\u00f3n de analitos, elementos formes, par\u00e1sitos tropicales y microbiota de importancia m\u00e9dica.<\/li><li>Capacidad de gerenciar el laboratorio cl\u00ednico mediante la planificaci\u00f3n, organizaci\u00f3n, atracci\u00f3n de recursos humanos, control, direcci\u00f3n y toma de decisiones.<\/li><li>Capacidad de realizar investigaciones en el \u00e1mbito de la salud humana.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2042\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2042\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2042\" tabindex=\"0\" hidden=\"hidden\"><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Introducci\u00f3n al Laboratorio Cl\u00ednico<\/li><li>Matem\u00e1tica Aplicada al Laboratorio Cl\u00ednico<\/li><li>F\u00edsica Aplicada al Laboratorio Cl\u00ednico<\/li><li>Qu\u00edmica General Aplicada al Laboratorio Cl\u00ednico<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>T\u00e9cnicas B\u00e1sicas del Laboratorio Cl\u00ednico<\/li><li>Qu\u00edmica Org\u00e1nica<\/li><li>Anatom\u00eda y fisiolog\u00eda humana<\/li><li>Biolog\u00eda General<\/li><li>Integrador II<b>\u00a0\u00a0<\/b><\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Parasitolog\u00eda tropical I<\/li><li>Inmunolog\u00eda<\/li><li>Histolog\u00eda<\/li><li>Bioqu\u00edmica General<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Hematolog\u00eda general<\/li><li>Biolog\u00eda molecular y celular<\/li><li>Parasitolog\u00eda tropical II<\/li><li>Fisiopatolog\u00eda<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Hematopatolog\u00eda<\/li><li>Qu\u00edmica Anal\u00edtica Cualicuantitativa<\/li><li>Epidemiologia<\/li><li>Bioestad\u00edstica aplicada al laboratorio<\/li><li>Integrador V<\/li><li>Optativo I<b>\u00a0\u00a0<\/b><\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Bioqu\u00edmica cl\u00ednica b\u00e1sica<\/li><li>An\u00e1lisis de l\u00edquidos corporales<\/li><li>Administraci\u00f3n del laboratorio cl\u00ednico<\/li><li>Investigaci\u00f3n cuantitativa<\/li><li>Integrador VI<\/li><li>Optativo II<b>\u00a0\u00a0<\/b><\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Bioqu\u00edmica cl\u00ednica especial<\/li><li>Inmunohematolog\u00eda b\u00e1sica<\/li><li>Gerencia aplicada al laboratorio cl\u00ednico<\/li><li>Investigaci\u00f3n cualitativa<\/li><li>Integrador VII<\/li><li>Optativo III<b>\u00a0\u00a0\u00a0\u00a0<\/b><\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Diagn\u00f3stico microbiol\u00f3gico<\/li><li>Inmunohematolog\u00eda cl\u00ednica<\/li><li>Gesti\u00f3n y control de Calidad<\/li><li>Investigaci\u00f3n mixta<\/li><li>Integrador VIII<\/li><li>Optativo IV<b>\u00a0\u00a0\u00a0<\/b><\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Pr\u00e1cticas profesionalizantes asistenciales<\/li><li>Integrador IX<\/li><li>Optativo V<b>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/b><\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas profesionalizantes administrativas<\/li><li>Integrador X<\/li><li>Optativo VI<b>\u00a0<\/b><\/li><\/ul><p><b>\u00a0\u00a0\u00a0<\/b><\/p><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2043\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2043\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2043\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Chontales<\/li><li>CUR-Matagalpa<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17603\" class=\"elementor elementor-17603\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b287ec8 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"5b287ec8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17d92c4c\" data-id=\"17d92c4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-33baa1df\" data-id=\"33baa1df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5671104c elementor-widget elementor-widget-heading\" data-id=\"5671104c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fisioterapia\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a336d1e elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"1a336d1e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-423b7a9f\" data-id=\"423b7a9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-630934d2 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"630934d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1661\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1661\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1662\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1662\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1663\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1663\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1661\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1661\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1661\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera de fisioterapia es el movimiento corporal humano, siendo esta una profesi\u00f3n del \u00e1rea de la salud de gran importancia. El Fisioterapeuta debe poseer habilidades que le permitan brindar una atenci\u00f3n integral dirigida a mejorar la capacidad funcional del ser humano, tomando en cuenta aspectos f\u00edsicos, psicol\u00f3gicos y sociales. Cumpliendo con los lineamientos nacionales e internacionales pertinentes al ejercicio de la profesi\u00f3n, con valores \u00e9ticos, morales y human\u00edsticos en los diferentes centros de asistencia p\u00fablicas y privadas, Instituciones, centros, federaciones deportivas y otras entidades vinculadas a fisioterapia.<\/p><p>Debe ser capaz de implementar programas de promoci\u00f3n de la salud f\u00edsica y prevenci\u00f3n de las enfermedades con un enfoque global regional e internacional. Este ejecuta procesos de gesti\u00f3n de recursos materiales y humanos para la habilitaci\u00f3n y administraci\u00f3n de servicios de fisioterapia que cumplan los requerimientos necesarios para una atenci\u00f3n con calidad y calidez.<\/p><p>Por otra parte, dicho profesional es capaz de desarrollar investigaciones para fortalecer el quehacer profesional y generar evidencia que contribuya a la soluci\u00f3n de los principales problemas del individuo, la familia y la comunidad, vinculados a Fisioterapia.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Centros de asistencia p\u00fablicas y privadas vinculadas a la fisioterapia<\/li><li>Institutos, centros y federaciones deportivas.<\/li><li>Otras entidades vinculadas a fisioterapia. (ONG, Empresas, consulta privada en la comunidad)<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><p>Competencias gen\u00e9ricas:<\/p><ul><li>Capacidad de comunicarse de manera oral y escrita en diferentes contextos de actuaci\u00f3n.<\/li><li>Capacidad de resolver problemas de manera individual y en equipos, en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n.<\/li><li>Capacidad de demostrar creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional donde se desempe\u00f1a.<\/li><li>Capacidad de utilizar las TIC como apoyo para mejorar el aprendizaje en diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional.<\/li><li>Capacidad de comprender la realidad socio-econ\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds.<\/li><\/ul><p>Competencias especificas:<\/p><ul><li>Capacidad para brindar atenci\u00f3n Integral en fisioterapia para mejorar la capacidad funcional del ser humano, seg\u00fan ciclo de vida considerando los aspectos f\u00edsicos, psicol\u00f3gicos y sociales<\/li><li>Capacidad de implementar acciones de promoci\u00f3n de la salud f\u00edsica y prevenci\u00f3n de discapacidades en personas y colectivos<\/li><li>Capacidad de ejecutar acciones de gesti\u00f3n en procesos administrativos de recursos materiales y humanos de los servicios en fisioterapia<\/li><li>Capacidad de ejecutar proyectos de investigaci\u00f3n que contribuyan a la resoluci\u00f3n de problemas en el contexto de Fisioterapia<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1662\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1662\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1662\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Anatom\u00eda Aplicada a Fisioterapia I<\/li><li>Fisiolog\u00eda I<\/li><li>Biolog\u00eda Celular<\/li><li>Matem\u00e1tica<\/li><li>Integrador 1<\/li><li>Electiva 1<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Anatom\u00eda Aplicada a Fisioterapia II<\/li><li>Fisiolog\u00eda II<\/li><li>Biomec\u00e1nica<\/li><li>F\u00edsica Aplicada a Fisioterapia<\/li><li>Integrador 2<\/li><li>Electiva 2<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Fisiopatolog\u00eda I<\/li><li>Bioqu\u00edmica B\u00e1sica<\/li><li>Evaluaci\u00f3n Cl\u00ednica<\/li><li>Funcional I<\/li><li>Patolog\u00eda Cl\u00ednica I<\/li><li>Integrador 3<\/li><li>Electiva 3<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Fisiopatolog\u00eda II<\/li><li>Evaluaci\u00f3n Cl\u00ednica Funcional II<\/li><li>Farmacolog\u00eda para Fisioterapeutas<\/li><li>Patolog\u00eda Cl\u00ednica II<\/li><li>Integrador 4<\/li><li>Electiva 2<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Fisioterapia Dermofuncional<\/li><li>Epidemiologia<\/li><li>Administraci\u00f3n en Salud I<\/li><li>Integrador 5<\/li><li>Optativo 1<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Fisioterapia del Sistema Osteomioarticular<\/li><li>Salud publica I<\/li><li>Metodolog\u00eda Cuantitativa<\/li><li>Integrador 6<\/li><li>Optativo 2<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Fisioterapia Cardiorrespiratoria<\/li><li>Salud Comunitaria<\/li><li>Metodolog\u00eda Cualitativa<\/li><li>Integrador 7<\/li><li>Optativo 3<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Fisioterapia Neurol\u00f3gica<\/li><li>Administraci\u00f3n en Salud II<\/li><li>Metodolog\u00eda Mixta<\/li><li>Salud P\u00fablica II<\/li><li>Integrador 8<\/li><li>Optativo 4<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Practica de Formaci\u00f3n Profesional Asistencial<\/li><li>Integrador 9<\/li><li>Optativo 5<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Practica de Formaci\u00f3n Profesional Administrativa<\/li><li>Integrador 10<\/li><li>Optativo 6<\/li><li>Modalidad de graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1663\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1663\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1663\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17610\" class=\"elementor elementor-17610\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2da4d3d1 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"2da4d3d1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2982930e\" data-id=\"2982930e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-54db43c5\" data-id=\"54db43c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7875a23f elementor-widget elementor-widget-heading\" data-id=\"7875a23f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Enfermer\u00eda<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50bc33cb elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"50bc33cb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78d63656\" data-id=\"78d63656\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2490ed35 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"2490ed35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6131\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6131\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6132\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6132\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6133\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6133\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6131\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6131\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6131\" tabindex=\"0\" hidden=\"false\"><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Unidades de salud de atenci\u00f3n primaria y secundaria<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>El objeto de estudio de la carrera, es el cuidado de la salud humana integrando los conocimientos, habilidades y destrezas propios de las Ciencias de Enfermer\u00eda. Realizando acciones de promoci\u00f3n de la salud y prevenci\u00f3n de enfermedades, as\u00ed como gestiona, dirige, monitorea, controla recursos humanos, equipos, materiales y desarrolla investigaci\u00f3n en salud.<\/li><li>El profesional de enfermer\u00eda puede desempe\u00f1arse en unidades de salud de atenci\u00f3n primaria y secundaria p\u00fablicas, privadas y otras instituciones, siendo capaz de trabajar con el equipo multidisciplinario en la atenci\u00f3n integral, mediante la comunicaci\u00f3n efectiva, con principios, valores \u00e9ticos, morales, espirituales y respeto a la diversidad cultural.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6132\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6132\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6132\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Anatom\u00eda Humana I.<\/li><li>Fisiolog\u00eda Humana I<\/li><li>Bioqu\u00edmica<\/li><li>Manejo de riesgo en enfermer\u00eda<\/li><li>Componente curricular integrador 1<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Anatom\u00eda Humana II<\/li><li>Fisiolog\u00eda Humana II<br \/>Asistencia de enfermer\u00eda en higiene y confort<\/li><li>Farmacolog\u00eda para Enfermer\u00eda I<\/li><li>Componente curricular integrador 2<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Fisiopatolog\u00eda<\/li><li>Enfermera I<\/li><li>Farmacolog\u00eda para enfermer\u00eda II<\/li><li>Enfermer\u00eda m\u00e9dico quir\u00fargica I<\/li><li>Enfermer\u00eda en la atenci\u00f3n primaria en salud<\/li><li>Componente curricular integrador 3<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Exploraci\u00f3n f\u00edsica<br \/>Fisiopatolog\u00eda<\/li><li>Enfermera II<\/li><li>Enfermer\u00eda m\u00e9dico quir\u00fargica II<\/li><li>Educaci\u00f3n para la salud en enfermer\u00eda<\/li><li>Componente curricular Integrador 4<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Enfermer\u00eda ginecol\u00f3gica<\/li><li>Proceso de atenci\u00f3n de enfermer\u00eda<\/li><li>Fundamentos de epidemiolog\u00eda para Enfermer\u00eda<\/li><li>Introducci\u00f3n a la investigaci\u00f3n<\/li><li>Componente curricular integrador 5<\/li><li>Optativo 1<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Enfermer\u00eda de la mujer<\/li><li>Asistencia de enfermer\u00eda pre hospitalaria<\/li><li>Enfermer\u00eda educativa<\/li><li>Investigaci\u00f3n cuantitativa<\/li><li>Componente curricular integrador 6<\/li><li>Optativo 2<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Enfermer\u00eda de la ni\u00f1ez y adolescencia<\/li><li>Programaci\u00f3n educativa en Enfermer\u00eda I<\/li><li>Introducci\u00f3n a la administraci\u00f3n<\/li><li>Investigaci\u00f3n cualitativa<\/li><li>Componente curricular integrador 7<\/li><li>Optativo 3<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Cuidados enfermeros de salud psicosocial<\/li><li>Programaci\u00f3n educativa en Enfermer\u00eda II<\/li><li>Administraci\u00f3n en salud<\/li><li>Investigaci\u00f3n mixta<\/li><li>Componente curricular integrador 8<\/li><li>Optativo 4<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Pr\u00e1cticas de formaci\u00f3n profesional asistencial<\/li><li>Componente curricular integrador 9<\/li><li>Optativo 5<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas de formaci\u00f3n profesional gerencial<\/li><li>Componente curricular integrador 10<\/li><li>Optativo 6<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6133\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6133\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6133\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Chontales<\/li><li>CUR-Matagalpa<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17613\" class=\"elementor elementor-17613\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#polisalleop\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-207f7a09 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"207f7a09\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-132de788\" data-id=\"132de788\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-350df222\" data-id=\"350df222\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46a28a08 elementor-widget elementor-widget-heading\" data-id=\"46a28a08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Enfermer\u00eda Obst\u00e9trica y Perinatal<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f43447f elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"2f43447f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33b5c208\" data-id=\"33b5c208\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35206b28 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"35206b28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8911\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8911\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8911\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8911\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8911\" tabindex=\"0\" hidden=\"false\"><p>El profesional de enfermer\u00eda de Licenciatura Obst\u00e9trica y Perinatal tiene la capacidad de brindar atenci\u00f3n integral durante el ciclo vital de la persona en todas sus fases: salud reproductiva, climaterio y sexualidad, lo que permite la detecci\u00f3n precoz de cualquier alteraci\u00f3n en el estado fisiol\u00f3gico y ofrecer las mejores pr\u00e1cticas desde el punto de vista t\u00e9cnico de la relaci\u00f3n interpersonal y de respeto a la interculturalidad; tambi\u00e9n permite el aseguramiento del bienestar del binomio madre \u2013 hijo en las mejores condiciones posibles.<\/p><p>Por su formaci\u00f3n en Obstetricia y Perinatolog\u00eda labora en los servicios de gineco-obstetricia, neonatolog\u00eda, programas de salud y otras instituciones tanto p\u00fablicas y privadas, integrando el equipo multidisciplinario en la atenci\u00f3n integral de la persona y familia, mediante la comunicaci\u00f3n efectiva, trabajo en equipo y liderazgo; con principios y valores \u00e9ticos, morales, espirituales y respeto a la diversidad cultural.<\/p><p><strong>Objeto de estudio de la profesi\u00f3n<\/strong><\/p><ul><li>El cuidado obst\u00e9trico y perinatal a la persona en los diferentes ciclos de vida.<\/li><\/ul><p><strong>\u00c1mbito de actuaci\u00f3n<\/strong><\/p><ul><li>Servicios de gineco-obstetricia y neonatolog\u00eda de hospitales p\u00fablicos y privados.<\/li><li>Programas de salud de la mujer y el neonato en el primer nivel de atenci\u00f3n.<\/li><li>Casa maternas<\/li><li>ONG<\/li><li>Universidades.<\/li><\/ul><p><strong>Competencias gen\u00e9ricas<\/strong><\/p><ul><li>Capacidad de comunicarse de manera oral y escrita en diferentes contextos de actuaci\u00f3n.<\/li><li>Capacidad de identificar y resolver problemas de manera individual y en equipos, en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n.<\/li><li>Capacidad de demostrar creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional donde se desempe\u00f1a.<\/li><li>Capacidad para utilizar las TIC como apoyo para mejorar el aprendizaje en diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional.<\/li><li>Capacidad de comprender la realidad socio-econ\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds y actuar en su desarrollo social.<\/li><\/ul><p><strong>Competencias Especificas<\/strong><\/p><ul><li>Capacidad de brindar cuidados de salud obst\u00e9tricos y perinatales mediante t\u00e9cnica y procedimientos especializados para la resoluci\u00f3n de problemas de salud de la persona en los diferentes ciclos de vida y niveles de atenci\u00f3n.<\/li><li>Capacidad de gerenciar programas y servicios de salud mediante la aplicaci\u00f3n de las etapas administrativa, con el fin de mejorar la calidad de atenci\u00f3n en salud y lograr la satisfacci\u00f3n de las demandas de las personas.<\/li><li>Capacidad de desarrollar actividades educativas de promoci\u00f3n de la salud sexual, reproductiva y neonatal, mediante estrategias de educaci\u00f3n para la salud con el fin de prevenir enfermedades y eventos de salud en los diferentes ciclos de vida de la persona.<\/li><li>Capacidad de desarrollar investigaci\u00f3n en salud mediante el m\u00e9todo cient\u00edfico para contribuir a la soluci\u00f3n de problemas relacionados a la sexual y reproductiva.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17632\" class=\"elementor elementor-17632\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#polisallecc\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66577049 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"66577049\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78f28f62\" data-id=\"78f28f62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59fff0e7\" data-id=\"59fff0e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-326970ff elementor-widget elementor-widget-heading\" data-id=\"326970ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Enfermer\u00eda en Cuidados Cr\u00edticos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35abef0c elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"35abef0c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-697b215a\" data-id=\"697b215a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c3549ef elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"4c3549ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1271\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1271\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1271\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1271\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1271\" tabindex=\"0\" hidden=\"false\"><p>El profesional de enfermer\u00eda de la ruta cr\u00edtica tiene s\u00f3lidas competencias disciplinares y alta sensibilidad social, con capacidad para dar respuesta a las personas cr\u00edticamente enfermas. Domina y maneja equipos biotecnol\u00f3gicos, as\u00ed como t\u00e9cnicas y procedimientos especializados, implementa modelos de gesti\u00f3n y proyectos de investigaci\u00f3n que contribuyen a un cuidado de calidad y la soluci\u00f3n de los problemas de salud de la poblaci\u00f3n.<\/p><p>Por su formaci\u00f3n en la ruta cr\u00edtica es capaz de trabajar en las instituciones prestadoras de servicios de salud p\u00fablicos, privados y otras instituciones, integrando el equipo multidisciplinario en la atenci\u00f3n integral del paciente en la ruta cr\u00edtica, mediante la comunicaci\u00f3n efectiva, trabajo en equipo y liderazgo; con principios y valores \u00e9ticos, morales, espirituales y respeto a la diversidad cultural.<\/p><p><strong>Objeto de estudio de la profesi\u00f3n<\/strong><\/p><ul><li>Prevenci\u00f3n y cuidado de la salud de la persona cr\u00edticamente enferma.<br \/>\u00c1mbito de actuaci\u00f3n<\/li><li>Ruta Cr\u00edtica de las instituciones prestadoras de servicios de salud p\u00fablicas y privadas.<\/li><li>Agencias de cuidados de salud.<\/li><li>Direcci\u00f3n de enfermer\u00eda en la ruta cr\u00edtica de hospitales p\u00fablicos o privados.<\/li><li>ONG<\/li><li>Universidades.<\/li><li>Consultor\u00eda.<\/li><\/ul><p><strong>Competencias Gen\u00e9ricas<\/strong><\/p><ul><li>Capacidad de comunicarse de manera oral y escrita en diferentes contextos de actuaci\u00f3n.<\/li><li>Capacidad de identificar y resolver problemas de manera individual y en equipos, en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n.<\/li><li>Capacidad de demostrar creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional donde se desempe\u00f1a.<\/li><li>Capacidad para utilizar las TIC como apoyo para mejorar el aprendizaje en diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional.<\/li><li>Capacidad de comprender la realidad socio-econ\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds y actuar en su desarrollo social.<\/li><\/ul><p><strong>Competencias Especificas<\/strong><\/p><ul><li>Capacidad de brindar cuidados a la salud en las unidades de la ruta cr\u00edtica mediante el uso y manejo de equipos biotecnol\u00f3gicos para incidir en la calidad de vida de la persona en los diferentes campos de actuaci\u00f3n en el desempe\u00f1o profesional.<\/li><li>Capacidad de administrar y ejecutar proyectos, programas y servicios de salud a trav\u00e9s de la implementaci\u00f3n de modelos de gesti\u00f3n de la calidad con el fin de mejorar los procesos de organizaci\u00f3n y satisfacer las demandas de las personas.<\/li><li>Capacidad de desarrollar investigaci\u00f3n en salud mediante el m\u00e9todo cient\u00edfico para contribuir a la soluci\u00f3n de problemas epidemiol\u00f3gicos y cl\u00ednicos dentro del objeto de estudio de la profesi\u00f3n.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17641\" class=\"elementor elementor-17641\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#polisalesp\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a3795f4 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"1a3795f4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4ec5a2c8\" data-id=\"4ec5a2c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6dcd125\" data-id=\"6dcd125\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44196fbe elementor-widget elementor-widget-heading\" data-id=\"44196fbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura Enfermer\u00eda en Salud P\u00fablica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a5d8a3e elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"3a5d8a3e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b674068\" data-id=\"1b674068\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5da4b9df elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"5da4b9df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1571\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1571\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1571\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1571\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1571\" tabindex=\"0\" hidden=\"false\"><p>La salud p\u00fablica es la encargada de la protecci\u00f3n de la salud a nivel poblacional. Tiene por objetivo mejorara la salud de la poblaci\u00f3n, as\u00ed como la vigilancia y control de las enfermedades, conlleva un proceso de intervenci\u00f3n en la comunidad, permite la innovaci\u00f3n de estrategias y creatividad al servicio de la persona, familia, y la comunidad.<br \/>Est\u00e1 dise\u00f1ada para comprender los problemas y necesidades biol\u00f3gicas, psicol\u00f3gicas y sociales en la salud y el medioambiente con base en las funciones esenciales de las saludes publica y las determinantes sociales de la salud en apoyo a los objetivos de desarrollo sostenibles (ODS).<br \/>Se auxilia de un conjunto de otras ciencias como las ciencias de la salud y particularmente de la epidemiologia, cuyo rol ha sido protag\u00f3nico al evaluar los fen\u00f3menos sanitarios, lo que vislumbran importantes desarrollos en \u00e1reas asociadas a la investigaci\u00f3n.<\/p><p>Objeto de la profesi\u00f3n: Cuidado de la Salud a Nivel Individual, Familiar y Comunitario.<\/p><p><strong>\u00c1mbito de actuaci\u00f3n<\/strong><\/p><ul><li>Instituciones de salud P\u00fablica y Privada.<\/li><li>Empresas medica previsionales.<\/li><li>Organismo no Gubernamentales (ONG).<\/li><li>Instituciones Educativas.<\/li><li>Hogares de Adulto Mayor.<\/li><li>Pr\u00e1cticas Profesionales Independiente (Cuidados enfermeros a domicilios).<\/li><li>Industrias (Centros alimenticios).<\/li><li>Competencia Gen\u00e9rica.<\/li><li>Capacidad de comunicarse de manera oral y escrita en diferentes contextos de actuaci\u00f3n.<\/li><li>Habilidad para resolver problemas de manera individual y en equipos, en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n.<\/li><li>Capacidad de demostrar creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional donde se desempe\u00f1a.<\/li><li>Destreza para utiliza las TIC como apoyo para mejorar el aprendizaje de en diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional.<\/li><li>Capacidad para comprender la realidad socio-econ\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds.<\/li><li>Capacidad para mostrar respeto hacia la diversidad cultural como contribuci\u00f3n al buen vivir de los pueblos.<\/li><\/ul><p><strong>Competencia especifica<\/strong><\/p><ul><li>Domina las funciones esenciales y el arte de promocionar y restaurarla salud, prevenir enfermedades con el esfuerzo organizado de las personas, la familia, la comunidad y las alianzas intersectoriales.<\/li><li>Domina los procedimientos b\u00e1sicos y complementarios de la profesi\u00f3n, que les permita brindar atenci\u00f3n segura y de calidad en la prevenci\u00f3n, diagn\u00f3stico, tratamiento y rehabilitaci\u00f3n de la salud a trav\u00e9s del Proceso de Atenci\u00f3n de Enfermer\u00eda.<\/li><li>Capacidad de realizar an\u00e1lisis de la situaci\u00f3n de salud y sus determinantes, enfatizando en la identificaci\u00f3n de riesgos y da\u00f1os a la salud.<\/li><li>Capacidad de realizar investigaci\u00f3n cient\u00edfica y vigilancia epidemiol\u00f3gica para la toma de decisiones en todos los niveles de atenci\u00f3n.<\/li><li>Habilidad para implementar programas educativos que promuevan estilos de vida saludables con la activa participaci\u00f3n ciudadana, enfatizando en los grupos de poblaci\u00f3n en riesgo.<\/li><li>Habilidades gerenciales que destaquen el liderazgo, la comunicaci\u00f3n y negociaci\u00f3n en funci\u00f3n de acciones de promoci\u00f3n de la salud, constituci\u00f3n de redes y alianzas con la sociedad organizada.<\/li><li>Capacidad para planificar y ejecutar acciones de prevenci\u00f3n, mitigaci\u00f3n, preparaci\u00f3n y rehabilitaci\u00f3n temprana ante emergencias o posibles desastres que afectan la salud y la vida de las personas con la colaboraci\u00f3n intersectorial.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17654\" class=\"elementor elementor-17654\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ac1eb0e elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"1ac1eb0e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e9183d7\" data-id=\"6e9183d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-74487875\" data-id=\"74487875\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-475196bc elementor-widget elementor-widget-heading\" data-id=\"475196bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Microbiolog\u00eda\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dd5fe18 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"5dd5fe18\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41f9c5a8\" data-id=\"41f9c5a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6176fb78 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"6176fb78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1631\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1631\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1632\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1632\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1633\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1633\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1631\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1631\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1631\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la microbiolog\u00eda es el an\u00e1lisis microbiol\u00f3gico para la salud humana, industria, ambiente. Por ello, el licenciado en microbiolog\u00eda domina diferentes m\u00e9todos diagn\u00f3sticos para el aislamiento e identificaci\u00f3n de microorganismos en diferentes matrices, as\u00ed como la capacidad de investigar la presencia de microorganismos emergentes y reemergentes que afecten la salud humana, tambi\u00e9n identifica microrganismos ben\u00e9ficos para los humanos y medio ambiente.<\/p><p>Por su formaci\u00f3n en el an\u00e1lisis microbiol\u00f3gico, puede desempe\u00f1ase profesionalmente con \u00e9tica y humanismo en el campo laboral en la empresa privada, el sector p\u00fablico, u organismos no gubernamentales que demandan el servicio en las diferentes \u00e1reas de inter\u00e9s como: salud p\u00fablica, industria, farmac\u00e9utica, alimentaria, biotecnol\u00f3gica entre otros.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Unidades de salud de atenci\u00f3n primaria y secundaria p\u00fablica y privada.<\/li><li>Industrias alimentarias.<\/li><li>Otras entidades vinculadas al quehacer microbiol\u00f3gico.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><p>Competencias gen\u00e9ricas:<\/p><ul><li>Capacidad de comunicarse oral y escrita en diferentes contextos de actuaci\u00f3n.<\/li><li>Capacidad de resolver problemas de manera individual y en equipos, en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n.<\/li><li>Capacidad de demostrar creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional donde se desempe\u00f1a.<\/li><li>Capacidad de utilizar las TIC como apoyo para mejorar el aprendizaje de en diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional.<\/li><li>Capacidad de comprender la realidad socio-econ\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds.<\/li><\/ul><p>Competencias espec\u00edficas:<\/p><ul><li>Capacidad de identificar microorganismos, metabolitos y elementos formes en muestras infecciosas y no infecciosas aplicando t\u00e9cnicas diagn\u00f3sticas convencionales y especializadas.<\/li><li>Capacidad para investigar problemas del \u00e1mbito microbiol\u00f3gico que afecten la salud humana y ambiental, que contribuyan a su soluci\u00f3n.<\/li><li>Capacidad para aplicar el sistema de gesti\u00f3n de la calidad en un laboratorio, que garanticen el funcionamiento y la calidad de los procesos anal\u00edticos.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1632\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1632\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1632\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Eje introducci\u00f3n a los desempe\u00f1os profesionales y ciudadanos<\/li><li>Biolog\u00eda general y celular<\/li><li>Matem\u00e1tica aplicada a la Microbiolog\u00eda<\/li><li>Qu\u00edmica org\u00e1nica<\/li><li>T\u00e9cnicas b\u00e1sicas<\/li><li>Electivo<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>F\u00edsica aplicada a la microbiolog\u00eda<\/li><li>Anatom\u00eda humana<\/li><li>Fisiolog\u00eda Microbiana<\/li><li>Qu\u00edmica inorg\u00e1nica<\/li><li>Electivo<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Histolog\u00eda<\/li><li>Bioqu\u00edmica General<\/li><li>Parasitolog\u00eda cl\u00ednica 1<\/li><li>Diagnostico inmunol\u00f3gico<\/li><li>Electivo<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>An\u00e1lisis Instrumental aplicado a la Microbiolog\u00eda<\/li><li>Fisiopatolog\u00eda<\/li><li>Parasitolog\u00eda cl\u00ednica 2<\/li><li>Bacteriolog\u00eda 1<\/li><li>Electivo<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Virolog\u00eda<\/li><li>Bacteriolog\u00eda 2<\/li><li>Biolog\u00eda molecular<\/li><li>Epidemiologia<\/li><li>Optativo I A \/Optativo I B<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Bacteriolog\u00eda 3<\/li><li>Micolog\u00eda<\/li><li>Calidad Microbiol\u00f3gica del ambiente<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n cuantitativa<\/li><li>Optativo II A\/Optativo II B<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Metodolog\u00eda de la Investigaci\u00f3n cualitativa<\/li><li>Calidad Microbiol\u00f3gica de los alimentos<\/li><li>Microbiolog\u00eda Industrial<\/li><li>Administraci\u00f3n<\/li><li>Optativo IIIA\/Optativo III B<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Sistema de Gesti\u00f3n de la calidad<\/li><li>Investigaci\u00f3n Mixta<\/li><li>Biotecnolog\u00eda agr\u00edcola<\/li><li>Gen\u00e9tica Microbiana<\/li><li>Optativo IV A\/Optativo IV B<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Pr\u00e1cticas Profesionales (Asistenciales)<\/li><li>Optativo V A\/Optativo V B<\/li><li>Integrador XI<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Profesionalizante (Administrativas)<\/li><li>Optativo VI A\/Optativo VI B<\/li><li>Integrador X<\/li><li>Modalidad Graduaci\u00f3n<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1633\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1633\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1633\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17665\" class=\"elementor elementor-17665\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40afd081 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"40afd081\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-160c45ab\" data-id=\"160c45ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-93ed245\" data-id=\"93ed245\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-251dd892 elementor-widget elementor-widget-heading\" data-id=\"251dd892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nutrici\u00f3n <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27de0e79 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"27de0e79\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-259d3371\" data-id=\"259d3371\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3769d123 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3769d123\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9291\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9291\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9292\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9292\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9293\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9293\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9291\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9291\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9291\" tabindex=\"0\" hidden=\"false\"><p>El objeto de la profesi\u00f3n del nutricionista es la nutrici\u00f3n humana.<\/p><p>Por ello, debe ser capaz de brindar atenci\u00f3n nutricional al individuo, la familia y la comunidad, en situaciones de riesgo y enfermedad aplicando las normas nacionales y regionales. As\u00ed mismo, debe dar seguimiento a las intervenciones nutricionales y alimentarias para personas sanas y enfermas para contribuir a la salud p\u00fablica y al desarrollo humano sostenible, en entidades p\u00fablicas y privadas.<\/p><p>Adem\u00e1s, debe ser capaz de desarrollar acciones de promoci\u00f3n de la salud y prevenci\u00f3n de enfermedades con el fin de aportar a la mejora de la calidad de vida de la poblaci\u00f3n.<\/p><p>El profesional de la nutrici\u00f3n debe llevar a cabo investigaciones en los diferentes contextos de la nutrici\u00f3n para contribuir a la soluci\u00f3n de la problem\u00e1tica de salud, alimentaci\u00f3n y nutrici\u00f3n, considerando el perfil epidemiol\u00f3gico, la situaci\u00f3n socio- econ\u00f3mica, tecnol\u00f3gica, cultural y ambiental con sentido \u00e9tico y cr\u00edtico a nivel individual, familiar y comunitario.<\/p><p>Otro campo del profesional de la nutrici\u00f3n es la gesti\u00f3n administrativa de los servicios de alimentaci\u00f3n institucional para contribuir a la calidad alimentaria y al buen estado nutricional de la poblaci\u00f3n.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Unidades y servicios de salud p\u00fablicos y privados.<\/li><li>Otras instituciones afines al \u00e1rea de salud y nutrici\u00f3n.<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><p>Competencias gen\u00e9ricas:<\/p><ul><li>Capacidad para comunicarse de manera oral y escrita en diferentes contextos de actuaci\u00f3n<\/li><li>Capacidad de identificar y resolver problemas de manera individual y en equipos, en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n<\/li><li>Capacidad de demostrar creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional donde se desempe\u00f1a<\/li><li>Capacidad para utilizar las TIC como apoyo para mejorar el aprendizaje de en diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional<\/li><li>Capacidad de comprender la realidad socio-econ\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds y actuar en su desarrollo social<\/li><\/ul><p>Competencias espec\u00edficas:<\/p><ul><li>Capacidad de brindar atenci\u00f3n nutricional al individuo, la familia y la comunidad aplicando los protocolos, los m\u00e9todos, los procedimientos estandarizados y los normados a nivel nacional y regional para mejorar el estado de salud y nutrici\u00f3n<\/li><li>Capacidad de investigar cient\u00edficamente los problemas en el campo de la salud y la seguridad alimentaria y nutricional, para el planteamiento de soluciones considerando la pertinencia y el pensamiento cr\u00edtico<\/li><li>Capacidad de ejecutar acciones de promoci\u00f3n de la salud y nutrici\u00f3n, prevenci\u00f3n de enfermedades y de alteraciones en el estado nutricional para contribuir a la mejora de la calidad de vida<\/li><li>Capacidad de ejecutar acciones de gesti\u00f3n administrativa en los procesos involucrados en la planificaci\u00f3n, elaboraci\u00f3n, control y seguimiento de la producci\u00f3n de alimentos para la alimentaci\u00f3n colectiva, considerando par\u00e1metros alimentarios y nutricionales, que contribuyan a un buen estado de salud.<\/li><li>Estas competencias se integran de forma transversal en los componentes curriculares, que incluyen los ejes integradores. La competencia de investigaci\u00f3n es integradora por lo tanto es un elemento esencial de los ejes integradores.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9292\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9292\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9292\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Cuerpo Humano I<\/li><li>Matem\u00e1tica aplicada a la Nutrici\u00f3n<\/li><li>Evaluaci\u00f3n nutricional<\/li><li>Nutrici\u00f3n en el ciclo de vida y estados fisiol\u00f3gicos<br \/>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Cuerpo Humano II<\/li><li>Qu\u00edmica aplicada a la Nutrici\u00f3n<\/li><li>Educaci\u00f3n Alimentaria Nutricional<\/li><li>Atenci\u00f3n nutricional I<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Cuerpo Humano III<\/li><li>Bioqu\u00edmica de la nutrici\u00f3n<\/li><li>Atenci\u00f3n nutricional II<\/li><li>Consumo de alimentos<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Qu\u00edmica de los alimentos<\/li><li>An\u00e1lisis y control de alimentos<\/li><li>Alimentaci\u00f3n institucional I<\/li><li>Atenci\u00f3n nutricional III<\/li><li>Preparaci\u00f3n de alimentos I<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Bioestad\u00edstica<br \/>Epidemiologia aplicada a la Nutrici\u00f3n<\/li><li>Alimentaci\u00f3n institucional II<\/li><li>Preparaci\u00f3n de alimentos II<\/li><li>Optativa 1<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Salud p\u00fablica y nutrici\u00f3n<\/li><li>Investigaci\u00f3n I<\/li><li>Administraci\u00f3n y gerencia de los servicios de alimentaci\u00f3n I<\/li><li>Seguridad Alimentaria y Nutricional<\/li><li>Optativa 2<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Investigaci\u00f3n II<\/li><li>Proyectos de salud y nutrici\u00f3n I<\/li><li>Administraci\u00f3n y gerencia de los servicios de alimentaci\u00f3n II<\/li><li>Optativa 3<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Proyectos de salud y nutrici\u00f3n II<\/li><li>Nutrici\u00f3n en situaciones especiales<\/li><li>Legislaci\u00f3n en nutrici\u00f3n y salud<\/li><li>Optativa 4<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Pr\u00e1cticas de formaci\u00f3n profesional cl\u00ednica-gerenciales<\/li><li>Optativa 5<\/li><li>Integrador IX<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas de formaci\u00f3n profesional comunitarias<\/li><li>Optativa 6<\/li><li>Integrador X<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9293\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9293\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9293\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17671\" class=\"elementor elementor-17671\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#polisaltscc\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f3bdad9 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"5f3bdad9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51a0e50\" data-id=\"51a0e50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ddf1c61\" data-id=\"2ddf1c61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38e6b06b elementor-widget elementor-widget-heading\" data-id=\"38e6b06b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9cnico Superior en Citolog\u00eda Cervical<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-691e2629 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"691e2629\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e22578\" data-id=\"6e22578\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30e5ef2a elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"30e5ef2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8201\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8201\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8202\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8202\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8203\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8203\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8201\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8201\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8201\" tabindex=\"0\" hidden=\"false\"><p>Este profesional se desempe\u00f1ar\u00e1 en el campo del diagn\u00f3stico citol\u00f3gico y procesamiento citohistol\u00f3gico de muestras biol\u00f3gicas.<\/p><p>El T\u00e9cnico Superior en Citolog\u00eda Cervical se desarrollar\u00e1 en el \u00e1rea asistencial ya que es eminente la necesidad de diagn\u00f3stico citol\u00f3gico tanto para citolog\u00eda cervical como de otros sitios anat\u00f3micos, adem\u00e1s de ser capaz de realizar todas las t\u00e9cnicas de procesamiento de tejidos.<\/p><p>Tendr\u00e1 como elemento fundamental el servicio profesional basado en el humanismo, actitud propositiva, solidario y con liderazgo en laboratorios de patolog\u00eda interactuando con diferentes miembros del equipo de salud y la comunidad. El modelo basado en la familia, individuo y comunidad trasciende las metas de la formaci\u00f3n, mediante sus conocimientos se podr\u00e1 realizar investigaciones que contribuyan al manejo epidemiol\u00f3gico y toma de decisiones para enfrentar la carga de morbilidad referente a las patolog\u00edas malignas que afectan a la poblaci\u00f3n<\/p><p><strong>Competencias Gen\u00e9ricas<\/strong><\/p><ul><li>Se comunica de manera oral y escrita en diferentes contextos de actuaci\u00f3n.<\/li><li>Resuelve problemas de manera individual y en equipos, en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n.<\/li><li>Demuestra creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional donde se desempe\u00f1a.<\/li><li>Utiliza las TIC como apoyo para mejorar el aprendizaje de en diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional.<\/li><li>Comprende la realidad socio-econ\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds.<\/li><li>Muestra respeto hacia la diversidad cultural como contribuci\u00f3n al buen vivir de los pueblos.<\/li><\/ul><p><strong>Competencias Espec\u00edficas<\/strong><\/p><ul><li>Capacidad de preparar muestras de citolog\u00eda y espec\u00edmenes de biopsias.<\/li><li>Elimina residuos y selecciona los tejidos y muestras para el an\u00e1lisis de biopsias.<\/li><li>Aplica t\u00e9cnicas de tinciones b\u00e1sicas y especiales.<\/li><li>Capacidad de programar procesador de tejido para biopsias.<\/li><li>Tendr\u00e1 la capacidad de realizar investigaciones con equipos multidisciplinarios desde su \u00e1mbito de salud.<\/li><li>Verifica datos de filiaci\u00f3n.<\/li><li>Ingresa y numera filial a cada citolog\u00eda y biopsia.<\/li><li>Prepara tinciones y reactivos.<\/li><li>Prepara y cambia bater\u00eda de tinci\u00f3n.<\/li><li>Rotula l\u00e1minas con numero filial.<\/li><li>Aplica t\u00e9cnicas de tinciones b\u00e1sicas y especiales.<\/li><li>Realiza corte histol\u00f3gico.<\/li><li>Realiza montaje de biopsias.<\/li><li>Monta laminillas.<\/li><li>Programa procesador de tejido para biopsias.<\/li><li>Realiza diagnostico citol\u00f3gico.<\/li><\/ul><p><strong>Campo laboral<\/strong><\/p><ul><li>Laboratorios de patolog\u00eda en hospitales p\u00fablicos y privados.<\/li><li>Laboratorios privados.<\/li><li>Universidades.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8202\" aria-expanded=\"false\">Plan de estudio<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8202\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8202\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Introducci\u00f3n a la Biolog\u00eda,<\/li><li>Introducci\u00f3n al Laboratorio de Citolog\u00eda<\/li><li>T\u00e9cnicas de Lectura, Redacci\u00f3n y Ortograf\u00eda<\/li><li>Inform\u00e1tica B\u00e1sica<\/li><li>Anatom\u00eda y Fisiolog\u00eda Ginecol\u00f3gica<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Introducci\u00f3n a la Citolog\u00eda<\/li><li>Geograf\u00eda e Historia de Nicaragua<\/li><li>Histolog\u00eda<\/li><li>Matem\u00e1tica General<\/li><li>T\u00e9cnicas de Investigaci\u00f3n Documental<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Seminario de Formaci\u00f3n Integral<\/li><li>Introducci\u00f3n a la Qu\u00edmica<\/li><li>Citolog\u00eda del Cuello Uterino I<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Pr\u00e1cticas de Familiarizaci\u00f3n<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Citolog\u00eda del Cuello Uterino II<\/li><li>Cambios del Ciclo Hormonal<\/li><li>Pr\u00e1cticas de Especializaci\u00f3n I<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Citolog\u00eda del Cuello Uterino III<\/li><li>Efectos Post Radioterapia<\/li><li>Pr\u00e1cticas de Especializaci\u00f3n II<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Citolog\u00eda del Cuello Uterino IV<\/li><li>Pr\u00e1cticas de Especializaci\u00f3n III<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-8203\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8203\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8203\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17674\" class=\"elementor elementor-17674\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56ada896 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"56ada896\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-39b302f1\" data-id=\"39b302f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a8a2feb\" data-id=\"a8a2feb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19b2b133 elementor-widget elementor-widget-heading\" data-id=\"19b2b133\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9cnico Superior en Enfermer\u00eda General<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ca8b82c elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"4ca8b82c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1afcd1f8\" data-id=\"1afcd1f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b13964d elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"6b13964d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1791\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1791\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1791\" aria-expanded=\"false\">Presentaci\u00f3n de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1791\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1791\" tabindex=\"0\" hidden=\"false\"><p style=\"text-align: justify;\">La carrera de Enfermer\u00eda como profesi\u00f3n se inserta en un conjunto de fuerzas vivas de la sociedad, en defensa de la vida y del planeta, incorporando como eje transversal el enfoque de g\u00e9nero, la cultura de gesti\u00f3n de riesgo, cambio clim\u00e1tico y los derechos humanos e investigaci\u00f3n con el prop\u00f3sito superior de promover el bienestar de la persona, familia y comunidad, a trav\u00e9s de la gesti\u00f3n del auto cuidado, la investigaci\u00f3n y la educaci\u00f3n sanitaria desde una dimensi\u00f3n hol\u00edstica y \u00e9tica.<\/p><p style=\"text-align: justify;\">La Enfermera (o) General T\u00e9cnico Superior est\u00e1 facultada con capacidades para prestar atenci\u00f3n integral de enfermer\u00eda de alta calidad de manera din\u00e1mica a la persona, familia y la comunidad con \u00e9nfasis en la prevenci\u00f3n, promoci\u00f3n y restablecimiento de la salud, en el cuidado en situaciones de enfermedad y adversidad de bajo riesgo.<\/p><p style=\"text-align: justify;\"><strong>Funciones que realiza el T\u00e9cnico Superior de Enfermer\u00eda General<\/strong><\/p><ul><li style=\"text-align: justify;\">Promociona y protege la salud de las personas, familia y comunidad en el ciclo de vida, en un marco de principios \u00e9ticos y de derechos humanos.<\/li><li style=\"text-align: justify;\">Interviene en situaciones de riesgo y de desviaci\u00f3n de la salud implementando el modelo de Orem, Henderson, Gordon y las etapas del proceso de Atenci\u00f3n de Enfermer\u00eda como herramienta cient\u00edfica en la identificaci\u00f3n de necesidades.<\/li><li style=\"text-align: justify;\">Desarrolla el proceso de comunicaci\u00f3n y educaci\u00f3n sanitaria en correspondencia al perfil epidemiol\u00f3gico de la comunidad que le corresponde participando en procesos de capacitaci\u00f3n de los recursos en salud y en formaci\u00f3n.<\/li><li style=\"text-align: justify;\">Colabora de manera activa en los procesos administrativos en la prestaci\u00f3n del cuidado de enfermer\u00eda en los diferentes escenarios y niveles de atenci\u00f3n de Salud.<\/li><li style=\"text-align: justify;\">Elabora trabajos de investigaci\u00f3n Operativa, Procesos de Cuidado de Enfermer\u00eda en colaboraci\u00f3n con el equipo de salud multidisciplinario.<\/li><\/ul><p style=\"text-align: justify;\"><strong>Cargos que desempe\u00f1a el T\u00e9cnico Superior en Enfermer\u00eda General<\/strong><\/p><ul><li style=\"text-align: justify;\">Enfermera (o) General Asistencial.<\/li><li style=\"text-align: justify;\">Educadora (o) sanitaria.<\/li><li style=\"text-align: justify;\">Responsable de Unidades y Puestos de salud.<\/li><li style=\"text-align: justify;\">Supervisi\u00f3n de Unidades y Puestos de salud.<\/li><li style=\"text-align: justify;\">Colaboradora y autora de Trabajos de Investigaci\u00f3n.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17974\" class=\"elementor elementor-17974\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;pulse&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-497b5c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"497b5c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ca99094\" data-id=\"7ca99094\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-527ef965 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"527ef965\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5436bb52\" data-id=\"5436bb52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-729277bb elementor-widget elementor-widget-image\" data-id=\"729277bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg\" class=\"attachment-large size-large wp-image-805\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg 800w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-300x167.jpg 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-768x427.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2fb5d940\" data-id=\"2fb5d940\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c334080 elementor-shape-circle e-grid-align-right elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"7c334080\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-e465af8\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-53a1a2b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b33d841\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-1ed9e15\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-repeater-item-bd76d6c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Envelope<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-repeater-item-8ab4a17\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-calendar-alt elementor-repeater-item-4f86da0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Calendar-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b47cffa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b47cffa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c90ec43\" data-id=\"c90ec43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-336d0aa2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"336d0aa2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4bc8896f\" data-id=\"4bc8896f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2ef6a345\" data-id=\"2ef6a345\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17988\" class=\"elementor elementor-17988\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;pulse&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f76b0c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f76b0c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66259394\" data-id=\"66259394\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-74639c3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74639c3f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-54534fce\" data-id=\"54534fce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c3e19e7 elementor-widget elementor-widget-image\" data-id=\"2c3e19e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg\" class=\"attachment-large size-large wp-image-805\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg 800w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-300x167.jpg 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-768x427.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b72305a\" data-id=\"1b72305a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-380a4993 elementor-shape-circle e-grid-align-right e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"380a4993\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-e465af8\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-53a1a2b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b33d841\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-1ed9e15\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-repeater-item-bd76d6c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Envelope<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-repeater-item-8ab4a17\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-calendar-alt elementor-repeater-item-4f86da0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Calendar-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-580481b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"580481b0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c7724c0\" data-id=\"4c7724c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6daf3cda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6daf3cda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4018eeaf\" data-id=\"4018eeaf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6171d2bf\" data-id=\"6171d2bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17994\" class=\"elementor elementor-17994\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;pulse&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4abc53b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4abc53b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39f85f49\" data-id=\"39f85f49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-67ba92e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67ba92e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-112be9b4\" data-id=\"112be9b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11920be2 elementor-widget elementor-widget-image\" data-id=\"11920be2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg\" class=\"attachment-large size-large wp-image-805\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul.jpg 800w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-300x167.jpg 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/2019\/02\/unan-managua-marca-azul-768x427.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-430cbb36\" data-id=\"430cbb36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-718dacdd elementor-shape-circle e-grid-align-right e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"718dacdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-e465af8\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-53a1a2b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b33d841\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-1ed9e15\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-repeater-item-bd76d6c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Envelope<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-repeater-item-8ab4a17\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-calendar-alt elementor-repeater-item-4f86da0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Calendar-alt<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65bb6b2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65bb6b2f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d186082\" data-id=\"1d186082\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-17c1eb3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17c1eb3c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7eb644c4\" data-id=\"7eb644c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6519550\" data-id=\"6519550\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"30992\" class=\"elementor elementor-30992\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;fadeIn&quot;,&quot;exit_animation&quot;:&quot;fadeIn&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;0.8&quot;,&quot;sizes&quot;:[]},&quot;open_selector&quot;:&quot;a[href=\\&quot;#link-popup-buscar\\&quot;]&quot;,&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d5bbc4c elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5d5bbc4c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b9a401c\" data-id=\"6b9a401c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2df1565 hfe-search-layout-icon_text elementor-widget elementor-widget-hfe-search-button\" data-id=\"2df1565\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:38,&quot;sizes&quot;:[]},&quot;close_icon_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:12,&quot;sizes&quot;:[]},&quot;size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;16&quot;,&quot;sizes&quot;:[]},&quot;icon_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;close_icon_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;close_icon_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"hfe-search-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"hfe-search-button-wrapper\" role=\"search\" action=\"https:\/\/www.unan.edu.ni\/\" method=\"get\">\n\n\t\t\t\t\t\t<div class=\"hfe-search-form__container\">\n\t\t\t\t\t\t\t\t\t<input placeholder=\"Escribe y presiona Intro...\" class=\"hfe-search-form__input\" type=\"search\" name=\"s\" title=\"Buscar\" value=\"\">\n\t\t\t\t\t<button id=\"clear-with-button\" type=\"reset\">\n\t\t\t\t\t\t<i class=\"fas fa-times\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t<button class=\"hfe-search-submit\" type=\"submit\">\n\t\t\t\t\t\t<i class=\"fas fa-search\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"39003\" class=\"elementor elementor-39003\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fcei-iet\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-593880cb elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"593880cb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3830e91b\" data-id=\"3830e91b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2de813cd\" data-id=\"2de813cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-262be606 elementor-widget elementor-widget-heading\" data-id=\"262be606\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda en Telem\u00e1tica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-881c138 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"881c138\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2414f36d\" data-id=\"2414f36d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-640538da elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"640538da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1671\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1671\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1672\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1672\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1673\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1673\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1671\" aria-expanded=\"false\">Perfil profesional<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1671\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1671\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de Ingenier\u00eda en Telem\u00e1tica es la soluci\u00f3n integral a los problemas de la realidad socio econ\u00f3mica del pa\u00eds, mediante recursos y habilidades computacionales en el \u00e1rea de telem\u00e1tica, donde el ingeniero es capaz de administrar redes de computadoras, administrar servidores a nivel de software y administrar procesos de soporte especializados, en entidades p\u00fablicas y privadas destinadas a la producci\u00f3n, comercializaci\u00f3n y servicios, as\u00ed como en organismos no gubernamentales; basado en una formaci\u00f3n integral, humanista y critica.<\/p><p>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional:<\/p><ul><li>Entidades p\u00fablicas y privadas destinadas a la producci\u00f3n, comercializaci\u00f3n y servicios.<\/li><li>Organismos No Gubernamentales (ONGs).<\/li><\/ul><p>Tareas que puede realizar el profesional:<\/p><ul><li>Administraci\u00f3n de redes de computadoras.<\/li><li>Administraci\u00f3n de servidores a nivel de software.<\/li><li>Administraci\u00f3n de procesos de\u202fsoporte redes y servidores.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1672\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1672\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1672\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comunicaci\u00f3n T\u00e9cnica en Ingenier\u00eda<\/li><li>Soporte de Equipos<\/li><li>Computacionales I<\/li><li>Herramientas<\/li><li>Ofim\u00e1ticas<\/li><li>Ingl\u00e9s T\u00e9cnico I<\/li><li>Integrador I<\/li><li>Electiva I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Modelaci\u00f3n Matem\u00e1tica<\/li><li>Soporte Equipos<\/li><li>Computacional II<\/li><li>Fundamentos Redes<\/li><li>Ingl\u00e9s T\u00e9cnico II<\/li><li>Programaci\u00f3n I<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Estad\u00edstica<\/li><li>Cableado Estructurado<\/li><li>Comunicaci\u00f3n de Datos<\/li><li>Programaci\u00f3n II<\/li><li>INTEGRADOR III<\/li><li>ELECTIVA II<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Sistemas Operativos I<\/li><li>Soporte De Equipos<\/li><li>Computacionales De Redes<\/li><li>An\u00e1lisis y Dise\u00f1o de Redes<\/li><li>Estructura de Datos<\/li><li>Integrador IV<\/li><li>Electiva III<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Sistema Operativo II<\/li><li>Servidores I<\/li><li>Redes I<\/li><li>Bases De Datos I<\/li><li>Programaci\u00f3n De Procesos<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Servidores II<\/li><li>Soporte de Servidores<\/li><li>Redes II<\/li><li>Bases De Datos II<\/li><li>Programaci\u00f3n Web<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Virtualizaci\u00f3n I<\/li><li>Seguridad de Redes<\/li><li>Cloud Computing I<\/li><li>Optativa I<\/li><li>Ethical Hacking<\/li><li>Auditoria de Redes<\/li><li>Optativa II<\/li><li>Plataform Azure<\/li><li>Plataforma Openstack<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Virtualizaci\u00f3n II<\/li><li>Streaming<\/li><li>Cloud Computing II<\/li><li>Optativa III<\/li><li>Voip<\/li><li>Monitoreo y Optimizaci\u00f3n de Servicios<\/li><li>Optativa IV<\/li><li>Proyecto TI<\/li><li>Proyectos \u00c1giles<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Seguridad de Servidores<\/li><li>Optativa V<\/li><li>Comercializaci\u00f3n de Servicios<\/li><li>Emprendimiento en Telem\u00e1tica<\/li><li>Pr\u00e1cticas Pre &#8211; Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1cticas Profesionales<\/li><\/ul><\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1673\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1673\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1673\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17389\" class=\"elementor elementor-17389\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fei-cs\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5078d631 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"5078d631\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a49204f\" data-id=\"3a49204f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6684ece8\" data-id=\"6684ece8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-338931ba elementor-widget elementor-widget-heading\" data-id=\"338931ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ciencias Sociales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65d27866 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"65d27866\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f5a3420\" data-id=\"2f5a3420\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18bfe507 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"18bfe507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4151\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4151\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4152\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4152\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4153\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4153\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4151\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4151\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4151\" tabindex=\"0\" hidden=\"false\"><p>Formaci\u00f3n de docentes para la Ense\u00f1anza-aprendizaje de las Ciencias Sociales en Educaci\u00f3n Secundaria.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><ul><li>Institutos de Educaci\u00f3n Secundaria P\u00fablicos y Privados.<\/li><li>Institutos de Educaci\u00f3n T\u00e9cnica<\/li><li>Instituciones No Gubernamentales<\/li><li>Oficinas de atenci\u00f3n socioeducativa a la comunidad<\/li><\/ul><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Docencia en el \u00e1rea de Ciencias Sociales en Educaci\u00f3n Secundaria.<\/li><li>Asesor\u00eda t\u00e9cnica Pedag\u00f3gica en el \u00e1rea de Ciencias Sociales.<\/li><li>Consejer\u00eda y Promotor\u00eda Social y Educativa<br \/>Asesor e investigador en el campo social y educativo.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4152\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4152\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4152\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Integrador I<\/li><li>Ofim\u00e1tica<\/li><li>Comprensi\u00f3n Lectora y Expresi\u00f3n Oral<\/li><li>Sociolog\u00eda<\/li><li>Econom\u00eda y Sociedad<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Integrador II<\/li><li>Introducci\u00f3n a la Geograf\u00eda y Cartograf\u00eda<\/li><li>Filosof\u00eda<\/li><li>Historia de Nicaragua per\u00edodo precolonial al siglo XIX<\/li><li>Expresi\u00f3n Escrita<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Historia de Nicaragua del siglo XIX al XXI<\/li><li>Geograf\u00eda F\u00edsica y Humana de Nicaragua<\/li><li>Curr\u00edculo<\/li><li>Pedagog\u00eda General<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Historia de Am\u00e9rica<\/li><li>Geograf\u00eda de Am\u00e9rica, Ocean\u00eda y Ant\u00e1rtida<\/li><li>Did\u00e1ctica General con \u00e9nfasis en el Aprendizaje<\/li><li>Metodolog\u00eda de la Investigaci\u00f3n<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Historia Universal Antigua y Media<\/li><li>Geograf\u00eda de Europa, Asia y \u00c1frica<\/li><li>Psicolog\u00eda del Aprendizaje<\/li><li>Did\u00e1ctica de las Ciencias Sociales<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Optativo I<\/li><li>Optativo II<\/li><li>Evaluaci\u00f3n de los aprendizajes por competencias<\/li><li>Historia Universal Moderna y Contempor\u00e1nea<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo III<\/li><li>Optativo IV<\/li><li>Gesti\u00f3n Educativa<\/li><li>Did\u00e1ctica de la ense\u00f1anza en valores<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Optativo V<\/li><li>Optativo VI<\/li><li>Historia Oral Aplicada a la Educaci\u00f3n<\/li><li>Formulaci\u00f3n de Proyectos Educativos<br \/>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Investigaci\u00f3n Educativa<\/li><li>Educaci\u00f3n Socioambiental<\/li><li>Pr\u00e1cticas Pre Profesionales<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas Laborales e Investigativas<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4153\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4153\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4153\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><li>CUR-Carazo<\/li><li>CUR-Chontales<\/li><li>CUR-Estel\u00ed<\/li><li>CUR-Matagalpa<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"17392\" class=\"elementor elementor-17392\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fei-educom\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4e5ff8 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"d4e5ff8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b13ed2a\" data-id=\"7b13ed2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-10a6d643\" data-id=\"10a6d643\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5680f2d0 elementor-widget elementor-widget-heading\" data-id=\"5680f2d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura Educaci\u00f3n Comercial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bb93862 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"6bb93862\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41cdf4fc\" data-id=\"41cdf4fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fb187d4 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3fb187d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1061\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1061\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1062\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1062\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1063\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1063\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1061\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1061\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1061\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio de la carrera es el proceso de ense\u00f1anza y aprendizaje de la Educaci\u00f3n Comercial. Por tanto, dichos profesionales poseen dominio de estrategias did\u00e1cticas innovadoras, adem\u00e1s puede acompa\u00f1ar a los docentes durante las actividades de aula como estrategia para el mejoramiento de su labor; por consiguiente, pueden realizar investigaciones que conlleven a la soluci\u00f3n de problemas educativos y desarrollar capacitaciones en el campo de la Educaci\u00f3n Comercial para el fortalecimiento profesional de colaboradores de instituciones y empresas en general. Todos los conocimientos de este se pueden desarrollar en la docencia, acompa\u00f1amiento pedag\u00f3gico e investigaci\u00f3n educativa en el \u00e1mbito de la Educaci\u00f3n Comercial. Este profesional ser\u00e1 capaz de actuar conforme las leyes, principios, normas, valores y procedimientos que regulan el \u00e1mbito comercial.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1062\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1062\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1062\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comprensi\u00f3n lectora y expresi\u00f3n oral<\/li><li>Ofim\u00e1tica<\/li><li>C\u00e1lculo mercantil aplicado a la Educaci\u00f3n Comercial<\/li><li>Relaciones humanas y atenci\u00f3n al cliente<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Expresi\u00f3n escrita<\/li><li>Organizaci\u00f3n de oficina y archivo<\/li><li>Pedagog\u00eda general<\/li><li>Formaci\u00f3n ciudadana<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Estad\u00edstica aplicada a la Educaci\u00f3n Comercial<\/li><li>Principios de contabilidad<\/li><li>Administraci\u00f3n I<\/li><li>Psicolog\u00eda del aprendizaje<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Contabilidad Intermedia<\/li><li>Administraci\u00f3n II<\/li><li>Taller de investigaci\u00f3n aplicada a la Educaci\u00f3n Comercial I<\/li><li>Optativo I<\/li><li>Integrador IV<\/li><\/ul><\/td><\/tr><tr><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Matem\u00e1tica financiera aplicada a la Educaci\u00f3n Comercial<\/li><li>Did\u00e1ctica general con \u00e9nfasis en el aprendizaje<\/li><li>Evaluaci\u00f3n de los aprendizajes por competencias<\/li><li>Optativo II<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Finanzas<\/li><li>Curr\u00edculo<\/li><li>Gesti\u00f3n educativa<\/li><li>Optativo III<\/li><li>Integrador VI<\/li><\/ul><\/td><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Laboratorio contable<\/li><li>Organizaci\u00f3n y m\u00e9todos<\/li><li>Did\u00e1ctica comercial aplicada a la Educaci\u00f3n Comercial I<\/li><li>Optativo IV<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VIII<\/p><ul><li>Contabilidad de costos<\/li><li>Administraci\u00f3n de marketing<\/li><li>Did\u00e1ctica especial aplicada a la Educaci\u00f3n Comercial II<\/li><li>Optativo V<\/li><li>Integrador VIII<\/li><\/ul><\/td><\/tr><tr><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Contrataciones administrativas<\/li><li>Gesti\u00f3n del talento humano<\/li><li>Taller de investigaci\u00f3n aplicado a la Educaci\u00f3n Comercial II<\/li><li>Optativo VI<\/li><li>Pr\u00e1cticas de Pre Profesionalizaci\u00f3n<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Pr\u00e1cticas de Profesionalizaci\u00f3n<\/li><li>Modalidad de Graduaci\u00f3n<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1063\" aria-expanded=\"false\">Sedes<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1063\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1063\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Managua<\/li><\/ul><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"39067\" class=\"elementor elementor-39067\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#fei-eduesp\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-295aee70 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"295aee70\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aae6af3\" data-id=\"aae6af3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-149a1dc3\" data-id=\"149a1dc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75ffd98d elementor-widget elementor-widget-heading\" data-id=\"75ffd98d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Educaci\u00f3n Especial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-186c8214 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"186c8214\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15bdaa58\" data-id=\"15bdaa58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-188178ab elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"188178ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4111\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4111\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4112\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4112\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4111\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4111\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4111\" tabindex=\"0\" hidden=\"false\"><p>El objeto de estudio del Licenciado en la Carrera de Educaci\u00f3n Especial es el proceso de ense\u00f1anza \u2013 aprendizaje en Educaci\u00f3n Especial.<\/p><p><strong>Perfil del t\u00e9cnico superior en educaci\u00f3n especial<\/strong><\/p><p>El objeto de estudio de t\u00e9cnico superior en Educaci\u00f3n Especial es el proceso de ense\u00f1anza y aprendizaje de la educaci\u00f3n especial.<\/p><p>Por lo tanto el profesional tiene la capacidad de utilizar a nivel b\u00e1sico de aplicaci\u00f3n los diferentes Sistemas Aumentativos y Alternativos de Comunicaci\u00f3n (SAAC); asimismo es capaz de caracterizar las necesidades educativas de los estudiantes con o sin discapacidad en su \u00e1mbito; de aplicar la planificaci\u00f3n did\u00e1ctica de acuerdo a las necesidades educativas especiales de los estudiantes con o sin discapacidad y es capaz de aplicar los elementos b\u00e1sicos de las TIC para la atenci\u00f3n de las necesidades educativas especiales con o sin discapacidad.<\/p><p>Su campo de acci\u00f3n es la docencia y desarrollar investigaci\u00f3n de acuerdo al contexto y su \u00e1mbito de actuaci\u00f3n son las Escuelas de educaci\u00f3n especial, educaci\u00f3n infantil y educaci\u00f3n primaria.<\/p><p>Capacidad para coordinar con los padres de familia y de la comunidad acciones pedag\u00f3gicas, socio-culturales y recreativas que las escuelas llevan a cabo.<\/p><p>El profesional de la licenciatura en educaci\u00f3n especial<\/p><p>El profesional licenciado de la carrera en Educaci\u00f3n Especial tiene la capacidad para desarrollar procesos did\u00e1cticos atendiendo enfoque y modelos educativos, con el fin de generar innovaciones pedag\u00f3gicas.<\/p><p>Cada una de sus diferentes competencias las puede desempe\u00f1ar en los diferentes campos de acci\u00f3n (Docencia, Asesor\u00eda pedag\u00f3gica en la inclusividad, investigaci\u00f3n y Dise\u00f1o de proyectos de intervenci\u00f3n educativa), sus \u00e1mbitos de actuaci\u00f3n son las Escuelas de Educaci\u00f3n Especial, Educaci\u00f3n Infantil y Educaci\u00f3n Primaria.<\/p><p>De tener la capacidad para comunicarse de manera oral y escrita en diferentes contextos de actuaci\u00f3n.<\/p><p>El Profesional tiene la habilidad de utilizar los diferentes Sistemas Aumentativos y Alternativos de Comunicaci\u00f3n (SAAC) y la lengua de se\u00f1as para atender oportunamente a los estudiantes.<\/p><p>Capacidad para comunicarse de manera oral y escrita en diferentes contextos de actuaci\u00f3n.<\/p><p>Habilidad para dominar conceptos b\u00e1sicos de educaci\u00f3n especial, de educaci\u00f3n inclusiva y de la atenci\u00f3n educativa a la diversidad.<\/p><p>Capacidad para coordinar con los padres de familia y de la comunidad acciones pedag\u00f3gicas, socio-culturales y recreativas que las escuelas llevan a cabo.<\/p><p>Dise\u00f1ar proyectos de intervenci\u00f3n educativa para que propicien la calidad de los procesos de ense\u00f1anza aprendizaje a ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes asociados o no a una discapacidad.<\/p><p>Poner en pr\u00e1ctica la comunicaci\u00f3n asertiva entre estudiantes, maestros y padres de familia.<\/p><p>Divulgar mediante campa\u00f1as de sensibilizaci\u00f3n la importancia de la inclusi\u00f3n educativa y de los derechos de las personas con discapacidad.<\/p><p>Efectuar coordinaciones con redes de apoyo afines a la atenci\u00f3n de estudiantes con necesidades educativas con o sin discapacidades incluidos en las escuelas especiales y primarias.<\/p><p><strong>\u00c1mbitos de actuaci\u00f3n donde se desempe\u00f1ar\u00e1 el profesional<\/strong><\/p><p>Escuelas de educaci\u00f3n especial, educaci\u00f3n infantil y educaci\u00f3n primaria.<\/p><p><strong>Tareas que puede realizar el profesional<\/strong><\/p><ul><li>Elaborar estrategias de ense\u00f1anza en la planificaci\u00f3n curricular orientada a los estudiantes con o sin discapacidad incluidos en las escuelas especiales y regulares.<\/li><li>Realizar evaluaciones psicopedag\u00f3gicas a estudiantes con o sin discapacidad con el fin de determinar sus necesidades educativas.<\/li><li>Emplear Software Educativos para la atenci\u00f3n de estudiantes con discapacidad: cognitiva, auditiva, visual y motriz, s\u00edndrome de Down y Autismo).<\/li><li>Desarrollar pr\u00e1cticas inclusivas que sirvan de referencia para la atenci\u00f3n pedag\u00f3gica a los estudiantes incluidos en el sistema educativo del pa\u00eds.<\/li><li>Asesorar a los docentes y a asociaciones no gubernamentales en las tem\u00e1ticas: Lengua de se\u00f1as, Sistema Braille, \u00c1baco, Orientaci\u00f3n y Movilidad, Trastornos de Espectro Autista (TEA), Discapacidad M\u00faltiples, discapacidad cognitiva, discapacidad motriz, trastornos en el desarrollo del lenguaje, D\u00e9ficit Atencional e Hiperactividad. (TDAH).<\/li><li>Realizar encuentros a padres de familia y docentes con tem\u00e1ticas relacionadas a la atenci\u00f3n educativa orientada a las necesidades educativas con o sin discapacidad.<\/li><li>Divulgar mediante campa\u00f1as de sensibilizaci\u00f3n la importancia de la inclusi\u00f3n educativa y de los derechos de las personas con discapacidad.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4112\" aria-expanded=\"false\">Plan de estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4112\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4112\" tabindex=\"0\" hidden=\"hidden\"><p><style type=\"text\/css\">\n.tftable {font-size:12px;color:#FFFFFF;width:100%;}<br \/>.tftable td {font-size:12px; border-collapse:collapse; border:none;}<br \/>.tftable tr:hover {background-color:#ffffff;}<br \/><\/style><\/p><table class=\"tftable\" border=\"1\"><tbody><tr><td><p><strong>I A\u00d1O<\/strong><\/p><p>SEMESTRE I<\/p><ul><li>Comprensi\u00f3n lectora y expresi\u00f3n oral<\/li><li>Estad\u00edstica Descriptiva<\/li><li>Introducci\u00f3n a la Educaci\u00f3n Especial<\/li><li>Formaci\u00f3n ciudadana<\/li><li>Integrador I<\/li><\/ul><p>SEMESTRE II<\/p><ul><li>Expresi\u00f3n escrita<\/li><li>Ofim\u00e1tica<\/li><li>Educaci\u00f3n inclusiva desde el curr\u00edculum<\/li><li>Pedagog\u00eda General<\/li><li>Integrador II<\/li><\/ul><\/td><td><p><strong>II A\u00d1O<\/strong><\/p><p>SEMESTRE III<\/p><ul><li>Metodolog\u00eda de investigaci\u00f3n Educativa<\/li><li>Principios del Diagn\u00f3stico en la Educaci\u00f3n Especial y para la Diversidad.<\/li><li>Matem\u00e1tica General<\/li><li>Psicolog\u00eda de los Aprendizajes<\/li><li>Integrador III<\/li><\/ul><p>SEMESTRE IV<\/p><ul><li>Lengua de se\u00f1as de Nicaragua I<\/li><li>Tic Aplicada a la Educaci\u00f3n<\/li><li>Diversidad e Interculturalidad<\/li><li>Integrador IV<\/li><\/ul><\/td><td><p><strong>III A\u00d1O<\/strong><\/p><p>SEMESTRE V<\/p><ul><li>Did\u00e1ctica de la Educaci\u00f3n Laboral<\/li><li>Sistemas Aumentativos y Alternativos de la Comunicaci\u00f3n.<\/li><li>Evaluaci\u00f3n de los aprendizajes por competencias.<\/li><li>Curr\u00edculo I<\/li><li>Integrador V<\/li><\/ul><p>SEMESTRE VI<\/p><ul><li>Optativo I<\/li><li>Introducci\u00f3n a la Neurociencia.<\/li><li>Discapacidad I \u2013sensorial.<\/li><li>Did\u00e1ctica general con \u00e9nfasis en el aprendizaje.<\/li><li>Integrador VI<\/li><\/ul><\/td><\/tr><tr><td><p><strong>IV A\u00d1O<\/strong><\/p><p>SEMESTRE VII<\/p><ul><li>Optativo II<\/li><li>Lengua de se\u00f1as de Nicaragua II<\/li><li>Investigaci\u00f3n Aplicada.<\/li><li>Desarrollo Humano.<\/li><li>Taller de Medios de Ense\u00f1anza<\/li><li>Integrador VII<\/li><\/ul><p>SEMESTRE VII<\/p><ul><li>Optativo III<\/li><li>Formulaci\u00f3n y Eval. de Proyectos Educativos<\/li><li>Pedagog\u00eda de los Trastornos en el aprendizaje<\/li><li>Curr\u00edculo II<\/li><li>Integrador VIII<\/li><\/ul><\/td><td><p><strong>V A\u00d1O<\/strong><\/p><p>SEMESTRE IX<\/p><ul><li>Gesti\u00f3n Educativa<\/li><li>Pr\u00e1ctica Preprofesional<\/li><\/ul><p>SEMESTRE X<\/p><ul><li>Modalidad de Graduaci\u00f3n<\/li><li>Pr\u00e1ctica Profesional<\/li><\/ul><\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"40059\" class=\"elementor elementor-40059\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#polisallem\\&quot;]&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-602984e7 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"602984e7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52851f57\" data-id=\"52851f57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-770be2ec\" data-id=\"770be2ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-762c3e96 elementor-widget elementor-widget-heading\" data-id=\"762c3e96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Licenciatura en Enfermer\u00eda en Materno Infantil<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f751bc7 elementor-section-content-bottom elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"2f751bc7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f95fd41\" data-id=\"6f95fd41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27981803 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"27981803\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6641\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6641\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6641\" aria-expanded=\"false\">Perfil de la carrera<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6641\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6641\" tabindex=\"0\" hidden=\"false\"><p>La licenciada o licenciado en Enfermer\u00eda Materno Infantil, tiene como objeto de estudio el cuidado a la mujer con enfoque en la salud sexual y reproductiva en las diferentes etapas del ciclo vital, atenci\u00f3n integral a la ni\u00f1ez y adolescencia, la participaci\u00f3n del hombre como parte del microsistema en la adopci\u00f3n del rol maternal, respetando la gestaci\u00f3n como una experiencia personal y familiar, preservando la privacidad y autonom\u00eda de la mujer; que vive un importante momento de transici\u00f3n con transformaciones biol\u00f3gicas, emocionales y sociales consecuentes del proceso de la gestaci\u00f3n, inherente al cambio de papel, o sea, ser madre.<br \/>El desempe\u00f1o profesional en Enfermer\u00eda Materno Infantil, se fundamenta en los principios \u00e9ticos de la profesi\u00f3n y el trabajo interdisciplinario para el fortalecimiento de los pilares de la maternidad segura y la restituci\u00f3n de derechos a la ni\u00f1ez y adolescencia desde el entorno familiar y comunitario.<\/p><p><strong>Objeto de la profesi\u00f3n<\/strong><\/p><ul><li>cuidado a la mujer, ni\u00f1ez y adolescencia<br \/>\u00c1mbitos de actuaci\u00f3n<\/li><li>Unidades de atenci\u00f3n primaria en salud p\u00fablicas y privadas<\/li><li>Unidades hospitalarias p\u00fablicas y privadas<\/li><li>Escuelas p\u00fablicas y privadas<\/li><\/ul><p><strong>Competencia Gen\u00e9ricas<\/strong><\/p><ul><li>Se comunica de manera oral y escrita en los diferentes \u00e1mbitos de actuaci\u00f3n<\/li><li>Resuelve problemas de manera individual y en equipo en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional, a trav\u00e9s de la investigaci\u00f3n.<\/li><li>Comprende la realidad socioecon\u00f3mica, pol\u00edtica e hist\u00f3rica del pa\u00eds.<\/li><li>Demuestra creatividad para hacer avanzar los diferentes \u00e1mbitos de actuaci\u00f3n<\/li><li>Utiliza las TIC como apoya para mejorar el aprendizaje en los diferentes \u00e1mbitos de actuaci\u00f3n y campos de acci\u00f3n profesional<\/li><\/ul><p><strong>Competencias Espec\u00edficas<\/strong><\/p><ul><li>Capacidad de brindar atenci\u00f3n segura y de calidad en la prevenci\u00f3n, diagn\u00f3stico, tratamiento y rehabilitaci\u00f3n de la salud, contribuyendo a mejorar la salud de la mujer, ni\u00f1ez y adolescencia, seg\u00fan necesidades identificadas que conduzcan al bienestar materno infantil en el seno familiar y comunitario.<\/li><li>Capacidad para implementar las estrategias de atenci\u00f3n orientadas a la promoci\u00f3n de la salud, prevenci\u00f3n de enfermedades y rehabilitaci\u00f3n en la poblaci\u00f3n materna infantil y su entorno.<\/li><li>Capacidad en el desarrollo de investigaciones cient\u00edficas y el Proceso de Atenci\u00f3n de Enfermer\u00eda como herramientas que favorezcan la pr\u00e1ctica profesional del cuidado Materno Infantil, en equipos de trabajo inter y multidisciplinario.<\/li><li>Capacidad de gerencia y liderazgo que le permitan el ejercicio emprendedor en programas y servicios integrales de enfermer\u00eda materna infantil en funci\u00f3n del bienestar familiar y comunitario.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"47707\" class=\"elementor elementor-47707\" data-elementor-settings=\"{&quot;open_selector&quot;:&quot;a[href=\\&quot;#link-popup-sigi-cuadricula\\&quot;]&quot;,&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64a32f9 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"64a32f9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;0.5&quot;,&quot;sizes&quot;:[]},&quot;background_motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;background_motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c87dc17\" data-id=\"c87dc17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-82af371 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82af371\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-98beab3\" data-id=\"98beab3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d57497d elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d57497d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/sigi.unan.edu.ni\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Administrativo\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-tie\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/sigi.unan.edu.ni\/\" target=\"_blank\" >\n\t\t\t\t\t\t\tAdministrativo\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-cc96061\" data-id=\"cc96061\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b45a751 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b45a751\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\/index.php\/institucional\/calendario-de-gestion-academica-y-administrativa-2020.odp\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Calendario\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\/index.php\/institucional\/calendario-de-gestion-academica-y-administrativa-2020.odp\" target=\"_blank\" >\n\t\t\t\t\t\t\tCalendario\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-6300568\" data-id=\"6300568\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eebb90 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3eebb90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/sigi.unan.edu.ni\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Docente\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-circle\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/sigi.unan.edu.ni\/\" target=\"_blank\" >\n\t\t\t\t\t\t\tDocente\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-956d10a\" data-id=\"956d10a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c645fef elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c645fef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/sigi.unan.edu.ni\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Estudiante\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-graduate\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/sigi.unan.edu.ni\/\" target=\"_blank\" >\n\t\t\t\t\t\t\tEstudiante\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-9ef347e\" data-id=\"9ef347e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8868c80 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8868c80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\/index.php\/requisitos-para-tramite-de-titulo\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Tr\u00e1mites Acad\u00e9micos\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-users\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.unan.edu.ni\/index.php\/requisitos-para-tramite-de-titulo\" target=\"_blank\" >\n\t\t\t\t\t\t\tTr\u00e1mites Acad\u00e9micos\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"47744\" class=\"elementor elementor-47744\" data-elementor-settings=\"{&quot;open_selector&quot;:&quot;a[href=\\&quot;#link-popup-cei-cuadricula\\&quot;]&quot;,&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ccb13b7 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"6ccb13b7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;0.5&quot;,&quot;sizes&quot;:[]},&quot;background_motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;background_motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36006f25\" data-id=\"36006f25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-76db53a4 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76db53a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7d9239ad\" data-id=\"7d9239ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c36aaa4 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c36aaa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/outlook.office.com\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Outlook (365)\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/outlook.office.com\" target=\"_blank\" >\n\t\t\t\t\t\t\tOutlook (365)\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-62a13f60\" data-id=\"62a13f60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-673d2563 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"673d2563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/owa.unan.edu.ni\/owa\/auth\/logon.aspx?replaceCurrent=1&#038;url=https%3a%2f%2fowa.unan.edu.ni%2fowa\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Outlook (web)\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/owa.unan.edu.ni\/owa\/auth\/logon.aspx?replaceCurrent=1&#038;url=https%3a%2f%2fowa.unan.edu.ni%2fowa\" target=\"_blank\" >\n\t\t\t\t\t\t\tOutlook (web)\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"47761\" class=\"elementor elementor-47761\" data-elementor-settings=\"{&quot;open_selector&quot;:&quot;a[href=\\&quot;#link-popup-rs-cuadricula\\&quot;]&quot;,&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68331a83 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"68331a83\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;0.5&quot;,&quot;sizes&quot;:[]},&quot;background_motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;background_motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2aea3c91\" data-id=\"2aea3c91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-741a6757 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"741a6757\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-77048412\" data-id=\"77048412\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77fcfeff elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"77fcfeff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.facebook.com\/UNAN.Managua\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Facebook\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/UNAN.Managua\/\" target=\"_blank\" >\n\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-a5bdcfc\" data-id=\"a5bdcfc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c487bd elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4c487bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.instagram.com\/unan.managua\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Instagram\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/unan.managua\/\" target=\"_blank\" >\n\t\t\t\t\t\t\tInstagram\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-8f459c2\" data-id=\"8f459c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-783eaa4f elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"783eaa4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/twitter.com\/UNANManagua\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"X\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-x-twitter\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/twitter.com\/UNANManagua\" target=\"_blank\" >\n\t\t\t\t\t\t\tX\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-c45789f\" data-id=\"c45789f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04bf791 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"04bf791\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.tiktok.com\/@unanmanagua\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"TikTok\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-tiktok\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.tiktok.com\/@unanmanagua\" target=\"_blank\" >\n\t\t\t\t\t\t\tTikTok\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-6e53c599\" data-id=\"6e53c599\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c92f89 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1c92f89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.youtube.com\/channel\/UCaAtEPINZNv738R3vZI2Kjg\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"YouTube\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/channel\/UCaAtEPINZNv738R3vZI2Kjg\" target=\"_blank\" >\n\t\t\t\t\t\t\tYouTube\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div data-elementor-type=\"popup\" data-elementor-id=\"124114\" class=\"elementor elementor-124114\" data-elementor-settings=\"{&quot;entrance_animation&quot;:&quot;fadeIn&quot;,&quot;exit_animation&quot;:&quot;fadeIn&quot;,&quot;entrance_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;1&quot;,&quot;sizes&quot;:[]},&quot;avoid_multiple_popups&quot;:&quot;yes&quot;,&quot;open_selector&quot;:&quot;a[href=\\&quot;#LIN_INV\\&quot;]&quot;,&quot;a11y_navigation&quot;:&quot;yes&quot;,&quot;timing&quot;:[]}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-2c695b4b e-flex e-con-boxed e-con e-parent\" data-id=\"2c695b4b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a30ce48 elementor-widget elementor-widget-heading\" data-id=\"5a30ce48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L\u00edneas de investigaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c2f1009 e-con-full e-flex e-con e-parent\" data-id=\"4c2f1009\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f0f870b elementor-widget elementor-widget-bae-pdf-native-embedder\" data-id=\"6f0f870b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bae-pdf-native-embedder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class =\"native_style\">\r\n\t\t\t     \t\t<div class=\"download\">\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"my_native\">\r\n\t\t\t<iframe src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/lineas_de_investigacion.pdf\"><\/iframe>\r\n\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c43f9ff elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"3c43f9ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/lineas_de_investigacion.pdf\" target=\"_blank\" download=\"\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descargar<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a715f5a elementor-section-height-min-height elementor-section-full_width elementor-section-items-top elementor-section-height-default\" data-id=\"4a715f5a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5709500f\" data-id=\"5709500f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-695fd698 elementor-widget elementor-widget-image\" data-id=\"695fd698\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"524\" height=\"358\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/Somos-UNAN-Managua.png\" class=\"attachment-full size-full wp-image-117150\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/Somos-UNAN-Managua.png 524w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/Somos-UNAN-Managua-300x205.png 300w\" sizes=\"(max-width: 524px) 100vw, 524px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-13460a3d\" data-id=\"13460a3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52c3213f elementor-widget elementor-widget-text-editor\" data-id=\"52c3213f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contacto<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7812d3b5 elementor-widget elementor-widget-text-editor\" data-id=\"7812d3b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tRotonda Universitaria Rigoberto L\u00f3pez P\u00e9rez 150 metros al este, Managua.<br \/>\nC\u00f3digo postal: 663<br \/>\nTel\u00e9fonos: (+505) 2278 6764 \/ 2278 6769<br \/>\nCorreo: &#105;n&#x66;o&#x40;u&#x6e;a&#x6e;&#46;&#x65;&#100;&#x75;&#46;&#x6e;&#105;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7ed801c7 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"7ed801c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45447abe elementor-widget elementor-widget-text-editor\" data-id=\"45447abe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"color: #01136f;\"><a style=\"color: #01136f;\" href=\"https:\/\/www.unan.edu.ni\/index.php\/institucional\/dictamen-del-ceai-udual.odp\">Acreditaci\u00f3n Universitaria<\/a><\/span><br \/>\n<span style=\"color: #01136f;\"><a style=\"color: #01136f;\" href=\"https:\/\/www.unan.edu.ni\/index.php\/oferta-educativa-areas-del-conocimiento\">Carreras Universitarias<\/a><\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3f0c4905 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"3f0c4905\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d78f1ac elementor-widget elementor-widget-text-editor\" data-id=\"1d78f1ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"color: #01136f;\"><a style=\"color: #01136f;\" href=\"https:\/\/www.unan.edu.ni\/index.php\/cnu\/marco-estrategico-de-la-educacion-superior-2022-2030.odp\" target=\"_blank\" rel=\"noopener\">Marco Estrat\u00e9gico<\/a><\/span>\n<br \/>\n<span style=\"color: #01136f;\"><a style=\"color: #01136f;\" href=\"https:\/\/www.unan.edu.ni\/index.php\/institucional\/estrategia-nacional-de-educacion-en-todas-sus-modalidades-bendiciones-y-victorias-2024-2026.odp\" target=\"_blank\" rel=\"noopener\">Estrategia Nacional de Educaci\u00f3n<\/a><\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c07167d elementor-section-height-min-height elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"6c07167d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-78c2a967\" data-id=\"78c2a967\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2196542d\" data-id=\"2196542d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2bf9eb35\" data-id=\"2bf9eb35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27634b27 elementor-widget elementor-widget-image\" data-id=\"27634b27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/setec.edu.ni\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"273\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/Elementos-Graficos-07.png\" class=\"elementor-animation-shrink attachment-full size-full wp-image-149621\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/Elementos-Graficos-07.png 724w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/Elementos-Graficos-07-300x113.png 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-187a4b27\" data-id=\"187a4b27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5122e8af elementor-widget elementor-widget-image\" data-id=\"5122e8af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/udualc.org\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"240\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/UDUAL-2.png\" class=\"elementor-animation-shrink attachment-full size-full wp-image-117154\" alt=\"\" srcset=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/UDUAL-2.png 800w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/UDUAL-2-300x90.png 300w, https:\/\/www.unan.edu.ni\/wp-content\/uploads\/UDUAL-2-768x230.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-753fd605\" data-id=\"753fd605\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5991822a elementor-widget elementor-widget-image\" data-id=\"5991822a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ceai.website\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"186\" height=\"177\" src=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/CEAI-1-1.png\" class=\"elementor-animation-shrink attachment-full size-full wp-image-117153\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>External-link-alt Mail-bulk Phone-alt Search External-link-alt Mail-bulk Phone-alt Search SINGU Finca ExperimentalEspacio t\u00e9cnico cient\u00edfico destinado al desarrollo, validaci\u00f3n y aplicaci\u00f3n de investigaciones, innovaciones y tecnolog\u00edas en el \u00e1mbito socioproductivo. Su prop\u00f3sito es generar, adaptar, validar y transferir conocimientos mediante pr\u00e1cticas experimentales controladas que permiten evaluar sistemas de producci\u00f3n, mejorar procesos, fortalecer la sostenibilidad y promover alternativas &#8230; <a title=\"Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental\" class=\"read-more\" href=\"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental\" aria-label=\"Leer m\u00e1s sobre Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":18727,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"class_list":["post-177320","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental - UNAN-Managua<\/title>\n<meta name=\"description\" content=\"Espacio t\u00e9cnico cient\u00edfico destinado al desarrollo, validaci\u00f3n y aplicaci\u00f3n de investigaciones, innovaciones y tecnolog\u00edas en el \u00e1mbito socioproductivo. Su prop\u00f3sito es generar, adaptar, validar y transferir conocimientos mediante pr\u00e1cticas experimentales controladas que permiten evaluar sistemas de producci\u00f3n, mejorar procesos, fortalecer la sostenibilidad y promover alternativas tecnol\u00f3gicas pertinentes para el territorio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental\" \/>\n<meta property=\"og:description\" content=\"Espacio t\u00e9cnico cient\u00edfico destinado al desarrollo, validaci\u00f3n y aplicaci\u00f3n de investigaciones, innovaciones y tecnolog\u00edas en el \u00e1mbito socioproductivo. Su prop\u00f3sito es generar, adaptar, validar y transferir conocimientos mediante pr\u00e1cticas experimentales controladas que permiten evaluar sistemas de producci\u00f3n, mejorar procesos, fortalecer la sostenibilidad y promover alternativas tecnol\u00f3gicas pertinentes para el territorio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental\" \/>\n<meta property=\"og:site_name\" content=\"UNAN-Managua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UNAN.Managua\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T23:46:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UNANManagua\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"168 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/index.php\\\/investigacion-e-innovacion-finca-experimental\",\"url\":\"https:\\\/\\\/www.unan.edu.ni\\\/index.php\\\/investigacion-e-innovacion-finca-experimental\",\"name\":\"Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental - UNAN-Managua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/index.php\\\/investigacion-e-innovacion-finca-experimental#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/index.php\\\/investigacion-e-innovacion-finca-experimental#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unan.edu.ni\\\/wp-content\\\/uploads\\\/unan-managua-marca-institucional-2904202002.jpg\",\"datePublished\":\"2026-07-14T23:37:37+00:00\",\"dateModified\":\"2026-07-14T23:46:30+00:00\",\"description\":\"Espacio t\u00e9cnico cient\u00edfico destinado al desarrollo, validaci\u00f3n y aplicaci\u00f3n de investigaciones, innovaciones y tecnolog\u00edas en el \u00e1mbito socioproductivo. Su prop\u00f3sito es generar, adaptar, validar y transferir conocimientos mediante pr\u00e1cticas experimentales controladas que permiten evaluar sistemas de producci\u00f3n, mejorar procesos, fortalecer la sostenibilidad y promover alternativas tecnol\u00f3gicas pertinentes para el territorio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/index.php\\\/investigacion-e-innovacion-finca-experimental#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unan.edu.ni\\\/index.php\\\/investigacion-e-innovacion-finca-experimental\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/index.php\\\/investigacion-e-innovacion-finca-experimental#primaryimage\",\"url\":\"https:\\\/\\\/www.unan.edu.ni\\\/wp-content\\\/uploads\\\/unan-managua-marca-institucional-2904202002.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unan.edu.ni\\\/wp-content\\\/uploads\\\/unan-managua-marca-institucional-2904202002.jpg\",\"width\":1080,\"height\":576,\"caption\":\"UNAN-Managua, Marca Institucional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/index.php\\\/investigacion-e-innovacion-finca-experimental#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unan.edu.ni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/#website\",\"url\":\"https:\\\/\\\/www.unan.edu.ni\\\/\",\"name\":\"UNAN-Managua\",\"description\":\"Universidad Nacional Aut\u00f3noma de Nicaragua\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/#organization\"},\"alternateName\":\"Universidad Nacional Aut\u00f3noma de Nicaragua\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unan.edu.ni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/#organization\",\"name\":\"UNAN-Managua\",\"alternateName\":\"Universidad Nacional Aut\u00f3noma de Nicaragua\",\"url\":\"https:\\\/\\\/www.unan.edu.ni\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unan.edu.ni\\\/wp-content\\\/uploads\\\/unan-managua-marca-institucional-2904202002.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unan.edu.ni\\\/wp-content\\\/uploads\\\/unan-managua-marca-institucional-2904202002.jpg\",\"width\":1080,\"height\":576,\"caption\":\"UNAN-Managua\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unan.edu.ni\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UNAN.Managua\\\/\",\"https:\\\/\\\/x.com\\\/UNANManagua\",\"https:\\\/\\\/www.instagram.com\\\/unan.managua\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@UnanManaguaOficial\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental - UNAN-Managua","description":"Espacio t\u00e9cnico cient\u00edfico destinado al desarrollo, validaci\u00f3n y aplicaci\u00f3n de investigaciones, innovaciones y tecnolog\u00edas en el \u00e1mbito socioproductivo. Su prop\u00f3sito es generar, adaptar, validar y transferir conocimientos mediante pr\u00e1cticas experimentales controladas que permiten evaluar sistemas de producci\u00f3n, mejorar procesos, fortalecer la sostenibilidad y promover alternativas tecnol\u00f3gicas pertinentes para el territorio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental","og_locale":"es_ES","og_type":"article","og_title":"Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental","og_description":"Espacio t\u00e9cnico cient\u00edfico destinado al desarrollo, validaci\u00f3n y aplicaci\u00f3n de investigaciones, innovaciones y tecnolog\u00edas en el \u00e1mbito socioproductivo. Su prop\u00f3sito es generar, adaptar, validar y transferir conocimientos mediante pr\u00e1cticas experimentales controladas que permiten evaluar sistemas de producci\u00f3n, mejorar procesos, fortalecer la sostenibilidad y promover alternativas tecnol\u00f3gicas pertinentes para el territorio.","og_url":"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental","og_site_name":"UNAN-Managua","article_publisher":"https:\/\/www.facebook.com\/UNAN.Managua\/","article_modified_time":"2026-07-14T23:46:30+00:00","og_image":[{"width":1080,"height":576,"url":"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@UNANManagua","twitter_misc":{"Tiempo de lectura":"168 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental","url":"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental","name":"Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental - UNAN-Managua","isPartOf":{"@id":"https:\/\/www.unan.edu.ni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental#primaryimage"},"image":{"@id":"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental#primaryimage"},"thumbnailUrl":"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg","datePublished":"2026-07-14T23:37:37+00:00","dateModified":"2026-07-14T23:46:30+00:00","description":"Espacio t\u00e9cnico cient\u00edfico destinado al desarrollo, validaci\u00f3n y aplicaci\u00f3n de investigaciones, innovaciones y tecnolog\u00edas en el \u00e1mbito socioproductivo. Su prop\u00f3sito es generar, adaptar, validar y transferir conocimientos mediante pr\u00e1cticas experimentales controladas que permiten evaluar sistemas de producci\u00f3n, mejorar procesos, fortalecer la sostenibilidad y promover alternativas tecnol\u00f3gicas pertinentes para el territorio.","breadcrumb":{"@id":"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental#primaryimage","url":"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg","contentUrl":"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg","width":1080,"height":576,"caption":"UNAN-Managua, Marca Institucional"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unan.edu.ni\/index.php\/investigacion-e-innovacion-finca-experimental#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unan.edu.ni\/"},{"@type":"ListItem","position":2,"name":"Investigaci\u00f3n e Innovaci\u00f3n: Finca Experimental"}]},{"@type":"WebSite","@id":"https:\/\/www.unan.edu.ni\/#website","url":"https:\/\/www.unan.edu.ni\/","name":"UNAN-Managua","description":"Universidad Nacional Aut\u00f3noma de Nicaragua","publisher":{"@id":"https:\/\/www.unan.edu.ni\/#organization"},"alternateName":"Universidad Nacional Aut\u00f3noma de Nicaragua","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unan.edu.ni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.unan.edu.ni\/#organization","name":"UNAN-Managua","alternateName":"Universidad Nacional Aut\u00f3noma de Nicaragua","url":"https:\/\/www.unan.edu.ni\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.unan.edu.ni\/#\/schema\/logo\/image\/","url":"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg","contentUrl":"https:\/\/www.unan.edu.ni\/wp-content\/uploads\/unan-managua-marca-institucional-2904202002.jpg","width":1080,"height":576,"caption":"UNAN-Managua"},"image":{"@id":"https:\/\/www.unan.edu.ni\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UNAN.Managua\/","https:\/\/x.com\/UNANManagua","https:\/\/www.instagram.com\/unan.managua\/","https:\/\/www.youtube.com\/@UnanManaguaOficial"]}]}},"jetpack_shortlink":"https:\/\/wp.me\/Pb1ER8-K80","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/pages\/177320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=177320"}],"version-history":[{"count":7,"href":"https:\/\/www.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/pages\/177320\/revisions"}],"predecessor-version":[{"id":177333,"href":"https:\/\/www.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/pages\/177320\/revisions\/177333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/18727"}],"wp:attachment":[{"href":"https:\/\/www.unan.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=177320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}